{"id":476,"date":"2022-10-06T09:46:38","date_gmt":"2022-10-06T07:46:38","guid":{"rendered":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/?p=476"},"modified":"2022-10-06T09:47:48","modified_gmt":"2022-10-06T07:47:48","slug":"mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\/","title":{"rendered":"McDonald\u2019s apre un nuovo punto a Grugliasco e cerca 40 lavoratori"},"content":{"rendered":"<p>Sono aperte le selezioni online per individuare i candidati che parteciperanno alla tappa di Orbassano del McDonald\u2019s Job Tour che si terr\u00e0 nella seconda met\u00e0 di ottobre. Il McDonald\u2019s Job Tour \u00e8 l\u2019evento itinerante di selezione del personale organizzato per le nuove aperture e le assunzioni McDonald\u2019s su tutto il territorio italiano.<!--more--><\/p>\n<p>Voglia di mettersi in gioco, di lavorare in squadra e a contatto con i clienti: queste sono alcune delle principali caratteristiche che l\u2019azienda ricerca nelle persone che lavorano nei suoi ristoranti. McDonald\u2019s offre un\u2019opportunit\u00e0 di lavoro concreta, grazie a contratti stabili (che rappresentano il 92% del totale) e possibilit\u00e0 di crescita professionale rapida, grazie a un programma di formazione strutturato. Entrare in McDonald\u2019s significa lavorare in un contesto dalla forte identit\u00e0 di gruppo, giovane, inclusivo e meritocratico, capace di garantire a tutti i dipendenti le medesime opportunit\u00e0.<\/p>\n<p>Le persone selezionate verranno inserite in un percorso di formazione propedeutico alle mansioni che svolgeranno; verranno inserite con contratti part-time o full-time, in base alle esigenze del ristorante, e inquadrate secondo il contratto nazionale del turismo. La retribuzione \u00e8 quella prevista dallo stesso contratto, chiaramente parametrata al numero di ore lavorative settimanali.<\/p>\n<p>Entro il 16 ottobre, i candidati interessati a lavorare per il nuovo McDonald\u2019s di Orbassano potranno partecipare alla prima fase di selezione sul sito McDonalds.it rispondendo a un questionario e inserendo il proprio cv. Ai candidati idonei verr\u00e0 richiesta la compilazione di un test volto a individuare i punti di forza dei candidati.<\/p>\n<p>Coloro che supereranno il test riceveranno dall\u2019azienda una convocazione con data e orario per partecipare alla tappa del McDonald\u2019s Job Tour, dove avranno accesso ai colloqui individuali. L\u2019evento sar\u00e0 l\u2019occasione per i candidati di raccogliere informazioni sull\u2019azienda e sul lavoro in McDonald\u2019s, direttamente da chi vi \u00e8 coinvolto in prima linea: saranno infatti presenti presone che lavorano nei ristoranti della zona che racconteranno e condivideranno la propria esperienza.<\/p>\n<p>Per la nuova apertura di Orbassano McDonald\u2019s \u00e8 alla ricerca di 40 persone, posizioni che rientrano nel piano di crescita nazionale, che quest\u2019anno prevede l\u2019assunzione di 5.000 nuove persone in tutta Italia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono aperte le selezioni online per individuare i candidati che parteciperanno alla tappa di Orbassano del McDonald\u2019s Job Tour che si terr\u00e0 nella seconda met\u00e0 di ottobre. Il McDonald\u2019s Job Tour \u00e8 l\u2019evento itinerante di selezione del personale organizzato per le nuove aperture e le assunzioni McDonald\u2019s su tutto il territorio italiano.<\/p>\n","protected":false},"author":1,"featured_media":477,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[63],"class_list":["post-476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-offerte-lavoro","tag-mc-donalds"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>McDonald\u2019s apre un nuovo punto a Grugliasco e cerca 40 lavoratori - Offerte di Lavoro in Piemonte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"McDonald\u2019s apre un nuovo punto a Grugliasco e cerca 40 lavoratori - Offerte di Lavoro in Piemonte\" \/>\n<meta property=\"og:description\" content=\"Sono aperte le selezioni online per individuare i candidati che parteciperanno alla tappa di Orbassano del McDonald\u2019s Job Tour che si terr\u00e0 nella seconda met\u00e0 di ottobre. Il McDonald\u2019s Job Tour \u00e8 l\u2019evento itinerante di selezione del personale organizzato per le nuove aperture e le assunzioni McDonald\u2019s su tutto il territorio italiano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\/\" \/>\n<meta property=\"og:site_name\" content=\"Offerte di Lavoro in Piemonte\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-06T07:46:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-06T07:47:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2022\/10\/McDonalds_Quarter_Pounder.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"846\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@quotidianopiem\" \/>\n<meta name=\"twitter:site\" content=\"@quotidianopiem\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"headline\":\"McDonald\u2019s apre un nuovo punto a Grugliasco e cerca 40 lavoratori\",\"datePublished\":\"2022-10-06T07:46:38+00:00\",\"dateModified\":\"2022-10-06T07:47:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\\\/\"},\"wordCount\":366,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/files\\\/2022\\\/10\\\/McDonalds_Quarter_Pounder.jpg\",\"keywords\":[\"mc donald's\"],\"articleSection\":[\"Offerte Lavoro\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\\\/\",\"name\":\"McDonald\u2019s apre un nuovo punto a Grugliasco e cerca 40 lavoratori - Offerte di Lavoro in Piemonte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/files\\\/2022\\\/10\\\/McDonalds_Quarter_Pounder.jpg\",\"datePublished\":\"2022-10-06T07:46:38+00:00\",\"dateModified\":\"2022-10-06T07:47:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/files\\\/2022\\\/10\\\/McDonalds_Quarter_Pounder.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/files\\\/2022\\\/10\\\/McDonalds_Quarter_Pounder.jpg\",\"width\":1200,\"height\":846},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"McDonald\u2019s apre un nuovo punto a Grugliasco e cerca 40 lavoratori\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/\",\"name\":\"Offerte di Lavoro in Piemonte\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte\",\"sameAs\":[\"http:\\\/\\\/www.quotidianopiemontese.it\\\/\",\"https:\\\/\\\/www.facebook.com\\\/quotidianopiemontese\",\"https:\\\/\\\/x.com\\\/quotidianopiem\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/author\\\/administrator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"McDonald\u2019s apre un nuovo punto a Grugliasco e cerca 40 lavoratori - Offerte di Lavoro in Piemonte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\/","og_locale":"it_IT","og_type":"article","og_title":"McDonald\u2019s apre un nuovo punto a Grugliasco e cerca 40 lavoratori - Offerte di Lavoro in Piemonte","og_description":"Sono aperte le selezioni online per individuare i candidati che parteciperanno alla tappa di Orbassano del McDonald\u2019s Job Tour che si terr\u00e0 nella seconda met\u00e0 di ottobre. Il McDonald\u2019s Job Tour \u00e8 l\u2019evento itinerante di selezione del personale organizzato per le nuove aperture e le assunzioni McDonald\u2019s su tutto il territorio italiano.","og_url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\/","og_site_name":"Offerte di Lavoro in Piemonte","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese","article_author":"https:\/\/www.facebook.com\/quotidianopiemontese","article_published_time":"2022-10-06T07:46:38+00:00","article_modified_time":"2022-10-06T07:47:48+00:00","og_image":[{"width":1200,"height":846,"url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2022\/10\/McDonalds_Quarter_Pounder.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@quotidianopiem","twitter_site":"@quotidianopiem","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\/"},"author":{"name":"Redazione","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"headline":"McDonald\u2019s apre un nuovo punto a Grugliasco e cerca 40 lavoratori","datePublished":"2022-10-06T07:46:38+00:00","dateModified":"2022-10-06T07:47:48+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\/"},"wordCount":366,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2022\/10\/McDonalds_Quarter_Pounder.jpg","keywords":["mc donald's"],"articleSection":["Offerte Lavoro"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\/","url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\/","name":"McDonald\u2019s apre un nuovo punto a Grugliasco e cerca 40 lavoratori - Offerte di Lavoro in Piemonte","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2022\/10\/McDonalds_Quarter_Pounder.jpg","datePublished":"2022-10-06T07:46:38+00:00","dateModified":"2022-10-06T07:47:48+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2022\/10\/McDonalds_Quarter_Pounder.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2022\/10\/McDonalds_Quarter_Pounder.jpg","width":1200,"height":846},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-apre-un-nuovo-punto-a-grugliasco-e-cerca-40-lavoratori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/"},{"@type":"ListItem","position":2,"name":"McDonald\u2019s apre un nuovo punto a Grugliasco e cerca 40 lavoratori"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#website","url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/","name":"Offerte di Lavoro in Piemonte","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","caption":"Redazione"},"description":"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte","sameAs":["http:\/\/www.quotidianopiemontese.it\/","https:\/\/www.facebook.com\/quotidianopiemontese","https:\/\/x.com\/quotidianopiem"],"url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/author\/administrator\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/posts\/476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/comments?post=476"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/posts\/476\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/media\/477"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/media?parent=476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/categories?post=476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/tags?post=476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}