{"id":414,"date":"2020-05-30T16:54:30","date_gmt":"2020-05-30T14:54:30","guid":{"rendered":"http:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/?p=414"},"modified":"2020-05-30T16:54:30","modified_gmt":"2020-05-30T14:54:30","slug":"ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\/","title":{"rendered":"Ferrero cerca personale per la sede di Alba &#8211; Ecco le posizioni aperte &#8211;"},"content":{"rendered":"<p>Ferrero\u00a0multinazionale piemontese specializzata in prodotti dolciari, fondata da Pietro Ferrero nel 1946, \u00e8 alla ricerca di personale per la sua sede storia di Alba.<\/p>\n<div class=\"stream-item stream-item-in-post stream-item-inline-post aligncenter\">\n<p>Nello specifico le posizioni aperte sono:<\/p>\n<p><span class=\"jobTitle hidden-phone\"><a class=\"jobTitle-link\" href=\"https:\/\/jobs.ferrero.com\/job\/Alba-Sustainable-Packaging-Design-Specialist\/596143701\/\">Sustainable Packaging Design Specialist<\/a><\/span><\/p>\n<p><span class=\"jobTitle hidden-phone\"><a class=\"jobTitle-link\" href=\"https:\/\/jobs.ferrero.com\/job\/Alba-Junior-Product-Manager-Praline-1-1\/601229401\/\">Junior Product Manager Praline 1 1<\/a><\/span><\/p>\n<p><span class=\"jobTitle hidden-phone\"><a class=\"jobTitle-link\" href=\"https:\/\/jobs.ferrero.com\/job\/Alba-Brand-Manager-Seasonal-Kinder\/601996201\/\">Brand Manager Seasonal Kinder<\/a><\/span><\/p>\n<p><span class=\"jobTitle hidden-phone\"><a class=\"jobTitle-link\" href=\"https:\/\/jobs.ferrero.com\/job\/Alba-Junior-Brand-Manager\/591512501\/\">Junior Brand Manager<\/a><\/span><\/p>\n<p><span class=\"jobTitle hidden-phone\"><a class=\"jobTitle-link\" href=\"https:\/\/jobs.ferrero.com\/job\/Alba-Junior-Supply-Chain-Controller-CN\/598889701\/\">Junior Supply Chain Controller<\/a><\/span><\/p>\n<p><span class=\"jobTitle hidden-phone\"><a class=\"jobTitle-link\" href=\"https:\/\/jobs.ferrero.com\/job\/Alba-Food-regulatory-Specialist-CN\/601733901\/\">Food regulatory Specialist<\/a><\/span><\/p>\n<p><span class=\"jobTitle hidden-phone\"><a class=\"jobTitle-link\" href=\"https:\/\/jobs.ferrero.com\/job\/Alba-Organization-&amp;-Improvement-Project-Manager-CN\/601849601\/\">Organization &amp; Improvement Project Manager<\/a><\/span><\/p>\n<\/div>\n<p>Il tipo di inquadramento contrattuale varia a seconda della posizione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ferrero\u00a0multinazionale piemontese specializzata in prodotti dolciari, fondata da Pietro Ferrero nel 1946, \u00e8 alla ricerca di personale per la sua sede storia di Alba. Nello specifico le posizioni aperte sono: Sustainable Packaging Design Specialist Junior Product Manager Praline 1 1 Brand Manager Seasonal Kinder Junior Brand Manager Junior Supply Chain Controller Food regulatory Specialist Organization &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Ferrero cerca personale per la sede di Alba &#8211; Ecco le posizioni aperte &#8211;&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":112,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[44],"class_list":["post-414","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-offerte-lavoro","tag-ferrero"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ferrero cerca personale per la sede di Alba - Ecco le posizioni aperte - Offerte di Lavoro in Piemonte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferrero cerca personale per la sede di Alba - Ecco le posizioni aperte - Offerte di Lavoro in Piemonte\" \/>\n<meta property=\"og:description\" content=\"Ferrero\u00a0multinazionale piemontese specializzata in prodotti dolciari, fondata da Pietro Ferrero nel 1946, \u00e8 alla ricerca di personale per la sua sede storia di Alba. Nello specifico le posizioni aperte sono: Sustainable Packaging Design Specialist Junior Product Manager Praline 1 1 Brand Manager Seasonal Kinder Junior Brand Manager Junior Supply Chain Controller Food regulatory Specialist Organization &hellip; Leggi tutto &quot;Ferrero cerca personale per la sede di Alba &#8211; Ecco le posizioni aperte &#8211;&quot;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\/\" \/>\n<meta property=\"og:site_name\" content=\"Offerte di Lavoro in Piemonte\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-30T14:54:30+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2017\/03\/1024px-Stadtallendorf_Ferreo_Factory.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"659\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@quotidianopiem\" \/>\n<meta name=\"twitter:site\" content=\"@quotidianopiem\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"headline\":\"Ferrero cerca personale per la sede di Alba &#8211; Ecco le posizioni aperte &#8211;\",\"datePublished\":\"2020-05-30T14:54:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\\\/\"},\"wordCount\":80,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/files\\\/2017\\\/03\\\/1024px-Stadtallendorf_Ferreo_Factory.jpg\",\"keywords\":[\"ferrero\"],\"articleSection\":[\"Offerte Lavoro\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\\\/\",\"name\":\"Ferrero cerca personale per la sede di Alba - Ecco le posizioni aperte - Offerte di Lavoro in Piemonte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/files\\\/2017\\\/03\\\/1024px-Stadtallendorf_Ferreo_Factory.jpg\",\"datePublished\":\"2020-05-30T14:54:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/files\\\/2017\\\/03\\\/1024px-Stadtallendorf_Ferreo_Factory.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/files\\\/2017\\\/03\\\/1024px-Stadtallendorf_Ferreo_Factory.jpg\",\"width\":1024,\"height\":659,\"caption\":\"https:\\\/\\\/it.wikipedia.org\\\/wiki\\\/Ferrero_(azienda)#\\\/media\\\/File:Stadtallendorf_Ferreo_Factory.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ferrero cerca personale per la sede di Alba &#8211; Ecco le posizioni aperte &#8211;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/\",\"name\":\"Offerte di Lavoro in Piemonte\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte\",\"sameAs\":[\"http:\\\/\\\/www.quotidianopiemontese.it\\\/\",\"https:\\\/\\\/www.facebook.com\\\/quotidianopiemontese\",\"https:\\\/\\\/x.com\\\/quotidianopiem\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/author\\\/administrator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ferrero cerca personale per la sede di Alba - Ecco le posizioni aperte - Offerte di Lavoro in Piemonte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\/","og_locale":"it_IT","og_type":"article","og_title":"Ferrero cerca personale per la sede di Alba - Ecco le posizioni aperte - Offerte di Lavoro in Piemonte","og_description":"Ferrero\u00a0multinazionale piemontese specializzata in prodotti dolciari, fondata da Pietro Ferrero nel 1946, \u00e8 alla ricerca di personale per la sua sede storia di Alba. Nello specifico le posizioni aperte sono: Sustainable Packaging Design Specialist Junior Product Manager Praline 1 1 Brand Manager Seasonal Kinder Junior Brand Manager Junior Supply Chain Controller Food regulatory Specialist Organization &hellip; Leggi tutto \"Ferrero cerca personale per la sede di Alba &#8211; Ecco le posizioni aperte &#8211;\"","og_url":"http:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\/","og_site_name":"Offerte di Lavoro in Piemonte","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese","article_author":"https:\/\/www.facebook.com\/quotidianopiemontese","article_published_time":"2020-05-30T14:54:30+00:00","og_image":[{"width":1024,"height":659,"url":"http:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2017\/03\/1024px-Stadtallendorf_Ferreo_Factory.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@quotidianopiem","twitter_site":"@quotidianopiem","twitter_misc":{"Scritto da":"Redazione"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\/"},"author":{"name":"Redazione","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"headline":"Ferrero cerca personale per la sede di Alba &#8211; Ecco le posizioni aperte &#8211;","datePublished":"2020-05-30T14:54:30+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\/"},"wordCount":80,"commentCount":0,"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2017\/03\/1024px-Stadtallendorf_Ferreo_Factory.jpg","keywords":["ferrero"],"articleSection":["Offerte Lavoro"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\/","url":"http:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\/","name":"Ferrero cerca personale per la sede di Alba - Ecco le posizioni aperte - Offerte di Lavoro in Piemonte","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#website"},"primaryImageOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\/#primaryimage"},"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2017\/03\/1024px-Stadtallendorf_Ferreo_Factory.jpg","datePublished":"2020-05-30T14:54:30+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"breadcrumb":{"@id":"http:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2017\/03\/1024px-Stadtallendorf_Ferreo_Factory.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2017\/03\/1024px-Stadtallendorf_Ferreo_Factory.jpg","width":1024,"height":659,"caption":"https:\/\/it.wikipedia.org\/wiki\/Ferrero_(azienda)#\/media\/File:Stadtallendorf_Ferreo_Factory.jpg"},{"@type":"BreadcrumbList","@id":"http:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/ferrero-cerca-personale-per-la-sede-di-alba-ecco-le-posizioni-aperte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/"},{"@type":"ListItem","position":2,"name":"Ferrero cerca personale per la sede di Alba &#8211; Ecco le posizioni aperte &#8211;"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#website","url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/","name":"Offerte di Lavoro in Piemonte","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","caption":"Redazione"},"description":"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte","sameAs":["http:\/\/www.quotidianopiemontese.it\/","https:\/\/www.facebook.com\/quotidianopiemontese","https:\/\/x.com\/quotidianopiem"],"url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/author\/administrator\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/posts\/414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/comments?post=414"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/posts\/414\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/media\/112"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/media?parent=414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/categories?post=414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/tags?post=414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}