{"id":343,"date":"2019-04-26T09:29:09","date_gmt":"2019-04-26T07:29:09","guid":{"rendered":"http:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/?p=343"},"modified":"2019-04-26T09:29:47","modified_gmt":"2019-04-26T07:29:47","slug":"il-21-maggio-job-day-esselunga-a-torino","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-21-maggio-job-day-esselunga-a-torino\/","title":{"rendered":"Il 21 maggio Job Day Esselunga a Torino"},"content":{"rendered":"<p>Il 21 maggio si svolger\u00e0 a Torino il Job Day Esselunga, una giornata dedicata alla conoscenza dell&#8217;azienda ed alla selezione delle figure ricercate sul territorio.<!--more--><\/p>\n<p>&#8220;Partecipando al Job Day, i candidati convocati hanno la possibilit\u00e0 di conoscere la nostra organizzazione, scoprire i percorsi di crescita professionale all\u2019interno dell\u2019azienda e incontrare il nostro team di Selezione: l\u2019iniziativa prevede, infatti, una presentazione della realt\u00e0 Esselunga e, a seguire, i colloqui individuali con i selezionatori.&#8221;<\/p>\n<p><a href=\"https:\/\/www.esselungajob.it\/content\/ejb20\/it\/homepage\/job-day-eventi.html\">Qui le iscrizioni da effetturare entro il 30 aprile<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 21 maggio si svolger\u00e0 a Torino il Job Day Esselunga, una giornata dedicata alla conoscenza dell&#8217;azienda ed alla selezione delle figure ricercate sul territorio.<\/p>\n","protected":false},"author":1,"featured_media":344,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[25],"class_list":["post-343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-offerte-lavoro","tag-esselunga"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il 21 maggio Job Day Esselunga a Torino - Offerte di Lavoro in Piemonte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-21-maggio-job-day-esselunga-a-torino\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il 21 maggio Job Day Esselunga a Torino - Offerte di Lavoro in Piemonte\" \/>\n<meta property=\"og:description\" content=\"Il 21 maggio si svolger\u00e0 a Torino il Job Day Esselunga, una giornata dedicata alla conoscenza dell&#8217;azienda ed alla selezione delle figure ricercate sul territorio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-21-maggio-job-day-esselunga-a-torino\/\" \/>\n<meta property=\"og:site_name\" content=\"Offerte di Lavoro in Piemonte\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-26T07:29:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-26T07:29:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2019\/04\/Job-Day-Esselunga-Torino.png\" \/>\n\t<meta property=\"og:image:width\" content=\"939\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@quotidianopiem\" \/>\n<meta name=\"twitter:site\" content=\"@quotidianopiem\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-21-maggio-job-day-esselunga-a-torino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-21-maggio-job-day-esselunga-a-torino\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"headline\":\"Il 21 maggio Job Day Esselunga a Torino\",\"datePublished\":\"2019-04-26T07:29:09+00:00\",\"dateModified\":\"2019-04-26T07:29:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-21-maggio-job-day-esselunga-a-torino\\\/\"},\"wordCount\":90,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-21-maggio-job-day-esselunga-a-torino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/files\\\/2019\\\/04\\\/Job-Day-Esselunga-Torino.png\",\"keywords\":[\"esselunga\"],\"articleSection\":[\"Offerte Lavoro\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-21-maggio-job-day-esselunga-a-torino\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-21-maggio-job-day-esselunga-a-torino\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-21-maggio-job-day-esselunga-a-torino\\\/\",\"name\":\"Il 21 maggio Job Day Esselunga a Torino - Offerte di Lavoro in Piemonte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-21-maggio-job-day-esselunga-a-torino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-21-maggio-job-day-esselunga-a-torino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/files\\\/2019\\\/04\\\/Job-Day-Esselunga-Torino.png\",\"datePublished\":\"2019-04-26T07:29:09+00:00\",\"dateModified\":\"2019-04-26T07:29:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-21-maggio-job-day-esselunga-a-torino\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-21-maggio-job-day-esselunga-a-torino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-21-maggio-job-day-esselunga-a-torino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/files\\\/2019\\\/04\\\/Job-Day-Esselunga-Torino.png\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/files\\\/2019\\\/04\\\/Job-Day-Esselunga-Torino.png\",\"width\":939,\"height\":340},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-21-maggio-job-day-esselunga-a-torino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il 21 maggio Job Day Esselunga a Torino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/\",\"name\":\"Offerte di Lavoro in Piemonte\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte\",\"sameAs\":[\"http:\\\/\\\/www.quotidianopiemontese.it\\\/\",\"https:\\\/\\\/www.facebook.com\\\/quotidianopiemontese\",\"https:\\\/\\\/x.com\\\/quotidianopiem\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/author\\\/administrator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il 21 maggio Job Day Esselunga a Torino - Offerte di Lavoro in Piemonte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-21-maggio-job-day-esselunga-a-torino\/","og_locale":"it_IT","og_type":"article","og_title":"Il 21 maggio Job Day Esselunga a Torino - Offerte di Lavoro in Piemonte","og_description":"Il 21 maggio si svolger\u00e0 a Torino il Job Day Esselunga, una giornata dedicata alla conoscenza dell&#8217;azienda ed alla selezione delle figure ricercate sul territorio.","og_url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-21-maggio-job-day-esselunga-a-torino\/","og_site_name":"Offerte di Lavoro in Piemonte","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese","article_author":"https:\/\/www.facebook.com\/quotidianopiemontese","article_published_time":"2019-04-26T07:29:09+00:00","article_modified_time":"2019-04-26T07:29:47+00:00","og_image":[{"width":939,"height":340,"url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2019\/04\/Job-Day-Esselunga-Torino.png","type":"image\/png"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@quotidianopiem","twitter_site":"@quotidianopiem","twitter_misc":{"Scritto da":"Redazione"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-21-maggio-job-day-esselunga-a-torino\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-21-maggio-job-day-esselunga-a-torino\/"},"author":{"name":"Redazione","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"headline":"Il 21 maggio Job Day Esselunga a Torino","datePublished":"2019-04-26T07:29:09+00:00","dateModified":"2019-04-26T07:29:47+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-21-maggio-job-day-esselunga-a-torino\/"},"wordCount":90,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-21-maggio-job-day-esselunga-a-torino\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2019\/04\/Job-Day-Esselunga-Torino.png","keywords":["esselunga"],"articleSection":["Offerte Lavoro"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-21-maggio-job-day-esselunga-a-torino\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-21-maggio-job-day-esselunga-a-torino\/","url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-21-maggio-job-day-esselunga-a-torino\/","name":"Il 21 maggio Job Day Esselunga a Torino - Offerte di Lavoro in Piemonte","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-21-maggio-job-day-esselunga-a-torino\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-21-maggio-job-day-esselunga-a-torino\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2019\/04\/Job-Day-Esselunga-Torino.png","datePublished":"2019-04-26T07:29:09+00:00","dateModified":"2019-04-26T07:29:47+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-21-maggio-job-day-esselunga-a-torino\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-21-maggio-job-day-esselunga-a-torino\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-21-maggio-job-day-esselunga-a-torino\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2019\/04\/Job-Day-Esselunga-Torino.png","contentUrl":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2019\/04\/Job-Day-Esselunga-Torino.png","width":939,"height":340},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-21-maggio-job-day-esselunga-a-torino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/"},{"@type":"ListItem","position":2,"name":"Il 21 maggio Job Day Esselunga a Torino"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#website","url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/","name":"Offerte di Lavoro in Piemonte","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","caption":"Redazione"},"description":"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte","sameAs":["http:\/\/www.quotidianopiemontese.it\/","https:\/\/www.facebook.com\/quotidianopiemontese","https:\/\/x.com\/quotidianopiem"],"url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/author\/administrator\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/posts\/343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/comments?post=343"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/posts\/343\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/media\/344"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/media?parent=343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/categories?post=343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/tags?post=343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}