{"id":238,"date":"2018-02-26T15:20:24","date_gmt":"2018-02-26T14:20:24","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/offerte-lavoro-piemonte\/?p=238"},"modified":"2018-02-26T15:23:01","modified_gmt":"2018-02-26T14:23:01","slug":"il-museo-a-come-ambiente-di-torino-cerca-personale","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-museo-a-come-ambiente-di-torino-cerca-personale\/","title":{"rendered":"Il Museo A come Ambiente di Torino cerca personale"},"content":{"rendered":"<p>Il MAcA \u00e8 alla ricerca di personale da dedicare alle attivit\u00e0 di educazione ambientale e per il pubblico.<br \/>\nSe siete interessati a lavorare nell\u2019ambito educativo e possedete i requisiti indicati dovete:<!--more--><\/p>\n<p>inviare il curriculum vitae a: segreteria@acomeambiente.org, oggetto \u201cCall Pilot anno 2018\u201d.<\/p>\n<p>inviare la domanda di partecipazione (Allegato 3) a segreteria@acomeambiente.org<\/p>\n<p>compilare il form<\/p>\n<p>Scadenza: luned\u00ec 12 marzo 2018 ore 10.00<\/p>\n<p>Tutti <a href=\"http:\/\/www.acomeambiente.org\/blog\/2018\/02\/26\/animatori-cercasi-avviso-selezione-pubblica-collaboratori-pilot-2018\/\">i documenti necessari (requisiti, domanda e form) sono sul sito<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il MAcA \u00e8 alla ricerca di personale da dedicare alle attivit\u00e0 di educazione ambientale e per il pubblico. Se siete interessati a lavorare nell\u2019ambito educativo e possedete i requisiti indicati dovete:<\/p>\n","protected":false},"author":1,"featured_media":239,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-238","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-offerte-lavoro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il Museo A come Ambiente di Torino cerca personale - Offerte di Lavoro in Piemonte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-museo-a-come-ambiente-di-torino-cerca-personale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Museo A come Ambiente di Torino cerca personale - Offerte di Lavoro in Piemonte\" \/>\n<meta property=\"og:description\" content=\"Il MAcA \u00e8 alla ricerca di personale da dedicare alle attivit\u00e0 di educazione ambientale e per il pubblico. Se siete interessati a lavorare nell\u2019ambito educativo e possedete i requisiti indicati dovete:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-museo-a-come-ambiente-di-torino-cerca-personale\/\" \/>\n<meta property=\"og:site_name\" content=\"Offerte di Lavoro in Piemonte\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-26T14:20:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-26T14:23:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2018\/02\/a-come-ambiente.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1698\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@quotidianopiem\" \/>\n<meta name=\"twitter:site\" content=\"@quotidianopiem\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-museo-a-come-ambiente-di-torino-cerca-personale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-museo-a-come-ambiente-di-torino-cerca-personale\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"headline\":\"Il Museo A come Ambiente di Torino cerca personale\",\"datePublished\":\"2018-02-26T14:20:24+00:00\",\"dateModified\":\"2018-02-26T14:23:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-museo-a-come-ambiente-di-torino-cerca-personale\\\/\"},\"wordCount\":80,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-museo-a-come-ambiente-di-torino-cerca-personale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/files\\\/2018\\\/02\\\/a-come-ambiente.jpg\",\"articleSection\":[\"Offerte Lavoro\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-museo-a-come-ambiente-di-torino-cerca-personale\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-museo-a-come-ambiente-di-torino-cerca-personale\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-museo-a-come-ambiente-di-torino-cerca-personale\\\/\",\"name\":\"Il Museo A come Ambiente di Torino cerca personale - Offerte di Lavoro in Piemonte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-museo-a-come-ambiente-di-torino-cerca-personale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-museo-a-come-ambiente-di-torino-cerca-personale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/files\\\/2018\\\/02\\\/a-come-ambiente.jpg\",\"datePublished\":\"2018-02-26T14:20:24+00:00\",\"dateModified\":\"2018-02-26T14:23:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-museo-a-come-ambiente-di-torino-cerca-personale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-museo-a-come-ambiente-di-torino-cerca-personale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-museo-a-come-ambiente-di-torino-cerca-personale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/files\\\/2018\\\/02\\\/a-come-ambiente.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/files\\\/2018\\\/02\\\/a-come-ambiente.jpg\",\"width\":1698,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-museo-a-come-ambiente-di-torino-cerca-personale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Museo A come Ambiente di Torino cerca personale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/\",\"name\":\"Offerte di Lavoro in Piemonte\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte\",\"sameAs\":[\"http:\\\/\\\/www.quotidianopiemontese.it\\\/\",\"https:\\\/\\\/www.facebook.com\\\/quotidianopiemontese\",\"https:\\\/\\\/x.com\\\/quotidianopiem\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/author\\\/administrator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Museo A come Ambiente di Torino cerca personale - Offerte di Lavoro in Piemonte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-museo-a-come-ambiente-di-torino-cerca-personale\/","og_locale":"it_IT","og_type":"article","og_title":"Il Museo A come Ambiente di Torino cerca personale - Offerte di Lavoro in Piemonte","og_description":"Il MAcA \u00e8 alla ricerca di personale da dedicare alle attivit\u00e0 di educazione ambientale e per il pubblico. Se siete interessati a lavorare nell\u2019ambito educativo e possedete i requisiti indicati dovete:","og_url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-museo-a-come-ambiente-di-torino-cerca-personale\/","og_site_name":"Offerte di Lavoro in Piemonte","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese","article_author":"https:\/\/www.facebook.com\/quotidianopiemontese","article_published_time":"2018-02-26T14:20:24+00:00","article_modified_time":"2018-02-26T14:23:01+00:00","og_image":[{"width":1698,"height":1500,"url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2018\/02\/a-come-ambiente.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@quotidianopiem","twitter_site":"@quotidianopiem","twitter_misc":{"Scritto da":"Redazione"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-museo-a-come-ambiente-di-torino-cerca-personale\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-museo-a-come-ambiente-di-torino-cerca-personale\/"},"author":{"name":"Redazione","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"headline":"Il Museo A come Ambiente di Torino cerca personale","datePublished":"2018-02-26T14:20:24+00:00","dateModified":"2018-02-26T14:23:01+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-museo-a-come-ambiente-di-torino-cerca-personale\/"},"wordCount":80,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-museo-a-come-ambiente-di-torino-cerca-personale\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2018\/02\/a-come-ambiente.jpg","articleSection":["Offerte Lavoro"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-museo-a-come-ambiente-di-torino-cerca-personale\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-museo-a-come-ambiente-di-torino-cerca-personale\/","url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-museo-a-come-ambiente-di-torino-cerca-personale\/","name":"Il Museo A come Ambiente di Torino cerca personale - Offerte di Lavoro in Piemonte","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-museo-a-come-ambiente-di-torino-cerca-personale\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-museo-a-come-ambiente-di-torino-cerca-personale\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2018\/02\/a-come-ambiente.jpg","datePublished":"2018-02-26T14:20:24+00:00","dateModified":"2018-02-26T14:23:01+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-museo-a-come-ambiente-di-torino-cerca-personale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-museo-a-come-ambiente-di-torino-cerca-personale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-museo-a-come-ambiente-di-torino-cerca-personale\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2018\/02\/a-come-ambiente.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2018\/02\/a-come-ambiente.jpg","width":1698,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-museo-a-come-ambiente-di-torino-cerca-personale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/"},{"@type":"ListItem","position":2,"name":"Il Museo A come Ambiente di Torino cerca personale"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#website","url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/","name":"Offerte di Lavoro in Piemonte","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","caption":"Redazione"},"description":"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte","sameAs":["http:\/\/www.quotidianopiemontese.it\/","https:\/\/www.facebook.com\/quotidianopiemontese","https:\/\/x.com\/quotidianopiem"],"url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/author\/administrator\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/posts\/238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/comments?post=238"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/posts\/238\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/media\/239"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/media?parent=238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/categories?post=238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/tags?post=238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}