{"id":222,"date":"2018-01-16T13:43:04","date_gmt":"2018-01-16T12:43:04","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/offerte-lavoro-piemonte\/?p=222"},"modified":"2018-01-16T13:43:57","modified_gmt":"2018-01-16T12:43:57","slug":"la-torinese-ennova-cerca-500-tecnici-specializzati-2","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\/","title":{"rendered":"La torinese Ennova cerca 500 Tecnici Specializzati"},"content":{"rendered":"<p>La torinese Ennova avvia il potenziamento della propria struttura con il progetto \u201cDigital Transformation\u201d e cerca 500 Tecnici Specializzati per la progettazione, la realizzazione e la gestione di reti di telecomunicazioni,<!--more--> apparati e servizi digitali.<\/p>\n<p>Ennova, l\u2019azienda torinese che ha sviluppato un innovativo modello di assistenza digitale per le imprese che vogliono affrontare la Digital Transformation, annuncia il varo di un piano di ricerca di personale per circa 500 Tecnici Specializzati in tutta Italia.<\/p>\n<p>In particolare, la ricerca \u00e8 indirizzata a:<br \/>\n&#8211; Liberi Professionisti con esperienza nel mondo delle reti connesse e dei servizi Digitali (tecnici installatori, antennisti), con i quali instaurare un rapporto di collaborazione continuativo;<br \/>\n&#8211; Personale giovane, con buona conoscenza di base, da inserire in azienda attraverso uno specifico percorso formativo.<\/p>\n<p>Nata nel 2010 e sviluppata nell\u2019incubatore I3P del Politecnico di Torino, Ennova \u00e8 entrata a novembre 2017 nel programma ELITE: grazie ad un\u2019innovativa piattaforma tecnologica proprietaria, declinata su una macchina operativa di natura industriale che conta oltre 4 milioni di interventi di assistenza tecnica all\u2019anno, i tecnici di Ennova sono in grado di intervenire in modo preventivo sulla rete e su tutti i dispositivi digitali del cliente ad essa collegati. La novit\u00e0 assoluta della Piattaforma One Solution di Ennova \u00e8 quella di consentire la gestione integrata di differenti tipologie di Tecnici, sia da remoto che a casa del cliente.<\/p>\n<p>\u201cProprio in questo ambito si pone la ricerca di personale specializzato\u201d, spiega Giuliano Montebove, Direttore Risorse Umane di Ennova. \u201cIl nostro piano di sviluppo prevede l\u2019inserimento nei prossimi mesi di circa 500 Tecnici Specializzati per completare l\u2019organico. Cerchiamo candidati per le attivit\u00e0 legate agli impianti di telecomunicazione dei clienti consumer e business, dall\u2019installazione alla configurazione delle reti, fino all\u2019assistenza tecnica dei dispositivi digitali.<\/p>\n<p>I tecnici specializzati certificati e abilitati a operare per Ennova prenderanno in carico gli interventi sul territorio, accedendo direttamente attraverso la piattaforma One Solution. La cabina di regia li coordiner\u00e0 e supporter\u00e0 in tutte le fasi, dall\u2019assegnazione delle attivit\u00e0 alla loro gestione fino alla soluzione dell\u2019intervento, interagendo direttamente con il centro di supporto specialistico per eventuali necessit\u00e0. Il cliente, lato suo, potr\u00e0 monitorarne i tempi di arrivo, attraverso il tracking della posizione e del percorso e valutare la qualit\u00e0 dell\u2019intervento, con un semplice sistema di feedback qualitativo.<\/p>\n<p>In questo modo, Ennova intende posizionarsi sul mercato come \u201cinterlocutore unico\u201d in grado di erogare tutti i servizi necessari alla realizzazione e gestione di un ecosistema digitale: dalla rete di accesso all\u2019oggetto digitale connesso<\/p>\n<p>Per proporre la propria candidatura <a href=\"http:\/\/www.ennova.it\">i candidati possono accedere al sito<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La torinese Ennova avvia il potenziamento della propria struttura con il progetto \u201cDigital Transformation\u201d e cerca 500 Tecnici Specializzati per la progettazione, la realizzazione e la gestione di reti di telecomunicazioni,<\/p>\n","protected":false},"author":1,"featured_media":223,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-offerte-lavoro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La torinese Ennova cerca 500 Tecnici Specializzati - Offerte di Lavoro in Piemonte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La torinese Ennova cerca 500 Tecnici Specializzati - Offerte di Lavoro in Piemonte\" \/>\n<meta property=\"og:description\" content=\"La torinese Ennova avvia il potenziamento della propria struttura con il progetto \u201cDigital Transformation\u201d e cerca 500 Tecnici Specializzati per la progettazione, la realizzazione e la gestione di reti di telecomunicazioni,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Offerte di Lavoro in Piemonte\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-16T12:43:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-01-16T12:43:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2018\/01\/ennova.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@quotidianopiem\" \/>\n<meta name=\"twitter:site\" content=\"@quotidianopiem\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"headline\":\"La torinese Ennova cerca 500 Tecnici Specializzati\",\"datePublished\":\"2018-01-16T12:43:04+00:00\",\"dateModified\":\"2018-01-16T12:43:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\\\/\"},\"wordCount\":428,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/files\\\/2018\\\/01\\\/ennova.jpg\",\"articleSection\":[\"Offerte Lavoro\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\\\/\",\"name\":\"La torinese Ennova cerca 500 Tecnici Specializzati - Offerte di Lavoro in Piemonte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/files\\\/2018\\\/01\\\/ennova.jpg\",\"datePublished\":\"2018-01-16T12:43:04+00:00\",\"dateModified\":\"2018-01-16T12:43:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/files\\\/2018\\\/01\\\/ennova.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/files\\\/2018\\\/01\\\/ennova.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La torinese Ennova cerca 500 Tecnici Specializzati\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/\",\"name\":\"Offerte di Lavoro in Piemonte\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte\",\"sameAs\":[\"http:\\\/\\\/www.quotidianopiemontese.it\\\/\",\"https:\\\/\\\/www.facebook.com\\\/quotidianopiemontese\",\"https:\\\/\\\/x.com\\\/quotidianopiem\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/author\\\/administrator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La torinese Ennova cerca 500 Tecnici Specializzati - Offerte di Lavoro in Piemonte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\/","og_locale":"it_IT","og_type":"article","og_title":"La torinese Ennova cerca 500 Tecnici Specializzati - Offerte di Lavoro in Piemonte","og_description":"La torinese Ennova avvia il potenziamento della propria struttura con il progetto \u201cDigital Transformation\u201d e cerca 500 Tecnici Specializzati per la progettazione, la realizzazione e la gestione di reti di telecomunicazioni,","og_url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\/","og_site_name":"Offerte di Lavoro in Piemonte","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese","article_author":"https:\/\/www.facebook.com\/quotidianopiemontese","article_published_time":"2018-01-16T12:43:04+00:00","article_modified_time":"2018-01-16T12:43:57+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2018\/01\/ennova.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@quotidianopiem","twitter_site":"@quotidianopiem","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\/"},"author":{"name":"Redazione","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"headline":"La torinese Ennova cerca 500 Tecnici Specializzati","datePublished":"2018-01-16T12:43:04+00:00","dateModified":"2018-01-16T12:43:57+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\/"},"wordCount":428,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2018\/01\/ennova.jpg","articleSection":["Offerte Lavoro"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\/","url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\/","name":"La torinese Ennova cerca 500 Tecnici Specializzati - Offerte di Lavoro in Piemonte","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2018\/01\/ennova.jpg","datePublished":"2018-01-16T12:43:04+00:00","dateModified":"2018-01-16T12:43:57+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2018\/01\/ennova.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2018\/01\/ennova.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/la-torinese-ennova-cerca-500-tecnici-specializzati-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/"},{"@type":"ListItem","position":2,"name":"La torinese Ennova cerca 500 Tecnici Specializzati"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#website","url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/","name":"Offerte di Lavoro in Piemonte","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","caption":"Redazione"},"description":"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte","sameAs":["http:\/\/www.quotidianopiemontese.it\/","https:\/\/www.facebook.com\/quotidianopiemontese","https:\/\/x.com\/quotidianopiem"],"url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/author\/administrator\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/posts\/222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/comments?post=222"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/posts\/222\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/media\/223"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/media?parent=222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/categories?post=222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/tags?post=222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}