{"id":151,"date":"2017-07-20T10:52:43","date_gmt":"2017-07-20T08:52:43","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/offerte-lavoro-piemonte\/?p=151"},"modified":"2017-07-20T10:55:33","modified_gmt":"2017-07-20T08:55:33","slug":"mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\/","title":{"rendered":"McDonald&#8217;s cerca addetti alla ristorazione per nuova apertura dentro Mondo Juve"},"content":{"rendered":"<p>McDonald&#8217;s apre un nuovo fast food a Nichelino, all&#8217;interno di Mondo Juve, ed \u00e8 alla ricerca di addetti alla ristorazione veloce. Cuore pulsante del ristorante, l&#8217;Addetto\/a Ristorazione Veloce \u00e8 parte di una squadra affiatata che accoglie i Clienti alla cassa<!--more--> o in sala e svolge, nel rispetto degli standard di pulizia, qualit\u00e0, igiene e sicurezza, tutte le attivit\u00e0 operative finalizzate alla preparazione, conservazione e vendita del prodotto. E\u2019 responsabile della qualit\u00e0 e del servizio al Cliente.<\/p>\n<p>Descrizione della posizione:<\/p>\n<p>Accoglie il Cliente, lo segue nell\u2019ordinazione e nel pagamento. Prepara con competenza i prodotti e li consegna al Cliente;<br \/>\nPrepara, rispettando le procedure, tutti i prodotti per la vendita al pubblico;<br \/>\nSegue le procedure aziendali per mantenere costantemente alti standard di pulizia e igiene;<br \/>\nConosce e rispetta le procedure di conservazione e di avvicendamento dei prodotti nell\u2019armadietto di transizione, nell\u2019area di stoccaggio e nelle celle frigorifere;<br \/>\nEsegue nel rispetto delle procedure tutte le attivit\u00e0 previste nelle postazioni Cucina, Cassa, McCaf\u00e9, Cassa Automatica, Delivery e Magazzino.<\/p>\n<p>Requisiti:<\/p>\n<p>Diploma di scuola media superiore<br \/>\nDomicilio nelle vicinanze della sede di lavoro;<br \/>\nOttime doti relazionali;<br \/>\nOrientamento al teamworking;<br \/>\nFlessibilit\u00e0 e disponibilit\u00e0 a lavorare su turni, durante i weekend e giorni festivi<\/p>\n<p>Le candidature vanno <a href=\"http:\/\/offerte-lavoro.monster.it\/addetti-ristorazione-veloce-mcdonald's-torino-nichelino-offerta-lavoro-nichelino-piemonte-185861482.aspx?mescoid=3500611001001&amp;jobPosition=1\">inviate al sito<\/a> oppure \u00e8 necessario presentarsi, muniti di curriculum vitae, al Mc di Moncalieri marted\u00ec 25 luglio (tra le 10.30 e le 12.30 e tra le 14.30 e le 16.30) o al Mc di Torino \u2013 piazza Castello gioved\u00ec 26 luglio negli stessi orari.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>McDonald&#8217;s apre un nuovo fast food a Nichelino, all&#8217;interno di Mondo Juve, ed \u00e8 alla ricerca di addetti alla ristorazione veloce. Cuore pulsante del ristorante, l&#8217;Addetto\/a Ristorazione Veloce \u00e8 parte di una squadra affiatata che accoglie i Clienti alla cassa<\/p>\n","protected":false},"author":1,"featured_media":152,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-offerte-lavoro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>McDonald&#039;s cerca addetti alla ristorazione per nuova apertura dentro Mondo Juve - Offerte di Lavoro in Piemonte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"McDonald&#039;s cerca addetti alla ristorazione per nuova apertura dentro Mondo Juve - Offerte di Lavoro in Piemonte\" \/>\n<meta property=\"og:description\" content=\"McDonald&#8217;s apre un nuovo fast food a Nichelino, all&#8217;interno di Mondo Juve, ed \u00e8 alla ricerca di addetti alla ristorazione veloce. Cuore pulsante del ristorante, l&#8217;Addetto\/a Ristorazione Veloce \u00e8 parte di una squadra affiatata che accoglie i Clienti alla cassa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\/\" \/>\n<meta property=\"og:site_name\" content=\"Offerte di Lavoro in Piemonte\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-20T08:52:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-07-20T08:55:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2017\/07\/lavoro-mcdonalds.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"399\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@quotidianopiem\" \/>\n<meta name=\"twitter:site\" content=\"@quotidianopiem\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"headline\":\"McDonald&#8217;s cerca addetti alla ristorazione per nuova apertura dentro Mondo Juve\",\"datePublished\":\"2017-07-20T08:52:43+00:00\",\"dateModified\":\"2017-07-20T08:55:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\\\/\"},\"wordCount\":253,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/files\\\/2017\\\/07\\\/lavoro-mcdonalds.jpg\",\"articleSection\":[\"Offerte Lavoro\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\\\/\",\"name\":\"McDonald's cerca addetti alla ristorazione per nuova apertura dentro Mondo Juve - Offerte di Lavoro in Piemonte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/files\\\/2017\\\/07\\\/lavoro-mcdonalds.jpg\",\"datePublished\":\"2017-07-20T08:52:43+00:00\",\"dateModified\":\"2017-07-20T08:55:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/files\\\/2017\\\/07\\\/lavoro-mcdonalds.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/files\\\/2017\\\/07\\\/lavoro-mcdonalds.jpg\",\"width\":600,\"height\":399},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"McDonald&#8217;s cerca addetti alla ristorazione per nuova apertura dentro Mondo Juve\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/\",\"name\":\"Offerte di Lavoro in Piemonte\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte\",\"sameAs\":[\"http:\\\/\\\/www.quotidianopiemontese.it\\\/\",\"https:\\\/\\\/www.facebook.com\\\/quotidianopiemontese\",\"https:\\\/\\\/x.com\\\/quotidianopiem\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/author\\\/administrator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"McDonald's cerca addetti alla ristorazione per nuova apertura dentro Mondo Juve - Offerte di Lavoro in Piemonte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\/","og_locale":"it_IT","og_type":"article","og_title":"McDonald's cerca addetti alla ristorazione per nuova apertura dentro Mondo Juve - Offerte di Lavoro in Piemonte","og_description":"McDonald&#8217;s apre un nuovo fast food a Nichelino, all&#8217;interno di Mondo Juve, ed \u00e8 alla ricerca di addetti alla ristorazione veloce. Cuore pulsante del ristorante, l&#8217;Addetto\/a Ristorazione Veloce \u00e8 parte di una squadra affiatata che accoglie i Clienti alla cassa","og_url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\/","og_site_name":"Offerte di Lavoro in Piemonte","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese","article_author":"https:\/\/www.facebook.com\/quotidianopiemontese","article_published_time":"2017-07-20T08:52:43+00:00","article_modified_time":"2017-07-20T08:55:33+00:00","og_image":[{"width":600,"height":399,"url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2017\/07\/lavoro-mcdonalds.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@quotidianopiem","twitter_site":"@quotidianopiem","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\/"},"author":{"name":"Redazione","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"headline":"McDonald&#8217;s cerca addetti alla ristorazione per nuova apertura dentro Mondo Juve","datePublished":"2017-07-20T08:52:43+00:00","dateModified":"2017-07-20T08:55:33+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\/"},"wordCount":253,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2017\/07\/lavoro-mcdonalds.jpg","articleSection":["Offerte Lavoro"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\/","url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\/","name":"McDonald's cerca addetti alla ristorazione per nuova apertura dentro Mondo Juve - Offerte di Lavoro in Piemonte","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2017\/07\/lavoro-mcdonalds.jpg","datePublished":"2017-07-20T08:52:43+00:00","dateModified":"2017-07-20T08:55:33+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2017\/07\/lavoro-mcdonalds.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2017\/07\/lavoro-mcdonalds.jpg","width":600,"height":399},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/mcdonalds-cerca-addetti-alla-ristorazione-per-nuova-apertura-dentro-mondo-juve\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/"},{"@type":"ListItem","position":2,"name":"McDonald&#8217;s cerca addetti alla ristorazione per nuova apertura dentro Mondo Juve"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#website","url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/","name":"Offerte di Lavoro in Piemonte","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","caption":"Redazione"},"description":"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte","sameAs":["http:\/\/www.quotidianopiemontese.it\/","https:\/\/www.facebook.com\/quotidianopiemontese","https:\/\/x.com\/quotidianopiem"],"url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/author\/administrator\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/posts\/151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/comments?post=151"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/posts\/151\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/media\/152"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/media?parent=151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/categories?post=151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/tags?post=151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}