{"id":293,"date":"2015-09-30T09:09:50","date_gmt":"2015-09-30T09:09:50","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/lamiaeuropa\/?p=293"},"modified":"2015-09-30T09:09:50","modified_gmt":"2015-09-30T09:09:50","slug":"ue-50-milioni-di-euro-per-giovani-agricoltori","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/ue-50-milioni-di-euro-per-giovani-agricoltori\/","title":{"rendered":"UE: 50 milioni di euro per giovani agricoltori"},"content":{"rendered":"<p><a href=\"http:\/\/www.quotidianopiemontese.it\/lamiaeuropa\/files\/2015\/01\/mietitura.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-67 alignright\" src=\"http:\/\/www.quotidianopiemontese.it\/lamiaeuropa\/files\/2015\/01\/mietitura-300x225.jpg\" alt=\"mietitura\" width=\"300\" height=\"225\" srcset=\"https:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/files\/2015\/01\/mietitura-300x225.jpg 300w, https:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/files\/2015\/01\/mietitura-1024x770.jpg 1024w, https:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/files\/2015\/01\/mietitura.jpg 1280w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/a>\u00a0Il Consiglio di Amministrazione della Banca Europea degli Investimenti (BEI) ha autorizzato la concessione all&#8217;<acronym title=\"Istituto di Servizi per Mercato Agricolo Alimentare\">ISMEA (Istituto di servizi per il mercato agricolo alimentare)\u00a0<\/acronym> di una prima linea di credito di 50 milioni di euro. Questi soldi saranno destinati\u00a0finanziamento di iniziative di start-up e ampliamento di imprese agricole da parte di agricoltori che siano under 40. I giovani imprenditori agricoli potranno utilizzare tali fondi in particolare per\u00a0investimenti destinati al miglioramento dell&#8217;efficienza aziendale, all&#8217;internazionalizzazione e al commercio elettronico.<\/p>\n<p>Nelle prossime settimane verranno definite le modalit\u00e0 di intervento dell&#8217;Istituto e potranno essere avviate le prime istruttorie di fido da parte dell&#8217;<acronym title=\"Istituto di Servizi per Mercato Agricolo Alimentare\">ISMEA<\/acronym>.<\/p>\n<p>Si tratta di una importante occasione per il nostro territorio che pu\u00f2 essere utile per molti dei giovani imprenditori agricoli che incontro spesso quando visito le aziende piemontesi e che si contraddistinguono per il loro entusiasmo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Il Consiglio di Amministrazione della Banca Europea degli Investimenti (BEI) ha autorizzato la concessione all&#8217;ISMEA (Istituto di servizi per il mercato agricolo alimentare)\u00a0 di una prima linea di credito di 50 milioni di euro. Questi soldi saranno destinati\u00a0finanziamento di iniziative di start-up e ampliamento di imprese agricole da parte di agricoltori che siano under 40. &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/ue-50-milioni-di-euro-per-giovani-agricoltori\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;UE: 50 milioni di euro per giovani agricoltori&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1286,"featured_media":67,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[83,1,82],"tags":[30,221,7,220,25,223,222],"class_list":["post-293","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europaenoi","category-europa","category-mercedes-bresso","tag-agricoltura","tag-banca-europea-degli-investimenti","tag-bei","tag-finanziamenti","tag-giovani","tag-ismea","tag-istituto-di-servizi-per-il-mercato-agricolo-alimentare"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UE: 50 milioni di euro per giovani agricoltori - La Mia Europa<\/title>\n<meta name=\"description\" content=\"50 milioni di euro destinati finanziamento di iniziative di start-up e ampliamento di imprese agricole da parte di agricoltori che siano under 40.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/ue-50-milioni-di-euro-per-giovani-agricoltori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UE: 50 milioni di euro per giovani agricoltori - La Mia Europa\" \/>\n<meta property=\"og:description\" content=\"50 milioni di euro destinati finanziamento di iniziative di start-up e ampliamento di imprese agricole da parte di agricoltori che siano under 40.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/ue-50-milioni-di-euro-per-giovani-agricoltori\/\" \/>\n<meta property=\"og:site_name\" content=\"La Mia Europa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-30T09:09:50+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/files\/2015\/01\/mietitura.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"963\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mbresso\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mbresso\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/lamiaeuropa\\\/ue-50-milioni-di-euro-per-giovani-agricoltori\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/lamiaeuropa\\\/ue-50-milioni-di-euro-per-giovani-agricoltori\\\/\"},\"author\":{\"name\":\"mbresso\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/lamiaeuropa\\\/#\\\/schema\\\/person\\\/5404bf635e12249c5640961478ce882a\"},\"headline\":\"UE: 50 milioni di euro per giovani agricoltori\",\"datePublished\":\"2015-09-30T09:09:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/lamiaeuropa\\\/ue-50-milioni-di-euro-per-giovani-agricoltori\\\/\"},\"wordCount\":146,\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/lamiaeuropa\\\/ue-50-milioni-di-euro-per-giovani-agricoltori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/lamiaeuropa\\\/files\\\/2015\\\/01\\\/mietitura.jpg\",\"keywords\":[\"agricoltura\",\"Banca Europea degli Investimenti\",\"Bei\",\"finanziamenti\",\"giovani\",\"ISMEA\",\"Istituto di servizi per il mercato agricolo alimentare\"],\"articleSection\":[\"#EuropaeNoi\",\"Europa\",\"Mercedes Bresso\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/lamiaeuropa\\\/ue-50-milioni-di-euro-per-giovani-agricoltori\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/lamiaeuropa\\\/ue-50-milioni-di-euro-per-giovani-agricoltori\\\/\",\"name\":\"UE: 50 milioni di euro per giovani agricoltori - La Mia Europa\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/lamiaeuropa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/lamiaeuropa\\\/ue-50-milioni-di-euro-per-giovani-agricoltori\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/lamiaeuropa\\\/ue-50-milioni-di-euro-per-giovani-agricoltori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/lamiaeuropa\\\/files\\\/2015\\\/01\\\/mietitura.jpg\",\"datePublished\":\"2015-09-30T09:09:50+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/lamiaeuropa\\\/#\\\/schema\\\/person\\\/5404bf635e12249c5640961478ce882a\"},\"description\":\"50 milioni di euro destinati finanziamento di iniziative di start-up e ampliamento di imprese agricole da parte di agricoltori che siano under 40.\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/lamiaeuropa\\\/ue-50-milioni-di-euro-per-giovani-agricoltori\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/lamiaeuropa\\\/ue-50-milioni-di-euro-per-giovani-agricoltori\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/lamiaeuropa\\\/files\\\/2015\\\/01\\\/mietitura.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/lamiaeuropa\\\/files\\\/2015\\\/01\\\/mietitura.jpg\",\"width\":1280,\"height\":963},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/lamiaeuropa\\\/#website\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/lamiaeuropa\\\/\",\"name\":\"La Mia Europa\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/lamiaeuropa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/lamiaeuropa\\\/#\\\/schema\\\/person\\\/5404bf635e12249c5640961478ce882a\",\"name\":\"mbresso\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9c678a6a55ec881e51c1e353dd3bb7f0a51c47da6fc0e8df34d8deb93ec8463?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9c678a6a55ec881e51c1e353dd3bb7f0a51c47da6fc0e8df34d8deb93ec8463?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9c678a6a55ec881e51c1e353dd3bb7f0a51c47da6fc0e8df34d8deb93ec8463?s=96&d=mm&r=g\",\"caption\":\"mbresso\"},\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/lamiaeuropa\\\/author\\\/mbresso\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UE: 50 milioni di euro per giovani agricoltori - La Mia Europa","description":"50 milioni di euro destinati finanziamento di iniziative di start-up e ampliamento di imprese agricole da parte di agricoltori che siano under 40.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/ue-50-milioni-di-euro-per-giovani-agricoltori\/","og_locale":"it_IT","og_type":"article","og_title":"UE: 50 milioni di euro per giovani agricoltori - La Mia Europa","og_description":"50 milioni di euro destinati finanziamento di iniziative di start-up e ampliamento di imprese agricole da parte di agricoltori che siano under 40.","og_url":"http:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/ue-50-milioni-di-euro-per-giovani-agricoltori\/","og_site_name":"La Mia Europa","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2015-09-30T09:09:50+00:00","og_image":[{"width":1280,"height":963,"url":"http:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/files\/2015\/01\/mietitura.jpg","type":"image\/jpeg"}],"author":"mbresso","twitter_misc":{"Scritto da":"mbresso","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/ue-50-milioni-di-euro-per-giovani-agricoltori\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/ue-50-milioni-di-euro-per-giovani-agricoltori\/"},"author":{"name":"mbresso","@id":"http:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/#\/schema\/person\/5404bf635e12249c5640961478ce882a"},"headline":"UE: 50 milioni di euro per giovani agricoltori","datePublished":"2015-09-30T09:09:50+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/ue-50-milioni-di-euro-per-giovani-agricoltori\/"},"wordCount":146,"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/ue-50-milioni-di-euro-per-giovani-agricoltori\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/files\/2015\/01\/mietitura.jpg","keywords":["agricoltura","Banca Europea degli Investimenti","Bei","finanziamenti","giovani","ISMEA","Istituto di servizi per il mercato agricolo alimentare"],"articleSection":["#EuropaeNoi","Europa","Mercedes Bresso"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/ue-50-milioni-di-euro-per-giovani-agricoltori\/","url":"http:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/ue-50-milioni-di-euro-per-giovani-agricoltori\/","name":"UE: 50 milioni di euro per giovani agricoltori - La Mia Europa","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/#website"},"primaryImageOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/ue-50-milioni-di-euro-per-giovani-agricoltori\/#primaryimage"},"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/ue-50-milioni-di-euro-per-giovani-agricoltori\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/files\/2015\/01\/mietitura.jpg","datePublished":"2015-09-30T09:09:50+00:00","author":{"@id":"http:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/#\/schema\/person\/5404bf635e12249c5640961478ce882a"},"description":"50 milioni di euro destinati finanziamento di iniziative di start-up e ampliamento di imprese agricole da parte di agricoltori che siano under 40.","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/ue-50-milioni-di-euro-per-giovani-agricoltori\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/ue-50-milioni-di-euro-per-giovani-agricoltori\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/files\/2015\/01\/mietitura.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/files\/2015\/01\/mietitura.jpg","width":1280,"height":963},{"@type":"WebSite","@id":"http:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/#website","url":"http:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/","name":"La Mia Europa","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/#\/schema\/person\/5404bf635e12249c5640961478ce882a","name":"mbresso","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e9c678a6a55ec881e51c1e353dd3bb7f0a51c47da6fc0e8df34d8deb93ec8463?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e9c678a6a55ec881e51c1e353dd3bb7f0a51c47da6fc0e8df34d8deb93ec8463?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e9c678a6a55ec881e51c1e353dd3bb7f0a51c47da6fc0e8df34d8deb93ec8463?s=96&d=mm&r=g","caption":"mbresso"},"url":"https:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/author\/mbresso\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/wp-json\/wp\/v2\/posts\/293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/wp-json\/wp\/v2\/users\/1286"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/wp-json\/wp\/v2\/comments?post=293"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/wp-json\/wp\/v2\/posts\/293\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/wp-json\/wp\/v2\/media\/67"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/wp-json\/wp\/v2\/media?parent=293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/wp-json\/wp\/v2\/categories?post=293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/lamiaeuropa\/wp-json\/wp\/v2\/tags?post=293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}