{"id":35,"date":"2018-11-23T13:36:07","date_gmt":"2018-11-23T12:36:07","guid":{"rendered":"http:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/?p=35"},"modified":"2018-11-23T13:36:07","modified_gmt":"2018-11-23T12:36:07","slug":"cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\/","title":{"rendered":"Cambiano le regole in tema di recesso dai contratti di telefonia, internet e pay tv"},"content":{"rendered":"<p>Buone nuove per gli utenti di servizi di telefonia, televisivi e di comunicazione elettronica.<\/p>\n<p>Con l\u2019adozione delle nuove Linee Guida, pubblicate con la delibera n. 487\/18, l\u2019Autorit\u00e0 per le Garanzie nelle Comunicazioni ha introdotto importanti novit\u00e0 in tema di recesso e\/o passaggio dell\u2019utenza ad altro operatore.<\/p>\n<p>La prima novit\u00e0 riguarda la <u>facolt\u00e0 di recesso o di trasferimento<\/u> delle utenze presso altro operatore, gi\u00e0 riconosciuta dal c.d. Decreto Bersani (D.L. n. 7\/2007): grazie alle nuove linee guida, l\u2019utente non perde tale facolt\u00e0 con il passare del tempo e potr\u00e0 da oggi esercitarla in ogni momento, <u>senza alcun limite temporale<\/u>, fatto salvo l\u2019obbligo di preavviso che non potr\u00e0 per\u00f2 essere superiore a 30 giorni.<\/p>\n<p>La seconda importante novit\u00e0 \u00e8 rappresentata dall\u2019applicazione dei principi di equit\u00e0 e di proporzionalit\u00e0 al regime delle spese che vengono addebitate agli utenti in caso di recesso e\/o trasferimento ad altro operatore.<\/p>\n<p>L\u2019Autorit\u00e0, infatti, pone un freno alla possibilit\u00e0 per gli operatori di innalzarle a dismisura, precisando che \u201c<em>le spese di recesso devono essere eque e proporzionate al valore del contratto e alla durata residua della promozione offerta<\/em>\u201d e anche nel caso in cui all\u2019utente debbano essere addebitati gli sconti di cui ha beneficiato in sede di attivazione, questi dovranno essere commisurati al valore del contratto nonch\u00e9 essere equi e <u>proporzionali alla durata residua dell\u2019eventuale promozione<\/u>.<\/p>\n<p>Inoltre, le Linee Guida specificano che ogni operatore in fase di sottoscrizione del contratto, ha l\u2019obbligo di rendere note verbalmente e attraverso idonea informativa \u2013 chiara e sintetica \u2013 da allegare al contratto, tutte le spese che l\u2019utente dovr\u00e0 sostenere in corrispondenza di ogni mese in cui il recesso potrebbe essere esercitato.<\/p>\n<p>Infine, con riferimento al credito residuo presente sulla SIM in caso di trasferimento ad altro operatore, l\u2019Autorit\u00e0 chiarisce che \u201c<em>a seguito dello scioglimento del rapporto contrattuale per qualsiasi causa il cliente ha diritto al riconoscimento dell\u2019eventuale credito residuo<\/em>\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Dott.ssa Rossana Tirenna<\/p>\n<p><a href=\"http:\/\/www.studiolegalefranzettadassano.it\">Studio Legale Franzetta Dassano<\/a><\/p>\n<p><em>&#8211; Riproduzione Riservata &#8211;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buone nuove per gli utenti di servizi di telefonia, televisivi e di comunicazione elettronica. Con l\u2019adozione delle nuove Linee Guida, pubblicate con la delibera n. 487\/18, l\u2019Autorit\u00e0 per le Garanzie nelle Comunicazioni ha introdotto importanti novit\u00e0 in tema di recesso e\/o passaggio dell\u2019utenza ad altro operatore. La prima novit\u00e0 riguarda la facolt\u00e0 di recesso o &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Cambiano le regole in tema di recesso dai contratti di telefonia, internet e pay tv&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1365,"featured_media":16,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-35","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diritto-del-consumo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cambiano le regole in tema di recesso dai contratti di telefonia, internet e pay tv - Il diritto intorno al cittadino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cambiano le regole in tema di recesso dai contratti di telefonia, internet e pay tv - Il diritto intorno al cittadino\" \/>\n<meta property=\"og:description\" content=\"Buone nuove per gli utenti di servizi di telefonia, televisivi e di comunicazione elettronica. Con l\u2019adozione delle nuove Linee Guida, pubblicate con la delibera n. 487\/18, l\u2019Autorit\u00e0 per le Garanzie nelle Comunicazioni ha introdotto importanti novit\u00e0 in tema di recesso e\/o passaggio dell\u2019utenza ad altro operatore. La prima novit\u00e0 riguarda la facolt\u00e0 di recesso o &hellip; Leggi tutto &quot;Cambiano le regole in tema di recesso dai contratti di telefonia, internet e pay tv&quot;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\/\" \/>\n<meta property=\"og:site_name\" content=\"Il diritto intorno al cittadino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-23T12:36:07+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/files\/2018\/05\/stemma-studio-nuovo-vettoriale.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"492\" \/>\n\t<meta property=\"og:image:height\" content=\"354\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Studio Legale Franzetta Dassano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@quotidianopiem\" \/>\n<meta name=\"twitter:site\" content=\"@quotidianopiem\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Studio Legale Franzetta Dassano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-diritto-intorno-al-cittadino\\\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-diritto-intorno-al-cittadino\\\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\\\/\"},\"author\":{\"name\":\"Studio Legale Franzetta Dassano\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-diritto-intorno-al-cittadino\\\/#\\\/schema\\\/person\\\/c1cfca91710b50f8e941e22f05a1ab8e\"},\"headline\":\"Cambiano le regole in tema di recesso dai contratti di telefonia, internet e pay tv\",\"datePublished\":\"2018-11-23T12:36:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-diritto-intorno-al-cittadino\\\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\\\/\"},\"wordCount\":346,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-diritto-intorno-al-cittadino\\\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/il-diritto-intorno-al-cittadino\\\/files\\\/2018\\\/05\\\/stemma-studio-nuovo-vettoriale.jpeg\",\"articleSection\":[\"Diritto del Consumo\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-diritto-intorno-al-cittadino\\\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-diritto-intorno-al-cittadino\\\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-diritto-intorno-al-cittadino\\\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\\\/\",\"name\":\"Cambiano le regole in tema di recesso dai contratti di telefonia, internet e pay tv - Il diritto intorno al cittadino\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-diritto-intorno-al-cittadino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-diritto-intorno-al-cittadino\\\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-diritto-intorno-al-cittadino\\\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/il-diritto-intorno-al-cittadino\\\/files\\\/2018\\\/05\\\/stemma-studio-nuovo-vettoriale.jpeg\",\"datePublished\":\"2018-11-23T12:36:07+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-diritto-intorno-al-cittadino\\\/#\\\/schema\\\/person\\\/c1cfca91710b50f8e941e22f05a1ab8e\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-diritto-intorno-al-cittadino\\\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-diritto-intorno-al-cittadino\\\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-diritto-intorno-al-cittadino\\\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/il-diritto-intorno-al-cittadino\\\/files\\\/2018\\\/05\\\/stemma-studio-nuovo-vettoriale.jpeg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/il-diritto-intorno-al-cittadino\\\/files\\\/2018\\\/05\\\/stemma-studio-nuovo-vettoriale.jpeg\",\"width\":492,\"height\":354},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-diritto-intorno-al-cittadino\\\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-diritto-intorno-al-cittadino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cambiano le regole in tema di recesso dai contratti di telefonia, internet e pay tv\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-diritto-intorno-al-cittadino\\\/#website\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-diritto-intorno-al-cittadino\\\/\",\"name\":\"Il diritto intorno al cittadino\",\"description\":\"Ecco un altro sito Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-diritto-intorno-al-cittadino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-diritto-intorno-al-cittadino\\\/#\\\/schema\\\/person\\\/c1cfca91710b50f8e941e22f05a1ab8e\",\"name\":\"Studio Legale Franzetta Dassano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94ef3983eb695cdbc529c6d5d4188111528edb9efa0630a17d02ab709449b1dd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94ef3983eb695cdbc529c6d5d4188111528edb9efa0630a17d02ab709449b1dd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94ef3983eb695cdbc529c6d5d4188111528edb9efa0630a17d02ab709449b1dd?s=96&d=mm&r=g\",\"caption\":\"Studio Legale Franzetta Dassano\"},\"sameAs\":[\"http:\\\/\\\/www.studiolegalefranzettadassano.it\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/il-diritto-intorno-al-cittadino\\\/author\\\/studiolegalefranzettadassano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cambiano le regole in tema di recesso dai contratti di telefonia, internet e pay tv - Il diritto intorno al cittadino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\/","og_locale":"it_IT","og_type":"article","og_title":"Cambiano le regole in tema di recesso dai contratti di telefonia, internet e pay tv - Il diritto intorno al cittadino","og_description":"Buone nuove per gli utenti di servizi di telefonia, televisivi e di comunicazione elettronica. Con l\u2019adozione delle nuove Linee Guida, pubblicate con la delibera n. 487\/18, l\u2019Autorit\u00e0 per le Garanzie nelle Comunicazioni ha introdotto importanti novit\u00e0 in tema di recesso e\/o passaggio dell\u2019utenza ad altro operatore. La prima novit\u00e0 riguarda la facolt\u00e0 di recesso o &hellip; Leggi tutto \"Cambiano le regole in tema di recesso dai contratti di telefonia, internet e pay tv\"","og_url":"http:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\/","og_site_name":"Il diritto intorno al cittadino","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese","article_published_time":"2018-11-23T12:36:07+00:00","og_image":[{"width":492,"height":354,"url":"http:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/files\/2018\/05\/stemma-studio-nuovo-vettoriale.jpeg","type":"image\/jpeg"}],"author":"Studio Legale Franzetta Dassano","twitter_card":"summary_large_image","twitter_creator":"@quotidianopiem","twitter_site":"@quotidianopiem","twitter_misc":{"Scritto da":"Studio Legale Franzetta Dassano","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\/"},"author":{"name":"Studio Legale Franzetta Dassano","@id":"http:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/#\/schema\/person\/c1cfca91710b50f8e941e22f05a1ab8e"},"headline":"Cambiano le regole in tema di recesso dai contratti di telefonia, internet e pay tv","datePublished":"2018-11-23T12:36:07+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\/"},"wordCount":346,"commentCount":0,"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/files\/2018\/05\/stemma-studio-nuovo-vettoriale.jpeg","articleSection":["Diritto del Consumo"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\/","url":"http:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\/","name":"Cambiano le regole in tema di recesso dai contratti di telefonia, internet e pay tv - Il diritto intorno al cittadino","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/#website"},"primaryImageOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\/#primaryimage"},"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/files\/2018\/05\/stemma-studio-nuovo-vettoriale.jpeg","datePublished":"2018-11-23T12:36:07+00:00","author":{"@id":"http:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/#\/schema\/person\/c1cfca91710b50f8e941e22f05a1ab8e"},"breadcrumb":{"@id":"http:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/files\/2018\/05\/stemma-studio-nuovo-vettoriale.jpeg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/files\/2018\/05\/stemma-studio-nuovo-vettoriale.jpeg","width":492,"height":354},{"@type":"BreadcrumbList","@id":"http:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/cambiano-le-regole-in-tema-di-recesso-dai-contratti-di-telefonia-internet-e-pay-tv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/"},{"@type":"ListItem","position":2,"name":"Cambiano le regole in tema di recesso dai contratti di telefonia, internet e pay tv"}]},{"@type":"WebSite","@id":"http:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/#website","url":"http:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/","name":"Il diritto intorno al cittadino","description":"Ecco un altro sito Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/#\/schema\/person\/c1cfca91710b50f8e941e22f05a1ab8e","name":"Studio Legale Franzetta Dassano","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/94ef3983eb695cdbc529c6d5d4188111528edb9efa0630a17d02ab709449b1dd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/94ef3983eb695cdbc529c6d5d4188111528edb9efa0630a17d02ab709449b1dd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/94ef3983eb695cdbc529c6d5d4188111528edb9efa0630a17d02ab709449b1dd?s=96&d=mm&r=g","caption":"Studio Legale Franzetta Dassano"},"sameAs":["http:\/\/www.studiolegalefranzettadassano.it"],"url":"https:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/author\/studiolegalefranzettadassano\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/wp-json\/wp\/v2\/posts\/35","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/wp-json\/wp\/v2\/users\/1365"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/wp-json\/wp\/v2\/comments?post=35"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/wp-json\/wp\/v2\/posts\/35\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/wp-json\/wp\/v2\/media\/16"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/wp-json\/wp\/v2\/media?parent=35"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/wp-json\/wp\/v2\/categories?post=35"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/il-diritto-intorno-al-cittadino\/wp-json\/wp\/v2\/tags?post=35"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}