{"id":282,"date":"2018-02-22T22:34:48","date_gmt":"2018-02-22T21:34:48","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/il-cielo-sopra-torino\/?p=282"},"modified":"2018-02-23T10:53:04","modified_gmt":"2018-02-23T09:53:04","slug":"stentata-neve-prima-del-freddo","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/stentata-neve-prima-del-freddo\/","title":{"rendered":"Stentata neve prima del freddo"},"content":{"rendered":"<figure id=\"attachment_284\" aria-describedby=\"caption-attachment-284\" style=\"width: 217px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.grazianorey.it\/2018\/01\/05\/le-bambole-di-dresda-ierofanie\/\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-284 size-medium\" src=\"http:\/\/www.quotidianopiemontese.it\/il-cielo-sopra-torino\/files\/2018\/02\/img_0081-217x300.jpg\" alt=\"Graziano Rey - Le Bambole di Dresda\" width=\"217\" height=\"300\" srcset=\"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/files\/2018\/02\/img_0081-217x300.jpg 217w, https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/files\/2018\/02\/img_0081-768x1061.jpg 768w, https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/files\/2018\/02\/img_0081-741x1024.jpg 741w, https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/files\/2018\/02\/img_0081.jpg 1077w\" sizes=\"auto, (max-width: 217px) 85vw, 217px\" \/><\/a><figcaption id=\"caption-attachment-284\" class=\"wp-caption-text\">Graziano Rey &#8211; Le Bambole di Dresda<\/figcaption><\/figure>\n<p>Beh, non so quanti se ne siano accorti ma oggi, gioved\u00ec, qua e l\u00e0 tra la pioggia debole c&#8217;era anche qualche infiltrato fiocco di neve. Il fenomeno dovrebbe proseguire cos\u00ec con qualche possibile picco di maggiore intensit\u00e0 l&#8217;indomani mentre sabato (ma a fare la differenza basteranno variazioni di pochissimi e poco prevedibili gradi) ce ne potranno essere un po&#8217; di pi\u00f9 e per domenica mattina prevarranno sulla pioggia in maniera per\u00f2 molto debole, al confine dell&#8217;inossevabilit\u00e0.<\/p>\n<p>In compenso, dal pomeriggio del d\u00ec di festa il vento freddo abbatter\u00e0 di colpo le temperature e per i primi giorni della settimana le attuali temperature pi\u00f9 fredde saranno quelle delle ore pi\u00f9 calde, mentre le minime ci faranno provare l&#8217;ebbrezza dei meno undici.<\/p>\n<p>Al riaffacciarsi del nevischio debole gioved\u00ec e venerd\u00ec, dopo una settimana pressoch\u00e9 costantemente nuvolosa, il fenomeno si invertir\u00e0 e per il weekend, seppure con lo stesso cielo nuvoloso ma senza rovesci, torneremo ad avere le temperature di questo fine settimana e probabilmente proseguir\u00e0 cos\u00ec anche per quella successiva.<\/p>\n<p>Il giorno delle elezioni spunter\u00e0 un sole troppo debole e non abbastanza caldo da invogliare a gite fuori porta (anche se forse in montagna le cose andranno meglio).<\/p>\n<p>In immagine &#8220;<a href=\"http:\/\/www.grazianorey.it\/2018\/01\/05\/le-bambole-di-dresda-ierofanie\/\">Le bambole di Dresda<\/a>&#8221; \u2013 smalti e sabbia su tela 100 x 80&#8243; di Graziano Rey 2011 &#8211; Collezione Ierofanie<\/p>\n<p>Brano suggerito da SpotifyRus di questa settimana:<\/p>\n<p align=\"left\"><a href=\"https:\/\/spotifyrus.com\/2018\/02\/04\/be-a-man-get-in-the-cold-shower-kidepo\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/spotifyrus.files.wordpress.com\/2018\/02\/img_0940.jpg\" alt=\"\" width=\"1050\" height=\"1050\"><\/a><\/p>\n<p><a href=\"https:\/\/spotifyrus.com\/2018\/02\/04\/be-a-man-get-in-the-cold-shower-kidepo\/\"> BE A MAN (GET IN THE COLD SHOWER) | KIDEPO<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nevischio prima del nuvoloso freddo<\/p>\n","protected":false},"author":27,"featured_media":284,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,7],"tags":[9,40,32,10],"class_list":["post-282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-lungo-periodo","category-previsioni","tag-freddo","tag-nevischio","tag-nuvoloso","tag-pioggia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stentata neve prima del freddo - Il Cielo Sopra Torino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/stentata-neve-prima-del-freddo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stentata neve prima del freddo - Il Cielo Sopra Torino\" \/>\n<meta property=\"og:description\" content=\"Nevischio prima del nuvoloso freddo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/stentata-neve-prima-del-freddo\/\" \/>\n<meta property=\"og:site_name\" content=\"Il Cielo Sopra Torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-22T21:34:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-23T09:53:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/files\/2018\/02\/img_0081.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1077\" \/>\n\t<meta property=\"og:image:height\" content=\"1488\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ennio Martignago\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Flashennio\" \/>\n<meta name=\"twitter:site\" content=\"@quotidianopiem\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ennio Martignago\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/il-cielo-sopra-torino\\\/stentata-neve-prima-del-freddo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/il-cielo-sopra-torino\\\/stentata-neve-prima-del-freddo\\\/\"},\"author\":{\"name\":\"Ennio Martignago\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-cielo-sopra-torino\\\/#\\\/schema\\\/person\\\/57cba28e5895c7f90ec5fa8542d3aa7c\"},\"headline\":\"Stentata neve prima del freddo\",\"datePublished\":\"2018-02-22T21:34:48+00:00\",\"dateModified\":\"2018-02-23T09:53:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/il-cielo-sopra-torino\\\/stentata-neve-prima-del-freddo\\\/\"},\"wordCount\":253,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/il-cielo-sopra-torino\\\/stentata-neve-prima-del-freddo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/il-cielo-sopra-torino\\\/files\\\/2018\\\/02\\\/img_0081.jpg\",\"keywords\":[\"Freddo\",\"Nevischio\",\"Nuvoloso\",\"Pioggia\"],\"articleSection\":[\"A lungo periodo\",\"Previsioni\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/il-cielo-sopra-torino\\\/stentata-neve-prima-del-freddo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/il-cielo-sopra-torino\\\/stentata-neve-prima-del-freddo\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/il-cielo-sopra-torino\\\/stentata-neve-prima-del-freddo\\\/\",\"name\":\"Stentata neve prima del freddo - Il Cielo Sopra Torino\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-cielo-sopra-torino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/il-cielo-sopra-torino\\\/stentata-neve-prima-del-freddo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/il-cielo-sopra-torino\\\/stentata-neve-prima-del-freddo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/il-cielo-sopra-torino\\\/files\\\/2018\\\/02\\\/img_0081.jpg\",\"datePublished\":\"2018-02-22T21:34:48+00:00\",\"dateModified\":\"2018-02-23T09:53:04+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-cielo-sopra-torino\\\/#\\\/schema\\\/person\\\/57cba28e5895c7f90ec5fa8542d3aa7c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/il-cielo-sopra-torino\\\/stentata-neve-prima-del-freddo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/il-cielo-sopra-torino\\\/stentata-neve-prima-del-freddo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/il-cielo-sopra-torino\\\/stentata-neve-prima-del-freddo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/il-cielo-sopra-torino\\\/files\\\/2018\\\/02\\\/img_0081.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/il-cielo-sopra-torino\\\/files\\\/2018\\\/02\\\/img_0081.jpg\",\"width\":1077,\"height\":1488},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/il-cielo-sopra-torino\\\/stentata-neve-prima-del-freddo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-cielo-sopra-torino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stentata neve prima del freddo\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-cielo-sopra-torino\\\/#website\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-cielo-sopra-torino\\\/\",\"name\":\"Il Cielo Sopra Torino\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-cielo-sopra-torino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/il-cielo-sopra-torino\\\/#\\\/schema\\\/person\\\/57cba28e5895c7f90ec5fa8542d3aa7c\",\"name\":\"Ennio Martignago\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0fa08b27d798857f4a9b7f364ec4eb0f99d7413886f6da79092de46d4e6a43bb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0fa08b27d798857f4a9b7f364ec4eb0f99d7413886f6da79092de46d4e6a43bb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0fa08b27d798857f4a9b7f364ec4eb0f99d7413886f6da79092de46d4e6a43bb?s=96&d=mm&r=g\",\"caption\":\"Ennio Martignago\"},\"sameAs\":[\"http:\\\/\\\/mepassport.wordpress.com\\\/about\\\/\",\"https:\\\/\\\/x.com\\\/Flashennio\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/il-cielo-sopra-torino\\\/author\\\/ennio-martignago\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stentata neve prima del freddo - Il Cielo Sopra Torino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/stentata-neve-prima-del-freddo\/","og_locale":"it_IT","og_type":"article","og_title":"Stentata neve prima del freddo - Il Cielo Sopra Torino","og_description":"Nevischio prima del nuvoloso freddo","og_url":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/stentata-neve-prima-del-freddo\/","og_site_name":"Il Cielo Sopra Torino","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese","article_published_time":"2018-02-22T21:34:48+00:00","article_modified_time":"2018-02-23T09:53:04+00:00","og_image":[{"width":1077,"height":1488,"url":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/files\/2018\/02\/img_0081.jpg","type":"image\/jpeg"}],"author":"Ennio Martignago","twitter_card":"summary_large_image","twitter_creator":"@Flashennio","twitter_site":"@quotidianopiem","twitter_misc":{"Scritto da":"Ennio Martignago","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/stentata-neve-prima-del-freddo\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/stentata-neve-prima-del-freddo\/"},"author":{"name":"Ennio Martignago","@id":"http:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/#\/schema\/person\/57cba28e5895c7f90ec5fa8542d3aa7c"},"headline":"Stentata neve prima del freddo","datePublished":"2018-02-22T21:34:48+00:00","dateModified":"2018-02-23T09:53:04+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/stentata-neve-prima-del-freddo\/"},"wordCount":253,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/stentata-neve-prima-del-freddo\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/files\/2018\/02\/img_0081.jpg","keywords":["Freddo","Nevischio","Nuvoloso","Pioggia"],"articleSection":["A lungo periodo","Previsioni"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/stentata-neve-prima-del-freddo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/stentata-neve-prima-del-freddo\/","url":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/stentata-neve-prima-del-freddo\/","name":"Stentata neve prima del freddo - Il Cielo Sopra Torino","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/stentata-neve-prima-del-freddo\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/stentata-neve-prima-del-freddo\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/files\/2018\/02\/img_0081.jpg","datePublished":"2018-02-22T21:34:48+00:00","dateModified":"2018-02-23T09:53:04+00:00","author":{"@id":"http:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/#\/schema\/person\/57cba28e5895c7f90ec5fa8542d3aa7c"},"breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/stentata-neve-prima-del-freddo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/stentata-neve-prima-del-freddo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/stentata-neve-prima-del-freddo\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/files\/2018\/02\/img_0081.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/files\/2018\/02\/img_0081.jpg","width":1077,"height":1488},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/stentata-neve-prima-del-freddo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/"},{"@type":"ListItem","position":2,"name":"Stentata neve prima del freddo"}]},{"@type":"WebSite","@id":"http:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/#website","url":"http:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/","name":"Il Cielo Sopra Torino","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/#\/schema\/person\/57cba28e5895c7f90ec5fa8542d3aa7c","name":"Ennio Martignago","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0fa08b27d798857f4a9b7f364ec4eb0f99d7413886f6da79092de46d4e6a43bb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0fa08b27d798857f4a9b7f364ec4eb0f99d7413886f6da79092de46d4e6a43bb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0fa08b27d798857f4a9b7f364ec4eb0f99d7413886f6da79092de46d4e6a43bb?s=96&d=mm&r=g","caption":"Ennio Martignago"},"sameAs":["http:\/\/mepassport.wordpress.com\/about\/","https:\/\/x.com\/Flashennio"],"url":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/author\/ennio-martignago\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/wp-json\/wp\/v2\/posts\/282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/wp-json\/wp\/v2\/comments?post=282"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/wp-json\/wp\/v2\/posts\/282\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/wp-json\/wp\/v2\/media\/284"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/wp-json\/wp\/v2\/media?parent=282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/wp-json\/wp\/v2\/categories?post=282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/il-cielo-sopra-torino\/wp-json\/wp\/v2\/tags?post=282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}