{"id":177,"date":"2010-05-19T13:56:55","date_gmt":"2010-05-19T11:56:55","guid":{"rendered":"http:\/\/agora.torinovalley.com\/digitaleterrestre\/?p=177"},"modified":"2010-05-19T13:56:55","modified_gmt":"2010-05-19T11:56:55","slug":"rainews-oscurata-dallo-switch-off-del-digitale-terrestre","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/rainews-oscurata-dallo-switch-off-del-digitale-terrestre\/","title":{"rendered":"RaiNews oscurata dallo switch off del digitale terrestre"},"content":{"rendered":"<p><a href=\"http:\/\/www.pasteris.it\/blog\/2010\/05\/18\/rai-news-24-oscurata-dallo-switch-off-del-digitale-terrestre-lombardo\/\">Basta risintonizzare il decoder per ritrovare il segnale<\/a><\/p>\n<blockquote><p>\u201cRainews informa che da questa mattina gli utenti non ci trovano pi\u00f9   al Canale 42 della piattaforma digitale terrestre: ci scusiamo con gli   utenti, faremo di tutto per comprendere le ragioni di questo  oscuramento  e di porvi rimedio\u201d. Corradino Mineo, direttore di Rainews,  commenta  cos\u00ec la scomparsa di Rainews canale 42 della piattaforma del  digitale  terrestre e dal canale 506 della piattaforma Sky.<\/p>\n<p>Mineo sottolinea come le \u201ccentinaia di mail pervenute al nostro sito e   altrettante telefonate testimoniano che, in realt\u00e0, molti spettatori   non riescono pi\u00f9 in alcun modo a sintonizzarsi sul nostro Canale\u201d. Da   oggi il canale non si chiama pi\u00f9 Rainews24 ma solo Rainews e che, per   omologare l\u2019intera offerta aziendale, \u201cla Direzione Generale ha deciso   di spostare il logo in alto a destra dello schermo. Il logo, purtroppo,   risulta poco leggibile, mentre la nuova grafica impedisce, per il   momento, di mandare in onda i flash, strumento indispensabile per una   all news. Anche di questo ci scusiamo con gli utenti\u201d, conclude Mineo.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Basta risintonizzare il decoder per ritrovare il segnale \u201cRainews informa che da questa mattina gli utenti non ci trovano pi\u00f9 al Canale 42 della piattaforma digitale terrestre: ci scusiamo con gli utenti, faremo di tutto per comprendere le ragioni di questo oscuramento e di porvi rimedio\u201d. Corradino Mineo, direttore di Rainews, commenta cos\u00ec la scomparsa &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/rainews-oscurata-dallo-switch-off-del-digitale-terrestre\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;RaiNews oscurata dallo switch off del digitale terrestre&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,9],"tags":[72,39],"class_list":["post-177","post","type-post","status-publish","format-standard","hentry","category-rai","category-regioni","tag-rai","tag-switch-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RaiNews oscurata dallo switch off del digitale terrestre - Digitale Terrestre<\/title>\n<meta name=\"description\" content=\"Basta risintonizzare il decoder per ritrovare il segnale \u201cRainews informa che da questa mattina gli utenti non ci trovano pi\u00f9 al Canale 42 della\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/rainews-oscurata-dallo-switch-off-del-digitale-terrestre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RaiNews oscurata dallo switch off del digitale terrestre - Digitale Terrestre\" \/>\n<meta property=\"og:description\" content=\"Basta risintonizzare il decoder per ritrovare il segnale \u201cRainews informa che da questa mattina gli utenti non ci trovano pi\u00f9 al Canale 42 della\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/rainews-oscurata-dallo-switch-off-del-digitale-terrestre\/\" \/>\n<meta property=\"og:site_name\" content=\"Digitale Terrestre\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:published_time\" content=\"2010-05-19T11:56:55+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/digitale-terrestre\\\/rainews-oscurata-dallo-switch-off-del-digitale-terrestre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/digitale-terrestre\\\/rainews-oscurata-dallo-switch-off-del-digitale-terrestre\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/digitale-terrestre\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"headline\":\"RaiNews oscurata dallo switch off del digitale terrestre\",\"datePublished\":\"2010-05-19T11:56:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/digitale-terrestre\\\/rainews-oscurata-dallo-switch-off-del-digitale-terrestre\\\/\"},\"wordCount\":178,\"commentCount\":2,\"keywords\":[\"Rai\",\"switch off\"],\"articleSection\":[\"Rai\",\"Regioni\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/digitale-terrestre\\\/rainews-oscurata-dallo-switch-off-del-digitale-terrestre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/digitale-terrestre\\\/rainews-oscurata-dallo-switch-off-del-digitale-terrestre\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/digitale-terrestre\\\/rainews-oscurata-dallo-switch-off-del-digitale-terrestre\\\/\",\"name\":\"RaiNews oscurata dallo switch off del digitale terrestre - Digitale Terrestre\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/digitale-terrestre\\\/#website\"},\"datePublished\":\"2010-05-19T11:56:55+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/digitale-terrestre\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"description\":\"Basta risintonizzare il decoder per ritrovare il segnale \u201cRainews informa che da questa mattina gli utenti non ci trovano pi\u00f9 al Canale 42 della\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/digitale-terrestre\\\/rainews-oscurata-dallo-switch-off-del-digitale-terrestre\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/digitale-terrestre\\\/rainews-oscurata-dallo-switch-off-del-digitale-terrestre\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/digitale-terrestre\\\/rainews-oscurata-dallo-switch-off-del-digitale-terrestre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/digitale-terrestre\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RaiNews oscurata dallo switch off del digitale terrestre\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/digitale-terrestre\\\/#website\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/digitale-terrestre\\\/\",\"name\":\"Digitale Terrestre\",\"description\":\"Solo un altro sito  Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/digitale-terrestre\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/digitale-terrestre\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte\",\"sameAs\":[\"http:\\\/\\\/www.quotidianopiemontese.it\\\/\",\"https:\\\/\\\/www.facebook.com\\\/quotidianopiemontese\",\"https:\\\/\\\/x.com\\\/quotidianopiem\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/digitale-terrestre\\\/author\\\/administrator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RaiNews oscurata dallo switch off del digitale terrestre - Digitale Terrestre","description":"Basta risintonizzare il decoder per ritrovare il segnale \u201cRainews informa che da questa mattina gli utenti non ci trovano pi\u00f9 al Canale 42 della","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/rainews-oscurata-dallo-switch-off-del-digitale-terrestre\/","og_locale":"it_IT","og_type":"article","og_title":"RaiNews oscurata dallo switch off del digitale terrestre - Digitale Terrestre","og_description":"Basta risintonizzare il decoder per ritrovare il segnale \u201cRainews informa che da questa mattina gli utenti non ci trovano pi\u00f9 al Canale 42 della","og_url":"https:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/rainews-oscurata-dallo-switch-off-del-digitale-terrestre\/","og_site_name":"Digitale Terrestre","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"https:\/\/www.facebook.com\/quotidianopiemontese","article_published_time":"2010-05-19T11:56:55+00:00","author":"Redazione","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/rainews-oscurata-dallo-switch-off-del-digitale-terrestre\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/rainews-oscurata-dallo-switch-off-del-digitale-terrestre\/"},"author":{"name":"Redazione","@id":"http:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"headline":"RaiNews oscurata dallo switch off del digitale terrestre","datePublished":"2010-05-19T11:56:55+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/rainews-oscurata-dallo-switch-off-del-digitale-terrestre\/"},"wordCount":178,"commentCount":2,"keywords":["Rai","switch off"],"articleSection":["Rai","Regioni"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/rainews-oscurata-dallo-switch-off-del-digitale-terrestre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/rainews-oscurata-dallo-switch-off-del-digitale-terrestre\/","url":"https:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/rainews-oscurata-dallo-switch-off-del-digitale-terrestre\/","name":"RaiNews oscurata dallo switch off del digitale terrestre - Digitale Terrestre","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/#website"},"datePublished":"2010-05-19T11:56:55+00:00","author":{"@id":"http:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"description":"Basta risintonizzare il decoder per ritrovare il segnale \u201cRainews informa che da questa mattina gli utenti non ci trovano pi\u00f9 al Canale 42 della","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/rainews-oscurata-dallo-switch-off-del-digitale-terrestre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/rainews-oscurata-dallo-switch-off-del-digitale-terrestre\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/rainews-oscurata-dallo-switch-off-del-digitale-terrestre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/"},{"@type":"ListItem","position":2,"name":"RaiNews oscurata dallo switch off del digitale terrestre"}]},{"@type":"WebSite","@id":"http:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/#website","url":"http:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/","name":"Digitale Terrestre","description":"Solo un altro sito  Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","caption":"Redazione"},"description":"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte","sameAs":["http:\/\/www.quotidianopiemontese.it\/","https:\/\/www.facebook.com\/quotidianopiemontese","https:\/\/x.com\/quotidianopiem"],"url":"https:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/author\/administrator\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/wp-json\/wp\/v2\/posts\/177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/wp-json\/wp\/v2\/comments?post=177"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/wp-json\/wp\/v2\/posts\/177\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/wp-json\/wp\/v2\/media?parent=177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/wp-json\/wp\/v2\/categories?post=177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/digitale-terrestre\/wp-json\/wp\/v2\/tags?post=177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}