{"id":404,"date":"2019-01-09T13:56:45","date_gmt":"2019-01-09T12:56:45","guid":{"rendered":"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/?p=404"},"modified":"2019-01-09T13:56:45","modified_gmt":"2019-01-09T12:56:45","slug":"petrit-halilaj-scintille-balcaniche-alla-fondazione-merz","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/petrit-halilaj-scintille-balcaniche-alla-fondazione-merz\/","title":{"rendered":"Petrit Halilaj: \u201cScintille\u201d balcaniche alla Fondazione Merz"},"content":{"rendered":"<p>Ad accogliere il visitatore \u00e8 un letto intorno al quale sono sospese in aria tegole, mattoni, pietre, frammenti di legno e altre macerie, che paiono il frutto di un\u2019esplosione bellica. Come quella che ha lacerato il Kosovo, Paese natale di <strong>Petrit Halilaj <\/strong>(1986), vincitore della seconda edizione del <strong>Mario Merz Prize<\/strong> e ora ospite fino al <strong> 3 febbraio<\/strong> alla <strong>Fondazione Merz<\/strong> con la personale intitolata \u00ab<strong>Shkrep\u00ebtima<\/strong>\u00bb<strong>. <\/strong><strong>Petrit<\/strong><strong> Halilaj<\/strong> vive e lavora tra Germania, Kosovo e Italia, si \u00e8 formato all\u2019Accademia di Belle Arti di Brera, e nel 2013 ha rappresentato il suo Paese alla Biennale di Venezia. Nelle sue opere si intrecciano la storia e la memoria personale a quelle della sua comunit\u00e0, come nell\u2019installazione \u00ab<strong>Abetare<\/strong>\u00bb<strong>,<\/strong> una scuola elementare kosovara ricostruita con tanto di banchi e graffiti, con cui l\u2019artista ha vinto il <strong>Mario Merz Price. <\/strong><!--more--><\/p>\n<p>Attraverso sculture ed installazioni monumentali,<strong> Halilaj <\/strong>ha ricostruito e ricontestualizzato le scenografie, i costumi e gli oggetti di scena della performance tenutasi nel luglio del 2018 presso le rovine della <strong>Casa della Cultura<\/strong> di <strong>Runik<\/strong>, edificio che un tempo ospitava una biblioteca con oltre 7.000 volumi, un teatro, la sede della cooperativa sociale del villaggio, e che venne parzialmente distrutto durante il conflitto.<\/p>\n<p><a href=\"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2019\/01\/49441983_10217514184788152_5454410407798112256_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-406\" src=\"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2019\/01\/49441983_10217514184788152_5454410407798112256_n-300x231.jpg\" alt=\"\" width=\"300\" height=\"231\" srcset=\"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2019\/01\/49441983_10217514184788152_5454410407798112256_n-300x231.jpg 300w, https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2019\/01\/49441983_10217514184788152_5454410407798112256_n-768x592.jpg 768w, https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2019\/01\/49441983_10217514184788152_5454410407798112256_n.jpg 960w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/a><\/p>\n<p>In lingua albanese <strong>\u00ab<\/strong><strong>Shkrep\u00ebtima\u00bb<\/strong> &#8211; che era anche il nome della rivista culturale multietnica pubblicata a Runik tra gli anni Settanta e Ottanta dagli insegnanti della scuola locale &#8211; significa \u201clampo\u201d, \u201cfulmine\u201d, \u201cscintilla\u201d, ovvero un pensiero improvviso e intenso che funziona come attivatore di coscienze in grado di riavviare un processo di riflessione sulla nostra identit\u00e0.<\/p>\n<p><a href=\"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2019\/01\/50170575_10217514182548096_469583716662902784_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-407\" src=\"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2019\/01\/50170575_10217514182548096_469583716662902784_n-300x232.jpg\" alt=\"\" width=\"300\" height=\"232\" srcset=\"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2019\/01\/50170575_10217514182548096_469583716662902784_n-300x232.jpg 300w, https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2019\/01\/50170575_10217514182548096_469583716662902784_n-768x594.jpg 768w, https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2019\/01\/50170575_10217514182548096_469583716662902784_n.jpg 960w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/a><\/p>\n<p>I sipari rossi e i fondali dipinti usati nella performance sono disposti lungo l\u2019asse longitudinale dell\u2019edificio della <strong>Fondazione Merz<\/strong> e trasformano lo spazio espositivo in un palcoscenico dove si alternano le storie che <strong>Halilaj <\/strong>ha tratto da alcuni dei pi\u00f9 importanti drammi albanesi recitati a Runik da compagnie amatoriali. Dall\u2019alto degli uccelli, sculture realizzate con i costumi indossati dagli attori a Runik, osservano tutta la scena. Gli uccelli sono un animale ricorrente nell\u2019immaginario e nelle opere dell\u2019artista come metafora della capacit\u00e0 di essere liberi e in grado di oltrepassare confini geografici e barriere culturali. Infine, una serie di disegni e studi concettuali della performance realizzati su vecchi documenti trovati dall\u2019artista nelle stanze della Casa della Cultura. Si tratta di relazioni commerciali\u00a0e di fatture che facevano parte dell\u2019archivio della cooperativa locale, testimonianza di una vita quotidiana che non c\u2019\u00e8 pi\u00f9. Artefatti neolitici a forma di uccello, battute prese dai copioni teatrali, studi per i costumi degli uccelli, oggetti di scena usati nello spettacolo: uno storyboard concettuale della performance e un ritratto visivo della storia culturale del villaggio dove il passato incontra il presente.<\/p>\n<p><a href=\"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2019\/01\/50560836_10217514185348166_7964879536032579584_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-408\" src=\"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2019\/01\/50560836_10217514185348166_7964879536032579584_n-300x243.jpg\" alt=\"\" width=\"300\" height=\"243\" srcset=\"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2019\/01\/50560836_10217514185348166_7964879536032579584_n-300x243.jpg 300w, https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2019\/01\/50560836_10217514185348166_7964879536032579584_n-768x622.jpg 768w, https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2019\/01\/50560836_10217514185348166_7964879536032579584_n.jpg 960w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/a><\/p>\n<p>\u00abAttraverso il suo linguaggio onirico e visionario, <strong>Halilaj <\/strong>ha raggiunto un sorprendente bilanciamento tra il peso della storia di questi frammenti e la leggerezza fisica data dalla loro sospensione-spiega il curatore <strong>Leonardo Bigazzi<\/strong>-intervenendo direttamente sui processi di costruzione della storia collettiva della sua comunit\u00e0, riavvicinandola alle proprie origini, <strong>Halilaj <\/strong>propone anche una riflessione universale sul potenziale dell\u2019arte e il suo potere di trasformare la realt\u00e0.\u00bb<\/p>\n<p><a href=\"http:\/\/www.fondazionemerz.org\">http:\/\/www.fondazionemerz.org<\/a><\/p>\n<h5>Emanuele Rebuffini<\/h5>\n<p><a href=\"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2019\/01\/49761367_10217514185948181_5133146300006531072_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-409\" src=\"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2019\/01\/49761367_10217514185948181_5133146300006531072_n-300x124.jpg\" alt=\"\" width=\"300\" height=\"124\" srcset=\"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2019\/01\/49761367_10217514185948181_5133146300006531072_n-300x124.jpg 300w, https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2019\/01\/49761367_10217514185948181_5133146300006531072_n-768x318.jpg 768w, https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2019\/01\/49761367_10217514185948181_5133146300006531072_n.jpg 960w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/a><\/p>\n<p><strong><em>Photo by Renato Ghiazza<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ad accogliere il visitatore \u00e8 un letto intorno al quale sono sospese in aria tegole, mattoni, pietre, frammenti di legno e altre macerie, che paiono il frutto di un\u2019esplosione bellica. Come quella che ha lacerato il Kosovo, Paese natale di Petrit Halilaj (1986), vincitore della seconda edizione del Mario Merz Prize e ora ospite fino &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/petrit-halilaj-scintille-balcaniche-alla-fondazione-merz\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Petrit Halilaj: \u201cScintille\u201d balcaniche alla Fondazione Merz&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1361,"featured_media":405,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[18,111],"class_list":["post-404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-arte-spettacolo","tag-fondazione-merz","tag-petrit-halilaj"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Petrit Halilaj: \u201cScintille\u201d balcaniche alla Fondazione Merz - 9 Gennaio 2019<\/title>\n<meta name=\"description\" content=\"Petrit Halilaj: \u201cScintille\u201d balcaniche alla Fondazione Merz - Cultura, Arte e Spettacolo a Torino - Ad accogliere il visitatore \u00e8 un letto intorno al quale sono sospese in aria tegole, mattoni, pietre, frammenti di legno e altre macerie, che paiono il - Fondazione Merz, Petrit Halilaj\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/petrit-halilaj-scintille-balcaniche-alla-fondazione-merz\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Petrit Halilaj: \u201cScintille\u201d balcaniche alla Fondazione Merz - 9 Gennaio 2019\" \/>\n<meta property=\"og:description\" content=\"Petrit Halilaj: \u201cScintille\u201d balcaniche alla Fondazione Merz - Cultura, Arte e Spettacolo a Torino - Ad accogliere il visitatore \u00e8 un letto intorno al quale sono sospese in aria tegole, mattoni, pietre, frammenti di legno e altre macerie, che paiono il - Fondazione Merz, Petrit Halilaj\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/petrit-halilaj-scintille-balcaniche-alla-fondazione-merz\/\" \/>\n<meta property=\"og:site_name\" content=\"Cultura, Arte e Spettacolo a Torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-09T12:56:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2019\/01\/49661506_10217514186068184_4604555831550148608_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Emanuele Rebuffini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Emanuele Rebuffini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/petrit-halilaj-scintille-balcaniche-alla-fondazione-merz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/petrit-halilaj-scintille-balcaniche-alla-fondazione-merz\\\/\"},\"author\":{\"name\":\"Emanuele Rebuffini\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/#\\\/schema\\\/person\\\/b035109a4cc7d3e93911b78d8cebf3a0\"},\"headline\":\"Petrit Halilaj: \u201cScintille\u201d balcaniche alla Fondazione Merz\",\"datePublished\":\"2019-01-09T12:56:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/petrit-halilaj-scintille-balcaniche-alla-fondazione-merz\\\/\"},\"wordCount\":527,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/petrit-halilaj-scintille-balcaniche-alla-fondazione-merz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/files\\\/2019\\\/01\\\/49661506_10217514186068184_4604555831550148608_n.jpg\",\"keywords\":[\"Fondazione Merz\",\"Petrit Halilaj\"],\"articleSection\":[\"Cultura, arte, spettacolo\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/petrit-halilaj-scintille-balcaniche-alla-fondazione-merz\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/petrit-halilaj-scintille-balcaniche-alla-fondazione-merz\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/petrit-halilaj-scintille-balcaniche-alla-fondazione-merz\\\/\",\"name\":\"Petrit Halilaj: \u201cScintille\u201d balcaniche alla Fondazione Merz - 9 Gennaio 2019\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/petrit-halilaj-scintille-balcaniche-alla-fondazione-merz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/petrit-halilaj-scintille-balcaniche-alla-fondazione-merz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/files\\\/2019\\\/01\\\/49661506_10217514186068184_4604555831550148608_n.jpg\",\"datePublished\":\"2019-01-09T12:56:45+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/#\\\/schema\\\/person\\\/b035109a4cc7d3e93911b78d8cebf3a0\"},\"description\":\"Petrit Halilaj: \u201cScintille\u201d balcaniche alla Fondazione Merz - Cultura, Arte e Spettacolo a Torino - Ad accogliere il visitatore \u00e8 un letto intorno al quale sono sospese in aria tegole, mattoni, pietre, frammenti di legno e altre macerie, che paiono il - Fondazione Merz, Petrit Halilaj\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/petrit-halilaj-scintille-balcaniche-alla-fondazione-merz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/petrit-halilaj-scintille-balcaniche-alla-fondazione-merz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/files\\\/2019\\\/01\\\/49661506_10217514186068184_4604555831550148608_n.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/files\\\/2019\\\/01\\\/49661506_10217514186068184_4604555831550148608_n.jpg\",\"width\":960,\"height\":640},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/#website\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/\",\"name\":\"Cultura, Arte e Spettacolo a Torino\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/#\\\/schema\\\/person\\\/b035109a4cc7d3e93911b78d8cebf3a0\",\"name\":\"Emanuele Rebuffini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/519a0a38be4cbbcf40fb5bc1b1173a85af291a3a8697df454a94ad7e05574628?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/519a0a38be4cbbcf40fb5bc1b1173a85af291a3a8697df454a94ad7e05574628?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/519a0a38be4cbbcf40fb5bc1b1173a85af291a3a8697df454a94ad7e05574628?s=96&d=mm&r=g\",\"caption\":\"Emanuele Rebuffini\"},\"sameAs\":[\"http:\\\/\\\/www.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/author\\\/emanuelerebuffini\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Petrit Halilaj: \u201cScintille\u201d balcaniche alla Fondazione Merz - 9 Gennaio 2019","description":"Petrit Halilaj: \u201cScintille\u201d balcaniche alla Fondazione Merz - Cultura, Arte e Spettacolo a Torino - Ad accogliere il visitatore \u00e8 un letto intorno al quale sono sospese in aria tegole, mattoni, pietre, frammenti di legno e altre macerie, che paiono il - Fondazione Merz, Petrit Halilaj","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/petrit-halilaj-scintille-balcaniche-alla-fondazione-merz\/","og_locale":"it_IT","og_type":"article","og_title":"Petrit Halilaj: \u201cScintille\u201d balcaniche alla Fondazione Merz - 9 Gennaio 2019","og_description":"Petrit Halilaj: \u201cScintille\u201d balcaniche alla Fondazione Merz - Cultura, Arte e Spettacolo a Torino - Ad accogliere il visitatore \u00e8 un letto intorno al quale sono sospese in aria tegole, mattoni, pietre, frammenti di legno e altre macerie, che paiono il - Fondazione Merz, Petrit Halilaj","og_url":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/petrit-halilaj-scintille-balcaniche-alla-fondazione-merz\/","og_site_name":"Cultura, Arte e Spettacolo a Torino","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2019-01-09T12:56:45+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2019\/01\/49661506_10217514186068184_4604555831550148608_n.jpg","type":"image\/jpeg"}],"author":"Emanuele Rebuffini","twitter_misc":{"Scritto da":"Emanuele Rebuffini","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/petrit-halilaj-scintille-balcaniche-alla-fondazione-merz\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/petrit-halilaj-scintille-balcaniche-alla-fondazione-merz\/"},"author":{"name":"Emanuele Rebuffini","@id":"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/#\/schema\/person\/b035109a4cc7d3e93911b78d8cebf3a0"},"headline":"Petrit Halilaj: \u201cScintille\u201d balcaniche alla Fondazione Merz","datePublished":"2019-01-09T12:56:45+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/petrit-halilaj-scintille-balcaniche-alla-fondazione-merz\/"},"wordCount":527,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/petrit-halilaj-scintille-balcaniche-alla-fondazione-merz\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2019\/01\/49661506_10217514186068184_4604555831550148608_n.jpg","keywords":["Fondazione Merz","Petrit Halilaj"],"articleSection":["Cultura, arte, spettacolo"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/petrit-halilaj-scintille-balcaniche-alla-fondazione-merz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/petrit-halilaj-scintille-balcaniche-alla-fondazione-merz\/","url":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/petrit-halilaj-scintille-balcaniche-alla-fondazione-merz\/","name":"Petrit Halilaj: \u201cScintille\u201d balcaniche alla Fondazione Merz - 9 Gennaio 2019","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/petrit-halilaj-scintille-balcaniche-alla-fondazione-merz\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/petrit-halilaj-scintille-balcaniche-alla-fondazione-merz\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2019\/01\/49661506_10217514186068184_4604555831550148608_n.jpg","datePublished":"2019-01-09T12:56:45+00:00","author":{"@id":"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/#\/schema\/person\/b035109a4cc7d3e93911b78d8cebf3a0"},"description":"Petrit Halilaj: \u201cScintille\u201d balcaniche alla Fondazione Merz - Cultura, Arte e Spettacolo a Torino - Ad accogliere il visitatore \u00e8 un letto intorno al quale sono sospese in aria tegole, mattoni, pietre, frammenti di legno e altre macerie, che paiono il - Fondazione Merz, Petrit Halilaj","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/petrit-halilaj-scintille-balcaniche-alla-fondazione-merz\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/petrit-halilaj-scintille-balcaniche-alla-fondazione-merz\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2019\/01\/49661506_10217514186068184_4604555831550148608_n.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2019\/01\/49661506_10217514186068184_4604555831550148608_n.jpg","width":960,"height":640},{"@type":"WebSite","@id":"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/#website","url":"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/","name":"Cultura, Arte e Spettacolo a Torino","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/#\/schema\/person\/b035109a4cc7d3e93911b78d8cebf3a0","name":"Emanuele Rebuffini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/519a0a38be4cbbcf40fb5bc1b1173a85af291a3a8697df454a94ad7e05574628?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/519a0a38be4cbbcf40fb5bc1b1173a85af291a3a8697df454a94ad7e05574628?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/519a0a38be4cbbcf40fb5bc1b1173a85af291a3a8697df454a94ad7e05574628?s=96&d=mm&r=g","caption":"Emanuele Rebuffini"},"sameAs":["http:\/\/www.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/"],"url":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/author\/emanuelerebuffini\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/wp-json\/wp\/v2\/posts\/404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/wp-json\/wp\/v2\/users\/1361"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/wp-json\/wp\/v2\/comments?post=404"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/wp-json\/wp\/v2\/posts\/404\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/wp-json\/wp\/v2\/media\/405"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/wp-json\/wp\/v2\/media?parent=404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/wp-json\/wp\/v2\/categories?post=404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/wp-json\/wp\/v2\/tags?post=404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}