{"id":38,"date":"2015-07-13T17:07:47","date_gmt":"2015-07-13T15:07:47","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/?p=38"},"modified":"2015-07-14T08:01:20","modified_gmt":"2015-07-14T06:01:20","slug":"al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana\/","title":{"rendered":"Al teatro Regio a luglio \u00e8 il trionfo dell&#8217;opera italiana"},"content":{"rendered":"<p>Continua fino al 26 luglio prossimo la kermesse al Teatro Regio dal titolo &#8220;The Best of \u00a0Italian Opera&#8221;, offerta culturale proposta nell&#8217;ambito di Expo To, che si articola nella messinscena di quattro grandi opere del panorama italiano: la Boheme di Giacomo Puccini, \u00a0il Barbiere di Siviglia di Gioacchino Rossini, la Traviata di Giuseppe Verdi e la Norma di Vincenzo Bellini. Protagonisti il Coro e l&#8217;Orchestra del Teatro Regio. La Boheme viene proposta il 14, 18 e 23 luglio nella storica versione con bozzetti e figurini firmati da Eugenio Guglielminetti, \u00a0per la regia di Vittorio Borrelli. Protagonista Barbara Frittoli, \u00a0con Stefano Secco, Maria Teresa Leva e Markus Werba, \u00a0per la direzione del giovane Andrea Battistoni. Saranno protagonisti del Barbiere di Siviglia (il 15, 19 e 24 luglio) importanti cantanti lirici che si distinguono nel genere buffo, come Antonino Siragusa, \u00a0Marco Filippo Romano, Chiara Amaru&#8217; eRoberto De Candia. \u00a0La Traviata, premiata dalla critica giapponese nel corso della tourn\u00e9e del Teatro Regio nel Sol Levante, nel 2010, \u00e8 firmata dal regista Laurent Pelly e diretta da Francesco Ivan Ciampa. Nel ruolo di Violetta Desiree&#8217; Rancatore, \u00a0accanto a Piero Pretti e Luca Salsa. \u00a0Alberto \u00a0Fassini firma l&#8217;allestimento della Norma, che verr\u00e0 rappresentata il 17, 22 e 26 luglio, con, sul podio, un direttore moto affermato, \u00a0Roberto Abbado.<\/p>\n<p>Gli\u00a0appassionati potranno anche acquistare un carnet di abbonamento a quattro opere, al costo di 250, 190 o 150 euro a seconda del settore, o a tre ( a 200, 150 o 120 euro a seconda del settore). \u00a0L&#8217;acquisto pu\u00f2 avvenire alla biglietteria del Teatro Regio o telefonicamente allo 0118815270, tramite carta di credito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Continua fino al 26 luglio prossimo la kermesse al Teatro Regio dal titolo &#8220;The Best of \u00a0Italian Opera&#8221;, offerta culturale proposta nell&#8217;ambito di Expo To, che si articola nella messinscena di quattro grandi opere del panorama italiano: la Boheme di Giacomo Puccini, \u00a0il Barbiere di Siviglia di Gioacchino Rossini, la Traviata di Giuseppe Verdi e &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Al teatro Regio a luglio \u00e8 il trionfo dell&#8217;opera italiana&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":28,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-38","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-arte-spettacolo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Al teatro Regio a luglio \u00e8 il trionfo dell&#039;opera italiana - 13 Luglio 2015<\/title>\n<meta name=\"description\" content=\"Al teatro Regio a luglio \u00e8 il trionfo dell&#039;opera italiana - Cultura, Arte e Spettacolo a Torino - Continua fino al 26 luglio prossimo la kermesse al Teatro Regio dal titolo &quot;The Best of \u00a0Italian Opera&quot;, offerta culturale proposta nell&#039;ambito di Expo -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al teatro Regio a luglio \u00e8 il trionfo dell&#039;opera italiana - 13 Luglio 2015\" \/>\n<meta property=\"og:description\" content=\"Al teatro Regio a luglio \u00e8 il trionfo dell&#039;opera italiana - Cultura, Arte e Spettacolo a Torino - Continua fino al 26 luglio prossimo la kermesse al Teatro Regio dal titolo &quot;The Best of \u00a0Italian Opera&quot;, offerta culturale proposta nell&#039;ambito di Expo -\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana\/\" \/>\n<meta property=\"og:site_name\" content=\"Cultura, Arte e Spettacolo a Torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-13T15:07:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-07-14T06:01:20+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2015\/06\/Teatro_Regio_-_sala_grandangolo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"headline\":\"Al teatro Regio a luglio \u00e8 il trionfo dell&#8217;opera italiana\",\"datePublished\":\"2015-07-13T15:07:47+00:00\",\"dateModified\":\"2015-07-14T06:01:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana\\\/\"},\"wordCount\":262,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/files\\\/2015\\\/06\\\/Teatro_Regio_-_sala_grandangolo.jpg\",\"articleSection\":[\"Cultura, arte, spettacolo\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana\\\/\",\"name\":\"Al teatro Regio a luglio \u00e8 il trionfo dell'opera italiana - 13 Luglio 2015\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/files\\\/2015\\\/06\\\/Teatro_Regio_-_sala_grandangolo.jpg\",\"datePublished\":\"2015-07-13T15:07:47+00:00\",\"dateModified\":\"2015-07-14T06:01:20+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"description\":\"Al teatro Regio a luglio \u00e8 il trionfo dell'opera italiana - Cultura, Arte e Spettacolo a Torino - Continua fino al 26 luglio prossimo la kermesse al Teatro Regio dal titolo \\\"The Best of \u00a0Italian Opera\\\", offerta culturale proposta nell'ambito di Expo -\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/files\\\/2015\\\/06\\\/Teatro_Regio_-_sala_grandangolo.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/files\\\/2015\\\/06\\\/Teatro_Regio_-_sala_grandangolo.jpg\",\"width\":1024,\"height\":683},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/#website\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/\",\"name\":\"Cultura, Arte e Spettacolo a Torino\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte\",\"sameAs\":[\"http:\\\/\\\/www.quotidianopiemontese.it\\\/\",\"https:\\\/\\\/www.facebook.com\\\/quotidianopiemontese\",\"https:\\\/\\\/x.com\\\/quotidianopiem\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cultura-arte-e-spettacolo-a-torino\\\/author\\\/administrator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Al teatro Regio a luglio \u00e8 il trionfo dell'opera italiana - 13 Luglio 2015","description":"Al teatro Regio a luglio \u00e8 il trionfo dell'opera italiana - Cultura, Arte e Spettacolo a Torino - Continua fino al 26 luglio prossimo la kermesse al Teatro Regio dal titolo \"The Best of \u00a0Italian Opera\", offerta culturale proposta nell'ambito di Expo -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana\/","og_locale":"it_IT","og_type":"article","og_title":"Al teatro Regio a luglio \u00e8 il trionfo dell'opera italiana - 13 Luglio 2015","og_description":"Al teatro Regio a luglio \u00e8 il trionfo dell'opera italiana - Cultura, Arte e Spettacolo a Torino - Continua fino al 26 luglio prossimo la kermesse al Teatro Regio dal titolo \"The Best of \u00a0Italian Opera\", offerta culturale proposta nell'ambito di Expo -","og_url":"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana\/","og_site_name":"Cultura, Arte e Spettacolo a Torino","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"https:\/\/www.facebook.com\/quotidianopiemontese","article_published_time":"2015-07-13T15:07:47+00:00","article_modified_time":"2015-07-14T06:01:20+00:00","og_image":[{"width":1024,"height":683,"url":"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2015\/06\/Teatro_Regio_-_sala_grandangolo.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana\/"},"author":{"name":"Redazione","@id":"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"headline":"Al teatro Regio a luglio \u00e8 il trionfo dell&#8217;opera italiana","datePublished":"2015-07-13T15:07:47+00:00","dateModified":"2015-07-14T06:01:20+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana\/"},"wordCount":262,"commentCount":0,"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2015\/06\/Teatro_Regio_-_sala_grandangolo.jpg","articleSection":["Cultura, arte, spettacolo"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana\/","url":"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana\/","name":"Al teatro Regio a luglio \u00e8 il trionfo dell'opera italiana - 13 Luglio 2015","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/#website"},"primaryImageOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana\/#primaryimage"},"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2015\/06\/Teatro_Regio_-_sala_grandangolo.jpg","datePublished":"2015-07-13T15:07:47+00:00","dateModified":"2015-07-14T06:01:20+00:00","author":{"@id":"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"description":"Al teatro Regio a luglio \u00e8 il trionfo dell'opera italiana - Cultura, Arte e Spettacolo a Torino - Continua fino al 26 luglio prossimo la kermesse al Teatro Regio dal titolo \"The Best of \u00a0Italian Opera\", offerta culturale proposta nell'ambito di Expo -","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/al-teatro-regio-a-luglio-e-il-trionfo-dellopera-italiana\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2015\/06\/Teatro_Regio_-_sala_grandangolo.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/files\/2015\/06\/Teatro_Regio_-_sala_grandangolo.jpg","width":1024,"height":683},{"@type":"WebSite","@id":"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/#website","url":"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/","name":"Cultura, Arte e Spettacolo a Torino","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","caption":"Redazione"},"description":"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte","sameAs":["http:\/\/www.quotidianopiemontese.it\/","https:\/\/www.facebook.com\/quotidianopiemontese","https:\/\/x.com\/quotidianopiem"],"url":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/author\/administrator\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/wp-json\/wp\/v2\/posts\/38","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/wp-json\/wp\/v2\/comments?post=38"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/wp-json\/wp\/v2\/posts\/38\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/wp-json\/wp\/v2\/media\/28"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/wp-json\/wp\/v2\/media?parent=38"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/wp-json\/wp\/v2\/categories?post=38"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cultura-arte-e-spettacolo-a-torino\/wp-json\/wp\/v2\/tags?post=38"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}