{"id":49,"date":"2011-03-20T18:38:15","date_gmt":"2011-03-20T18:38:15","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/cronachedicostume\/?p=49"},"modified":"2011-03-20T18:42:01","modified_gmt":"2011-03-20T18:42:01","slug":"etica-del-tradimento","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/etica-del-tradimento\/","title":{"rendered":"Etica del tradimento"},"content":{"rendered":"<p><strong>Prologo<\/strong><\/p>\n<p><a href=\"http:\/\/www.quotidianopiemontese.it\/cronachedicostume\/files\/2011\/03\/corna.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-51\" src=\"http:\/\/www.quotidianopiemontese.it\/cronachedicostume\/files\/2011\/03\/corna-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>L\u2019impresa \u00e8 quasi titanica perch\u00e9 il fedifrago \u00e8 un essere odioso, falso, pavido, irrispettoso, opportunista, camaleontico\u2026e, schiettamente, fa rivoltare lo stomaco.<\/p>\n<p>Ma ci sono casi commoventi di evasioni per disperazione, ammettiamolo. E, comunque le corna sono con noi, in noi o su di noi. Comunque la pensiate, insomma, fanno parte del nostro orizzonte probabile. Come tentazione, spada di Damocle, esperienza dolorosa o squallido exploit di trasgressione.<\/p>\n<p>Potessi dunque bollerei il tradimento d\u2019infamia e chiuderei l\u2019argomento a chiave nel ripostiglio degli umani orrori. Ma la realt\u00e0 incombe e, per quanto fortunatamente non ho conoscenza diretta e personale di simile onta, non posso chiudere gli occhi e far finta di non vedere il balletto di cornuti e infedeli. La storia e la vita ce ne hanno consegnato esempi illustri, potenti, clamorosi e l\u2019esercizio della tresca \u00e8 universale, trasversale, perversamente democratico.<\/p>\n<p>Troviamo vittime e carnefici tra i giovani come tra i vecchi, tra i belli e tra i brutti, nelle fila dei poveri e<a href=\"http:\/\/www.quotidianopiemontese.it\/cronachedicostume\/files\/2011\/03\/etica-del-tradimento.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-52\" src=\"http:\/\/www.quotidianopiemontese.it\/cronachedicostume\/files\/2011\/03\/etica-del-tradimento-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a> nei salotti dei ricchi. L\u2019attentato alla fedelt\u00e0 pu\u00f2 sfiorare o colpire il cuore di tutti. Come una maledizione. O come un\u2019inclinazione invincibile della natura.<\/p>\n<p>Verificata quindi l\u2019impossibilit\u00e0 di vincere la guerra con le corna possiamo almeno condurre una battaglia di rigore per un codice di decenza che ne attenui la villana essenza.<\/p>\n<p>Scrivo serenamente perch\u00e9 non ho l\u2019animo in subbuglio: non sono stata tradita o ignoro di esserlo stata, che meraviglia! E non ho neanche la patente di adultera quindi non ho polvere da nascondere sotto il tappeto o giustificazioni da cercare.<\/p>\n<p>Ma non per questo mi pongo qui come maestra davanti al pubblico di allievi, per carit\u00e0. Anzi! Questo codice lo scriveremo <strong>insieme<\/strong>, a decine, centinaia, migliaia di mani. <strong>A puntate, dibattito dopo dibattito<\/strong>.<\/p>\n<p>Ci sar\u00e0 spazio per chiunque abbia buoni consigli, illuminanti chiavi di lettura, graziosi aneddoti, speciali lezioni da offrire. Per chiunque voglia confrontarsi con questa grande avventura, non di piacere carnale ma intellettuale s\u2019intende\u2026<\/p>\n<p>Scopriremo che potremo amplificare all\u2019infinito le riflessioni perch\u00e9 il tradimento coinvolge sentimenti, relazioni, attitudini, valori. In amore, in amicizia, nei rapporti sociali. Forse ritrovarci <strong>periodicamente qui<\/strong>, talvolta con lievit\u00e0, qualche volta con serio spessore e sempre con vivace passione e acutezza di spirito potr\u00e0 portarci al compimento di un\u2019opera preziosa per la biblioteca umana e civile collettiva.<\/p>\n<p><a href=\"http:\/\/www.quotidianopiemontese.it\/cronachedicostume\/files\/2011\/03\/tradimento_.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-53\" src=\"http:\/\/www.quotidianopiemontese.it\/cronachedicostume\/files\/2011\/03\/tradimento_-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>E, lo so, faremo molto pi\u00f9 di un vademecum di bon ton applicato alle infedelt\u00e0, affronteremo le presunte o reali differenze emotive tra met\u00e0 del cielo, indagheremo impietosamente nelle pieghe delle parole, delle alleanze, degli impegni. Forse capiremo che il traditore \u00e8 spesso infedele innanzi tutto a se stesso\u2026O, chiss\u00e0, che la coerenza cieca \u00e8 virt\u00f9 talvolta barbara.<\/p>\n<p>Iniziamo, birichini e frizzanti, con una regola di stile da suggerire al fedifrago di coppia: adottare il minimo sindacale di disciplina ovvero non avviare troppi letti di trattativa, non pronunciare promesse impossibili, non pretendere troppo dall\u2019amante di turno\u2026<\/p>\n<p>E ora meditate, fornite spunti, lanciate provocazioni.<\/p>\n<p>Non solo corna in amore, ecco. La <strong>\u201ccategoria Etica del tradimento\u201d<\/strong> diventer\u00e0 un\u2019autentica enciclopedia dei legami, della fiducia, dell\u2019onest\u00e0, del coraggio!<\/p>\n<p>Alla prossima puntata.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prologo L\u2019impresa \u00e8 quasi titanica perch\u00e9 il fedifrago \u00e8 un essere odioso, falso, pavido, irrispettoso, opportunista, camaleontico\u2026e, schiettamente, fa rivoltare lo stomaco. Ma ci sono casi commoventi di evasioni per disperazione, ammettiamolo. E, comunque le corna sono con noi, in noi o su di noi. Comunque la pensiate, insomma, fanno parte del nostro orizzonte probabile. &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/etica-del-tradimento\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Etica del tradimento&#8221;<\/span><\/a><\/p>\n","protected":false},"author":49,"featured_media":53,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-49","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Etica del tradimento - Cronache di costume<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/etica-del-tradimento\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Etica del tradimento - Cronache di costume\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/etica-del-tradimento\/\" \/>\n<meta property=\"og:site_name\" content=\"Cronache di costume\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2011-03-20T18:38:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-03-20T18:42:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/files\/2011\/03\/tradimento_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"288\" \/>\n\t<meta property=\"og:image:height\" content=\"425\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Irene Spagnuolo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Irene Spagnuolo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/etica-del-tradimento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/etica-del-tradimento\\\/\"},\"author\":{\"name\":\"Irene Spagnuolo\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/#\\\/schema\\\/person\\\/c95598326023c3cb74d8c87afadfd22a\"},\"headline\":\"Etica del tradimento\",\"datePublished\":\"2011-03-20T18:38:15+00:00\",\"dateModified\":\"2011-03-20T18:42:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/etica-del-tradimento\\\/\"},\"wordCount\":518,\"commentCount\":4,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/etica-del-tradimento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/files\\\/2011\\\/03\\\/tradimento_.jpg\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/etica-del-tradimento\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/etica-del-tradimento\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/etica-del-tradimento\\\/\",\"name\":\"Etica del tradimento - Cronache di costume\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/etica-del-tradimento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/etica-del-tradimento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/files\\\/2011\\\/03\\\/tradimento_.jpg\",\"datePublished\":\"2011-03-20T18:38:15+00:00\",\"dateModified\":\"2011-03-20T18:42:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/#\\\/schema\\\/person\\\/c95598326023c3cb74d8c87afadfd22a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/etica-del-tradimento\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/etica-del-tradimento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/etica-del-tradimento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/files\\\/2011\\\/03\\\/tradimento_.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/files\\\/2011\\\/03\\\/tradimento_.jpg\",\"width\":\"288\",\"height\":\"425\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/etica-del-tradimento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Etica del tradimento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/\",\"name\":\"Cronache di costume\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/#\\\/schema\\\/person\\\/c95598326023c3cb74d8c87afadfd22a\",\"name\":\"Irene Spagnuolo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf879ac4f7f4f9a219343e5509729a2a37f728c6a749e63f8740b20032724bdd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf879ac4f7f4f9a219343e5509729a2a37f728c6a749e63f8740b20032724bdd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf879ac4f7f4f9a219343e5509729a2a37f728c6a749e63f8740b20032724bdd?s=96&d=mm&r=g\",\"caption\":\"Irene Spagnuolo\"},\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/author\\\/irene-spagnuolo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Etica del tradimento - Cronache di costume","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/etica-del-tradimento\/","og_locale":"it_IT","og_type":"article","og_title":"Etica del tradimento - Cronache di costume","og_url":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/etica-del-tradimento\/","og_site_name":"Cronache di costume","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2011-03-20T18:38:15+00:00","article_modified_time":"2011-03-20T18:42:01+00:00","og_image":[{"width":288,"height":425,"url":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/files\/2011\/03\/tradimento_.jpg","type":"image\/jpeg"}],"author":"Irene Spagnuolo","twitter_misc":{"Scritto da":"Irene Spagnuolo","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/etica-del-tradimento\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/etica-del-tradimento\/"},"author":{"name":"Irene Spagnuolo","@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/#\/schema\/person\/c95598326023c3cb74d8c87afadfd22a"},"headline":"Etica del tradimento","datePublished":"2011-03-20T18:38:15+00:00","dateModified":"2011-03-20T18:42:01+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/etica-del-tradimento\/"},"wordCount":518,"commentCount":4,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/etica-del-tradimento\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/files\/2011\/03\/tradimento_.jpg","inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/etica-del-tradimento\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/etica-del-tradimento\/","url":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/etica-del-tradimento\/","name":"Etica del tradimento - Cronache di costume","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/etica-del-tradimento\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/etica-del-tradimento\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/files\/2011\/03\/tradimento_.jpg","datePublished":"2011-03-20T18:38:15+00:00","dateModified":"2011-03-20T18:42:01+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/#\/schema\/person\/c95598326023c3cb74d8c87afadfd22a"},"breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/etica-del-tradimento\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/etica-del-tradimento\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/etica-del-tradimento\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/files\/2011\/03\/tradimento_.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/files\/2011\/03\/tradimento_.jpg","width":"288","height":"425"},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/etica-del-tradimento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/"},{"@type":"ListItem","position":2,"name":"Etica del tradimento"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/","name":"Cronache di costume","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/#\/schema\/person\/c95598326023c3cb74d8c87afadfd22a","name":"Irene Spagnuolo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cf879ac4f7f4f9a219343e5509729a2a37f728c6a749e63f8740b20032724bdd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cf879ac4f7f4f9a219343e5509729a2a37f728c6a749e63f8740b20032724bdd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cf879ac4f7f4f9a219343e5509729a2a37f728c6a749e63f8740b20032724bdd?s=96&d=mm&r=g","caption":"Irene Spagnuolo"},"url":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/author\/irene-spagnuolo\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/posts\/49","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/comments?post=49"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/posts\/49\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/media\/53"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/media?parent=49"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/categories?post=49"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/tags?post=49"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}