{"id":453,"date":"2014-12-09T19:49:30","date_gmt":"2014-12-09T19:49:30","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/cronachedicostume\/?p=453"},"modified":"2014-12-09T19:50:32","modified_gmt":"2014-12-09T19:50:32","slug":"453","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/453\/","title":{"rendered":"I soldi e la felicit\u00e0"},"content":{"rendered":"<p style=\"text-align: justify\"><a href=\"http:\/\/www.quotidianopiemontese.it\/cronachedicostume\/files\/2014\/12\/stati-danimo_cavez.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-454\" src=\"http:\/\/www.quotidianopiemontese.it\/cronachedicostume\/files\/2014\/12\/stati-danimo_cavez-264x300.jpg\" alt=\"stati d'animo_cavez\" width=\"264\" height=\"300\" srcset=\"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/files\/2014\/12\/stati-danimo_cavez-264x300.jpg 264w, https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/files\/2014\/12\/stati-danimo_cavez-901x1024.jpg 901w, https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/files\/2014\/12\/stati-danimo_cavez.jpg 1119w\" sizes=\"auto, (max-width: 264px) 85vw, 264px\" \/><\/a>I soldi, quelli che non danno la felicit\u00e0 ma fanno venire la vista ai ciechi, serviranno prima o poi alle cure di disintossicazione. C\u2019\u00e8 da augurarlo. A tutti quelli, che oltre ogni limite di comprensibile benessere, ne hanno fatto una malattia.<\/p>\n<p style=\"text-align: justify\">Potere e ricchezza, il fulcro della disfatta. Per gli altri. Che quelli che ci sguazzano dentro, la vita se la godono. Senza neanche incubi di notte. Per le ruberie, le ingiustizie, le evasioni, le truffe.<\/p>\n<p style=\"text-align: justify\">Marci e corrotti. E d\u2019altra parte gli siamo andati tutti dietro. A questo barbaro \u2018sistema\u2019 senza morale e senza cultura. Gi\u00e0, senza cultura. Perch\u00e9 in fondo \u00e8 tutto l\u00ec. Se ha smanie di conoscenza, musica, arte, teatro, letteratura non metti su castelli, non ti importa dello yacht e fai pure a meno di pailettes per le serate di gala. Hai amore. Per le cose belle, per i sentimenti, per le condivisioni, per la natura. Dentro, hai la fiammella. Quella della curiosit\u00e0, delle emozioni, perfino della tua integrit\u00e0. Se invece punti tutto su rolex e dintorni ti interessa solo avere il conto corrente bello gonfio.<\/p>\n<p style=\"text-align: justify\">D\u2019accordo, pure questa \u00e8 generalizzazione. Pure questa \u00e8 semplificazione. Pure questo \u00e8 parere del tutto arbitrario.<\/p>\n<p style=\"text-align: justify\">Lo ammetto, se volete. Provate il contrario e sar\u00f2 ben lieta di accogliere le eccezioni. Chi mette le mani in pasta e accumula alla faccia di tutti ha il pelo sullo stomaco, se ne infischia della poesia, monetizza qualsiasi cosa.<\/p>\n<p style=\"text-align: justify\">Che poi siano davvero felici resta da dimostrare, lo so. Magari sono sempre nervosi, insoddisfatti, mangiati dall\u2019invidia, inseguiti da qualche paura. Devono guardarsi le spalle quindi non hanno amici e partner fedeli. Hanno il cervello in fumo per conti, strategie, equilibrismi, affari.<\/p>\n<p style=\"text-align: justify\">Intanto per\u00f2 fanno quello che, scioccamente, consideriamo un\u2019esistenza al top: agi a gog\u00f2, jet privato, champagne a fiumi. Sniffate di coca e sesso a pagamento, a tutte le ore. Cosa ci sia di tanto allegro ed entusiasmante non mi \u00e8 dato capirlo, resta il fatto che a considerarli furbi e privilegiati sono ancora in molti\u2026<\/p>\n<p style=\"text-align: justify\">Sar\u00e0 la stupidata del secolo eppure sono convinta che se iniziassimo a considerarli per quello che sono ovvero ladri, miseri di spirito, crudeli sfruttatori e insensibili della peggior specie metteremmo un\u2019enorme pietra tombale sulla loro gloria, sul loro successo e sulla loro soddisfazione.<\/p>\n<p style=\"text-align: justify\">Diciamolo, certi pruriti sono alimentati dalla \u2018considerazione sociale\u2019, dall\u2019appeal esercitato su donne o uomini, dal sottile piacere di sentirsi ammirati e ambiti. Se gli togliessimo il piedistallo da sotto i piedi e li guardassimo con tutto lo sdegno che meritano abbasserebbero le ali. E, chiss\u00e0, tornerebbero magari a una dimensione umana.<\/p>\n<p style=\"text-align: justify\">Io lo faccio. E voi?<\/p>\n<p style=\"text-align: justify\">Irene Spagnuolo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I soldi, quelli che non danno la felicit\u00e0 ma fanno venire la vista ai ciechi, serviranno prima o poi alle cure di disintossicazione. C\u2019\u00e8 da augurarlo. A tutti quelli, che oltre ogni limite di comprensibile benessere, ne hanno fatto una malattia. Potere e ricchezza, il fulcro della disfatta. Per gli altri. Che quelli che ci &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/453\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;I soldi e la felicit\u00e0&#8221;<\/span><\/a><\/p>\n","protected":false},"author":49,"featured_media":454,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-453","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I soldi e la felicit\u00e0 - Cronache di costume<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/453\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I soldi e la felicit\u00e0 - Cronache di costume\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/453\/\" \/>\n<meta property=\"og:site_name\" content=\"Cronache di costume\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2014-12-09T19:49:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-12-09T19:50:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/files\/2014\/12\/stati-danimo_cavez.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1119\" \/>\n\t<meta property=\"og:image:height\" content=\"1271\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Irene Spagnuolo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Irene Spagnuolo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/453\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/453\\\/\"},\"author\":{\"name\":\"Irene Spagnuolo\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/#\\\/schema\\\/person\\\/c95598326023c3cb74d8c87afadfd22a\"},\"headline\":\"I soldi e la felicit\u00e0\",\"datePublished\":\"2014-12-09T19:49:30+00:00\",\"dateModified\":\"2014-12-09T19:50:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/453\\\/\"},\"wordCount\":440,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/453\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/files\\\/2014\\\/12\\\/stati-danimo_cavez.jpg\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/453\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/453\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/453\\\/\",\"name\":\"I soldi e la felicit\u00e0 - Cronache di costume\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/453\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/453\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/files\\\/2014\\\/12\\\/stati-danimo_cavez.jpg\",\"datePublished\":\"2014-12-09T19:49:30+00:00\",\"dateModified\":\"2014-12-09T19:50:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/#\\\/schema\\\/person\\\/c95598326023c3cb74d8c87afadfd22a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/453\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/453\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/453\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/files\\\/2014\\\/12\\\/stati-danimo_cavez.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/files\\\/2014\\\/12\\\/stati-danimo_cavez.jpg\",\"width\":1119,\"height\":1271},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/453\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I soldi e la felicit\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/\",\"name\":\"Cronache di costume\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/#\\\/schema\\\/person\\\/c95598326023c3cb74d8c87afadfd22a\",\"name\":\"Irene Spagnuolo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf879ac4f7f4f9a219343e5509729a2a37f728c6a749e63f8740b20032724bdd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf879ac4f7f4f9a219343e5509729a2a37f728c6a749e63f8740b20032724bdd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf879ac4f7f4f9a219343e5509729a2a37f728c6a749e63f8740b20032724bdd?s=96&d=mm&r=g\",\"caption\":\"Irene Spagnuolo\"},\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/author\\\/irene-spagnuolo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I soldi e la felicit\u00e0 - Cronache di costume","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/453\/","og_locale":"it_IT","og_type":"article","og_title":"I soldi e la felicit\u00e0 - Cronache di costume","og_url":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/453\/","og_site_name":"Cronache di costume","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2014-12-09T19:49:30+00:00","article_modified_time":"2014-12-09T19:50:32+00:00","og_image":[{"width":1119,"height":1271,"url":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/files\/2014\/12\/stati-danimo_cavez.jpg","type":"image\/jpeg"}],"author":"Irene Spagnuolo","twitter_misc":{"Scritto da":"Irene Spagnuolo","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/453\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/453\/"},"author":{"name":"Irene Spagnuolo","@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/#\/schema\/person\/c95598326023c3cb74d8c87afadfd22a"},"headline":"I soldi e la felicit\u00e0","datePublished":"2014-12-09T19:49:30+00:00","dateModified":"2014-12-09T19:50:32+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/453\/"},"wordCount":440,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/453\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/files\/2014\/12\/stati-danimo_cavez.jpg","inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/453\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/453\/","url":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/453\/","name":"I soldi e la felicit\u00e0 - Cronache di costume","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/453\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/453\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/files\/2014\/12\/stati-danimo_cavez.jpg","datePublished":"2014-12-09T19:49:30+00:00","dateModified":"2014-12-09T19:50:32+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/#\/schema\/person\/c95598326023c3cb74d8c87afadfd22a"},"breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/453\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/453\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/453\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/files\/2014\/12\/stati-danimo_cavez.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/files\/2014\/12\/stati-danimo_cavez.jpg","width":1119,"height":1271},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/453\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/"},{"@type":"ListItem","position":2,"name":"I soldi e la felicit\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/","name":"Cronache di costume","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/#\/schema\/person\/c95598326023c3cb74d8c87afadfd22a","name":"Irene Spagnuolo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cf879ac4f7f4f9a219343e5509729a2a37f728c6a749e63f8740b20032724bdd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cf879ac4f7f4f9a219343e5509729a2a37f728c6a749e63f8740b20032724bdd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cf879ac4f7f4f9a219343e5509729a2a37f728c6a749e63f8740b20032724bdd?s=96&d=mm&r=g","caption":"Irene Spagnuolo"},"url":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/author\/irene-spagnuolo\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/posts\/453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/comments?post=453"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/posts\/453\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/media\/454"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/media?parent=453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/categories?post=453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/tags?post=453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}