{"id":444,"date":"2014-11-22T14:37:54","date_gmt":"2014-11-22T14:37:54","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/cronachedicostume\/?p=444"},"modified":"2014-11-22T14:37:54","modified_gmt":"2014-11-22T14:37:54","slug":"sesso-on-line","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/sesso-on-line\/","title":{"rendered":"Sesso on line"},"content":{"rendered":"<p style=\"text-align: justify\"><a href=\"http:\/\/www.quotidianopiemontese.it\/cronachedicostume\/files\/2014\/11\/sesso_on_line.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-445\" src=\"http:\/\/www.quotidianopiemontese.it\/cronachedicostume\/files\/2014\/11\/sesso_on_line.jpg\" alt=\"sesso_on_line\" width=\"257\" height=\"196\" \/><\/a>E\u2019 ciclico. Non il sesso, lo scoop. Il grido di allarme, insomma. La verit\u00e0 \u00e8 che da anni il sesso, non solo on line, \u00e8 diventato una sorta di misuratore della cultura e della salute sociale. In un certo senso \u00e8 normalissimo, ne fa parte a pieno titolo, come espressione della mentalit\u00e0, delle tendenze, del concetto scivoloso di \u2018libert\u00e0\u2019 o di quello \u2013ancora pi\u00f9 delicato e tortuoso- di morale.<\/p>\n<p style=\"text-align: justify\">Ma sul grido bisogna intendersi.<\/p>\n<p style=\"text-align: justify\">Normalmente \u00e8 lanciato non perch\u00e9 si registra chiss\u00e0 quale fenomeno dopo chiss\u00e0 quale studio. Talvolta \u00e8 il classico polverone. Altre volte \u00e8 un espediente per attirare attenzione. Qualche volta ancora si muove su un caso, pi\u00f9 o meno eclatante, per tessere tutta una trama di considerazioni, pericoli, stupori, indignazioni.<\/p>\n<p style=\"text-align: justify\">Che le ragazzine barattino il corpo con un cellulare, tanto per fare un esempio, non \u00e8 una novit\u00e0. Che la soglia di percezione della bellezza o della gioia passi dalla conquista di sguardi lascivi, di advances di adulti possibilmente vip, di prodezze erotiche \u00e8 altrettanto noto. Che i social network siano spesso una carrellata di selfie provocanti anche.<\/p>\n<p style=\"text-align: justify\">Il sesso on line per la giovane et\u00e0 \u2013e forse, chiss\u00e0, pure per quella adulta- \u00e8 la panacea per tutti i mali. Conquisto quindi gongolo. Faccio godere quindi godo. Non corro i rischi del tete a tete reale quindi sono al sicuro. Sto su internet quindi nessuno lo sa. Che poi tutto questo possa essere terribile \u00e8 altra storia. Anzi. Il punto \u00e8 proprio questo. Guardarci dentro davvero, a questa via disperata del sesso on line.<\/p>\n<p style=\"text-align: justify\">E sarebbe il caso di farlo seriamente. Non con gli scoop. Andando a scovare cosa non funziona nei modelli del nostro tempo, nell\u2019educazione, nei rapporti umani completamente in tilt. E pure nel sesso vissuto senza pelle, accidenti. Con coraggio, ovviamente. Perch\u00e9 bisogna partire dalla voglia di sapere e capire. Allora bisogna ammettere, da una parte, la voglia di sesso, dall\u2019altra l\u2019assenza o la carenza di una relazione piena, profonda e importante tra le persone, tra genitori e figli, tra docenti e allievi, tra adulti e giovani.<\/p>\n<p style=\"text-align: justify\">Ecco, tolte le patologie o le situazioni estreme di qualche peculiare disagio, il sesso dovrebbe essere un sereno momento della natura della vita. O no?<\/p>\n<p style=\"text-align: justify\">Irene Spagnuolo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E\u2019 ciclico. Non il sesso, lo scoop. Il grido di allarme, insomma. La verit\u00e0 \u00e8 che da anni il sesso, non solo on line, \u00e8 diventato una sorta di misuratore della cultura e della salute sociale. In un certo senso \u00e8 normalissimo, ne fa parte a pieno titolo, come espressione della mentalit\u00e0, delle tendenze, del &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/sesso-on-line\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Sesso on line&#8221;<\/span><\/a><\/p>\n","protected":false},"author":49,"featured_media":445,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-444","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sesso on line - Cronache di costume<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/sesso-on-line\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sesso on line - Cronache di costume\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/sesso-on-line\/\" \/>\n<meta property=\"og:site_name\" content=\"Cronache di costume\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2014-11-22T14:37:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/files\/2014\/11\/sesso_on_line.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"257\" \/>\n\t<meta property=\"og:image:height\" content=\"196\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Irene Spagnuolo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Irene Spagnuolo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/sesso-on-line\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/sesso-on-line\\\/\"},\"author\":{\"name\":\"Irene Spagnuolo\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/#\\\/schema\\\/person\\\/c95598326023c3cb74d8c87afadfd22a\"},\"headline\":\"Sesso on line\",\"datePublished\":\"2014-11-22T14:37:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/sesso-on-line\\\/\"},\"wordCount\":365,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/sesso-on-line\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/files\\\/2014\\\/11\\\/sesso_on_line.jpg\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/sesso-on-line\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/sesso-on-line\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/sesso-on-line\\\/\",\"name\":\"Sesso on line - Cronache di costume\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/sesso-on-line\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/sesso-on-line\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/files\\\/2014\\\/11\\\/sesso_on_line.jpg\",\"datePublished\":\"2014-11-22T14:37:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/#\\\/schema\\\/person\\\/c95598326023c3cb74d8c87afadfd22a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/sesso-on-line\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/sesso-on-line\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/sesso-on-line\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/files\\\/2014\\\/11\\\/sesso_on_line.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/files\\\/2014\\\/11\\\/sesso_on_line.jpg\",\"width\":257,\"height\":196},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/sesso-on-line\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sesso on line\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/\",\"name\":\"Cronache di costume\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/#\\\/schema\\\/person\\\/c95598326023c3cb74d8c87afadfd22a\",\"name\":\"Irene Spagnuolo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf879ac4f7f4f9a219343e5509729a2a37f728c6a749e63f8740b20032724bdd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf879ac4f7f4f9a219343e5509729a2a37f728c6a749e63f8740b20032724bdd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf879ac4f7f4f9a219343e5509729a2a37f728c6a749e63f8740b20032724bdd?s=96&d=mm&r=g\",\"caption\":\"Irene Spagnuolo\"},\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/author\\\/irene-spagnuolo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sesso on line - Cronache di costume","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/sesso-on-line\/","og_locale":"it_IT","og_type":"article","og_title":"Sesso on line - Cronache di costume","og_url":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/sesso-on-line\/","og_site_name":"Cronache di costume","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2014-11-22T14:37:54+00:00","og_image":[{"width":257,"height":196,"url":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/files\/2014\/11\/sesso_on_line.jpg","type":"image\/jpeg"}],"author":"Irene Spagnuolo","twitter_misc":{"Scritto da":"Irene Spagnuolo","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/sesso-on-line\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/sesso-on-line\/"},"author":{"name":"Irene Spagnuolo","@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/#\/schema\/person\/c95598326023c3cb74d8c87afadfd22a"},"headline":"Sesso on line","datePublished":"2014-11-22T14:37:54+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/sesso-on-line\/"},"wordCount":365,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/sesso-on-line\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/files\/2014\/11\/sesso_on_line.jpg","inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/sesso-on-line\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/sesso-on-line\/","url":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/sesso-on-line\/","name":"Sesso on line - Cronache di costume","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/sesso-on-line\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/sesso-on-line\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/files\/2014\/11\/sesso_on_line.jpg","datePublished":"2014-11-22T14:37:54+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/#\/schema\/person\/c95598326023c3cb74d8c87afadfd22a"},"breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/sesso-on-line\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/sesso-on-line\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/sesso-on-line\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/files\/2014\/11\/sesso_on_line.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/files\/2014\/11\/sesso_on_line.jpg","width":257,"height":196},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/sesso-on-line\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/"},{"@type":"ListItem","position":2,"name":"Sesso on line"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/","name":"Cronache di costume","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/#\/schema\/person\/c95598326023c3cb74d8c87afadfd22a","name":"Irene Spagnuolo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cf879ac4f7f4f9a219343e5509729a2a37f728c6a749e63f8740b20032724bdd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cf879ac4f7f4f9a219343e5509729a2a37f728c6a749e63f8740b20032724bdd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cf879ac4f7f4f9a219343e5509729a2a37f728c6a749e63f8740b20032724bdd?s=96&d=mm&r=g","caption":"Irene Spagnuolo"},"url":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/author\/irene-spagnuolo\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/posts\/444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/comments?post=444"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/posts\/444\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/media\/445"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/media?parent=444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/categories?post=444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/tags?post=444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}