{"id":105,"date":"2011-05-08T18:46:07","date_gmt":"2011-05-08T18:46:07","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/cronachedicostume\/?p=105"},"modified":"2011-05-08T18:46:07","modified_gmt":"2011-05-08T18:46:07","slug":"il-gusto-di-lady-gaga","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/il-gusto-di-lady-gaga\/","title":{"rendered":"Il gusto di Lady Gaga"},"content":{"rendered":"<p><a href=\"http:\/\/www.quotidianopiemontese.it\/cronachedicostume\/files\/2011\/05\/lady-gaga.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-106\" src=\"http:\/\/www.quotidianopiemontese.it\/cronachedicostume\/files\/2011\/05\/lady-gaga.jpg\" alt=\"\" width=\"140\" height=\"140\" \/><\/a>Al di l\u00e0 delle polemiche morali e religiose, canzoni, concerti e video di Lady Gaga sono un fenomeno culturale \u201cimbarazzante\u201d. La questione non \u00e8 tanto quella di incensare o censurare quella manifestazione eccentrica, provocatoria, irriverente, teatrale o trasgressiva. Quanto quella di capire il gusto dell\u2019elaborazione apocalittica, estrema, paradossale.<\/p>\n<p>Prescindendo dai contenuti insomma mi chiedo quanto sia sostenibile, umanamente e artisticamente, un\u2019espressione cos\u00ec abnorme. Perch\u00e9 il suo successo \u00e8 la misura di un gradimento e di un\u2019attrazione incontenibili per l\u2019esibizione sfrenata, la lacerazione deflagrante. Lo spettacolo lascivo, macabro e disgustoso si celebra in un rituale di trucchi, movenze, luci e scene che hanno tutta l\u2019urgenza di scioccare e suggestionare. E il pubblico di affascinati seguaci di quello show di horror impudico, dissacrante, clamoroso si fa d\u2019altra parte motore di sempre nuove impennate della diva Lady Gaga.<\/p>\n<p>Questo \u00e8 il punto: il mercato plaude a quella maschera che oltraggia i confini della bellezza, dell\u2019eleganza, del rispetto. E non credo che la ragione affondi in qualche messaggio positivo che si voglia intravedere in quella stravaganza che pu\u00f2 infrangere le ipocrisie delle apparenze. Prima di questo, ammesso sia una valutazione possibile, c\u2019\u00e8 l\u2019aspetto sociale generale. Ovvero c\u2019\u00e8 una platea di riferimento che in quella profanazione sguaiata del buon gusto trova abbondanti motivi di eccitazione, entusiasmo, piacere.<\/p>\n<p>Non credo sia un inno alla libert\u00e0. Affranchiamoci da questa smania di sventolare la libert\u00e0 per giustificare e permettere qualsiasi cosa, anche la pi\u00f9 turpe o la meno civile!<\/p>\n<p>C\u2019\u00e8 solo un\u2019insoddisfazione patologica. Uno stordimento pericoloso. Un\u2019ossessione spaventosa. Violare e beffare la decenza non \u00e8 una conquista di cui andare fieri, accidenti. Eppure oggi \u00e8 coraggioso sostenerlo.<\/p>\n<p>Non \u00e8 un processo a Lady Gaga, ovviamente. Temo al pi\u00f9 che scrivere di lei, nel bene o nel male, non faccia che alimentare il mito\u2026<\/p>\n<p>E\u2019 la rappresentazione di una realt\u00e0 raccapricciante come certi suoi video appunto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al di l\u00e0 delle polemiche morali e religiose, canzoni, concerti e video di Lady Gaga sono un fenomeno culturale \u201cimbarazzante\u201d. La questione non \u00e8 tanto quella di incensare o censurare quella manifestazione eccentrica, provocatoria, irriverente, teatrale o trasgressiva. Quanto quella di capire il gusto dell\u2019elaborazione apocalittica, estrema, paradossale. Prescindendo dai contenuti insomma mi chiedo quanto &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/il-gusto-di-lady-gaga\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Il gusto di Lady Gaga&#8221;<\/span><\/a><\/p>\n","protected":false},"author":49,"featured_media":106,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il gusto di Lady Gaga - Cronache di costume<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/il-gusto-di-lady-gaga\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il gusto di Lady Gaga - Cronache di costume\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/il-gusto-di-lady-gaga\/\" \/>\n<meta property=\"og:site_name\" content=\"Cronache di costume\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2011-05-08T18:46:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/files\/2011\/05\/lady-gaga.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"140\" \/>\n\t<meta property=\"og:image:height\" content=\"140\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Irene Spagnuolo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Irene Spagnuolo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/il-gusto-di-lady-gaga\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/il-gusto-di-lady-gaga\\\/\"},\"author\":{\"name\":\"Irene Spagnuolo\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/#\\\/schema\\\/person\\\/c95598326023c3cb74d8c87afadfd22a\"},\"headline\":\"Il gusto di Lady Gaga\",\"datePublished\":\"2011-05-08T18:46:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/il-gusto-di-lady-gaga\\\/\"},\"wordCount\":316,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/il-gusto-di-lady-gaga\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/files\\\/2011\\\/05\\\/lady-gaga.jpg\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/il-gusto-di-lady-gaga\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/il-gusto-di-lady-gaga\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/il-gusto-di-lady-gaga\\\/\",\"name\":\"Il gusto di Lady Gaga - Cronache di costume\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/il-gusto-di-lady-gaga\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/il-gusto-di-lady-gaga\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/files\\\/2011\\\/05\\\/lady-gaga.jpg\",\"datePublished\":\"2011-05-08T18:46:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/#\\\/schema\\\/person\\\/c95598326023c3cb74d8c87afadfd22a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/il-gusto-di-lady-gaga\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/il-gusto-di-lady-gaga\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/il-gusto-di-lady-gaga\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/files\\\/2011\\\/05\\\/lady-gaga.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/files\\\/2011\\\/05\\\/lady-gaga.jpg\",\"width\":\"140\",\"height\":\"140\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/il-gusto-di-lady-gaga\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il gusto di Lady Gaga\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/\",\"name\":\"Cronache di costume\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/#\\\/schema\\\/person\\\/c95598326023c3cb74d8c87afadfd22a\",\"name\":\"Irene Spagnuolo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf879ac4f7f4f9a219343e5509729a2a37f728c6a749e63f8740b20032724bdd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf879ac4f7f4f9a219343e5509729a2a37f728c6a749e63f8740b20032724bdd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf879ac4f7f4f9a219343e5509729a2a37f728c6a749e63f8740b20032724bdd?s=96&d=mm&r=g\",\"caption\":\"Irene Spagnuolo\"},\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cronachedicostume\\\/author\\\/irene-spagnuolo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il gusto di Lady Gaga - Cronache di costume","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/il-gusto-di-lady-gaga\/","og_locale":"it_IT","og_type":"article","og_title":"Il gusto di Lady Gaga - Cronache di costume","og_url":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/il-gusto-di-lady-gaga\/","og_site_name":"Cronache di costume","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2011-05-08T18:46:07+00:00","og_image":[{"width":140,"height":140,"url":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/files\/2011\/05\/lady-gaga.jpg","type":"image\/jpeg"}],"author":"Irene Spagnuolo","twitter_misc":{"Scritto da":"Irene Spagnuolo","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/il-gusto-di-lady-gaga\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/il-gusto-di-lady-gaga\/"},"author":{"name":"Irene Spagnuolo","@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/#\/schema\/person\/c95598326023c3cb74d8c87afadfd22a"},"headline":"Il gusto di Lady Gaga","datePublished":"2011-05-08T18:46:07+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/il-gusto-di-lady-gaga\/"},"wordCount":316,"commentCount":2,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/il-gusto-di-lady-gaga\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/files\/2011\/05\/lady-gaga.jpg","inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/il-gusto-di-lady-gaga\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/il-gusto-di-lady-gaga\/","url":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/il-gusto-di-lady-gaga\/","name":"Il gusto di Lady Gaga - Cronache di costume","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/il-gusto-di-lady-gaga\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/il-gusto-di-lady-gaga\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/files\/2011\/05\/lady-gaga.jpg","datePublished":"2011-05-08T18:46:07+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/#\/schema\/person\/c95598326023c3cb74d8c87afadfd22a"},"breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/il-gusto-di-lady-gaga\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/il-gusto-di-lady-gaga\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/il-gusto-di-lady-gaga\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/files\/2011\/05\/lady-gaga.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/files\/2011\/05\/lady-gaga.jpg","width":"140","height":"140"},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/il-gusto-di-lady-gaga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/"},{"@type":"ListItem","position":2,"name":"Il gusto di Lady Gaga"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/","name":"Cronache di costume","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/#\/schema\/person\/c95598326023c3cb74d8c87afadfd22a","name":"Irene Spagnuolo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cf879ac4f7f4f9a219343e5509729a2a37f728c6a749e63f8740b20032724bdd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cf879ac4f7f4f9a219343e5509729a2a37f728c6a749e63f8740b20032724bdd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cf879ac4f7f4f9a219343e5509729a2a37f728c6a749e63f8740b20032724bdd?s=96&d=mm&r=g","caption":"Irene Spagnuolo"},"url":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/author\/irene-spagnuolo\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/posts\/105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/comments?post=105"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/posts\/105\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/media\/106"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/media?parent=105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/categories?post=105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cronachedicostume\/wp-json\/wp\/v2\/tags?post=105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}