{"id":64,"date":"2011-12-30T18:51:20","date_gmt":"2011-12-30T18:51:20","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/costameno\/?p=64"},"modified":"2011-12-30T18:51:20","modified_gmt":"2011-12-30T18:51:20","slug":"il-primo-regalo-del-2012-musei-statali-gratis-in-piemonte-il-pomeriggio-del-1-gennaio","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/costameno\/il-primo-regalo-del-2012-musei-statali-gratis-in-piemonte-il-pomeriggio-del-1-gennaio\/","title":{"rendered":"Il primo regalo del 2012? Musei statali gratis in Piemonte il pomeriggio del 1\u00b0 gennaio"},"content":{"rendered":"<p>Dopo i piaceri della tavola, dunque del corpo, \u00a0gli appassionati di arte e cultura possono \u201cbanchettare\u201d soddisfacendo la mente il pomeriggio di domenica 1\u00b0 gennaio. Per Capodanno, infatti, i musei statali di Torino e del Piemonte aprono le loro porte anche se con orario ridotto. <!--more-->Dalle ore 13:30 alle 19 Palazzo Carignano, Villa della Regina, l\u2019Armeria Reale e il Castello di Agli\u00e8 e dalle 14 alle 19:30 il Museo di Antichit\u00e0 e il Castello di Racconigi aprono gratis. Gam, Mao e Borgo medievale sono aperti dalle 14 sino alle 18, Palazzo Madama (con la michelangiolesca <em>Madonna con il Bambino<\/em>) dalle 14 alle 20. Chiusi il Museo del Risorgimento, la Fondazione Merz, la Pinacoteca Agnelli, la Fondazione Accorsi e il Museo di Scienze Naturali. Il Museo dell\u2019Automobile e quello del Cinema aprono dalle 15 e chiudono, rispettivamente, alle 19 e alle 20. Il biglietto del Museo Egizio costa 1 euro (orario 10:30-19:30).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo i piaceri della tavola, dunque del corpo, \u00a0gli appassionati di arte e cultura possono \u201cbanchettare\u201d soddisfacendo la mente il pomeriggio di domenica 1\u00b0 gennaio. Per Capodanno, infatti, i musei statali di Torino e del Piemonte aprono le loro porte anche se con orario ridotto.<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[48,50,47,43,49,9,51,13],"class_list":["post-64","post","type-post","status-publish","format-standard","hentry","category-costa-meno","tag-1-gennaio","tag-capodanno","tag-gratis","tag-musei","tag-orari","tag-piemonte","tag-pomeriggio","tag-torino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il primo regalo del 2012? Musei statali gratis in Piemonte il pomeriggio del 1\u00b0 gennaio - Costa Meno<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/costameno\/il-primo-regalo-del-2012-musei-statali-gratis-in-piemonte-il-pomeriggio-del-1-gennaio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il primo regalo del 2012? Musei statali gratis in Piemonte il pomeriggio del 1\u00b0 gennaio - Costa Meno\" \/>\n<meta property=\"og:description\" content=\"Dopo i piaceri della tavola, dunque del corpo, \u00a0gli appassionati di arte e cultura possono \u201cbanchettare\u201d soddisfacendo la mente il pomeriggio di domenica 1\u00b0 gennaio. Per Capodanno, infatti, i musei statali di Torino e del Piemonte aprono le loro porte anche se con orario ridotto.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/costameno\/il-primo-regalo-del-2012-musei-statali-gratis-in-piemonte-il-pomeriggio-del-1-gennaio\/\" \/>\n<meta property=\"og:site_name\" content=\"Costa Meno\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2011-12-30T18:51:20+00:00\" \/>\n<meta name=\"author\" content=\"Davide Mazzocco\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Davide Mazzocco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/il-primo-regalo-del-2012-musei-statali-gratis-in-piemonte-il-pomeriggio-del-1-gennaio\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/il-primo-regalo-del-2012-musei-statali-gratis-in-piemonte-il-pomeriggio-del-1-gennaio\\\/\"},\"author\":{\"name\":\"Davide Mazzocco\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/#\\\/schema\\\/person\\\/bf9fd8def4eff5faacb4294c9354c800\"},\"headline\":\"Il primo regalo del 2012? Musei statali gratis in Piemonte il pomeriggio del 1\u00b0 gennaio\",\"datePublished\":\"2011-12-30T18:51:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/il-primo-regalo-del-2012-musei-statali-gratis-in-piemonte-il-pomeriggio-del-1-gennaio\\\/\"},\"wordCount\":153,\"commentCount\":0,\"keywords\":[\"1\u00b0 gennaio\",\"capodanno\",\"gratis\",\"musei\",\"orari\",\"piemonte\",\"pomeriggio\",\"torino\"],\"articleSection\":[\"Costa Meno\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/il-primo-regalo-del-2012-musei-statali-gratis-in-piemonte-il-pomeriggio-del-1-gennaio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/il-primo-regalo-del-2012-musei-statali-gratis-in-piemonte-il-pomeriggio-del-1-gennaio\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/il-primo-regalo-del-2012-musei-statali-gratis-in-piemonte-il-pomeriggio-del-1-gennaio\\\/\",\"name\":\"Il primo regalo del 2012? Musei statali gratis in Piemonte il pomeriggio del 1\u00b0 gennaio - Costa Meno\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/#website\"},\"datePublished\":\"2011-12-30T18:51:20+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/#\\\/schema\\\/person\\\/bf9fd8def4eff5faacb4294c9354c800\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/il-primo-regalo-del-2012-musei-statali-gratis-in-piemonte-il-pomeriggio-del-1-gennaio\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/#website\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/\",\"name\":\"Costa Meno\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/#\\\/schema\\\/person\\\/bf9fd8def4eff5faacb4294c9354c800\",\"name\":\"Davide Mazzocco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6eb81b0a007fca80a7dafc2d7c6c4ee743c69ab1dad3d1e7ec19028222c502b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6eb81b0a007fca80a7dafc2d7c6c4ee743c69ab1dad3d1e7ec19028222c502b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6eb81b0a007fca80a7dafc2d7c6c4ee743c69ab1dad3d1e7ec19028222c502b?s=96&d=mm&r=g\",\"caption\":\"Davide Mazzocco\"},\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/author\\\/davide-mazzocco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il primo regalo del 2012? Musei statali gratis in Piemonte il pomeriggio del 1\u00b0 gennaio - Costa Meno","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/costameno\/il-primo-regalo-del-2012-musei-statali-gratis-in-piemonte-il-pomeriggio-del-1-gennaio\/","og_locale":"it_IT","og_type":"article","og_title":"Il primo regalo del 2012? Musei statali gratis in Piemonte il pomeriggio del 1\u00b0 gennaio - Costa Meno","og_description":"Dopo i piaceri della tavola, dunque del corpo, \u00a0gli appassionati di arte e cultura possono \u201cbanchettare\u201d soddisfacendo la mente il pomeriggio di domenica 1\u00b0 gennaio. Per Capodanno, infatti, i musei statali di Torino e del Piemonte aprono le loro porte anche se con orario ridotto.","og_url":"http:\/\/web.quotidianopiemontese.it\/costameno\/il-primo-regalo-del-2012-musei-statali-gratis-in-piemonte-il-pomeriggio-del-1-gennaio\/","og_site_name":"Costa Meno","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2011-12-30T18:51:20+00:00","author":"Davide Mazzocco","twitter_misc":{"Scritto da":"Davide Mazzocco","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/costameno\/il-primo-regalo-del-2012-musei-statali-gratis-in-piemonte-il-pomeriggio-del-1-gennaio\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/costameno\/il-primo-regalo-del-2012-musei-statali-gratis-in-piemonte-il-pomeriggio-del-1-gennaio\/"},"author":{"name":"Davide Mazzocco","@id":"http:\/\/web.quotidianopiemontese.it\/costameno\/#\/schema\/person\/bf9fd8def4eff5faacb4294c9354c800"},"headline":"Il primo regalo del 2012? Musei statali gratis in Piemonte il pomeriggio del 1\u00b0 gennaio","datePublished":"2011-12-30T18:51:20+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/costameno\/il-primo-regalo-del-2012-musei-statali-gratis-in-piemonte-il-pomeriggio-del-1-gennaio\/"},"wordCount":153,"commentCount":0,"keywords":["1\u00b0 gennaio","capodanno","gratis","musei","orari","piemonte","pomeriggio","torino"],"articleSection":["Costa Meno"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/costameno\/il-primo-regalo-del-2012-musei-statali-gratis-in-piemonte-il-pomeriggio-del-1-gennaio\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/costameno\/il-primo-regalo-del-2012-musei-statali-gratis-in-piemonte-il-pomeriggio-del-1-gennaio\/","url":"http:\/\/web.quotidianopiemontese.it\/costameno\/il-primo-regalo-del-2012-musei-statali-gratis-in-piemonte-il-pomeriggio-del-1-gennaio\/","name":"Il primo regalo del 2012? Musei statali gratis in Piemonte il pomeriggio del 1\u00b0 gennaio - Costa Meno","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/costameno\/#website"},"datePublished":"2011-12-30T18:51:20+00:00","author":{"@id":"http:\/\/web.quotidianopiemontese.it\/costameno\/#\/schema\/person\/bf9fd8def4eff5faacb4294c9354c800"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/costameno\/il-primo-regalo-del-2012-musei-statali-gratis-in-piemonte-il-pomeriggio-del-1-gennaio\/"]}]},{"@type":"WebSite","@id":"http:\/\/web.quotidianopiemontese.it\/costameno\/#website","url":"http:\/\/web.quotidianopiemontese.it\/costameno\/","name":"Costa Meno","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/web.quotidianopiemontese.it\/costameno\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/web.quotidianopiemontese.it\/costameno\/#\/schema\/person\/bf9fd8def4eff5faacb4294c9354c800","name":"Davide Mazzocco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c6eb81b0a007fca80a7dafc2d7c6c4ee743c69ab1dad3d1e7ec19028222c502b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c6eb81b0a007fca80a7dafc2d7c6c4ee743c69ab1dad3d1e7ec19028222c502b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c6eb81b0a007fca80a7dafc2d7c6c4ee743c69ab1dad3d1e7ec19028222c502b?s=96&d=mm&r=g","caption":"Davide Mazzocco"},"url":"https:\/\/web.quotidianopiemontese.it\/costameno\/author\/davide-mazzocco\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/costameno\/wp-json\/wp\/v2\/posts\/64","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/costameno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/costameno\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/costameno\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/costameno\/wp-json\/wp\/v2\/comments?post=64"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/costameno\/wp-json\/wp\/v2\/posts\/64\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/costameno\/wp-json\/wp\/v2\/media?parent=64"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/costameno\/wp-json\/wp\/v2\/categories?post=64"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/costameno\/wp-json\/wp\/v2\/tags?post=64"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}