{"id":106,"date":"2012-01-23T07:19:33","date_gmt":"2012-01-23T07:19:33","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/costameno\/?p=106"},"modified":"2012-01-23T08:09:16","modified_gmt":"2012-01-23T08:09:16","slug":"con-le-liberalizzazioni-465-euro-di-spesa-in-meno-a-famiglia-ecco-come-e-dove-si-risparmiera","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/costameno\/con-le-liberalizzazioni-465-euro-di-spesa-in-meno-a-famiglia-ecco-come-e-dove-si-risparmiera\/","title":{"rendered":"Con le liberalizzazioni 465 euro di spesa in meno a famiglia. Ecco come e dove si risparmier\u00e0"},"content":{"rendered":"<p><a href=\"http:\/\/www.quotidianopiemontese.it\/costameno\/files\/2011\/12\/pompe-bianche.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-60\" src=\"http:\/\/www.quotidianopiemontese.it\/costameno\/files\/2011\/12\/pompe-bianche.jpg\" alt=\"\" width=\"130\" height=\"94\" \/><\/a>Il Casper, il Comitato contro le speculazioni e per il risparmio formato da Adoc, Codacons e Movimento Difesa del cittadino e Unione Nazionale Consumatori, stima in 465 euro la cifra che verr\u00e0 risparmiata dai cittadini grazie alle liberalizzazioni varate venerd\u00ec scorso dal governo. <!--more-->Con la prima bozza <a href=\"http:\/\/www.consumatori.it\/index.php?option=com_content&amp;task=view&amp;id=3642&amp;Itemid=1\" target=\"_blank\">la stima Casper<\/a> era addirittura di 900 euro ma con la sparizione della liberalizzazione dei saldi e l\u2019eliminazione della possibilit\u00e0 per tutti i distributori (e non solo per quelli di propriet\u00e0) di rifornirsi da compagnie diverse da quelle di riferimento nella versione definitiva il risparmio \u00e8 stato di fatto dimezzato. Facendo un stima sulla spesa media di una famiglia il risparmio di 465 euro dovrebbe essere cos\u00ec ripartito: 200 euro per pagamenti di professionisti, 100 per i trasporti, 20 per i farmaci, 100 per i carburanti e appena 50 per il commercio.<\/p>\n<p>E ora vediamo una breve guida in 14 punti per capire che cosa cambier\u00e0, nella pratica quotidiana, per i cittadini:<\/p>\n<p>1 \u2013 <strong>ASSICURAZIONI AUTO<\/strong> Sconti per chi installa la scatola nera sul proprio veicolo. Il contrassegno diventer\u00e0 elettronico (abbassando il numero di falsificazioni) e i periti che si renderanno autori di dichiarazioni mendaci riguardo alle invalidit\u00e0 da incidente rischieranno il carcere. Tutte le riparazioni eseguite dalle compagnie saranno garantite due anni.<\/p>\n<p>2 \u2013 <strong>BENZINA<\/strong> Dal prossimo 30 giugno i proprietari di impianti di distribuzione potranno acquistare il 50% del carburante venduto l\u2019anno prima da produttori diversi da quello di riferimento. Viene liberalizzata la vendita di prodotti <em>non-oil<\/em> come snack, bevande, giornali e tabacchi.<\/p>\n<p>3 \u2013 <strong>BANCHE <\/strong>Entro il 1\u00b0 giugno verranno abbassate le commissioni interbancarie, quindi coster\u00e0 meno prelevare denaro agli sportelli diversi da quelli della propria banca.<\/p>\n<p>4 &#8211; \u00a0<strong>SOCIETA\u2019<\/strong> Nasce la Societ\u00e0 semplificata a responsabilit\u00e0 limitata per gli imprenditori con meno di 35 anni. Niente notaio: baster\u00e0 farsi registrare all\u2019Ufficio del Registro delle imprese, esente da bollo, e dichiarare un capitale sociale anche minimo. Un\u2019eccezione pensata per far decollare l\u2019imprenditoria giovanile.<\/p>\n<p>5 \u2013 <strong>GAS<\/strong> Con lo scorporo fra trasporto e distribuzione del gas sar\u00e0 finalmente vera concorrenza con un\u2019auspicabile lotta al ribasso dei prezzi.<\/p>\n<p>6 \u2013 <strong>COMMERCIO<\/strong> Niente liberalizzazione dei saldi ma via libera alle vendite promozionali per abbinamenti di prodotti di diverse tipologie. Persino gli edicolanti potranno fare sconti su quotidiani e riviste e non saranno pi\u00f9 obbligati dai distributori ad acquistare prodotti complementari.<\/p>\n<p>7 \u2013 <strong>FARMACIE<\/strong> Gli orari, i turni e gli sconti sui farmaci diventano liberi. Nei prossimi cinque mesi verranno assegnate 5mila licenze in modo da raggiungere il nuovo quorum fissato in una farmacia ogni 3mila abitanti. Aperture anche in stazioni ferroviarie, aeroporti e autogrill.<\/p>\n<p>8 \u2013 <strong>TAXI <\/strong>Maggiore flessibilit\u00e0 sugli orari, possibilit\u00e0 di effettuare corse anche al di fuori delle consuete aree di competenza, maggiore libert\u00e0 nella definizione delle tariffe.<\/p>\n<p>9 \u2013 <strong>PROFESSIONISTI<\/strong> Viene semplificato l\u2019accesso alla professione (6 dei 18 mesi di tirocinio per l\u2019esame di Stato potranno essere svolti all\u2019Universit\u00e0), abbattuti massimali e minimali dei tariffari e inserito l\u2019obbligo di preventivo. Entro il 2014 in Italia ci saranno 1500 notai in pi\u00f9 e una maggiore concorrenza dovrebbe calmierare i prezzi.<\/p>\n<p>10 \u2013 <strong>FERROVIE<\/strong> Le aziende concorrenti non dovranno pi\u00f9 aderire al contratto nazionale dei ferrovieri. Grazie alla carta dei servizi pubblici i cittadini saranno maggiormente tutelati in caso di disservizi.<\/p>\n<p>11 \u2013 <strong>AUTOSTRADE<\/strong> Per le nuove concessioni autostradali viene introdotto il <em>price cap, <\/em>principio col quale le tariffe verranno commisurate all\u2019efficienza del servizio. Per le concessioni in essere i prezzi continueranno a essere definiti da Anas e Ministero dei Trasporti.<\/p>\n<p>12 \u2013 <strong>SERVIZI LOCALI<\/strong> \u00a0Viene promossa la \u201cconcorrenza nei servizi pubblici locali\u201d. Nelle aziende in mano agli enti locali i privati entreranno con quote crescenti. Viene rispettato il referendum sull\u2019acqua: nella prima bozza \u2013 eliminata dopo una forte mobilitazione popolare \u2013 sarebbe stata vietata la gestione del servizio idrico attraverso enti di diritto pubblico, quali le aziende speciali. Andando praticamente contro il 95,8% dei votanti del referendum di otto mesi fa.<\/p>\n<p>13 \u2013 <strong>CLASS ACTION<\/strong> Vengono eliminate alcune norme della manovra Cresci Italia che avrebbero dovuto estendere le opportunit\u00e0 per azioni giudizarie della collettivit\u00e0 contro aziende e imprese. Le vertenze saranno di competenza del nascente Tribunale delle imprese.<\/p>\n<p>14 \u2013 <strong>DIRITTO D\u2019AUTORE<\/strong> Decade il monopolio della Siae e per gli artisti potrebbe dunque prospettarsi la possibilit\u00e0 di cedere l\u2019incarico della riscossione dei propri diritti d\u2019autore all\u2019agenzia che sapr\u00e0 offrire le condizioni pi\u00f9 vantaggiose.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Casper, il Comitato contro le speculazioni e per il risparmio formato da Adoc, Codacons e Movimento Difesa del cittadino e Unione Nazionale Consumatori, stima in 465 euro la cifra che verr\u00e0 risparmiata dai cittadini grazie alle liberalizzazioni varate venerd\u00ec scorso dal governo.<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[102,105,98,101,99,100,103,104,52],"class_list":["post-106","post","type-post","status-publish","format-standard","hentry","category-costa-meno","tag-autostrade","tag-consumatori","tag-cosa-cambia-con","tag-governo","tag-liberalizzazioni","tag-mario-monti","tag-negozi","tag-risparmio","tag-saldi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Con le liberalizzazioni 465 euro di spesa in meno a famiglia. Ecco come e dove si risparmier\u00e0  - Costa Meno<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/costameno\/con-le-liberalizzazioni-465-euro-di-spesa-in-meno-a-famiglia-ecco-come-e-dove-si-risparmiera\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Con le liberalizzazioni 465 euro di spesa in meno a famiglia. Ecco come e dove si risparmier\u00e0  - Costa Meno\" \/>\n<meta property=\"og:description\" content=\"Il Casper, il Comitato contro le speculazioni e per il risparmio formato da Adoc, Codacons e Movimento Difesa del cittadino e Unione Nazionale Consumatori, stima in 465 euro la cifra che verr\u00e0 risparmiata dai cittadini grazie alle liberalizzazioni varate venerd\u00ec scorso dal governo.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/costameno\/con-le-liberalizzazioni-465-euro-di-spesa-in-meno-a-famiglia-ecco-come-e-dove-si-risparmiera\/\" \/>\n<meta property=\"og:site_name\" content=\"Costa Meno\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2012-01-23T07:19:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-01-23T08:09:16+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.quotidianopiemontese.it\/costameno\/files\/2011\/12\/pompe-bianche.jpg\" \/>\n<meta name=\"author\" content=\"Davide Mazzocco\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Davide Mazzocco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/con-le-liberalizzazioni-465-euro-di-spesa-in-meno-a-famiglia-ecco-come-e-dove-si-risparmiera\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/con-le-liberalizzazioni-465-euro-di-spesa-in-meno-a-famiglia-ecco-come-e-dove-si-risparmiera\\\/\"},\"author\":{\"name\":\"Davide Mazzocco\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/#\\\/schema\\\/person\\\/bf9fd8def4eff5faacb4294c9354c800\"},\"headline\":\"Con le liberalizzazioni 465 euro di spesa in meno a famiglia. Ecco come e dove si risparmier\u00e0\",\"datePublished\":\"2012-01-23T07:19:33+00:00\",\"dateModified\":\"2012-01-23T08:09:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/con-le-liberalizzazioni-465-euro-di-spesa-in-meno-a-famiglia-ecco-come-e-dove-si-risparmiera\\\/\"},\"wordCount\":705,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/con-le-liberalizzazioni-465-euro-di-spesa-in-meno-a-famiglia-ecco-come-e-dove-si-risparmiera\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.quotidianopiemontese.it\\\/costameno\\\/files\\\/2011\\\/12\\\/pompe-bianche.jpg\",\"keywords\":[\"autostrade\",\"consumatori\",\"Cosa cambia con\",\"governo\",\"liberalizzazioni\",\"mario monti\",\"negozi\",\"risparmio\",\"saldi\"],\"articleSection\":[\"Costa Meno\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/con-le-liberalizzazioni-465-euro-di-spesa-in-meno-a-famiglia-ecco-come-e-dove-si-risparmiera\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/con-le-liberalizzazioni-465-euro-di-spesa-in-meno-a-famiglia-ecco-come-e-dove-si-risparmiera\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/con-le-liberalizzazioni-465-euro-di-spesa-in-meno-a-famiglia-ecco-come-e-dove-si-risparmiera\\\/\",\"name\":\"Con le liberalizzazioni 465 euro di spesa in meno a famiglia. Ecco come e dove si risparmier\u00e0 - Costa Meno\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/con-le-liberalizzazioni-465-euro-di-spesa-in-meno-a-famiglia-ecco-come-e-dove-si-risparmiera\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/con-le-liberalizzazioni-465-euro-di-spesa-in-meno-a-famiglia-ecco-come-e-dove-si-risparmiera\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.quotidianopiemontese.it\\\/costameno\\\/files\\\/2011\\\/12\\\/pompe-bianche.jpg\",\"datePublished\":\"2012-01-23T07:19:33+00:00\",\"dateModified\":\"2012-01-23T08:09:16+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/#\\\/schema\\\/person\\\/bf9fd8def4eff5faacb4294c9354c800\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/con-le-liberalizzazioni-465-euro-di-spesa-in-meno-a-famiglia-ecco-come-e-dove-si-risparmiera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/con-le-liberalizzazioni-465-euro-di-spesa-in-meno-a-famiglia-ecco-come-e-dove-si-risparmiera\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.quotidianopiemontese.it\\\/costameno\\\/files\\\/2011\\\/12\\\/pompe-bianche.jpg\",\"contentUrl\":\"http:\\\/\\\/www.quotidianopiemontese.it\\\/costameno\\\/files\\\/2011\\\/12\\\/pompe-bianche.jpg\"},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/#website\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/\",\"name\":\"Costa Meno\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/#\\\/schema\\\/person\\\/bf9fd8def4eff5faacb4294c9354c800\",\"name\":\"Davide Mazzocco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6eb81b0a007fca80a7dafc2d7c6c4ee743c69ab1dad3d1e7ec19028222c502b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6eb81b0a007fca80a7dafc2d7c6c4ee743c69ab1dad3d1e7ec19028222c502b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6eb81b0a007fca80a7dafc2d7c6c4ee743c69ab1dad3d1e7ec19028222c502b?s=96&d=mm&r=g\",\"caption\":\"Davide Mazzocco\"},\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/costameno\\\/author\\\/davide-mazzocco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Con le liberalizzazioni 465 euro di spesa in meno a famiglia. Ecco come e dove si risparmier\u00e0  - Costa Meno","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/costameno\/con-le-liberalizzazioni-465-euro-di-spesa-in-meno-a-famiglia-ecco-come-e-dove-si-risparmiera\/","og_locale":"it_IT","og_type":"article","og_title":"Con le liberalizzazioni 465 euro di spesa in meno a famiglia. Ecco come e dove si risparmier\u00e0  - Costa Meno","og_description":"Il Casper, il Comitato contro le speculazioni e per il risparmio formato da Adoc, Codacons e Movimento Difesa del cittadino e Unione Nazionale Consumatori, stima in 465 euro la cifra che verr\u00e0 risparmiata dai cittadini grazie alle liberalizzazioni varate venerd\u00ec scorso dal governo.","og_url":"http:\/\/web.quotidianopiemontese.it\/costameno\/con-le-liberalizzazioni-465-euro-di-spesa-in-meno-a-famiglia-ecco-come-e-dove-si-risparmiera\/","og_site_name":"Costa Meno","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2012-01-23T07:19:33+00:00","article_modified_time":"2012-01-23T08:09:16+00:00","og_image":[{"url":"http:\/\/www.quotidianopiemontese.it\/costameno\/files\/2011\/12\/pompe-bianche.jpg","type":"","width":"","height":""}],"author":"Davide Mazzocco","twitter_misc":{"Scritto da":"Davide Mazzocco","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/costameno\/con-le-liberalizzazioni-465-euro-di-spesa-in-meno-a-famiglia-ecco-come-e-dove-si-risparmiera\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/costameno\/con-le-liberalizzazioni-465-euro-di-spesa-in-meno-a-famiglia-ecco-come-e-dove-si-risparmiera\/"},"author":{"name":"Davide Mazzocco","@id":"http:\/\/web.quotidianopiemontese.it\/costameno\/#\/schema\/person\/bf9fd8def4eff5faacb4294c9354c800"},"headline":"Con le liberalizzazioni 465 euro di spesa in meno a famiglia. Ecco come e dove si risparmier\u00e0","datePublished":"2012-01-23T07:19:33+00:00","dateModified":"2012-01-23T08:09:16+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/costameno\/con-le-liberalizzazioni-465-euro-di-spesa-in-meno-a-famiglia-ecco-come-e-dove-si-risparmiera\/"},"wordCount":705,"commentCount":0,"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/costameno\/con-le-liberalizzazioni-465-euro-di-spesa-in-meno-a-famiglia-ecco-come-e-dove-si-risparmiera\/#primaryimage"},"thumbnailUrl":"http:\/\/www.quotidianopiemontese.it\/costameno\/files\/2011\/12\/pompe-bianche.jpg","keywords":["autostrade","consumatori","Cosa cambia con","governo","liberalizzazioni","mario monti","negozi","risparmio","saldi"],"articleSection":["Costa Meno"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/costameno\/con-le-liberalizzazioni-465-euro-di-spesa-in-meno-a-famiglia-ecco-come-e-dove-si-risparmiera\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/costameno\/con-le-liberalizzazioni-465-euro-di-spesa-in-meno-a-famiglia-ecco-come-e-dove-si-risparmiera\/","url":"http:\/\/web.quotidianopiemontese.it\/costameno\/con-le-liberalizzazioni-465-euro-di-spesa-in-meno-a-famiglia-ecco-come-e-dove-si-risparmiera\/","name":"Con le liberalizzazioni 465 euro di spesa in meno a famiglia. Ecco come e dove si risparmier\u00e0 - Costa Meno","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/costameno\/#website"},"primaryImageOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/costameno\/con-le-liberalizzazioni-465-euro-di-spesa-in-meno-a-famiglia-ecco-come-e-dove-si-risparmiera\/#primaryimage"},"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/costameno\/con-le-liberalizzazioni-465-euro-di-spesa-in-meno-a-famiglia-ecco-come-e-dove-si-risparmiera\/#primaryimage"},"thumbnailUrl":"http:\/\/www.quotidianopiemontese.it\/costameno\/files\/2011\/12\/pompe-bianche.jpg","datePublished":"2012-01-23T07:19:33+00:00","dateModified":"2012-01-23T08:09:16+00:00","author":{"@id":"http:\/\/web.quotidianopiemontese.it\/costameno\/#\/schema\/person\/bf9fd8def4eff5faacb4294c9354c800"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/costameno\/con-le-liberalizzazioni-465-euro-di-spesa-in-meno-a-famiglia-ecco-come-e-dove-si-risparmiera\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/web.quotidianopiemontese.it\/costameno\/con-le-liberalizzazioni-465-euro-di-spesa-in-meno-a-famiglia-ecco-come-e-dove-si-risparmiera\/#primaryimage","url":"http:\/\/www.quotidianopiemontese.it\/costameno\/files\/2011\/12\/pompe-bianche.jpg","contentUrl":"http:\/\/www.quotidianopiemontese.it\/costameno\/files\/2011\/12\/pompe-bianche.jpg"},{"@type":"WebSite","@id":"http:\/\/web.quotidianopiemontese.it\/costameno\/#website","url":"http:\/\/web.quotidianopiemontese.it\/costameno\/","name":"Costa Meno","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/web.quotidianopiemontese.it\/costameno\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/web.quotidianopiemontese.it\/costameno\/#\/schema\/person\/bf9fd8def4eff5faacb4294c9354c800","name":"Davide Mazzocco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c6eb81b0a007fca80a7dafc2d7c6c4ee743c69ab1dad3d1e7ec19028222c502b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c6eb81b0a007fca80a7dafc2d7c6c4ee743c69ab1dad3d1e7ec19028222c502b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c6eb81b0a007fca80a7dafc2d7c6c4ee743c69ab1dad3d1e7ec19028222c502b?s=96&d=mm&r=g","caption":"Davide Mazzocco"},"url":"https:\/\/web.quotidianopiemontese.it\/costameno\/author\/davide-mazzocco\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/costameno\/wp-json\/wp\/v2\/posts\/106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/costameno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/costameno\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/costameno\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/costameno\/wp-json\/wp\/v2\/comments?post=106"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/costameno\/wp-json\/wp\/v2\/posts\/106\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/costameno\/wp-json\/wp\/v2\/media?parent=106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/costameno\/wp-json\/wp\/v2\/categories?post=106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/costameno\/wp-json\/wp\/v2\/tags?post=106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}