{"id":270,"date":"2024-05-10T09:15:16","date_gmt":"2024-05-10T07:15:16","guid":{"rendered":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/?p=270"},"modified":"2024-05-10T09:17:05","modified_gmt":"2024-05-10T07:17:05","slug":"e-un-classico","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/e-un-classico\/","title":{"rendered":"E\u2019 un classico!"},"content":{"rendered":"<p><strong>\u201cUn classico \u00e8 un libro che non ha mai finito di dire quel che ha da dire\u201d.<\/strong><\/p>\n<p><strong>Italo Calvino<\/strong><\/p>\n<p>Ipse dixit, cara E.,<\/p>\n<p>E mi sa che, idealmente, sono abbastanza d\u2019accordo.<!--more--><\/p>\n<p>In questi giorni di libri in ognidove in citt\u00e0, presentazioni, incontri, letture, la mia mente vaga tra pagine lette, pagine abbandonate, pagine sottolineate, pagine spiegazzate, pagine insabbiate, pagine memorabili e pagine dimenticabili, pagine desiderate e pagine detestate, pagine sognate e sognanti, pagine strappate, pagine sospese, in attesa di tempi e spazi diversi, nuovi. Mi tornano alla mente parole, frasi, citazioni, passaggi emozionali che sono diventati bagaglio verbale e di pensiero, espressioni che nel mio vivere sono diventate risposte ai perch\u00e9 e spiegazioni che si sono fatte domande. Insomma, parecchia roba.<\/p>\n<p>Il mio rapporto con i libri \u00e8 stato quasi carnale nei tempi che furono, li portavo con me ovunque, quasi un prolungamento di me stessa in quel momento: finch\u00e8 non lo finivo, il libro letto era tutto, tutti i miei pensieri, i miei desideri, le mie rabbie, i miei dubbi. Ogni libro del tempo che fu, \u00e8 stato sottolineato, citato, trascritto, riportato nei primi messaggi sui primi cellulari.<\/p>\n<p>A quei tempi, i classici erano pi\u00f9 che altro una noia potenziale: voglio dire, figlia di proff e al classico, \u00e8 chiaro che ero inseguita da gente che mi voleva a leggere Madame Bovary e Il Rosso e il Nero, ed \u00e8 chiaro che la rivoluzionaria che era in me, come ogni adolescente pu\u00f2 vantarsi di essere, puntava a letture certo meno \u2018passate\u2019 e certo pi\u00f9 vicine, nei modi, nel pensiero, nei temi. Benni, Allende, Hornby, Banana Yoshimoto e tante voci diverse rintracciate nei tanti Salone del Libro battuti palmo a palmo in caccia di letture inusuali, almeno nella mia testa di allora, mai viste in casa o sentite nella bocca altrui.<\/p>\n<p>E quindi? Questi classici? Cos\u2019\u00e8 un classico? Cos\u2019\u00e8 quel libro che ci fa dire \u201cdai, quello \u00e8 un classico!&#8221;.<\/p>\n<p>Credo ci siano libri che sanno attraversare il tempo e la storia, le mode del momento, il sentire collettivo. Libri che sanno parlare a tutti, o a molti numericamente parlando, e rimangono, nel cuore, nel pensiero, nell\u2019agire anche. Cos\u00ec, si fanno classici. E quelli sono i \u201c<strong>classici universali<\/strong>\u201d, come L\u2019Ulisse, La coscienza di zeno, Furore, la saga de Il signore degli anelli, i libri dei grandi della letteratura mondiale, quelli che non si discutono o se lo si fa, lo si fa a proprio rischio e pericolo o nell\u2019intimo di s\u00e9 stessi.<\/p>\n<p>Ci sono poi i \u201c<strong>classici \u2018personali<\/strong>\u201d, letture avvenute in un certo momento, in certi frangenti della vita, accanto a certe situazioni e certe persone, per cui finiscono per insinuarsi nelle pieghe della mente e del sentire e restano con te per tutta una vita, o per molta parte di essa. Ed emergono, negli anni, in certi altri momenti, sentimenti, occasioni, come bolle di champagne in un flute, e risalgono, dal fondo di noi stessi, fino al ricordo, alla sintonia. E ci fanno il loro regalo: ci ricordano un po\u2019 chi siamo stati, dove abbiamo vissuto, cosa abbiamo sentito, dove volevamo andare, cosa sognavamo e cosa desideravamo. Per farci sentire un po\u2019 pi\u00f9 noi e un po\u2019 meno soli, un po\u2019 pi\u00f9 pagine di un libro ancora da scrivere, anzich\u00e9 pagine lette e dimenticate.<\/p>\n<p>E tu, E.? Cosa ne pensi?<\/p>\n<p>Hai notato che non ti ho detto qual \u00e8 il mio grande classico personale o universale? Perch\u00e8, in effetti, possono coincidere i due! Ma ho una buona scusa per questa mia omissione: a fine mese, saremo di nuovo da Catia, la nostra ospite, la piola-libreria dove molto accade e molto nasce, e il tema sar\u00e0 proprio \u201c<strong>Porta il tuo classico con te!<\/strong>\u201d. Cos\u00ec, te lo sveler\u00f2 dal vivo, il mio classico, insieme a quanti vorranno venire con noi a ritrovarsi tra le pagine dei propri classici.<\/p>\n<p><a href=\"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/chi-e-chiara-avidano\/\">Chiara<\/a><\/p>\n<p><iframe loading=\"lazy\" title=\"Umberto Eco \u2013 Perch\u00e9 i classici\" width=\"840\" height=\"473\" src=\"https:\/\/www.youtube.com\/embed\/EJnbpWnMbD0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Cara C,<\/p>\n<p>per raccogliere la nostra sfida di \u201cporta un classico da Catia a fine mese\u201d, sono corsa a prendere la valigia grande, quella delle vacanze lunghe per riempirla dei libri che mi hanno accompagnata in questi anni.<\/p>\n<p>I libri sono la mia formazione personale e professionale, e come dici bene tu tra letture importanti ci sono i classici universali e i classici personali.<\/p>\n<p>Libri come copertine di Linus, pezzi di tempo con la copertina intessuta di trame e parole.<\/p>\n<p>Se scopri i miei libri puoi avere le chiavi della mia anima.<\/p>\n<p>Ti do il mio elenco di libri solo se mi fido di te.<\/p>\n<p>E\u2019 come darti il mio numero di telefono.<\/p>\n<p>Se vuoi un appuntamento mandami il tuo elenco di libri.<\/p>\n<p>Se diventiamo intimi ti faccio vedere il mio comodino.<\/p>\n<p>Il mio comodino \u00e8 la fotografia di quello che sto vivendo, studiando cercando, una fonte, una risposta, un\u2019ispirazione.<\/p>\n<p>Il mio comodino \u00e8 uno scaffale dell\u2019anima in cui ho sempre almeno tre pile di libri: un classico, un contemporaneo, uno spunto, una nuova conoscenza, o puro divertimento.<\/p>\n<p>Da Catia posso portarti l\u2019album delle foto dei miei comodini, dalle elementari a quelli che attualmente addormentano il mio stato cosciente.<\/p>\n<p>E visto che sei la mia compagna di banco, ti faccio un\u2019anticipazione sui titoli.<\/p>\n<p>Il primo classico che ho letto \u00e8 stato \u201cIl Milione\u201d di Marco Polo che presi in prestito alla biblioteca della scuola elementare.<\/p>\n<p>Quel libro ha fatto di me un\u2019esploratrice, ha plasmato le mie sinapsi verso l\u2019altrove e ha piegato la mia anima alla curiosit\u00e0 verso mondi lontani avvolti dal mito.<\/p>\n<p>Da Catia proviamo a leggere qualche pagina dei classici dell\u2019anima per vedere come quelle parole ci risuonano dentro la cassa toracica, ora.<\/p>\n<p>Preparati dunque l\u2019ugola e ci vediamo venerd\u00ec 31 alle 17.30 in via Bibiana 31, con tanti classici che saranno i primi titoli che metteremo nella biblioteca di Compagne di banco.<\/p>\n<p>A proposito di Catia su questi canali di comunicazione ci sentiamo la prossima settimana per parlare di librerie.<\/p>\n<p>E questo fine settimana ti auguro un buon salone!<\/p>\n<p><a href=\"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/chi-e-elena-forno\/\">Elena<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cUn classico \u00e8 un libro che non ha mai finito di dire quel che ha da dire\u201d. Italo Calvino Ipse dixit, cara E., E mi sa che, idealmente, sono abbastanza d\u2019accordo.<\/p>\n","protected":false},"author":1,"featured_media":271,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[35],"class_list":["post-270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-compagne-di-banco","tag-libri"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>E\u2019 un classico! - Compagne di Banco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/e-un-classico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"E\u2019 un classico! - Compagne di Banco\" \/>\n<meta property=\"og:description\" content=\"\u201cUn classico \u00e8 un libro che non ha mai finito di dire quel che ha da dire\u201d. Italo Calvino Ipse dixit, cara E., E mi sa che, idealmente, sono abbastanza d\u2019accordo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/e-un-classico\/\" \/>\n<meta property=\"og:site_name\" content=\"Compagne di Banco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-10T07:15:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-10T07:17:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/files\/2024\/05\/libri-classici.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1071\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@quotidianopiem\" \/>\n<meta name=\"twitter:site\" content=\"@quotidianopiem\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/e-un-classico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/e-un-classico\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"headline\":\"E\u2019 un classico!\",\"datePublished\":\"2024-05-10T07:15:16+00:00\",\"dateModified\":\"2024-05-10T07:17:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/e-un-classico\\\/\"},\"wordCount\":990,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/e-un-classico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/files\\\/2024\\\/05\\\/libri-classici.jpeg\",\"keywords\":[\"libri\"],\"articleSection\":[\"Compagne di Banco\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/e-un-classico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/e-un-classico\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/e-un-classico\\\/\",\"name\":\"E\u2019 un classico! - Compagne di Banco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/e-un-classico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/e-un-classico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/files\\\/2024\\\/05\\\/libri-classici.jpeg\",\"datePublished\":\"2024-05-10T07:15:16+00:00\",\"dateModified\":\"2024-05-10T07:17:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/e-un-classico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/e-un-classico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/e-un-classico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/files\\\/2024\\\/05\\\/libri-classici.jpeg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/files\\\/2024\\\/05\\\/libri-classici.jpeg\",\"width\":1600,\"height\":1071},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/e-un-classico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"E\u2019 un classico!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/\",\"name\":\"Compagne di Banco\",\"description\":\"Compagne di banco \u00e8 un diario sentimentale a due voci, due compagne di banco chiacchierano e si confrontano su temi culturali sociali e di attualit\u00e0 tra note, lodi e compiti a casa.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte\",\"sameAs\":[\"http:\\\/\\\/www.quotidianopiemontese.it\\\/\",\"https:\\\/\\\/www.facebook.com\\\/quotidianopiemontese\",\"https:\\\/\\\/x.com\\\/quotidianopiem\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/author\\\/administrator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"E\u2019 un classico! - Compagne di Banco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/e-un-classico\/","og_locale":"it_IT","og_type":"article","og_title":"E\u2019 un classico! - Compagne di Banco","og_description":"\u201cUn classico \u00e8 un libro che non ha mai finito di dire quel che ha da dire\u201d. Italo Calvino Ipse dixit, cara E., E mi sa che, idealmente, sono abbastanza d\u2019accordo.","og_url":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/e-un-classico\/","og_site_name":"Compagne di Banco","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese","article_author":"https:\/\/www.facebook.com\/quotidianopiemontese","article_published_time":"2024-05-10T07:15:16+00:00","article_modified_time":"2024-05-10T07:17:05+00:00","og_image":[{"width":1600,"height":1071,"url":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/files\/2024\/05\/libri-classici.jpeg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@quotidianopiem","twitter_site":"@quotidianopiem","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/e-un-classico\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/e-un-classico\/"},"author":{"name":"Redazione","@id":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"headline":"E\u2019 un classico!","datePublished":"2024-05-10T07:15:16+00:00","dateModified":"2024-05-10T07:17:05+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/e-un-classico\/"},"wordCount":990,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/e-un-classico\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/files\/2024\/05\/libri-classici.jpeg","keywords":["libri"],"articleSection":["Compagne di Banco"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/e-un-classico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/e-un-classico\/","url":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/e-un-classico\/","name":"E\u2019 un classico! - Compagne di Banco","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/e-un-classico\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/e-un-classico\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/files\/2024\/05\/libri-classici.jpeg","datePublished":"2024-05-10T07:15:16+00:00","dateModified":"2024-05-10T07:17:05+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/e-un-classico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/e-un-classico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/e-un-classico\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/files\/2024\/05\/libri-classici.jpeg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/files\/2024\/05\/libri-classici.jpeg","width":1600,"height":1071},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/e-un-classico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/"},{"@type":"ListItem","position":2,"name":"E\u2019 un classico!"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/#website","url":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/","name":"Compagne di Banco","description":"Compagne di banco \u00e8 un diario sentimentale a due voci, due compagne di banco chiacchierano e si confrontano su temi culturali sociali e di attualit\u00e0 tra note, lodi e compiti a casa.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","caption":"Redazione"},"description":"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte","sameAs":["http:\/\/www.quotidianopiemontese.it\/","https:\/\/www.facebook.com\/quotidianopiemontese","https:\/\/x.com\/quotidianopiem"],"url":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/author\/administrator\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/wp-json\/wp\/v2\/posts\/270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/wp-json\/wp\/v2\/comments?post=270"}],"version-history":[{"count":1,"href":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/wp-json\/wp\/v2\/posts\/270\/revisions"}],"predecessor-version":[{"id":272,"href":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/wp-json\/wp\/v2\/posts\/270\/revisions\/272"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/wp-json\/wp\/v2\/media\/271"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/wp-json\/wp\/v2\/media?parent=270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/wp-json\/wp\/v2\/categories?post=270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/wp-json\/wp\/v2\/tags?post=270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}