{"id":171,"date":"2024-03-08T13:55:01","date_gmt":"2024-03-08T12:55:01","guid":{"rendered":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/?p=171"},"modified":"2024-03-08T13:55:01","modified_gmt":"2024-03-08T12:55:01","slug":"primo-giorno-di-scuola-classe-dirigente-o-raga","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/primo-giorno-di-scuola-classe-dirigente-o-raga\/","title":{"rendered":"Primo giorno di scuola. Classe Dirigente o Raga\u2026?"},"content":{"rendered":"<p>Cara C.,<br \/>\nstamattina alle otto e diciotto sono passata in corso Dante, e Lei era l\u00ec come ai vecchi tempi. L\u2019Alfieri, la nostra scuola, il Liceo Classico Vittorio Alfieri. Il semaforo durava quasi il tempo di una canzone ed io imbambolata, fissando la vetrata trasparente, ho cominciato a ripensare agli anni della scuola, a me a te, al nostro banco che ha raccolto tante domande con risate e briciole di merende infinite consumate sul sacro altare dell\u2019Istituzione Skolastica.<!--more--><br \/>\nL\u2019automobilista dietro di me fa per suonare il clacson poi scorge il mio sguardo sognante e mi supera, credo che mi abbia scambiata per una madre che attende il suono della campanella per vedere l\u2019entrata del figlio o della figlia. MADRE! IO!? Senti bello, io non sono qui per questo, io solo ieri ero qui che stavo per entrare e\u2026 quando guardo lo specchietto retrovisore con cui stavo parlando (come De Niro in Taxi driver \u201cehi dici a me?) mi accorgo che l\u2019uomo se ne \u00e8 andato via gi\u00e0 da un bel pezzo.<br \/>\nMetto la freccia ma non giro, accosto l\u2019auto al noto marciapiedi dell\u2019Alfieri. Avrei giusto il tempo di un caff\u00e8 con una collega ma le mando un messaggio. \u201cCiao ho avuto un contrattempo, un incontro con il tempo, un non so cosa sto per fare\u201d. Scendo dall\u2019auto e mi butto in mezzo alla folla degli studenti che stanno per entrare a scuola.<br \/>\nCome me nel 1990, tanti anni e mesi e minuti fa.<\/p>\n<p>Correva l\u2019anno scolastico Millenovecentonovanta-Novantuno e nel mondo era gi\u00e0 successo di tutto. Erano gi\u00e0 stati coniati i concetti di crisi di tutti i tipi cos\u00ec come quelli di fine del mondo. Crisi in Giappone l\u2019Oms cancella l\u2019omosessualit\u00e0 dalle malattie mentali i crucchi vincono i mondiali guerra del Golfo riunificazione tedesca\u2026 che anno \u00e8 il 1990?<\/p>\n<p>Guardo davanti a me: c\u2019\u00e8 il cancellone, torno a voltarmi verso il Po e vedo la collina.<br \/>\nPresagi: la playlist musicale mi sputa fuori dalla categoria cantautorato italiano \u201cGenerale dietro la collina\u201d di De Gregori ma non riesco a concentrarmi sulla mia musica. Un ragazzino accanto a me, coetaneo di uno dei miei figli, ha i cuffioni bianchi che lasciano uscire le parole del brano di Madame \u201cSolo tu mi hai capito\u201d. Inizio a canticchiare, lui mi guarda sconvolto e si allontana velocemente.<\/p>\n<p>E mi immergo nel mio nostro C., <strong>primo giorno di scuola<\/strong>.<br \/>\nSono arrivata un\u2019ora prima per osservare chi e come.<br \/>\nEro l\u00ec e aspettavo l\u2019apertura delle porte del futuro con il walkman nero e le cuffiette, non c\u2019erano i cuffioni, quelli li aveva solo Maurizio Seimandi, supertelegattone.<br \/>\nEra autunno e avevo il giubbotto di jeans e lo zaino Invicta su una spalla. Nell\u2019attesa guardavo la collina. Ti ricordi che noi si entrava alle otto e trenta per aspettare quelli chescendevanodallacollina?<br \/>\nIo non sapevo chi fossero quellichescendevanodallacollina ma tremavo di emozione all\u2019idea di incontrarli. Io venivo da Lingotto e fino ad allora mi ero spinta fuori dal mio seminato solo un isolato dopo piazza Carducci dove potevo incontrare quellidiviamadama. Quando c\u2019era spirito di ribellione cio\u00e8 la mia amica Giorgia alta e pi\u00f9 grande di me di un anno, potevo sfidare l\u2019ignoto verso quellidiviaventimiglia.<br \/>\nQuellidiPiazzaBengasi insieme a quellidiMirafiori restavano nella zona rossa tracciata da mia madre sulla citt\u00e0, e per me, in quel momento, erano solo leggende metropolitane irraggiungibili e inarrivabili.<br \/>\nArmata di walkman nero ho varcato la soglia dell\u2019Alfieri, non conoscevo quasi nessuno, solo un\u2019amica di un anno pi\u00f9 grande che era gi\u00e0 in quinta ginnasio e sarebbe entrata a scuola il giorno dopo.<br \/>\nAperti i cancelli mi ritrovai nella selva oscura e quel discorso mi arriv\u00f2 dritto in faccia come a una parata presidenziale.<\/p>\n<p>C. tutto \u00e8 cominciato da l\u00ec, dal discorso di quella donna che aveva una stampella di ferro e la puntava verso di noi, contro il nostro muso, noi il suo pubblico scelto e addestrato.<br \/>\nShakespeariana nelle movenze e nei testi. Anni dopo alla scuola di teatro la portai in un\u2019improvvisazione: \u201cIl mio regno per una stampella\u201d. La stampella come scettro.<br \/>\nLa Preside (ora si dice Dirigente scolastica) non ci puntava il dito addosso ma quella gamba di ferro. Sputava, non solo sentenze, mi ricord\u00f2 subito Queen Elisabeth o Margaretta la Thatcher.<br \/>\nSi sono aperti i cancelli e poi le porte del purgatorio e ci siamo trovate in un corridoio. Marciando marziali siamo entrate nella palestra. Brividi di freddo, cercavo la mia musica nel walkman, quella musicassetta mi aveva gi\u00e0 salvata da tutto il mondo delle Medie ed ora avrebbe sconfitto l\u2019universo mondo del Liceo.<br \/>\nEra una palestra di una scuola ed eravamo tutti l\u00ec in attesa del Verbo: assegnazioni, classi, sezioni.<br \/>\nIo cercavo un bro\u2019, come dicono i miei figli. Un sodale con cui sghignazzare di quel mondo antico in cui ci stavano buttando, un coetaneo che strabuzzasse gli occhi e trattenesse una risata muta all\u2019ennesimo schiarimento di voce della Preside ed ho trovato te.<\/p>\n<p>C. ti stavo cercando in tutti quegli occhi pieni di trepidante attesa del futuro, mi sentivo come il mio pesce rosso che girava nell\u2019ampolla senza tentare il salto.<br \/>\nLa palestra mi girava tutto intorno, ed io con lo sguardo la scrutavo cercando la via d\u2019uscita per una fuga durante il primo intervallo.<br \/>\nSi \u00e8 schiarita la voce gracchiante. Ma perch\u00e9 mai la vita \u00e8 fatta di personaggi cos\u00ec scontati?! Non appena la vidi prendere la rincorsa vocale per emettere il primo suono, sapevo che il timbro della voce mi sarebbe risultato fastidioso come unghie che graffiano i vetri.<br \/>\nIl discorso arriv\u00f2 da che pulpito! Sputacchiava arroganza dagli angoli della bocca. Mi ricordava una madre superiora. Ma qui non siamo nella scuola pubblica? Dove sono finita? Aiuto! Si sporgeva dal trespolo improvvisato, una pedana della palestra allestita a palco.<br \/>\nC., tu ti ricordi? Vero? Te lo ricordi?<br \/>\nEravamo disposti per file, non ce lo avevano imposto, ma alla vista dell\u2019archetipo \u201cvecchiamadresuperiora\u201d, il nostro Dna ci prese a calci nel culo e ci trasform\u00f2 in opliti, facendo file perfette e OP OP OP ci trovammo a marciare come soldati.<br \/>\n<strong>Il discorso presidenziale<\/strong>: \u201cAvete una grande responsabilit\u00e0, sarete la FUTURA CLASSE DIRIGENTE del paese\u201d<br \/>\nAhahahahahah!!!!! usciva dalla mia testa a forma di nuvola dei fumetti.<br \/>\nHo iniziato a fissare le mie scarpe Superga di tela fine, cercando un appiglio per non scoppiare a ridere.<br \/>\nLei continuava ad alzare i toni, la voce divenne acuta mentre declamava l\u2019orazione funebre di una generazione.<br \/>\nLa nausea mi prese la bocca dello stomaco e per non vomitare sulla scarpa ortopedica della donna finsi un improvviso attacco di tosse. Nella mia testa c\u2019era un motivo (musica) e non una motivazione per stare in fila ferma immobile di fronte alla donna.<br \/>\nTi ricordi C. ? Ad un certo punto il conato di tosse si \u00e8 trasformato nella intro di un pezzo, ho iniziato a canticchiare come un ventriloquo: \u201cNotti magiche inseguendo un goal, sotto il cielo di un\u2019estate italiana, e negli occhi tuoi voglia di vincere, un\u2019estate, un&#8217;avventura in pi\u00f9\u201d.<\/p>\n<p>E l\u00ec che la fratellanza generazionale, quella che oggi si chiama Raga, mi ha salvata da una sospensione, messa alla porta ancora prima di iniziare \u201ce gi\u00e0 ti fai conoscere!!!\u201d (la voce della madre nella testa)<br \/>\nMa tu mi sei corsa in aiuto senza pensarci due volte, per quale motivo?<br \/>\nPer l\u2019incondizionato amore generazionale, quello dove siamo sulla stessa barca, un Titanic del tempo e allora aiutiamoci e tentiamo di buttarci sulle scialuppe e non di affondare con la nave e tutto l&#8217;iceberg.<br \/>\nE cos\u00ec hai iniziato anche tu a tossire per coprire la mia stupidit\u00e0 e tutta un\u2019aula magna ti ha seguita a ruota, come se fossimo una banda di tisici.<br \/>\nIl professore di Educazione fisica ci ha subito individuate e messe in salvo dallo sguardo gelido di Margaretta che aveva gi\u00e0 capito con chi avrebbe avuto a che fare per i prossimi cinque anni: la futura classe dirigente, nella sua espressione migliore quella dei Fra\u2019 dei Bro\u2019 dei Raga.<br \/>\nCompagnia, combriccola, comitiva, brigata, banda.<\/p>\n<p>La combriccola del Blasco<\/p>\n<p><iframe loading=\"lazy\" title=\"Vasco Rossi - Blasco Rossi\" width=\"840\" height=\"630\" src=\"https:\/\/www.youtube.com\/embed\/hYyLH9l4_EM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<p><a href=\"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/chi-e-elena-forno\/\">Elena<\/a><\/p>\n<p>Cara E.,<br \/>\ncompagna di banco compagna di fila compagna di attimi e momenti che furono e sempre saranno.<\/p>\n<p>Ma veramente tu ricordi tutta questa roba?<br \/>\n\u201cInvece io ricordo solo il primo bacio che mi hai dato tu\u201d mi verrebbe da dire alla Vecchioni, e quel tu era un ragazzo dagli occhi azzurri rotondi come il mondo che sognavo e che stava al piano sopra il nostro, ma questo l\u2019avrei scoperto mesi dopo quel primo giorno di cui tu rammenti ogni parola e io ricordo solo colori, suoni, odori, sensazioni.<\/p>\n<p>Bianco: il colore della t-shirt scelta per dare il via a quell\u2019avventura che non volevo e in cui Madre mi aveva infilata perch\u00e9 \u201cesistono due scuole, il liceo classico e il liceo scientifico e non direi che sei una da matematica!\u201d.<br \/>\nL\u2019abito conta, l\u2019abbiamo sempre saputo, e se \u00e8 vero che la prima impressione si forma in 7 secondi, al liceo, classico poi, ne bastano 3 per finire nella schiera degli sfigati ed \u00e8 un rischio che a 14 anni non puoi correre. Men che meno se le tue amiche sono tutte dell\u2019Upper Side cittadino e le felpe Best Company le sprecano giocando a tennis. Devi camminare al passo, per quanto poco te ne freghi, sei nel vortice e affondare \u00e8 un attimo.<\/p>\n<p>La scelta, quindi, era stata un parto plurigemellare contraddistinto da una serie di considerazioni essenziali: 1. qualcosa di non troppo vistoso, ma nemmeno troppo anonimo; 2. qualcosa che potesse resistere al rischio (o segreta speranza al fine di racconti futuri e risate assicurate) di venire schiumati, vittime della caccia al primino; 3. qualcosa di comodo, che chiss\u00e0 dove ci mettono per queste prime tre ore di accoglienza o supplizio che sar\u00e0.<\/p>\n<p>Rosso-ansia: il tempo trascorso tra l\u2019idea e la scelta definitiva dell\u2019outfit (oggi si dice cos\u00ec, mia figlia dice cos\u00ec, la tua?), tempo di valutazioni con le sorelle pi\u00f9 grandi che sono sempre fonte di buoni consigli o pessime opinioni, tempo di telefonate chilometriche con le amiche per capire se cos\u00ec poteva filare liscio e come loro pensavano di cavarsela, tempo di arrovellamenti personali e privatissimi su singoli dettagli del perch\u00e9 e del per come potesse andare bene quello o quell\u2019altro, tempo di minacce di Madre che tuonava possibili punizioni corporali se avessi continuato a tenere occupato il telefono di casa con quelle futili assurdit\u00e0.<br \/>\nRisultato: t-shirt bianca non notabile e jeans Levis classici, ai piedi Superga blu degnamente usurate.<\/p>\n<p>Cos\u00ec, si va. Anzi si and\u00f2, per quella che fu una citt\u00e0 dolente per molti versi, ma fu anche una \u201cstrada dorada\u201d fatta di sogni, emozioni, sconfitte, delusioni, distruzione e ricostruzione e molti lampi di meraviglia sotto il cielo dell\u2019adolescenza.<\/p>\n<p>Blu: il cielo di quel primo giorno che fu un gran calderone di sensazioni molteplici, paure, batticuore, odori, occhi che si incrociano e fuggono, capelli che ondeggiano, colori di magliette giacche felpe cappelli, voci in sottofondo, informazioni sfuggite e dettagli registrati, banchi da scegliere e facce da scrutare, occhi negli occhi con le vecchie amiche delle medie e la sensazione che tutto improvvisamente stesse cambiando ad un ritmo per cui, forse, non eravamo attrezzati tutti allo stesso modo.<\/p>\n<p>Mi percorrevano una leggera nausea e un forte senso di oppressione, un\u2019eccitazione generata dalla novit\u00e0 che mi attraeva e mi respingeva al tempo stesso, un desiderio sotteso di conoscere tutto in un solo momento e mangiarmi voracemente ogni tassello di quel nuovo mondo e al tempo stesso la sensazione palpabile di essere fuori luogo, fuori posto, fuori tutto.<\/p>\n<p>Quei cinque piani di mattoni rossi dotati di finestre che aprivano lo sguardo sul grande corso cittadino e circondati di alberi da ogni lato, sarebbero stati la nostra casa per cinque anni? Quei venti e pi\u00f9 derelitti come me seduti con lo sguardo perso tra le file dei banchi avrebbero accompagnato i prossimi 1000 giorni della nostra vita? Quella palestra immensa dove ci avevano riuniti per l\u2019accoglienza sarebbe stata la sede delle nostre vittorie e sconfitte ginniche? Quella marea umana che brulicava per i piani vociando come in uno stadio ci avrebbe trascinato in un flusso fisico e di pensiero ogni giorno per sei giorni a settimana?<\/p>\n<p>Cos\u00ec \u00e8, se ti pare e pure se non ti pare cara E., e cos\u00ec fu.<br \/>\nMa questa \u00e8 un\u2019altra storia. Oggi, quel che fu \u00e8 solo l\u2019inizio di quel che sar\u00e0.<\/p>\n<p>La storia siamo noi<\/p>\n<p><iframe loading=\"lazy\" title=\"La storia\" width=\"840\" height=\"630\" src=\"https:\/\/www.youtube.com\/embed\/-VDve7HlQQU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<p><a href=\"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/chi-e-chiara-avidano\/\">\u00a0Chiara<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cara C., stamattina alle otto e diciotto sono passata in corso Dante, e Lei era l\u00ec come ai vecchi tempi. L\u2019Alfieri, la nostra scuola, il Liceo Classico Vittorio Alfieri. Il semaforo durava quasi il tempo di una canzone ed io imbambolata, fissando la vetrata trasparente, ho cominciato a ripensare agli anni della scuola, a me &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/primo-giorno-di-scuola-classe-dirigente-o-raga\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Primo giorno di scuola. Classe Dirigente o Raga\u2026?&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1378,"featured_media":176,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[15,16],"class_list":["post-171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-compagne-di-banco","tag-musica","tag-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Primo giorno di scuola. Classe Dirigente o Raga\u2026? - Compagne di Banco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/primo-giorno-di-scuola-classe-dirigente-o-raga\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Primo giorno di scuola. Classe Dirigente o Raga\u2026? - Compagne di Banco\" \/>\n<meta property=\"og:description\" content=\"Cara C., stamattina alle otto e diciotto sono passata in corso Dante, e Lei era l\u00ec come ai vecchi tempi. L\u2019Alfieri, la nostra scuola, il Liceo Classico Vittorio Alfieri. Il semaforo durava quasi il tempo di una canzone ed io imbambolata, fissando la vetrata trasparente, ho cominciato a ripensare agli anni della scuola, a me &hellip; Leggi tutto &quot;Primo giorno di scuola. Classe Dirigente o Raga\u2026?&quot;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/primo-giorno-di-scuola-classe-dirigente-o-raga\/\" \/>\n<meta property=\"og:site_name\" content=\"Compagne di Banco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-08T12:55:01+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/files\/2024\/03\/compagne-di-banco-copertina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@quotidianopiem\" \/>\n<meta name=\"twitter:site\" content=\"@quotidianopiem\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/primo-giorno-di-scuola-classe-dirigente-o-raga\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/primo-giorno-di-scuola-classe-dirigente-o-raga\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Primo giorno di scuola. Classe Dirigente o Raga\u2026?\",\"datePublished\":\"2024-03-08T12:55:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/primo-giorno-di-scuola-classe-dirigente-o-raga\\\/\"},\"wordCount\":2094,\"commentCount\":1,\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/primo-giorno-di-scuola-classe-dirigente-o-raga\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/files\\\/2024\\\/03\\\/compagne-di-banco-copertina.jpg\",\"keywords\":[\"musica\",\"scuola\"],\"articleSection\":[\"Compagne di Banco\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/primo-giorno-di-scuola-classe-dirigente-o-raga\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/primo-giorno-di-scuola-classe-dirigente-o-raga\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/primo-giorno-di-scuola-classe-dirigente-o-raga\\\/\",\"name\":\"Primo giorno di scuola. Classe Dirigente o Raga\u2026? - Compagne di Banco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/primo-giorno-di-scuola-classe-dirigente-o-raga\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/primo-giorno-di-scuola-classe-dirigente-o-raga\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/files\\\/2024\\\/03\\\/compagne-di-banco-copertina.jpg\",\"datePublished\":\"2024-03-08T12:55:01+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/primo-giorno-di-scuola-classe-dirigente-o-raga\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/primo-giorno-di-scuola-classe-dirigente-o-raga\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/primo-giorno-di-scuola-classe-dirigente-o-raga\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/files\\\/2024\\\/03\\\/compagne-di-banco-copertina.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/files\\\/2024\\\/03\\\/compagne-di-banco-copertina.jpg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/primo-giorno-di-scuola-classe-dirigente-o-raga\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Primo giorno di scuola. Classe Dirigente o Raga\u2026?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/\",\"name\":\"Compagne di Banco\",\"description\":\"Compagne di banco \u00e8 un diario sentimentale a due voci, due compagne di banco chiacchierano e si confrontano su temi culturali sociali e di attualit\u00e0 tra note, lodi e compiti a casa.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/compagne-di-banco\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Primo giorno di scuola. Classe Dirigente o Raga\u2026? - Compagne di Banco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/primo-giorno-di-scuola-classe-dirigente-o-raga\/","og_locale":"it_IT","og_type":"article","og_title":"Primo giorno di scuola. Classe Dirigente o Raga\u2026? - Compagne di Banco","og_description":"Cara C., stamattina alle otto e diciotto sono passata in corso Dante, e Lei era l\u00ec come ai vecchi tempi. L\u2019Alfieri, la nostra scuola, il Liceo Classico Vittorio Alfieri. Il semaforo durava quasi il tempo di una canzone ed io imbambolata, fissando la vetrata trasparente, ho cominciato a ripensare agli anni della scuola, a me &hellip; Leggi tutto \"Primo giorno di scuola. Classe Dirigente o Raga\u2026?\"","og_url":"http:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/primo-giorno-di-scuola-classe-dirigente-o-raga\/","og_site_name":"Compagne di Banco","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese","article_published_time":"2024-03-08T12:55:01+00:00","og_image":[{"width":2048,"height":1536,"url":"http:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/files\/2024\/03\/compagne-di-banco-copertina.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@quotidianopiem","twitter_site":"@quotidianopiem","twitter_misc":{"Scritto da":"","Tempo di lettura stimato":"12 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/primo-giorno-di-scuola-classe-dirigente-o-raga\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/primo-giorno-di-scuola-classe-dirigente-o-raga\/"},"author":{"name":"","@id":""},"headline":"Primo giorno di scuola. Classe Dirigente o Raga\u2026?","datePublished":"2024-03-08T12:55:01+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/primo-giorno-di-scuola-classe-dirigente-o-raga\/"},"wordCount":2094,"commentCount":1,"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/primo-giorno-di-scuola-classe-dirigente-o-raga\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/files\/2024\/03\/compagne-di-banco-copertina.jpg","keywords":["musica","scuola"],"articleSection":["Compagne di Banco"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/primo-giorno-di-scuola-classe-dirigente-o-raga\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/primo-giorno-di-scuola-classe-dirigente-o-raga\/","url":"http:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/primo-giorno-di-scuola-classe-dirigente-o-raga\/","name":"Primo giorno di scuola. Classe Dirigente o Raga\u2026? - Compagne di Banco","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/#website"},"primaryImageOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/primo-giorno-di-scuola-classe-dirigente-o-raga\/#primaryimage"},"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/primo-giorno-di-scuola-classe-dirigente-o-raga\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/files\/2024\/03\/compagne-di-banco-copertina.jpg","datePublished":"2024-03-08T12:55:01+00:00","author":{"@id":""},"breadcrumb":{"@id":"http:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/primo-giorno-di-scuola-classe-dirigente-o-raga\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/primo-giorno-di-scuola-classe-dirigente-o-raga\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/primo-giorno-di-scuola-classe-dirigente-o-raga\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/files\/2024\/03\/compagne-di-banco-copertina.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/files\/2024\/03\/compagne-di-banco-copertina.jpg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"http:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/primo-giorno-di-scuola-classe-dirigente-o-raga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/"},{"@type":"ListItem","position":2,"name":"Primo giorno di scuola. Classe Dirigente o Raga\u2026?"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/#website","url":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/","name":"Compagne di Banco","description":"Compagne di banco \u00e8 un diario sentimentale a due voci, due compagne di banco chiacchierano e si confrontano su temi culturali sociali e di attualit\u00e0 tra note, lodi e compiti a casa.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"","url":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/wp-json\/wp\/v2\/posts\/171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/wp-json\/wp\/v2\/users\/1378"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/wp-json\/wp\/v2\/comments?post=171"}],"version-history":[{"count":1,"href":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/wp-json\/wp\/v2\/posts\/171\/revisions"}],"predecessor-version":[{"id":172,"href":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/wp-json\/wp\/v2\/posts\/171\/revisions\/172"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/wp-json\/wp\/v2\/media\/176"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/wp-json\/wp\/v2\/media?parent=171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/wp-json\/wp\/v2\/categories?post=171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/compagne-di-banco\/wp-json\/wp\/v2\/tags?post=171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}