{"id":999,"date":"2012-06-18T12:38:54","date_gmt":"2012-06-18T12:38:54","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/cabiria\/?p=999"},"modified":"2012-06-18T12:40:33","modified_gmt":"2012-06-18T12:40:33","slug":"contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\/","title":{"rendered":"Contribuisci alla realizzazione di Five, il doc sul Quinto Direttorato di Max\u00ec Dejoie &#8211; intervista"},"content":{"rendered":"<p><strong>Max\u00ec Dejoie<\/strong> \u00e8 di nuovo in pista.<br \/>\nDopo l&#8217;ottimo successo di <a href=\"http:\/\/www.soloparolesparse.com\/2011\/11\/thff11-the-gerber-syndrome-come-si-fa-un-mockumentary\/\" target=\"_blank\"><strong>The Gerber Syndrome<\/strong><\/a>, il <em>mockumentary<\/em> che ha girato il mondo di festival in festival (e ancora non ha concluso il suo viaggio), il regista torinese \u00e8 pronto a cominciare il suo nuovo progetto.<\/p>\n<p><a href=\"http:\/\/www.quotidianopiemontese.it\/cabiria\/2012\/06\/18\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\/maxi-dejoie\/\" rel=\"attachment wp-att-1000\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1000\" src=\"http:\/\/www.quotidianopiemontese.it\/cabiria\/files\/2012\/06\/maxi-dejoie-500x280.jpg\" alt=\"\" width=\"500\" height=\"280\" srcset=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2012\/06\/maxi-dejoie-500x280.jpg 500w, https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2012\/06\/maxi-dejoie.jpg 615w\" sizes=\"auto, (max-width: 500px) 85vw, 500px\" \/><\/a><\/p>\n<p>Si tratta di <strong>Five (5)<\/strong>, un documentario (vero questa volta) sul <em>Quinto Direttorato del KGB<\/em>.<\/p>\n<p><!--more-->Per far partire il progetto ha per\u00f2 bisogno del vostro aiuto, una mano concreta che potete dare grazie ad un <a href=\"http:\/\/www.indiegogo.com\/kgb\" target=\"_blank\">CrowdFunding su IndieGogo<\/a> che gli permetter\u00e0 di dare il via alla nuova avventura.<\/p>\n<p>Abbiamo potuto intervistarlo per scoprire cosa sar\u00e0 Five (5).<\/p>\n<p><strong>1. Da un documentario finto ad un documentario vero. Stai sviluppando una passione per questo metodo di racconto?<\/strong><\/p>\n<p>Direi che questa sarebbe la mia prima esperienza seria con il documentario; <em>The Gerber Syndrome<\/em>, per quanto realistico, rimane comunque di finzione. Non penso che i documentaristi \u201cveri\u201d approverebbero se cercassi di metterlo sullo stesso piano di un documentario, cosa che infatti non ho intenzione di fare.<br \/>\nQuando ho iniziato a pensare all\u2019argomento del KGB, sono partito con l\u2019idea di farne un film di finzione. Poi, man mano che procedevo con le ricerche, mi \u00e8 balenata l\u2019idea di farne un documentario, prima, e magari un film di finzione dopo. Poi il pensiero si \u00e8 evoluto ulteriormente ed ha preso la forma che ha attualmente, cio\u00e8 di fare un documentario (vero) ma con un aspetto \u201ccinematic\u201d; vorrei realizzare qualcosa di interessante a livello di contenuti (rispettando le storie vere e i protagonisti che me le racconteranno) rendendolo anche un prodotto piacevole da guardare, e per piacevole mi riferisco al piacere che si pu\u00f2 provare nel guardare un bel film di finzione, anche se gli argomenti non sono propriamente piacevoli. Quindi si, direi che il documentario \u00e8 un modo di fare cinema che apprezzo molto e che sto scoprendo piano piano.<\/p>\n<p><strong>2. Il film che vuoi realizzare \u00e8 sul quinto direttorato del KGB, un tema importante. Vuoi spiegarci di cosa si tratta e perch\u00e9 pensi sia un argomento che merita un approfondimento filmico?<\/strong><\/p>\n<p>Il quinto direttorato del KGB \u00e8 quello che si occupava di \u201c<em>combattere con ogni mezzo contro la sovversione ideologica, reprimere il nazionalismo e le attivit\u00e0 anti Sovietiche.<\/em>\u201d<br \/>\nAttivit\u00e0 che erano presenti soprattutto nei paesi \u201cdominati\u201d dall\u2019Unione Sovietica, come la Lituania. Le categorie di persone principalmente controllate da questo direttorato erano artisti, intellettuali, membri del clero, religiosi e soprattutto giovani. Ragazzi e ragazze che avevano l\u2019et\u00e0 che ho io adesso. Persone che, da quanto sto vedendo, a volte venivano perseguitate per motivi davvero incredibili&#8230;Come il collezionista di monete antiche, arrestato e interrogato (cio\u00e8 torturato) con l\u2019accusa di violazione delle leggi di scambio monetario internazionale: soltanto per essere stato in possesso di una collezione di monete d\u2019oro del 1700, o dell\u2019enorme numero di ragazzi che come tanti loro coetanei degli anni \u201970, volevano ascoltare la grande musica di Bob Dylan, i Beatles o gli Stones, portare i jeans e i capelli lunghi. Tutte cose che il regime non approvava.<br \/>\nPenso che sarebbe interessante se anche noi (per noi mi riferisco ai paesi dell\u2019Europa occidentale) venissimo a conoscenza in modo un po\u2019 pi\u00f9 approfondito di storie come queste. Ovviamente non sono cos\u00ec pretenzioso da poter pensare di riuscire in un\u2019impresa simile, diciamo che voglio soltanto dare il mio piccolo contributo offrendo il mio punto di vista su argomenti che per me sono universali. A me non interessa fare un quadro storico-politico dell\u2019Unione Sovietica e del KGB. Io voglio solo raccontare delle storie umane: Storie drammatiche, ispiranti, curiose, come saranno non lo so ancora, ma quello di cui sono certo \u00e8 che saranno storie personali e vere. Perch\u00e9 quando si parla della violazione della libert\u00e0 di un uomo o di una donna, non ha nessuna importanza il paese di provenienza, la religione, il colore o il partito. E\u2019 un argomento che tocca ognuno di noi allo stesso modo.<\/p>\n<p><em>Leggi <a href=\"http:\/\/www.quotidianopiemontese.it\/cabiria\/2012\/06\/18\/intervista-con-maxi-dejoie-seconda-parte\/\">la seconda parte dell&#8217;intervista con Max\u00ec Dejoie<\/a>.\u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Max\u00ec Dejoie \u00e8 di nuovo in pista. Dopo l&#8217;ottimo successo di The Gerber Syndrome, il mockumentary che ha girato il mondo di festival in festival (e ancora non ha concluso il suo viaggio), il regista torinese \u00e8 pronto a cominciare il suo nuovo progetto. Si tratta di Five (5), un documentario (vero questa volta) sul &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Contribuisci alla realizzazione di Five, il doc sul Quinto Direttorato di Max\u00ec Dejoie &#8211; intervista&#8221;<\/span><\/a><\/p>\n","protected":false},"author":34,"featured_media":1000,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[298,297,178],"class_list":["post-999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interviste","tag-crowdfunding","tag-five","tag-maxi-dejoie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contribuisci alla realizzazione di Five, il doc sul Quinto Direttorato di Max\u00ec Dejoie - intervista - Cabiria<\/title>\n<meta name=\"description\" content=\"crowdfunding, five, Max\u00ec Dejoie\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contribuisci alla realizzazione di Five, il doc sul Quinto Direttorato di Max\u00ec Dejoie - intervista - Cabiria\" \/>\n<meta property=\"og:description\" content=\"crowdfunding, five, Max\u00ec Dejoie\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2012-06-18T12:38:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-06-18T12:40:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2012\/06\/maxi-dejoie.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"615\" \/>\n\t<meta property=\"og:image:height\" content=\"345\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Contribuisci alla realizzazione di Five, il doc sul Quinto Direttorato di Max\u00ec Dejoie &#8211; intervista\",\"datePublished\":\"2012-06-18T12:38:54+00:00\",\"dateModified\":\"2012-06-18T12:40:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\\\/\"},\"wordCount\":667,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2012\\\/06\\\/maxi-dejoie.jpg\",\"keywords\":[\"crowdfunding\",\"five\",\"Max\u00ec Dejoie\"],\"articleSection\":[\"interviste\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\\\/\",\"name\":\"Contribuisci alla realizzazione di Five, il doc sul Quinto Direttorato di Max\u00ec Dejoie - intervista - Cabiria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2012\\\/06\\\/maxi-dejoie.jpg\",\"datePublished\":\"2012-06-18T12:38:54+00:00\",\"dateModified\":\"2012-06-18T12:40:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"crowdfunding, five, Max\u00ec Dejoie\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2012\\\/06\\\/maxi-dejoie.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2012\\\/06\\\/maxi-dejoie.jpg\",\"width\":\"615\",\"height\":\"345\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contribuisci alla realizzazione di Five, il doc sul Quinto Direttorato di Max\u00ec Dejoie &#8211; intervista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contribuisci alla realizzazione di Five, il doc sul Quinto Direttorato di Max\u00ec Dejoie - intervista - Cabiria","description":"crowdfunding, five, Max\u00ec Dejoie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cabiria\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\/","og_locale":"it_IT","og_type":"article","og_title":"Contribuisci alla realizzazione di Five, il doc sul Quinto Direttorato di Max\u00ec Dejoie - intervista - Cabiria","og_description":"crowdfunding, five, Max\u00ec Dejoie","og_url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2012-06-18T12:38:54+00:00","article_modified_time":"2012-06-18T12:40:33+00:00","og_image":[{"width":615,"height":345,"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2012\/06\/maxi-dejoie.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Contribuisci alla realizzazione di Five, il doc sul Quinto Direttorato di Max\u00ec Dejoie &#8211; intervista","datePublished":"2012-06-18T12:38:54+00:00","dateModified":"2012-06-18T12:40:33+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\/"},"wordCount":667,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2012\/06\/maxi-dejoie.jpg","keywords":["crowdfunding","five","Max\u00ec Dejoie"],"articleSection":["interviste"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\/","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\/","name":"Contribuisci alla realizzazione di Five, il doc sul Quinto Direttorato di Max\u00ec Dejoie - intervista - Cabiria","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2012\/06\/maxi-dejoie.jpg","datePublished":"2012-06-18T12:38:54+00:00","dateModified":"2012-06-18T12:40:33+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"crowdfunding, five, Max\u00ec Dejoie","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2012\/06\/maxi-dejoie.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2012\/06\/maxi-dejoie.jpg","width":"615","height":"345"},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"Contribuisci alla realizzazione di Five, il doc sul Quinto Direttorato di Max\u00ec Dejoie &#8211; intervista"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=999"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/999\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/1000"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}