{"id":609,"date":"2011-10-24T14:58:02","date_gmt":"2011-10-24T14:58:02","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/cabiria\/?p=609"},"modified":"2016-11-07T16:43:40","modified_gmt":"2016-11-07T16:43:40","slug":"riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\/","title":{"rendered":"Riflessione (e speranze) sulla nomina di Ugo Nespolo a presidente del Museo Nazionale del Cinema"},"content":{"rendered":"<p>Scusate il titolo Voltairriano, ma quando cambia qualcosa ai vertici del <em>sistema cinema torinese<\/em> io un po&#8217; mi preoccupo sempre.<\/p>\n<p>Mi preoccupo perch\u00e8 il sistema cinema della nostra citt\u00e0 (pur con tutti i suoi difetti) \u00e8 un sistema che funziona, non ho paura di dire che \u00e8 quello che funziona meglio a livello nazionale (mica per niente abbiamo il maggior numero di produzioni cinematografiche sul territorio ogni anno da ormai quasi un decennio!).<\/p>\n<p><a href=\"http:\/\/www.quotidianopiemontese.it\/cabiria\/2011\/10\/24\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\/ugo-nespolo\/\" rel=\"attachment wp-att-611\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-611\" src=\"http:\/\/www.quotidianopiemontese.it\/cabiria\/files\/2011\/10\/ugo-nespolo-500x490.jpg\" alt=\"\" width=\"500\" height=\"490\" srcset=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2011\/10\/ugo-nespolo-500x490.jpg 500w, https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2011\/10\/ugo-nespolo.jpg 612w\" sizes=\"auto, (max-width: 500px) 85vw, 500px\" \/><\/a><\/p>\n<p>Cos\u00ec ogni volta che cambia qualcosa io un pochino mi preoccupo, mi preoccupo che il nuovo arrivato non sia bravo come il predecessore, ma pi\u00f9 ancora che non riesca ad integrarsi con gli altri attori del sistema e che rischi di bloccare cos\u00ec ingranaggi molto delicati.<\/p>\n<p>Detto delle paure generali, <a href=\"http:\/\/www.quotidianopiemontese.it\/2011\/10\/21\/ugo-nespolo-nuovo-presidente-del-museo-nazionale-del-cinema\/\" target=\"_blank\">la nomina di <strong>Ugo Nespolo<\/strong><\/a> a <em>presidente del Museo Nazionale del Cinema<\/em> mi preoccupa meno del solito.<br \/>\n<em>Nespolo<\/em> \u00e8 torinese nell&#8217;animo, conosce bene il cinema (per esserne amante e per averlo fatto in maniera massiccia) e soprattutto \u00e8 stato in grado di dare alla sua arte anche un aspetto commerciale molto marcato (parlo di monetizzare e pubblicizzare, non di vendersi al miglior offerente e di piegarsi al soldo).<br \/>\nE poi <em>Nespolo<\/em> \u00e8 gi\u00e0 dentro al sistema torinese.<br \/>\nConosce bene <strong>Alberto Barbera<\/strong>, <strong>Steve Della Casa<\/strong> e compagnia bella, ne condivide (almeno in parte) i dogmi e sapr\u00e0 confrontarsi sulle scelte fondamentali.<\/p>\n<p><!--more-->In pi\u00f9 (e qui sta il centro della questione) <em>Nespolo<\/em> si porta dietro una fama mondiale universalmente riconosciuta che non potr\u00e0 che far bene al <em>Museo Nazionale del Cinema<\/em>, portare nuovi visitatori, nuove collaborazioni e nuovi fondamentali sponsor, anche internazionali.<br \/>\nVi sembra poco?<\/p>\n<p>In conclusione vi sar\u00e0 ormai chiaro che in questo caso (al netto delle paure ataviche) sono molto fiducioso della scelta fatta (e mi tocca riconoscere la paternit\u00e0 dell&#8217;idea al personalmente poco amato <em>Michele Coppola<\/em>).<br \/>\nOra aspettiamo di vedere le prime mosse del nuovo presidente&#8230; pronti a ricacciarsi in gola le speranze.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Scusate il titolo Voltairriano, ma quando cambia qualcosa ai vertici del sistema cinema torinese io un po&#8217; mi preoccupo sempre. Mi preoccupo perch\u00e8 il sistema cinema della nostra citt\u00e0 (pur con tutti i suoi difetti) \u00e8 un sistema che funziona, non ho paura di dire che \u00e8 quello che funziona meglio a livello nazionale (mica &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Riflessione (e speranze) sulla nomina di Ugo Nespolo a presidente del Museo Nazionale del Cinema&#8221;<\/span><\/a><\/p>\n","protected":false},"author":34,"featured_media":611,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[6,170],"class_list":["post-609","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cabiria","tag-mnc","tag-ugo-nespolo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Riflessione (e speranze) sulla nomina di Ugo Nespolo a presidente del Museo Nazionale del Cinema - Cabiria<\/title>\n<meta name=\"description\" content=\"mnc, ugo nespolo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Riflessione (e speranze) sulla nomina di Ugo Nespolo a presidente del Museo Nazionale del Cinema - Cabiria\" \/>\n<meta property=\"og:description\" content=\"mnc, ugo nespolo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2011-10-24T14:58:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-11-07T16:43:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2011\/10\/ugo-nespolo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"612\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Riflessione (e speranze) sulla nomina di Ugo Nespolo a presidente del Museo Nazionale del Cinema\",\"datePublished\":\"2011-10-24T14:58:02+00:00\",\"dateModified\":\"2016-11-07T16:43:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\\\/\"},\"wordCount\":329,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2011\\\/10\\\/ugo-nespolo.jpg\",\"keywords\":[\"mnc\",\"ugo nespolo\"],\"articleSection\":[\"cabiria\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\\\/\",\"name\":\"Riflessione (e speranze) sulla nomina di Ugo Nespolo a presidente del Museo Nazionale del Cinema - Cabiria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2011\\\/10\\\/ugo-nespolo.jpg\",\"datePublished\":\"2011-10-24T14:58:02+00:00\",\"dateModified\":\"2016-11-07T16:43:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"mnc, ugo nespolo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2011\\\/10\\\/ugo-nespolo.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2011\\\/10\\\/ugo-nespolo.jpg\",\"width\":\"612\",\"height\":\"600\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Riflessione (e speranze) sulla nomina di Ugo Nespolo a presidente del Museo Nazionale del Cinema\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Riflessione (e speranze) sulla nomina di Ugo Nespolo a presidente del Museo Nazionale del Cinema - Cabiria","description":"mnc, ugo nespolo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cabiria\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\/","og_locale":"it_IT","og_type":"article","og_title":"Riflessione (e speranze) sulla nomina di Ugo Nespolo a presidente del Museo Nazionale del Cinema - Cabiria","og_description":"mnc, ugo nespolo","og_url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2011-10-24T14:58:02+00:00","article_modified_time":"2016-11-07T16:43:40+00:00","og_image":[{"width":612,"height":600,"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2011\/10\/ugo-nespolo.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Riflessione (e speranze) sulla nomina di Ugo Nespolo a presidente del Museo Nazionale del Cinema","datePublished":"2011-10-24T14:58:02+00:00","dateModified":"2016-11-07T16:43:40+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\/"},"wordCount":329,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2011\/10\/ugo-nespolo.jpg","keywords":["mnc","ugo nespolo"],"articleSection":["cabiria"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\/","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\/","name":"Riflessione (e speranze) sulla nomina di Ugo Nespolo a presidente del Museo Nazionale del Cinema - Cabiria","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2011\/10\/ugo-nespolo.jpg","datePublished":"2011-10-24T14:58:02+00:00","dateModified":"2016-11-07T16:43:40+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"mnc, ugo nespolo","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2011\/10\/ugo-nespolo.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2011\/10\/ugo-nespolo.jpg","width":"612","height":"600"},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/riflessione-e-speranze-sulla-nomina-di-ugo-nespolo-a-direttore-del-museo-nazionale-del-cinema\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"Riflessione (e speranze) sulla nomina di Ugo Nespolo a presidente del Museo Nazionale del Cinema"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=609"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/609\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/611"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}