{"id":5638,"date":"2023-05-04T09:54:35","date_gmt":"2023-05-04T09:54:35","guid":{"rendered":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?p=5638"},"modified":"2023-05-04T09:54:35","modified_gmt":"2023-05-04T09:54:35","slug":"a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\/","title":{"rendered":"A Torino si cercano comparse e figurazioni per la seconda stagione di Lidia Po\u00ebt &#8211; casting"},"content":{"rendered":"<p>Per la seconda stagione della serie &#8220;La legge di Lidia Po\u00ebt&#8221;, prodotta da Groenlandia srl per Netflix, le cui riprese sono previste in Piemonte da met\u00e0 giugno a met\u00e0 ottobre 2023, si cercano comparse e figurazioni speciali.<!--more--><\/p>\n<p>In particolare si cercano:<\/p>\n<p>&#8211; comparse maggiorenni di et\u00e0 compresa tra i 18 e i 75 anni<br \/>\n&#8211; comparse minorenni di et\u00e0 compresa tra i 6 e i 15 anni<br \/>\n&#8211; persone con esperienza di recitazione o attori amatoriali disponibili per delle figurazioni speciali<br \/>\n&#8211; persone che sappiano dipingere e che abbiano una buona manualit\u00e0 nel disegno<br \/>\n&#8211; persone che sappiano cantare in coro (anche minorenni)<br \/>\n&#8211; persone che sappiano suonare degli strumenti musicali dell&#8217;epoca<br \/>\n&#8211; persone che sappiano ballare il Valzer viennese<br \/>\n&#8211; persone che siano in grado di simulare un addestramento militare<\/p>\n<p>Si tratta di una serie in costume ambientata in Piemonte a fine dell&#8217;Ottocento.<br \/>\nPer ricostruire il periodo storico in cui \u00e8 ambientata la serie, gli uomini non devono avere i capelli rasati o il doppio taglio, ed \u00e8 preferibile che abbiano la barba e\/o i baffi e\/o che siano disposti a farli crescere.<br \/>\nLe donne non devono avere meches o colori dei capelli troppo moderni, ed \u00e8 preferibile che abbiano i capelli medio lunghi.<br \/>\nSi richiede la disponibilit\u00e0 ad eventuali tagli o modifiche di capelli di barba, a seconda delle necessit\u00e0.<br \/>\nNon devono esserci tatuaggi in parti del corpo visibili, come braccia, collo, mani, n\u00e9 sopracciglia tatuate o ritoccate.<\/p>\n<p>Per candidarsi occorre compilare i seguenti form:<br \/>\n&#8211; <a href=\"https:\/\/forms.gle\/AqSk9HiBfBMWtGE58\">Per i maggiorenni<\/a><br \/>\n&#8211; <a href=\"https:\/\/forms.gle\/CUpbdETqPABGruYQ9\">Per i minorenni<\/a><\/p>\n<p>Verr\u00e0 richiesto di caricare alcune foto. Non \u00e8 necessario ricorrere a fotografi professionisti, ma si raccomanda la massima cura nella selezione o nella realizzazione delle foto, che devono essere recenti\/ attuali, fatte sul momento.<br \/>\nIn particolare accertarsi che siano ben visibili, possibilmente scattate alla luce naturale o con una buona illuminazione artificiale su sfondo chiaro.<br \/>\nNon indossare occhiali da sole, e non inviare foto di gruppo. Non effettuare ritocchi alle fotografie, n\u00e9 aggiungere filtri.<\/p>\n<p>Il lavoro sar\u00e0 regolarmente retribuito.<br \/>\nLa ricerca \u00e8 rivolta preferibilmente ai residenti e\/o domiciliati in Piemonte.<\/p>\n<p>Casting a cura di Chiara Moretti<\/p>\n<p>Per info: lidia2comparse@gmail.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per la seconda stagione della serie &#8220;La legge di Lidia Po\u00ebt&#8221;, prodotta da Groenlandia srl per Netflix, le cui riprese sono previste in Piemonte da met\u00e0 giugno a met\u00e0 ottobre 2023, si cercano comparse e figurazioni speciali.<\/p>\n","protected":false},"author":34,"featured_media":5639,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[1437],"class_list":["post-5638","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casting","tag-la-legge-di-lidia-poet"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Torino si cercano comparse e figurazioni per la seconda stagione di Lidia Po\u00ebt - casting - Cabiria<\/title>\n<meta name=\"description\" content=\"la legge di lidia poet\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Torino si cercano comparse e figurazioni per la seconda stagione di Lidia Po\u00ebt - casting - Cabiria\" \/>\n<meta property=\"og:description\" content=\"la legge di lidia poet\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-04T09:54:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2023\/05\/casting-legge-lidia-poet.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"A Torino si cercano comparse e figurazioni per la seconda stagione di Lidia Po\u00ebt &#8211; casting\",\"datePublished\":\"2023-05-04T09:54:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\\\/\"},\"wordCount\":370,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2023\\\/05\\\/casting-legge-lidia-poet.jpeg\",\"keywords\":[\"la legge di lidia poet\"],\"articleSection\":[\"casting\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\\\/\",\"name\":\"A Torino si cercano comparse e figurazioni per la seconda stagione di Lidia Po\u00ebt - casting - Cabiria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2023\\\/05\\\/casting-legge-lidia-poet.jpeg\",\"datePublished\":\"2023-05-04T09:54:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"la legge di lidia poet\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2023\\\/05\\\/casting-legge-lidia-poet.jpeg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2023\\\/05\\\/casting-legge-lidia-poet.jpeg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Torino si cercano comparse e figurazioni per la seconda stagione di Lidia Po\u00ebt &#8211; casting\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Torino si cercano comparse e figurazioni per la seconda stagione di Lidia Po\u00ebt - casting - Cabiria","description":"la legge di lidia poet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cabiria\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\/","og_locale":"it_IT","og_type":"article","og_title":"A Torino si cercano comparse e figurazioni per la seconda stagione di Lidia Po\u00ebt - casting - Cabiria","og_description":"la legge di lidia poet","og_url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2023-05-04T09:54:35+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2023\/05\/casting-legge-lidia-poet.jpeg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"A Torino si cercano comparse e figurazioni per la seconda stagione di Lidia Po\u00ebt &#8211; casting","datePublished":"2023-05-04T09:54:35+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\/"},"wordCount":370,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2023\/05\/casting-legge-lidia-poet.jpeg","keywords":["la legge di lidia poet"],"articleSection":["casting"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\/","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\/","name":"A Torino si cercano comparse e figurazioni per la seconda stagione di Lidia Po\u00ebt - casting - Cabiria","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2023\/05\/casting-legge-lidia-poet.jpeg","datePublished":"2023-05-04T09:54:35+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"la legge di lidia poet","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2023\/05\/casting-legge-lidia-poet.jpeg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2023\/05\/casting-legge-lidia-poet.jpeg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/a-torino-si-cercano-comparse-e-figurazioni-per-la-seconda-stagione-di-lidia-poet-casting\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"A Torino si cercano comparse e figurazioni per la seconda stagione di Lidia Po\u00ebt &#8211; casting"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/5638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=5638"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/5638\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/5639"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=5638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=5638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=5638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}