{"id":5549,"date":"2022-09-22T06:36:43","date_gmt":"2022-09-22T06:36:43","guid":{"rendered":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?p=5549"},"modified":"2022-09-22T06:36:43","modified_gmt":"2022-09-22T06:36:43","slug":"tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\/","title":{"rendered":"Tutti i premi dell&#8217;edizione 2022 di Ortometraggi Film Festival"},"content":{"rendered":"<p>Si \u00e8 tenuta a Orti Generali dal 16 al 18 settembre la quinta edizione di Ortometraggi Film Festival: un\u2019edizione che si propone, con il suo titolo \u201cScenari futuri da un presente incerto\u201d, di ampliare il racconto della relazione tra essere umano e natura &#8211; tema cardine del festival &#8211; proponendo una riflessione a 360 gradi sul tema della sostenibilit\u00e0. La connessione tra crisi climatica e sociale, l\u2019importanza della dimensione comunitaria e il bisogno di sperimentare nuovi modelli lavorativi, sociali ed economici, sono stati affrontati attraverso il coinvolgimento diretto del quartiere di Mirafiori Sud, a partire dalle comunit\u00e0 che si riuniscono intorno a quelli che sono stati i due poli principali del festival, lo spazio di Orti Generali e quello della Chiesa di san Barnaba.<\/p>\n<p>Il programma si \u00e8 articolato tra talk, residenze artistiche, installazioni, laboratori e una sfilata di moda upcycled tenutasi negli orti urbani nella serata di sabato 17, coinvolgendo ospiti capaci di spaziare tra il mondo dell\u2019arte, quello della moda e quello della comunicazione, tra l\u2019impresa sociale e la grande distribuzione, tra realt\u00e0 culturali, reti di spazi e agenzie di formazione. Al centro della manifestazione &#8211; organizzata dall\u2019associazione Gomboc &#8211; c\u2019erano ovviamente le proiezioni dei cortometraggi: 31 le opere in concorso nelle categorie di animazione, fiction e documentari, a cui si aggiunge la categoria speciale dei videoarte, selezionate dalla direzione artistica di Matilde Ugolini. Tutti i corti, provenienti da diversi Paesi, sono stati proposti in lingua originale con sottotitoli in italiano a cura di Sarah Cannone, Roberta Ponti e Federica Quatraro, studentesse del corso di laurea magistrale in \u201cTraduzione e Interpretariato\u201d dell\u2019Universit\u00e0 del Salento, sotto la direzione della prof.ssa Francesca Bianchi.<\/p>\n<p>Nella serata conclusiva del 18 settembre, al termine delle proiezioni, sono stati assegnati i premi al \u201cMiglior Documentario\u201d, alla \u201cMiglior Fiction\u201d e alla \u201cMiglior Animazione\u201d e le menzioni speciali, una per ogni categoria. Sul palco del cinema di San Barnaba, per la premiazione, oltre all\u2019host Roberto Cruciani, c\u2019erano il regista Enrico Bisi, il compositore e sound designer Max Viale, il regista e videomaker nell&#8217;ambito dell&#8217;animazione e degli effetti speciali Donato Sansone e Milena Tipaldo, specializzata in animazione ed illustrazione, in rappresentanza della giuria presieduta dal regista Daniele Segre e completata dal montatore Stefano Cravero. Prima categoria ad essere premiata quella dell\u2019animazione, con l\u2019assegnazione della menzione e poi del primo premio.<\/p>\n<p>Per i cortometraggi di animazione vince la menzione speciale &#8220;per il coraggio mostrato nell\u2019utilizzo di un\u2019estetica punk accostata ad un linguaggio ironico su dense tematiche di attualit\u00e0&#8221; &#8216;Chick Wash&#8217; di Bethany Forest, mentre il premio miglior corto d\u2019animazione \u00e8 di Fabio Orlando e Tommaso Zerbi con \u2018Graziano e la giraffa\u2019 con la seguente motivazione: &#8220;per la bellezza estetica, la maturit\u00e0 grafica e narrativa di un racconto surreale che ci porta nel cuore delle problematiche relative al rapporto tra essere umano e natura&#8221;.<\/p>\n<p>Nelle fiction la menzione speciale viene assegnata dalla giuria a &#8216;Therefore, Socrates is Mortal&#8217; di Alexandre Isabelle &#8220;per l\u2019eleganza, l\u2019incisivit\u00e0 e l\u2019energia con cui viene trattato un tema di forte attualit\u00e0, senza cadere in facili moralismi&#8221;, mentre il primo premio per la categoria \u00e8 vinto da &#8216;Iceberg Licking Society&#8217; di Nathan Ceddia &#8220;per l\u2019approccio originale e inedito a una tematica cruciale e talvolta inflazionata. Tra finzione e realt\u00e0, il cortometraggio riesce a far riflettere lo spettatore e a toccare temi profondi con una leggerezza assai rara&#8221;.<\/p>\n<p>Nella sezione dedicata al cinema della realt\u00e0, la menzione speciale \u00e8 stata assegnata al corto documentario &#8220;Orti d&#8217;ortica&#8221; di Emilio Neri Tremolada, &#8220;per la capacit\u00e0 di raccontare una scelta al tempo stesso personale e collettiva, esempio concreto di come ci si possa riappropriare degli spazi urbani in modo costruttivo e addirittura romantico. La valutazione della giuria aggiunge tra i commenti &#8220;l\u2019augurio che questo film possa diventare testimonianza ed esempio non soltanto per le generazioni future, ma anche \u2013 e soprattutto \u2013 per quelle attuali&#8221;.<\/p>\n<p>Infine, il primo premio per il miglior documentario va al cortometraggio &#8220;When the shallows fly away&#8221; di Pins Sebastien &#8220;per avere portato sullo schermo un tema di grande profondit\u00e0 umana e di attualit\u00e0, mescolando con intelligenza i linguaggi del documentario e della finzione. Unendo le riprese dal vero a una sceneggiatura costruita sulla voce fuori campo, l\u2019autore riesce a costruire un racconto emozionante e coinvolgente, creando una genuina empatia con lo spettatore&#8221;.<\/p>\n<p>In parallelo, la giuria speciale degli studenti del corso di regia cinematografica del DAMS, composta da Martina Rocca, Chiara Rossi, Simone Orlando, Rebecca Perrin, Edoardo Poveromo ed Elena Venturiero, ha decretato una menzione speciale per ogni categoria, confermando &#8220;Graziano e la giraffa&#8221; come miglior cortometraggio di animazione. Ad Alexandre Isabelle viene assegnata la menzione speciale DAMS per la fiction, con &#8220;Therefore, Socrate is mortal&#8221;, che si aggiudica, quindi, la seconda menzione speciale in questa edizione, infine la menzione speciale DAMS per la sezione Documentario va a &#8220;Voice above water&#8221; di Dana Frankoff.<\/p>\n<p>\u201cQuella che si \u00e8 appena conclusa \u00e8 stata un\u2019edizione molto importante per Ortometraggi Film Festival, un nuovo inizio che, come in un processo ciclico, conserva ci\u00f2 che di positivo \u00e8 stato costruito in questi anni. \u00c8 quello che abbiamo voluto rappresentare scegliendo di riprendere e rielaborare il logo della nostra prima edizione e costruendo un programma nuovo, che mettesse le proiezioni al centro di appuntamenti diversi, per parlare di sostenibilit\u00e0 sotto punti di vista differenti ma tutti connessi. Sono stati momenti in cui noi e il pubblico ci siamo messi in discussione, perch\u00e8 anche dalla crisi possono nascere cambiamenti ed evoluzioni radicali e positive\u201d, la dichiarazione conclusiva dell\u2019associazione Gomboc.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si \u00e8 tenuta a Orti Generali dal 16 al 18 settembre la quinta edizione di Ortometraggi Film Festival: un\u2019edizione che si propone, con il suo titolo \u201cScenari futuri da un presente incerto\u201d, di ampliare il racconto della relazione tra essere umano e natura &#8211; tema cardine del festival &#8211; proponendo una riflessione a 360 gradi &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Tutti i premi dell&#8217;edizione 2022 di Ortometraggi Film Festival&#8221;<\/span><\/a><\/p>\n","protected":false},"author":34,"featured_media":5550,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[1400],"class_list":["post-5549","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-festival","tag-ortometraggi-film-festival"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tutti i premi dell&#039;edizione 2022 di Ortometraggi Film Festival - Cabiria<\/title>\n<meta name=\"description\" content=\"ortometraggi film festival\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tutti i premi dell&#039;edizione 2022 di Ortometraggi Film Festival - Cabiria\" \/>\n<meta property=\"og:description\" content=\"ortometraggi film festival\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-22T06:36:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2022\/09\/Ortometraggi-Film-Festival.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Tutti i premi dell&#8217;edizione 2022 di Ortometraggi Film Festival\",\"datePublished\":\"2022-09-22T06:36:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\\\/\"},\"wordCount\":926,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2022\\\/09\\\/Ortometraggi-Film-Festival.jpg\",\"keywords\":[\"ortometraggi film festival\"],\"articleSection\":[\"festival\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\\\/\",\"name\":\"Tutti i premi dell'edizione 2022 di Ortometraggi Film Festival - Cabiria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2022\\\/09\\\/Ortometraggi-Film-Festival.jpg\",\"datePublished\":\"2022-09-22T06:36:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"ortometraggi film festival\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2022\\\/09\\\/Ortometraggi-Film-Festival.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2022\\\/09\\\/Ortometraggi-Film-Festival.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tutti i premi dell&#8217;edizione 2022 di Ortometraggi Film Festival\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tutti i premi dell'edizione 2022 di Ortometraggi Film Festival - Cabiria","description":"ortometraggi film festival","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cabiria\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\/","og_locale":"it_IT","og_type":"article","og_title":"Tutti i premi dell'edizione 2022 di Ortometraggi Film Festival - Cabiria","og_description":"ortometraggi film festival","og_url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2022-09-22T06:36:43+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2022\/09\/Ortometraggi-Film-Festival.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Tutti i premi dell&#8217;edizione 2022 di Ortometraggi Film Festival","datePublished":"2022-09-22T06:36:43+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\/"},"wordCount":926,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2022\/09\/Ortometraggi-Film-Festival.jpg","keywords":["ortometraggi film festival"],"articleSection":["festival"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\/","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\/","name":"Tutti i premi dell'edizione 2022 di Ortometraggi Film Festival - Cabiria","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2022\/09\/Ortometraggi-Film-Festival.jpg","datePublished":"2022-09-22T06:36:43+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"ortometraggi film festival","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2022\/09\/Ortometraggi-Film-Festival.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2022\/09\/Ortometraggi-Film-Festival.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/tutti-i-premi-delledizione-2022-di-ortometraggi-film-festival\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"Tutti i premi dell&#8217;edizione 2022 di Ortometraggi Film Festival"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/5549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=5549"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/5549\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/5550"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=5549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=5549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=5549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}