{"id":5340,"date":"2021-07-02T09:39:11","date_gmt":"2021-07-02T09:39:11","guid":{"rendered":"http:\/\/web.quotidianopiemontese.it\/cabiria\/?p=5340"},"modified":"2021-07-02T09:39:11","modified_gmt":"2021-07-02T09:39:11","slug":"lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\/","title":{"rendered":"Lockdown di Antonio Annunziata vince la seconda edizione di Venaria in Corto"},"content":{"rendered":"<p>Scorrono i titoli di coda sulla seconda edizione del concorso di cortometraggi \u201cVenaria in Corto\u201d, promosso da Citt\u00e0 di Venaria Reale e Factory della Creativit\u00e0 e intitolato \u201cGiovani 21.0\u201d. Quest\u2019anno, ai registi \u00e8 stato chiesto di indagare, attraverso la videocamera, il rapporto tra le giovani generazioni e la tecnologia, nell\u2019ambito della comunicazione e del web.<!--more--><\/p>\n<p>Sette i cortometraggi in concorso, proiettati nella serata conclusiva che si \u00e8 svolta gioved\u00ec 1 luglio al Teatro della Concordia. Ad assistere, nel pieno rispetto delle norme anti Covid, un pubblico di appassionati, in maggioranza giovani.<br \/>\nDiversi i temi affrontati nelle opere: dall\u2019isolamento dato dall\u2019uso e abuso degli smartphone, revenge porn e cyber bullismo, fino ad arrivare alle criticit\u00e0 emerse dal sovra utilizzo della tecnologia nel periodo del lockdown.<br \/>\nA designare i vincitori, una giuria composta dal direttore artistico Ado Hasanovic, Stefano Ughetti e Daniel Coffaro.<\/p>\n<p>Fabio Giulivi, sindaco di Venaria Reale, afferma \u00abAbbiamo creduto tantissimo in questo progetto, soprattutto perch\u00e9 unisce l\u2019arte del cortometraggio con il digitale, tema di questo evento. In particolare, da apprezzare l\u2019impegno di tanti giovani. A premiare, una giuria importante per tre premi importanti, tra cui la Menzione Citt\u00e0 di Venaria Reale\u00bb.<br \/>\nIl sindaco Fabio Giulivi ha consegnato il premio \u201cMiglior cortometraggio\u201d e un buono acquisto da 750 euro ad Antonio Annunziata, con il suo \u201cLockdown\u201d. Un\u2019opera che ha colpito per l\u2019efficacia con la quale \u00e8 riuscita a raccontare l\u2019assurdit\u00e0 della tecnologia e l\u2019isolamento a cui porta, spesso confuso con libert\u00e0.<\/p>\n<p>Ado Hasanovic, direttore artistico di Venaria in Corto \u00abComplimenti a tutti i registi che hanno partecipato a Venaria in Corto. \u00c8 bello essere in un luogo cos\u00ec significativo della citt\u00e0, il Teatro della Concordia. I cortometraggi in concorso sono tutti molto creativi e belli, hanno centrato il tema del rapporto con la tecnologia e sono diversi uno dall\u2019altro\u00bb.<\/p>\n<p>Ha consegnato il premio \u201cMenzione Citt\u00e0 di Venaria Reale\u201d e un buono acquisto da 250 euro, riservati a chi \u00e8 riuscito a valorizzare maggiormente il territorio, l\u2019assessore alle Politiche Giovanili, Paola Marchese, a Simone Fanotto e Tiziano Raffa, registi di \u201cRumore Bianco\u201d. Cortometraggio che ha reso Venaria Reale parte integrante del racconto e che ha centrato l\u2019obiettivo di rappresentare la situazione di stallo avvertita dai giovani, di fronte alle tecnologie, nel periodo della pandemia.<\/p>\n<p>Paola Marchese, assessore alle Politiche Giovanili della Citt\u00e0 di Venaria Reale<br \/>\n\u00abPer questa seconda edizione di Venaria in Corto abbiamo voluto mettere in luce il rapporto che intercorre tra i giovani e la tecnologia. Sappiamo come le tecnologie abbiano cambiato la nostra quotidianit\u00e0. Abbiamo chiesto ai giovani, quindi, di raccontare quale sia la loro visione su questa tematica\u00bb.<\/p>\n<p>Una speciale giuria composta da Vittorio Billera capo ufficio stampa Citt\u00e0 di Venaria Reale; Vittorio Pasteris di QuotidianoPiemontese.it; Gianni Giacomino de La Stampa; Andrea Trovato de Il Risveglio del Canavese; Claudio Martinelli di Torino Cronaca; Silvia Iannuzzi di QuotidianoVenaria.it; Vittorio Savoia di La Nuova Periferia; Massimiliano Sciullo di TorinoOggi.it, Venaria24.it e 24Ovest.it e Magda Bersini di ObiettivoNews.it ha votato la \u201cMenzione Stampa\u201d e un buono acquisto da 250 euro. A premiare Ludovica Lopetti e Marco Formichella con \u201cIs1dor0\u201d, il vicesindaco e assessore al Bilancio, Gianpaolo Cerrini. Il corto \u00e8 una sorta di alter ego quale chiave per riavvicinare le persone, due fratelli, in realt\u00e0 separati da un device che ne allontana gli affetti. La rivolta di una coscienza, che in fondo, \u00e8 liberata dal contrasto tra analogico (il nano da giardino) e digitale, del mondo che gira attorno allo smartphone. Realizzato con sagace maestria e ritmo, merita l&#8217;attenzione del pubblico.<\/p>\n<p>Nei prossimi giorni i cortometraggi che hanno avuto accesso alla fase finale saranno pubblicati su Venaria Tv www.venaria.tv e sui social della Citt\u00e0 di Venaria Reale. Il tutto, in attesa della terza edizione di Venaria in Corto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Scorrono i titoli di coda sulla seconda edizione del concorso di cortometraggi \u201cVenaria in Corto\u201d, promosso da Citt\u00e0 di Venaria Reale e Factory della Creativit\u00e0 e intitolato \u201cGiovani 21.0\u201d. Quest\u2019anno, ai registi \u00e8 stato chiesto di indagare, attraverso la videocamera, il rapporto tra le giovani generazioni e la tecnologia, nell\u2019ambito della comunicazione e del web.<\/p>\n","protected":false},"author":34,"featured_media":5341,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[1405],"class_list":["post-5340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-festival","tag-venaria-in-corto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lockdown di Antonio Annunziata vince la seconda edizione di Venaria in Corto - Cabiria<\/title>\n<meta name=\"description\" content=\"venaria in corto\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/cabiria\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lockdown di Antonio Annunziata vince la seconda edizione di Venaria in Corto - Cabiria\" \/>\n<meta property=\"og:description\" content=\"venaria in corto\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/cabiria\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-02T09:39:11+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2021\/07\/Menzione-Citt\u00e0-di-Venaria-Reale-Da-sx-Raffa-e-Fanotto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1151\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Lockdown di Antonio Annunziata vince la seconda edizione di Venaria in Corto\",\"datePublished\":\"2021-07-02T09:39:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\\\/\"},\"wordCount\":641,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2021\\\/07\\\/Menzione-Citt\u00e0-di-Venaria-Reale-Da-sx-Raffa-e-Fanotto.jpg\",\"keywords\":[\"venaria in corto\"],\"articleSection\":[\"festival\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\\\/\",\"name\":\"Lockdown di Antonio Annunziata vince la seconda edizione di Venaria in Corto - Cabiria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2021\\\/07\\\/Menzione-Citt\u00e0-di-Venaria-Reale-Da-sx-Raffa-e-Fanotto.jpg\",\"datePublished\":\"2021-07-02T09:39:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"venaria in corto\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2021\\\/07\\\/Menzione-Citt\u00e0-di-Venaria-Reale-Da-sx-Raffa-e-Fanotto.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2021\\\/07\\\/Menzione-Citt\u00e0-di-Venaria-Reale-Da-sx-Raffa-e-Fanotto.jpg\",\"width\":1151,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lockdown di Antonio Annunziata vince la seconda edizione di Venaria in Corto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lockdown di Antonio Annunziata vince la seconda edizione di Venaria in Corto - Cabiria","description":"venaria in corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/cabiria\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\/","og_locale":"it_IT","og_type":"article","og_title":"Lockdown di Antonio Annunziata vince la seconda edizione di Venaria in Corto - Cabiria","og_description":"venaria in corto","og_url":"http:\/\/web.quotidianopiemontese.it\/cabiria\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2021-07-02T09:39:11+00:00","og_image":[{"width":1151,"height":768,"url":"http:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2021\/07\/Menzione-Citt\u00e0-di-Venaria-Reale-Da-sx-Raffa-e-Fanotto.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Lockdown di Antonio Annunziata vince la seconda edizione di Venaria in Corto","datePublished":"2021-07-02T09:39:11+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\/"},"wordCount":641,"commentCount":0,"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2021\/07\/Menzione-Citt\u00e0-di-Venaria-Reale-Da-sx-Raffa-e-Fanotto.jpg","keywords":["venaria in corto"],"articleSection":["festival"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/cabiria\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\/","url":"http:\/\/web.quotidianopiemontese.it\/cabiria\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\/","name":"Lockdown di Antonio Annunziata vince la seconda edizione di Venaria in Corto - Cabiria","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\/#primaryimage"},"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2021\/07\/Menzione-Citt\u00e0-di-Venaria-Reale-Da-sx-Raffa-e-Fanotto.jpg","datePublished":"2021-07-02T09:39:11+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"venaria in corto","breadcrumb":{"@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/cabiria\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2021\/07\/Menzione-Citt\u00e0-di-Venaria-Reale-Da-sx-Raffa-e-Fanotto.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2021\/07\/Menzione-Citt\u00e0-di-Venaria-Reale-Da-sx-Raffa-e-Fanotto.jpg","width":1151,"height":768},{"@type":"BreadcrumbList","@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/lockdown-antonio-annunziata-vince-la-seconda-edizione-venaria-corto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"Lockdown di Antonio Annunziata vince la seconda edizione di Venaria in Corto"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/5340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=5340"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/5340\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/5341"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=5340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=5340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=5340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}