{"id":5284,"date":"2021-05-04T06:30:26","date_gmt":"2021-05-04T06:30:26","guid":{"rendered":"http:\/\/web.quotidianopiemontese.it\/cabiria\/?p=5284"},"modified":"2021-05-04T06:30:26","modified_gmt":"2021-05-04T06:30:26","slug":"tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\/","title":{"rendered":"Il TOHorror Fantastic Film Fest recupera i titoli dell&#8217;edizione saltata"},"content":{"rendered":"<p>In piena fase di selezione dei contenuti per la 21\u00b0 edizione che si terr\u00e0 in presenza dal 19 al 24 ottobre 2021, la riapertura delle sale d\u00e0 finalmente al TOHorror Fantastic Film Fest la possibilit\u00e0 di proiettare al cinema i titoli che avrebbero dovuto comporre la line-up della 20\u00b0 edizione, l\u2019edizione-fantasma cancellata lo scorso autunno per la pandemia e che avrebbe portato sugli schermi del Cinema Massimo e del Cinema Ambrosio di Torino pi\u00f9 di 60 film fra cortometraggi e lungometraggi.<!--more--><\/p>\n<p>Se le condizioni lo permetteranno, da qui al prossimo ottobre il TOHFFF terr\u00e0 compagnia agli spettatori con un fitto programma mensile lungo il quale tutti, o quasi, i titoli perduti saranno recuperati dal vivo. A rompere il ghiaccio di penser\u00e0 La cosa di John Carpenter, il 12 maggio alle 19.45, al Cinema Ambrosio, in versione originale sottotitolata. Un cult assoluto con lo spessore adatto a far ripartire gli ingranaggi di una macchina che non vedeva l\u2019ora di rimettersi in moto. Un\u2019occasione per ammirare ancora una volta, ma stavolta su grande schermo, la maestria cinematografica di John Carpenter, la ruvida bravura di Kurt Russell, gli effetti speciali strepitosi di Rob Bottin e le musiche di Ennio Morricone, in un moderno classico della fantascienza che ha fatto scuola. Si prosegue il 22 maggio, con un doppio appuntamento.<\/p>\n<p>Al Cinema Massimo andr\u00e0 in scena un double feature con due film del concorso lungometraggi del TOHFFF 2020. Il pomeriggio si apre alle 17.30 con AV The Hunt di Emre Akay, un thriller di grande tensione e attualit\u00e0 politica in cui una donna si trova a dover fuggire dalla propria stessa famiglia che la vuole uccidere. La colpa? Aver tradito il marito poliziotto, in una Turchia (in un mondo) ancora governato da sistemi di potere sessisti e patriarcali. A seguire, alle 20.00, l\u2019impressionante Roh di Emir Ezwan, un folk horror parente prossimo del The Witch di Robert Eggers. Anche in questo caso infatti, una famiglia lontana dalla civilt\u00e0 deve vedersela con presenze demoniache ingannevoli, che agiscono celate dalla natura incontaminata della giungla malese. Incluso da molte riviste di settore nelle classifiche dei film asiatici pi\u00f9 belli del 2020, \u00e8 stato il candidato della Malesia agli Oscar 2021.<\/p>\n<p>Massimiliano Supporta, direttore del Festival: \u201cIl cinema fantastico e i suoi autori indipendenti intorno al mondo stanno reagendo a questo periodo complicato con grande determinazione. Mancano due mesi al termine della nostra call for entries TOHorror 2021 e abbiamo gi\u00e0 ricevuto pi\u00f9 opere, da 40 paesi diversi, di quante di solito arrivino nell\u2019intero periodo di iscrizione. Questa fase di lavorazione pre-festival \u00e8 la pi\u00f9 stimolante, perch\u00e9 possiamo toccare con mano la passione e la creativit\u00e0 dei filmmakers, scoprendo punti di vista inediti non solo sul cinema di genere e i suoi linguaggi, ma anche sull\u2019attualit\u00e0 e, soprattutto, sul futuro. Nel frattempo, siamo impazienti di proporre al pubblico in sala i film in sospeso della scorsa edizione\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In piena fase di selezione dei contenuti per la 21\u00b0 edizione che si terr\u00e0 in presenza dal 19 al 24 ottobre 2021, la riapertura delle sale d\u00e0 finalmente al TOHorror Fantastic Film Fest la possibilit\u00e0 di proiettare al cinema i titoli che avrebbero dovuto comporre la line-up della 20\u00b0 edizione, l\u2019edizione-fantasma cancellata lo scorso autunno &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Il TOHorror Fantastic Film Fest recupera i titoli dell&#8217;edizione saltata&#8221;<\/span><\/a><\/p>\n","protected":false},"author":34,"featured_media":5285,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[108],"class_list":["post-5284","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi","tag-tohorror-film-fest"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il TOHorror Fantastic Film Fest recupera i titoli dell&#039;edizione saltata - Cabiria<\/title>\n<meta name=\"description\" content=\"ToHorror Film Fest\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il TOHorror Fantastic Film Fest recupera i titoli dell&#039;edizione saltata - Cabiria\" \/>\n<meta property=\"og:description\" content=\"ToHorror Film Fest\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-04T06:30:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2021\/05\/Roh.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"527\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Il TOHorror Fantastic Film Fest recupera i titoli dell&#8217;edizione saltata\",\"datePublished\":\"2021-05-04T06:30:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\\\/\"},\"wordCount\":478,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2021\\\/05\\\/Roh.jpg\",\"keywords\":[\"ToHorror Film Fest\"],\"articleSection\":[\"eventi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\\\/\",\"name\":\"Il TOHorror Fantastic Film Fest recupera i titoli dell'edizione saltata - Cabiria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2021\\\/05\\\/Roh.jpg\",\"datePublished\":\"2021-05-04T06:30:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"ToHorror Film Fest\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2021\\\/05\\\/Roh.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2021\\\/05\\\/Roh.jpg\",\"width\":1000,\"height\":527},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il TOHorror Fantastic Film Fest recupera i titoli dell&#8217;edizione saltata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il TOHorror Fantastic Film Fest recupera i titoli dell'edizione saltata - Cabiria","description":"ToHorror Film Fest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cabiria\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\/","og_locale":"it_IT","og_type":"article","og_title":"Il TOHorror Fantastic Film Fest recupera i titoli dell'edizione saltata - Cabiria","og_description":"ToHorror Film Fest","og_url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2021-05-04T06:30:26+00:00","og_image":[{"width":1000,"height":527,"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2021\/05\/Roh.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Il TOHorror Fantastic Film Fest recupera i titoli dell&#8217;edizione saltata","datePublished":"2021-05-04T06:30:26+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\/"},"wordCount":478,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2021\/05\/Roh.jpg","keywords":["ToHorror Film Fest"],"articleSection":["eventi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\/","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\/","name":"Il TOHorror Fantastic Film Fest recupera i titoli dell'edizione saltata - Cabiria","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2021\/05\/Roh.jpg","datePublished":"2021-05-04T06:30:26+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"ToHorror Film Fest","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2021\/05\/Roh.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2021\/05\/Roh.jpg","width":1000,"height":527},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/tohorror-fantastic-film-fest-recupera-titoli-delledizione-saltata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"Il TOHorror Fantastic Film Fest recupera i titoli dell&#8217;edizione saltata"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/5284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=5284"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/5284\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/5285"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=5284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=5284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=5284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}