{"id":5189,"date":"2020-12-21T08:08:57","date_gmt":"2020-12-21T08:08:57","guid":{"rendered":"http:\/\/web.quotidianopiemontese.it\/cabiria\/?p=5189"},"modified":"2020-12-21T08:08:57","modified_gmt":"2020-12-21T08:08:57","slug":"parte-crowdfunding-la-post-produzione-del-film-torinese-vaso","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\/","title":{"rendered":"Parte il crowdfunding per la post produzione del film torinese Il vaso"},"content":{"rendered":"<p>\u00c8 online la campagna di crowdfunding per finanziare la post-produzione de Il Vaso, lungometraggio d&#8217;esordio del regista torinese Michael Bertuol. Un progetto di natura sperimentale e indipendente, nato nel 2019 con l&#8217;obiettivo di dimostrare che c&#8217;\u00e8 spazio per un nuovo tipo di cinema, svincolato dalle grandi produzioni, realizzabile con un budget molto inferiore, ma non per questo meno valido.<!--more--><\/p>\n<p>Ne Il Vaso un aspirante attore di mezza et\u00e0, ormai stanco e disilluso, ha un&#8217;ultima occasione di raccogliere e riunire i cocci della sua vita. L&#8217;uomo per\u00f2 dovr\u00e0 prima fare i conti con il suo disincanto, i fantasmi del passato, un lavoro alienante e dei rapporti d&#8217;amicizia logori.<\/p>\n<p>Il film, completamente autoprodotto, \u00e8 stato girato interamente a Torino e provincia, con maestranze del territorio, e ha avuto, sin dai primi passi, il supporto logistico della Film Commission Torino Piemonte.<\/p>\n<p>Il primo ciak de Il Vaso risale a ottobre 2019 e oggi, 14 mesi pi\u00f9 tardi, durante una pandemia, dopo due lockdown, il duro lavoro svolto sta finalmente raggiungendo la fine del suo percorso produttivo.<\/p>\n<p>Il progetto \u00e8 stato messo a dura prova durante questi difficili mesi di emergenza sanitaria: per questo motivo il team ha attivato <a href=\"https:\/\/www.produzionidalbasso.com\/project\/il-vaso\/\">una campagna di crowdfunding sulla piattaforma produzionidalbasso.com<\/a> per finanziare la fase di post-produzione (sound design, colonna sonora originale, color correction, etc.), senza la quale il film non potr\u00e0 vedere la luce.<\/p>\n<p>Sulla pagina \u00e8 possibile donare da 5\u20ac in su e ricevere ricompense diverse in base all&#8217;importo della donazione: dalla locandina alla colonna sonora, fino al ringraziamento nei credits e nei titoli di coda del film.<\/p>\n<p><iframe loading=\"lazy\" title=\"Il Vaso - Trailer (4K)\" src=\"https:\/\/player.vimeo.com\/video\/490435356?dnt=1&amp;app_id=122963\" width=\"840\" height=\"354\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c8 online la campagna di crowdfunding per finanziare la post-produzione de Il Vaso, lungometraggio d&#8217;esordio del regista torinese Michael Bertuol. Un progetto di natura sperimentale e indipendente, nato nel 2019 con l&#8217;obiettivo di dimostrare che c&#8217;\u00e8 spazio per un nuovo tipo di cinema, svincolato dalle grandi produzioni, realizzabile con un budget molto inferiore, ma non &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Parte il crowdfunding per la post produzione del film torinese Il vaso&#8221;<\/span><\/a><\/p>\n","protected":false},"author":34,"featured_media":5190,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":["post-5189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-set"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Parte il crowdfunding per la post produzione del film torinese Il vaso - Cabiria<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parte il crowdfunding per la post produzione del film torinese Il vaso - Cabiria\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-21T08:08:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2020\/12\/ilvaso.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Parte il crowdfunding per la post produzione del film torinese Il vaso\",\"datePublished\":\"2020-12-21T08:08:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\\\/\"},\"wordCount\":275,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2020\\\/12\\\/ilvaso.jpg\",\"articleSection\":[\"set\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\\\/\",\"name\":\"Parte il crowdfunding per la post produzione del film torinese Il vaso - Cabiria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2020\\\/12\\\/ilvaso.jpg\",\"datePublished\":\"2020-12-21T08:08:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2020\\\/12\\\/ilvaso.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2020\\\/12\\\/ilvaso.jpg\",\"width\":1920,\"height\":810},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parte il crowdfunding per la post produzione del film torinese Il vaso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parte il crowdfunding per la post produzione del film torinese Il vaso - Cabiria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cabiria\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\/","og_locale":"it_IT","og_type":"article","og_title":"Parte il crowdfunding per la post produzione del film torinese Il vaso - Cabiria","og_url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2020-12-21T08:08:57+00:00","og_image":[{"width":1920,"height":810,"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2020\/12\/ilvaso.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Parte il crowdfunding per la post produzione del film torinese Il vaso","datePublished":"2020-12-21T08:08:57+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\/"},"wordCount":275,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2020\/12\/ilvaso.jpg","articleSection":["set"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\/","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\/","name":"Parte il crowdfunding per la post produzione del film torinese Il vaso - Cabiria","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2020\/12\/ilvaso.jpg","datePublished":"2020-12-21T08:08:57+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2020\/12\/ilvaso.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2020\/12\/ilvaso.jpg","width":1920,"height":810},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/parte-crowdfunding-la-post-produzione-del-film-torinese-vaso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"Parte il crowdfunding per la post produzione del film torinese Il vaso"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/5189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=5189"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/5189\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/5190"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=5189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=5189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=5189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}