{"id":5169,"date":"2020-11-12T08:25:40","date_gmt":"2020-11-12T08:25:40","guid":{"rendered":"http:\/\/web.quotidianopiemontese.it\/cabiria\/?p=5169"},"modified":"2020-11-12T08:25:40","modified_gmt":"2020-11-12T08:25:40","slug":"premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\/","title":{"rendered":"Il Premio Maria Adriana Prolo alla carriera 2020 a Cecilia Mangini"},"content":{"rendered":"<p>In occasione del 38\u00b0 Torino Film Festival, l\u2019Associazione Museo Nazionale del Cinema (AMNC) ha deciso il conferimento del PREMIO MARIA ADRIANA PROLO ALLA CARRIERA 2020 a Cecilia Mangini, fotografa, documentarista, critico cinematografico, giornalista e sceneggiatrice.<!--more--><\/p>\n<p>Il Premio sar\u00e0 consegnato nell&#8217;ambito di una cerimonia che sar\u00e0 ospitata sulla piattaforma online dedicata al TFF nel pomeriggio di mercoled\u00ec 25 novembre. Alla premiazione seguir\u00e0 la proiezione del film Due scatole dimenticate \u2013 Viaggio in Vietnam (2020, 57&#8242;) di Cecilia Mangini e Paolo Pisanelli. Il film sar\u00e0 visibile per 48 ore su Mymovies a partire dalle ore 14.00 di marted\u00ec 24 novembre.<\/p>\n<p>Intitolato a Maria Adriana Prolo, fondatrice del Museo Nazionale del Cinema, il premio \u00e8 un riconoscimento assegnato a una personalit\u00e0 del mondo del cinema che si \u00e8 particolarmente distinta nel panorama italiano. In passato, il premio \u00e8 stato conferito ai registi Giuseppe Bertolucci, Marco Bellocchio, Ugo Gregoretti, Giuliano Montaldo, Massimo Scaglione, Daniele Segre, Bruno Bozzetto, Lorenza Mazzetti, Costa-Gavras, David Grieco, agli attori e attrici Piera Degli Esposti, Lucia Bos\u00e8, Ottavia Piccolo, Roberto Herlitzka, Elio Pandolfi, al compositore Manuel De Sica, allo sceneggiatore Giorgio Arlorio, al film-maker, artista e operaio Pietro Perotti, all&#8217;esercente e storico del cinema Lorenzo Ventavoli.<\/p>\n<p>La diciannovesima edizione del premio ha come protagonista Cecilia Mangini: nata a Mola di Bari nel 1927, fin dall\u2019inizio del suo lavoro porta uno sguardo impegnato, attento e personale sugli individui e sulla societ\u00e0, dedicando un\u2019attenzione particolare ai temi della marginalit\u00e0, dell\u2019immigrazione e delle ingiustizie sociali. Prima donna a girare documentari nel dopoguerra, sceneggiatrice di alcuni lungometraggi e di pi\u00f9 di quaranta cortometraggi, in gran parte realizzati insieme al marito Lino Del Fra, ha esplorato con la sua macchina da presa l\u2019Italia dalla fine degli anni Cinquanta fino ai primi anni Settanta, spesso volgendo lo sguardo al Sud Italia e alla Puglia, per cercare i rituali di una cultura antica che scompariva travolta dalle veloci trasformazioni imposte dal boom economico. Nel 2009 Cecilia ha ricevuto a Firenze la Medaglia del Presidente della Repubblica, \u00abper aver trasmesso alle generazioni future, attraverso la sua attivit\u00e0 di cineasta documentarista, alcune delle pi\u00f9 belle immagini dell&#8217;Italia degli anni \u201850 e \u201860\u00bb. Nell\u2019ultimo decennio le sono state dedicate numerose mostre fotografiche: nel 2008 a Trieste; nel 2010 in Francia, a Cr\u00e9teil nel corso della retrospettiva che le ha dedicato il 33\u00b0 Festival de Films des Femmes; nel 2011 a Barcellona nel corso della sua retrospettiva al Festival de Dones; nel 2015 a Lipari, nel 2016 a Bari, nell\u2019ambito del BIF&amp;ST e nei Cineporti di Puglia (Lecce e Foggia), nel 2017 al Museo Nazionale delle Arti e Tradizioni Popolari a Roma, nel 2017 la mostra CECILIA MANGINI \u2013 visioni e passioni, a cura di Claudio Domini e Paolo Pisanelli, realizzata da Big Sur, Erratacorrige, Cinema del reale, OfficinaVisioni. Dal 2013 \u00e8 tornata alla regia grazie al coinvolgimento della regista Mariangela Barbanente con la quale ha realizzato il documentario In viaggio con Cecilia. Recentemente Cecilia Mangini ha inoltre stretto un sodalizio artistico con il regista Paolo Pisanelli, con il quale ha realizzato i film: Il Vietnam sera libre (2018), Due scatole dimenticate (2020), e ha in lavorazione un nuovo film dedicato a Grazia Deledda, dal titolo Grazia Deledda, la rivoluzionaria.<\/p>\n<p>Come di consueto il numero di Mondo Niovo 18-24 ft\/s, la rivista dell&#8217;AMNC diretta da Caterina Taricano, sar\u00e0 interamente dedicato alla destinataria del premio, Cecilia Mangini. Curato da Micaela Veronesi con la collaborazione di Maria Giulia Petrini, il numero 105 di Mondo Niovo 18-24 ft\/s sar\u00e0 presentato in occasione della consegna del Premio Maria Adriana Prolo alla carriera e ospiter\u00e0 una lunga intervista alla regista che ci racconta il suo lavoro, la sua militanza nei circoli del cinema, la sua attenzione agli ultimi, alle periferie, al Sud, del lavoro con Pier Paolo Pasolini e Lino Del Fra e di cosa ha significato fare cinema documentario ed essere donna in un ambiente fortemente maschile. Il numero raccoglie anche numerose testimonianze di amici e collaboratori tra cui Mariangela Barbanente, Gabriella Gallozzi, Claudio Domini, Davide Barletti, Lorenzo Conte e Paolo Pisanelli, un apparato storico-critico sul lavoro della documentarista e moltissime immagini che raccontano anche il suo interessante lavoro come fotografa, e inoltre saggi e contributi di Silvia Nugara, Anna Masecchia, Daniela Persico e Gianluca Sciannameo.<\/p>\n<p>Dopo la premiazione sar\u00e0 proiettato Due scatole dimenticate \u2013 Viaggio in Vietnam di Cecilia Mangini e Paolo Pisanelli (Italia 2020, 57&#8242;, DCP, col.), una produzione OfficinaVisioni in collaborazione con Rai Cinema con il sostegno di Fondazione Sardegna Film Commission con il supporto dell&#8217;Istituto Superiore Regionale Etnografico, l&#8217;Archivio Audiovisivo del Movimento Operaio e Democratico, l&#8217;Archivio Cinema del reale, Erratacorrige e Big Sur; la distribuzione \u00e8 curata da Kin\u00e9.<\/p>\n<p>Dimenticate per pi\u00f9 di cinquant\u2019anni in un vecchio scaffale sono state inaspettatamente ritrovate due scatole da scarpe piene di negativi fotografici 6\u00d76. Nel 1965-66 Lino Del Fra e Cecilia Mangini hanno vissuto per tre mesi nel Vietnam del Nord in guerra con gli Stati Uniti effettuando i sopralluoghi per un film documentario sulla lotta di quel popolo deciso a conquistare l\u2019unit\u00e0 e l\u2019indipendenza. Dalla frontiera con la Cina fino al confine con il Sud, formalmente filo-statunitense e occupato militarmente dagli americani, Lino e Cecilia hanno esplorato le citt\u00e0, i porti, i paesi, le risaie, i fronti di guerra. Nel tentativo di piegarla, al Sud gli americani incendiavano le foreste con il napalm e al Nord avevano iniziato a fare terra bruciata con i bombardamenti a tappeto di giorno in giorno sempre pi\u00f9 vicini alla capitale. Per l\u2019assenza di rifugi antiaerei veri e propri Lino e Cecilia sono stati rimpatriati insieme alle tante delegazioni internazionali e a tutti gli stranieri presenti ad Hanoi. Quelle bombe americane interruppero la lavorazione del film. Durante tutti i sopralluoghi Cecilia Mangini aveva realizzato un grande reportage fotografico, in gran parte ancora inedito. Quella guerra, quella resistenza, quel popolo in armi rivive attraverso foto, scritti, ricordi e vuoti di memoria.<\/p>\n<p>Il Premio Maria Adriana Prolo \u00e8 un\u2019iniziativa curata dall&#8217;Associazione Museo Nazionale del Cinema nell&#8217;ambito del progetto Nuovo Cinema Piemonte 2020 sostenuto dal MiBACT, Regione Piemonte, Fondazione CRT e NovaCoop.<\/p>\n<p>(Foto di Paolo Pisanelli)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In occasione del 38\u00b0 Torino Film Festival, l\u2019Associazione Museo Nazionale del Cinema (AMNC) ha deciso il conferimento del PREMIO MARIA ADRIANA PROLO ALLA CARRIERA 2020 a Cecilia Mangini, fotografa, documentarista, critico cinematografico, giornalista e sceneggiatrice.<\/p>\n","protected":false},"author":34,"featured_media":5170,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,24],"tags":[],"class_list":["post-5169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi","category-festival"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il Premio Maria Adriana Prolo alla carriera 2020 a Cecilia Mangini - Cabiria<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Premio Maria Adriana Prolo alla carriera 2020 a Cecilia Mangini - Cabiria\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-12T08:25:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2020\/11\/Cecilia-Mangini_foto-di-Paolo-Pisanelli_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2953\" \/>\n\t<meta property=\"og:image:height\" content=\"2215\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Il Premio Maria Adriana Prolo alla carriera 2020 a Cecilia Mangini\",\"datePublished\":\"2020-11-12T08:25:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\\\/\"},\"wordCount\":1004,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2020\\\/11\\\/Cecilia-Mangini_foto-di-Paolo-Pisanelli_2.jpg\",\"articleSection\":[\"eventi\",\"festival\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\\\/\",\"name\":\"Il Premio Maria Adriana Prolo alla carriera 2020 a Cecilia Mangini - Cabiria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2020\\\/11\\\/Cecilia-Mangini_foto-di-Paolo-Pisanelli_2.jpg\",\"datePublished\":\"2020-11-12T08:25:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2020\\\/11\\\/Cecilia-Mangini_foto-di-Paolo-Pisanelli_2.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2020\\\/11\\\/Cecilia-Mangini_foto-di-Paolo-Pisanelli_2.jpg\",\"width\":2953,\"height\":2215},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Premio Maria Adriana Prolo alla carriera 2020 a Cecilia Mangini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Premio Maria Adriana Prolo alla carriera 2020 a Cecilia Mangini - Cabiria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cabiria\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\/","og_locale":"it_IT","og_type":"article","og_title":"Il Premio Maria Adriana Prolo alla carriera 2020 a Cecilia Mangini - Cabiria","og_url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2020-11-12T08:25:40+00:00","og_image":[{"width":2953,"height":2215,"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2020\/11\/Cecilia-Mangini_foto-di-Paolo-Pisanelli_2.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Il Premio Maria Adriana Prolo alla carriera 2020 a Cecilia Mangini","datePublished":"2020-11-12T08:25:40+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\/"},"wordCount":1004,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2020\/11\/Cecilia-Mangini_foto-di-Paolo-Pisanelli_2.jpg","articleSection":["eventi","festival"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\/","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\/","name":"Il Premio Maria Adriana Prolo alla carriera 2020 a Cecilia Mangini - Cabiria","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2020\/11\/Cecilia-Mangini_foto-di-Paolo-Pisanelli_2.jpg","datePublished":"2020-11-12T08:25:40+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2020\/11\/Cecilia-Mangini_foto-di-Paolo-Pisanelli_2.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2020\/11\/Cecilia-Mangini_foto-di-Paolo-Pisanelli_2.jpg","width":2953,"height":2215},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/premio-maria-adriana-prolo-alla-carriera-2020-cecilia-mangini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"Il Premio Maria Adriana Prolo alla carriera 2020 a Cecilia Mangini"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/5169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=5169"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/5169\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/5170"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=5169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=5169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=5169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}