{"id":4966,"date":"2020-02-17T07:56:39","date_gmt":"2020-02-17T07:56:39","guid":{"rendered":"http:\/\/web.quotidianopiemontese.it\/cabiria\/?p=4966"},"modified":"2020-02-17T07:56:39","modified_gmt":"2020-02-17T07:56:39","slug":"casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\/","title":{"rendered":"Casting per ruoli vari a Torino per 7 cortometraggi della scuola Holden"},"content":{"rendered":"<p>Gli studenti dell&#8217;ultimo anno del percorso formativo di College Cinema della Scuola Holden ricercano attori e attrici, preferibilmente domiciliati nel territorio piemontese, per 7 cortometraggi.<!--more--><\/p>\n<p>Le riprese avranno luogo in Torino e dintorni nel periodo Marzo\/Aprile 2020.<\/p>\n<p>I provini si svolgeranno, previo appuntamento, presso la Sala Casting di via Cagliari 40\/e (TO) con la supervisione della Casting Luana Velliscig, nella settimana dal 24 al 27 febbraio.<\/p>\n<p>Tutti i progetti verranno proiettati alla fine dell\u2019anno scolastico presso la Scuola Holden in presenza di produttori e distributori italiani e stranieri.<\/p>\n<p>E\u2019 previsto rimborso spese e\/o eventuale retribuzione.<\/p>\n<p>********************<\/p>\n<p>Per il cortometraggio Una Cena Insieme a Te si cercano le seguenti figure:<\/p>\n<p>&#8211; attrice et\u00e0 scenica 25-30 anni, longilinea e di bell\u2019aspetto. Sono richieste doti canore e di ballo. Protagonista.<\/p>\n<p>&#8211; anziana, attrice et\u00e0 scenica 50-60 anni. Protagonista.<\/p>\n<p>&#8211; attore et\u00e0 scenica 30-35 anni, costituzione robusta. Ruolo secondario.<\/p>\n<p>Gli interessati potranno inviare due \/ tre foto, curriculum vitae o breve presentazione, eventuale showreel e contatti telefonici via mail a castingunacenainsiemeate@gmail.com entro il 24 febbraio 2020.<\/p>\n<p>********************<\/p>\n<p>Per il cortometraggio Tierra si cercano le seguenti figure:<\/p>\n<p>&#8211; attore et\u00e0 scenica compresa tra i 30 e i 35 anni, aspetto ordinario (se possibile senza alcun segno particolare sul volto), dall\u2019aspetto gradevole e simpatico, abbastanza magro e preferibilmente con capelli castani. E\u2019 indispensabile che i candidati abbiano una barba folta ed essere disponibili a tagliarla durante le riprese. Protagonista.<\/p>\n<p>Gli interessati potranno inviare due \/ tre foto, curriculum vitae o breve presentazione, eventuale showreel e contatti telefonici via mail a castingtierra@gmail.com entro il 22 febbraio 2020.<\/p>\n<p>********************<\/p>\n<p>Per il cortometraggio Il Mostro si cercano le seguenti figure:<\/p>\n<p>&#8211; attore et\u00e0 scenica di 50 anni, uomo di bell\u2019aspetto ma non pi\u00f9 nel fiore degli anni. Protagonista.<\/p>\n<p>&#8211; bambina di 10 anni dai lineamenti graziosi, quasi angelici. Protagonista.<\/p>\n<p>&#8211; attore et\u00e0 compresa tra i 20 e i 50 anni, corporatura esile, altezza minima 190cm per interpretare l\u2019antagonista. Ruolo secondario.<\/p>\n<p>&#8211; bambina di 10 anni, la figlia del protagonista. Dall\u2019aspetto delicato ed amichevole. Ruolo secondario.<\/p>\n<p>&#8211; attrice et\u00e0 scenica 40 anni, una donna elegante. Ruolo secondario.<\/p>\n<p>&#8211; attore et\u00e0 scenica di 40 anni. Ruolo secondario.<\/p>\n<p>Gli interessati potranno inviare due \/ tre foto, curriculum vitae o breve presentazione, eventuale showreel e contatti telefonici via mail a cortometraggio.ilmostro@gmail.com entro il 23 febbraio 2020.<\/p>\n<p>********************<\/p>\n<p>Per il cortometraggio Athena si cercano leseguenti figure:<\/p>\n<p>&#8211; una ragazza di origine africana tra i 20 e 30 anni di bella presenza, esperienza pregressa in recitazione, preferibilmente con attitudine alla danza. Protagonista.<\/p>\n<p>&#8211; attrice et\u00e0 scenica 20 anni, carnagione pallida, corporatura esile, preferibilmente con attitudine alla danza. Ruolo secondario.<\/p>\n<p>&#8211; attore et\u00e0 scenica 50 anni di robusta costituzione. Ruolo secondario.<\/p>\n<p>&#8211; Attori Amatoriali tra i 45 e i 60 anni, di robusta costituzione, magari con tatuaggi in vista. Ruolo secondario.<\/p>\n<p>Gli interessati potranno inviare due \/ tre foto, curriculum vitae o breve presentazione, eventuale showreel e contatti telefonici via mail ad athenailfilm@gmail.com entro il 25 febbraio 2020.<\/p>\n<p>********************<\/p>\n<p>Per il cortometraggio Dandelion si cercano le seguenti figure:<\/p>\n<p>&#8211; bambino di 6\/7 anni, sguardo vispo. E\u2019 fondamentale che il minore abbia ancora tutti i denti da latte. Protagonista.<\/p>\n<p>&#8211; ragazzo, et\u00e0 compresa tra i 16 e i 18 anni. Ruolo secondario.<\/p>\n<p>Gli interessati potranno inviare a casting.dandelion@gmail.com entro il 23 febbraio 2020: due \/ tre foto, data di nascita, residenza o domicilio del proprio figlio e contatto telefonico di un genitore o da chi ne fa le veci. Gradito breve video di presentazione.<\/p>\n<p>********************<\/p>\n<p>Per il cortometraggio Solo Una Notte si cercano le seguenti figure:<\/p>\n<p>&#8211; attore \u00e8t\u00e0 scenica di 40 anni, aspetto curato, capelli e occhi scuri. Protagonista.<\/p>\n<p>&#8211; attrice et\u00e0 scenica di 40 anni, donna di bell\u2019aspetto, capelli e occhi chiari. Protagonista.<\/p>\n<p>&#8211; attore \u00e8t\u00e0 scenica 30\/35 anni, capelli lunghi chiari. Ruolo secondario.<\/p>\n<p>Gli interessati potranno inviare due \/ tre foto, curriculum vitae o breve presentazione, eventuale showreel e contatti telefonici via mail a solounanotte.casting@gmail.com entro il 25 febbraio 2020.<\/p>\n<p>********************<\/p>\n<p>Per il cortometraggio Casa di famiglia si cercano le seguenti figure:<\/p>\n<p>-Attrice et\u00e0 di scenica 18\/20 anni, incarnato chiaro, lineamenti dolci, occhi intensi ed espressivi. Protagonista.<\/p>\n<p>-Attore di et\u00e0 scenica 20\/25 anni, lineamenti morbidi. Protagonista.<\/p>\n<p>-Attore di et\u00e0 scenica 55\/65 di bell&#8217;aspetto. Protagonista.<\/p>\n<p>-Attrice di et\u00e0 scenica 50\/60 di bell&#8217; aspetto. Protagonista.<\/p>\n<p>-Attore di 60\/70 anni. Ruolo secondario.<\/p>\n<p>-Attrice di 50\/60. Ruolo secondario.<\/p>\n<p>-Attrice di 20\/25. Ruolo secondario.<\/p>\n<p>Gli interessati potranno inviare due \/ tre foto, curriculum vitae o breve presentazione, eventuale showreel e contatti telefonici via mail a casting.casadifamiglia@gmail.com entro il 24 febbraio 2020.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gli studenti dell&#8217;ultimo anno del percorso formativo di College Cinema della Scuola Holden ricercano attori e attrici, preferibilmente domiciliati nel territorio piemontese, per 7 cortometraggi.<\/p>\n","protected":false},"author":34,"featured_media":4967,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[923],"class_list":["post-4966","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casting","tag-scuola-holden"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Casting per ruoli vari a Torino per 7 cortometraggi della scuola Holden - Cabiria<\/title>\n<meta name=\"description\" content=\"scuola holden\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casting per ruoli vari a Torino per 7 cortometraggi della scuola Holden - Cabiria\" \/>\n<meta property=\"og:description\" content=\"scuola holden\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-17T07:56:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2020\/02\/scuola-holden.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"815\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Casting per ruoli vari a Torino per 7 cortometraggi della scuola Holden\",\"datePublished\":\"2020-02-17T07:56:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\\\/\"},\"wordCount\":732,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2020\\\/02\\\/scuola-holden.jpg\",\"keywords\":[\"scuola holden\"],\"articleSection\":[\"casting\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\\\/\",\"name\":\"Casting per ruoli vari a Torino per 7 cortometraggi della scuola Holden - Cabiria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2020\\\/02\\\/scuola-holden.jpg\",\"datePublished\":\"2020-02-17T07:56:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"scuola holden\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2020\\\/02\\\/scuola-holden.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2020\\\/02\\\/scuola-holden.jpg\",\"width\":1024,\"height\":815},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casting per ruoli vari a Torino per 7 cortometraggi della scuola Holden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casting per ruoli vari a Torino per 7 cortometraggi della scuola Holden - Cabiria","description":"scuola holden","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\/","og_locale":"it_IT","og_type":"article","og_title":"Casting per ruoli vari a Torino per 7 cortometraggi della scuola Holden - Cabiria","og_description":"scuola holden","og_url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2020-02-17T07:56:39+00:00","og_image":[{"width":1024,"height":815,"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2020\/02\/scuola-holden.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Casting per ruoli vari a Torino per 7 cortometraggi della scuola Holden","datePublished":"2020-02-17T07:56:39+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\/"},"wordCount":732,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2020\/02\/scuola-holden.jpg","keywords":["scuola holden"],"articleSection":["casting"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\/","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\/","name":"Casting per ruoli vari a Torino per 7 cortometraggi della scuola Holden - Cabiria","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2020\/02\/scuola-holden.jpg","datePublished":"2020-02-17T07:56:39+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"scuola holden","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2020\/02\/scuola-holden.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2020\/02\/scuola-holden.jpg","width":1024,"height":815},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-ruoli-vari-torino-7-cortometraggi-della-scuola-holden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"Casting per ruoli vari a Torino per 7 cortometraggi della scuola Holden"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/4966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=4966"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/4966\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/4967"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=4966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=4966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=4966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}