{"id":4341,"date":"2018-10-02T12:57:08","date_gmt":"2018-10-02T12:57:08","guid":{"rendered":"http:\/\/web.quotidianopiemontese.it\/cabiria\/?p=4341"},"modified":"2018-10-02T12:57:08","modified_gmt":"2018-10-02T12:57:08","slug":"agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\/","title":{"rendered":"Agenda Brasil, il festival del cinema brasiliano arriva a Torino"},"content":{"rendered":"<p>Si apre Agenda Brasil, il Festival Internazionale del Cinema Brasiliano, promosso dall\u2019Associazione Vagaluna, giunto alla sua settima edizione a Milano, che per la prima volta arriva a Torino con tutto il<!--more--> meglio della produzione contemporanea del pi\u00f9 grande Paese del Sud America.<\/p>\n<p>Il festival, che sar\u00e0 in programmazione presso il Cinema Massimo di via Verdi dal 3 al 7 ottobre, \u00e8 realizzato in partnership con Museo del Cinema di Torino, Casa Brasil Torino (gi\u00e0 Associazione War\u00e3) e Associazione Italo-portoghese Tuc\u00e1tul\u00e1, con il contributo del BRDE, FSA, ANCINE (Ministero della Cultura in Brasile) e del Consolato-Generale del Brasile a Milano e con il patrocinio dell\u2019Ambasciata del Brasile a Roma.<\/p>\n<p>Si inizia mercoled\u00ec 3 ottobre: dopo il brindisi inaugurale (ore 19.00) alle 20 sar\u00e0 la volta di \u201cBingo, o rei das manh\u00e3s\u201d, regia di Daniel Rezende. Basato su una storia vera, racconta la ricerca del successo e il decadimento di un clown che animava le mattine televisive brasiliane negli anni \u201880. Miglior film al Festival del Cinema Brasiliano di Parigi 2018, ha ricevuto anche il premio Conema do Brasil e il premio per il miglior attore dall\u2019Associa\u00e7\u00e3o Paulista de Cr\u00edticos de Artes (APCA).<\/p>\n<p>Venerd\u00ec 5 si riparte alle ore 16.00 con \u201cCidades Fantasmas\u201d, di Tyrell Spencer, un documentario che porta gli spettatori attraverso il deserto cileno, l\u2019Amazzonia brasiliana, le Ande colombiane e le Pampas argentine per parlare di localit\u00e0 abbandonate attraverso la memoria di chi ci ha abitato e non vuole dimenticare. \u00c8 stato eletto miglior documentario al Festival \u00c9 TudoVerdade 2017 e ha vinto il premio della critica al Festival Agenda Brasil Milano 2018.<\/p>\n<p>Segue, alle 18.00, \u201cCentral\u201d, di Tatiana Sager e Renato Dornelles. Vincitore del premio come miglior documentario al FESTin di Lisbona e del 33\u00b0 premio Diritti Umani del Movimento de Justi\u00e7a e Direitos Humanos, il film apre uno squarcio sulla drammatica situazione carceraria brasiliana e il il rapporto con la societ\u00e0 contemporanea.<\/p>\n<p>Alle 20.30 sar\u00e0 la volta di \u201cEstive em Lisboa e lembrei de voc\u00ea\u201d, di Jos\u00e9 Barahona, che sar\u00e0 presente in sala. Qui il regista traccia ambiguit\u00e0 e frustrazioni di un viaggio oltreoceano a ritroso, dove le identit\u00e0 svaporano nella solitudine.<\/p>\n<p>Un&#8217;altra giornata di stili variegati quella di sabato 6 ottobre. Alle 10.30, il film per famiglie \u201cTain\u00e0\u201d, di Rosane Svartman: le avventure di una piccola indigena che sogna di diventare una grande guerriera e di scoprire la sua vera origine. Nel pomeriggio si riprende alle 16.00, con il portoghese\u00a0\u201cSao Jorge\u201d, di Marco Martins, uno sguardo dall\u2019interno di Lisbona in piena crisi economica, Premio Orizzonti come miglior attore a Nuno Lopes al Festival di Venezia. A seguire alle 18 \u201cBig Jato\u201d, di Claudio Assis, divagante romanzo di formazione tra ironia grottesca e tenerezza, scatologia e poesia. Per chiudere la serata, alle 20.30 \u201cAntes que eu me esque\u00e7a\u201d di Thiago Arakilian, storia piena di humour di un ottantenne che decide di stravolgere la sua stabile vita da giudice pensionato e diventa socio di un nightclub, scontrandosi con la famiglia. Premio del pubblico al Festival Agenda Brasil Milano 2018.<\/p>\n<p>Nell\u2019ultimo giorno di programmazione, domenica 7 ottobre, alle ore 16.00 ci sar\u00e0 \u201cA hist\u00f3ria da eternidade\u201d, di Camilo Cavalcante. Le storie di amore e desiderio di tre donne di et\u00e0 differente in un villaggio di 40 abitanti, in un paesaggio desertico del \u2018Nordeste\u2019 brasiliano. Miglior film, miglior regista, migliori attore e attrice protagonisti, premio della critica al Festival di Paulinia.<\/p>\n<p>La musica, una delle eccellenze brasiliane pi\u00f9 apprezzate nel mondo, sar\u00e0 la protagonista alle 18.15 con \u201cEu, Meu Pai e Os Cariocas \u2013 70 anos de M\u00fasica no Brasil\u201d: L\u00facia Ver\u00edssimo, figlia del Maestro Severino Filho, fondatore del gruppo vocale Os Cariocas, \u00e8 ideatrice, regista e narratrice del documentario sulla storia della musica brasiliana, partendo dalla famosa R\u00e1dio Nacional e passando per Bossa Nova, Tropic\u00e1lia, Samba e MPB. Premiato come miglior film al In-Edit Film Festival di S\u00e3o Paolo e Barcellona, al MUVi di Lisbona e vincitore del premio del pubblico come miglio documentario al Festival Agenda Brasil Milano, 2018. La regista sar\u00e0 presente in sala.<\/p>\n<p>Alle 20.30, la chiusura del Festival con la commedia \u201cLa vingan\u00e7a\u201d, di Fernando Fraiha, road movie incentrato sulla storica rivalit\u00e0 tra brasiliani e argentini. Premio come Miglior Regista esordiente al Brooklyn Film Festival 2017. Menzione speciale al Rencontres du Cin\u00e9ma Sud &#8211; Am\u00e9ricain de Marseille, 2017. Premio del pubblico al Festival Agenda Brasil Milano, 2017.<\/p>\n<p>PROGRAMMA<\/p>\n<p>I film sono in lingua originale con sottotitoli in italiano, eccetto Tain\u00e1, che sar\u00e0 accompagnato da una voce recitante.<\/p>\n<p>MERCOLED\u00cc 3 OTTOBRE<br \/>\nh 19.00 Brindisi di inaugurazione<br \/>\nh 20.30 Bingo, o rei das manh\u00e3s (Brasile 2017, 113\u2019) Regia: Daniel Rezende. Con Vladimir Brichta, Leandra Leal, Tain\u00e1 Muller.<br \/>\nBasato su una storia vera, &#8220;Bingo&#8221; \u00e8 un film sull&#8217;uomo dietro la maschera. Augusto \u00e8 un attore desideroso della luce dei riflettori. Mentre recita in vari soft porno e soap opera, ha finalmente la possibilit\u00e0 di conquistare il grande pubblico quando viene scelto per interpretare &#8220;Bingo&#8221;, un clown televisivo. Grazie al suo umorismo irriverente e al suo talento naturale, lo spettacolo \u00e8 un grande successo, ma una clausola del contratto da lui firmato gli proibisce di rivelare la sua vera identit\u00e0. Augusto diventa una celebrit\u00e0 anonima che, nel tentativo di affermare il suo valore artistico, trova il suo personale decadimento. Premio miglior attore dall\u2019Associa\u00e7\u00e3o Paulista de Cr\u00edticos de Artes (APCA) e miglior film al festival del cinema brasiliano di Parigi.<\/p>\n<p>VENERD\u00cc 5 OTTOBRE<br \/>\nh 16.00 Cidades fantasmas (Brasile 2017, 71\u2019) Regia di Tyrell Spencer.<br \/>\nDeserto cileno, Amazzonia brasiliana, Ande colombiane e Pampa argentina. Quattro destinazioni dell\u2019America Latina dove rovine e silenzio fanno da sfondo a un viaggio attraverso i racconti e le memorie di un passato che, chi vi ha abitato, non vuole dimenticare. Miglior documentario al Festival \u00c9 Tudo Verdade 2017. Premio della giuria come miglior documentario al Festival Agenda Brasil Milano.<\/p>\n<p>h 18.00 Central (Brasile 2017, 75\u2019) Regia di Tatiana Sager e Renato Dornelles.<br \/>\nPres\u00eddio Central, carcere di Porto Alegre. Detenuti, famigliari e polizia militare parlano della vita quotidiana nella prigione. Sovrappopolamento, violenza, immagini oltre le sbarre dove gli stessi carcerati, organizzati in fazioni, detengono il comando. Un\u2019indagine di carattere sociale sulle tragiche conseguenze riflesse nella societ\u00e0 civile. Premio come Miglior Documentario al FESTin di Lisbona 2016. 33\u00b0 Premio Diritti Umani del Movimento de Justi\u00e7a e Direitos Humanos.<\/p>\n<p>h 20.30 Estive em Lisboa e lembrei de voc\u00ea (Brasile\/Portogallo 2016, 94\u2019). Regia di Jos\u00e9 Barahona. Con Amanda Fontoura, Henrique Frade, Paulo Azevedo, Renata Ferraz. Basato sul romanzo di Luiz Ruffato. S\u00e9rgio vive in MinasGerais e lavora nella compagnia industriale di Cataguases. La sua vita modesta avr\u00e0 una svolta quando, da emigrante, partir\u00e0 per Lisbona. Non trover\u00e0 ci\u00f2 che si aspettava.<br \/>\nPresente il regista.<\/p>\n<p>SABATO 6 OTTOBRE<br \/>\nh 10.30 Tain\u00e0, una leggenda amazzonica (Brasile 2011, 80\u2019, v.o. con voce recitante in italiano). Regia di Rosane Svartman. Film per famiglie. Le avventure di una piccola orfanella indigena di cinque anni che sogna di diventare una grande guerriera e di scoprire la sua vera origine. Con i suoi amici Laurinha, una bambina della citt\u00e0 che si \u00e8 persa nella foresta, e Gobi, un piccolo indigeno nerd, Tain\u00e1 si trover\u00e0 di fronte a una grave minaccia per la Natura: Jurupari, l\u2019ancestrale nemico della sua famiglia, vuole distruggere il Grande Albero che ha dato origine a tutta la foresta. Tra avventure, amicizia e magia, i bambini impareranno a superare le proprie differenze e combatteranno il nemico.<br \/>\nVoce recitante: Cristina Palermo<\/p>\n<p>h 16.00 S\u00e3o Jorge (Portogallo\/Francia 2016, 112\u2019) Regia di Marco Martins. Con Nuno Lopes, Mariana Nunes, David Semedo, Gon\u00e7alo Waddington. Un pugile da tempo disoccupato e indebitato, che si muove tra la comunit\u00e0 di brasiliani immigrati di cui fa parte anche sua moglie e le zone pi\u00f9 povere di Lisbona, lavora in un&#8217;agenzia di recupero crediti per far fronte ai suoi stessi debiti. Premio Orizzonti come miglior attore a Nuno Lopes al Festival di Venezia. Pluripremiato al Premio Sophia.<\/p>\n<p>h 18.00 Big Jato (Brasile 2016, 93\u2019) Regia di Claudio Assis. Con Matheus Nachtergaele, Marc\u00e9lia Cartaxo, Rafael Nic\u00e1cio, Artur Maia, Vertin Moura, Francisco de Assis Moraes. Francisco attraversa le strade del Pernambuco e guarda il mondo dal finestrino del Big Jato, il camion autospurgo su cui lavora con il padre. Il suo animo per\u00f2 \u00e8 quello di un poeta, di un artista, libero e anarchico, proprio come suo zio Nelson. Indeciso tra seguire il padre che crede solo nel duro lavoro e i sogni di libert\u00e0, dovr\u00e0 prendere una decisione. Premio miglior film, migliore attrice, miglior attore e migliore sceneggiatura al Festival di Brasilia del Cinema Brasiliano, 2016. Premio miglior film al FESTin Lisbona, 2016.<\/p>\n<p>h 20.30 Antes Que Eu Me Esque\u00e7a (Brasile 2017, 95\u2019) Regia di Thiago Arakilian. Con Jos\u00e9 de Abreu, Danton Mello, Guta Stresser, Mariana Lima, Augusto Madeira, Let\u00edcia Isnard, Eucir.<br \/>\nA 80 anni, Polidoro decide di stravolgere la sua stabile vita da giudice pensionato e di diventare socio di un nightclub. Beatriz, sua figlia, cerca di impedirglielo legalmente, invece il figlio Paulo si dichiara incapace di giudicare la situazione, perch\u00e9 non ha pi\u00f9 contatti col padre. Il tribunale stabilisce un incontro forzato tra padre e figlio, ravvicinamento che cambier\u00e0 le loro vite. Premio del pubblico al Festival Agenda Brasil Milano, 2018.<\/p>\n<p>DOMENICA 7 OTTOBRE<br \/>\nh 16.00 A hist\u00f3ria da eternidade (Brasile 2014, 120\u2019). Regia di Camilo Cavalcante. Con Irandhir Santos, Marcelia Cartaxo, Zezita Matos.<br \/>\nLe storie di amore e desiderio di tre donne di et\u00e0 differente in un villaggio di 40 abitanti, in un paesaggio desertico del \u2018Nordeste\u2019 brasiliano. Miglior film, miglior regista, migliori attore e attrice protagonisti, premio della critica al Festival di Paulinia.<\/p>\n<p>h 18.15 Eu, meu pai e Os Cariocas \u2013 70 anos de M\u00fasica no Brasil (Brasile 2017, 112\u2019) Regia di L\u00facia Ver\u00edssimo. Con Caetano Veloso, Gal Costa, Gilberto Gil, Paulo Jobim, Dori Caymmi, Maria Beth\u00e2nia, Chico Buarque, Djavan, Milton Nascimento.<br \/>\nL\u00facia Ver\u00edssimo, figlia del Maestro Severino Filho, fondatore del gruppo vocale Os Cariocas, \u00e8 ideatrice, regista e narratrice del documentario che mostra la storia della musica brasiliana, partendo dalla famosa R\u00e1dio Nacional e passando per Bossa Nova, Tropic\u00e1lia, Samba e MPB. Premio della Giuria Ufficiale come Miglior Film all\u2019In-Edit Film Festival di San Paolo e Barcellona e Premio della Giuria Ufficiale e della Giuria Popolare come Miglior Film al MUVi di Lisbona, premio del pubblico al Festival Agenda Brasil Milano, 2018.<br \/>\nPresente la regista.<\/p>\n<p>h 20.30 La vingan\u00e7a (Brasile 2016, 90\u2019). Regia\u00a0: Fernando Fraiha. Con Felipe Rocha,\u00a0Daniel Furlan,\u00a0Leandra Leal, Ana Pauls, Aylin Prandi, Adri\u00e1n Navarro, Gast\u00f3n Ricaud.<br \/>\nRicevuto l\u2019enigmatico messaggio: \u201cDobbiamo parlare!\u201d, Caco decide di fare una sorpresa alla fidanzata e chiederla in sposa ma la trova tra le braccia di un argentino. Vad\u00e3o, il miglior amico, trascina l\u2019ex futuro sposo, in un viaggio in Argentina per una vendetta senza senso. Mentre Vad\u00e3o rivive la sua adolescenza, Caco pensa di riconquistare il suo amore perduto. Nulla di ci\u00f2 che era pianificato, avverr\u00e0.<br \/>\nPremio come Miglior Regista esordiente al Brooklyn Film Festival 2017. Menzione speciale al Rencontres du Cin\u00e9ma Sud &#8211; Am\u00e9ricain de Marseille, 2017. Premio del pubblico al Festival Agenda Brasil Milano, 2017.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si apre Agenda Brasil, il Festival Internazionale del Cinema Brasiliano, promosso dall\u2019Associazione Vagaluna, giunto alla sua settima edizione a Milano, che per la prima volta arriva a Torino con tutto il<\/p>\n","protected":false},"author":34,"featured_media":4342,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[1312],"class_list":["post-4341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-festival","tag-agenda-brasil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Agenda Brasil, il festival del cinema brasiliano arriva a Torino - Cabiria<\/title>\n<meta name=\"description\" content=\"agenda brasil\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agenda Brasil, il festival del cinema brasiliano arriva a Torino - Cabiria\" \/>\n<meta property=\"og:description\" content=\"agenda brasil\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-02T12:57:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/10\/Poster_CENTRAL_low.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1991\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Agenda Brasil, il festival del cinema brasiliano arriva a Torino\",\"datePublished\":\"2018-10-02T12:57:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\\\/\"},\"wordCount\":1808,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2018\\\/10\\\/Poster_CENTRAL_low.jpg\",\"keywords\":[\"agenda brasil\"],\"articleSection\":[\"festival\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\\\/\",\"name\":\"Agenda Brasil, il festival del cinema brasiliano arriva a Torino - Cabiria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2018\\\/10\\\/Poster_CENTRAL_low.jpg\",\"datePublished\":\"2018-10-02T12:57:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"agenda brasil\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2018\\\/10\\\/Poster_CENTRAL_low.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2018\\\/10\\\/Poster_CENTRAL_low.jpg\",\"width\":1500,\"height\":1991},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agenda Brasil, il festival del cinema brasiliano arriva a Torino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Agenda Brasil, il festival del cinema brasiliano arriva a Torino - Cabiria","description":"agenda brasil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cabiria\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\/","og_locale":"it_IT","og_type":"article","og_title":"Agenda Brasil, il festival del cinema brasiliano arriva a Torino - Cabiria","og_description":"agenda brasil","og_url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2018-10-02T12:57:08+00:00","og_image":[{"width":1500,"height":1991,"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/10\/Poster_CENTRAL_low.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Agenda Brasil, il festival del cinema brasiliano arriva a Torino","datePublished":"2018-10-02T12:57:08+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\/"},"wordCount":1808,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/10\/Poster_CENTRAL_low.jpg","keywords":["agenda brasil"],"articleSection":["festival"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\/","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\/","name":"Agenda Brasil, il festival del cinema brasiliano arriva a Torino - Cabiria","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/10\/Poster_CENTRAL_low.jpg","datePublished":"2018-10-02T12:57:08+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"agenda brasil","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/10\/Poster_CENTRAL_low.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/10\/Poster_CENTRAL_low.jpg","width":1500,"height":1991},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/agenda-brasil-il-festival-del-cinema-brasiliano-arriva-a-torino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"Agenda Brasil, il festival del cinema brasiliano arriva a Torino"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/4341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=4341"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/4341\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/4342"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=4341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=4341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=4341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}