{"id":4229,"date":"2018-07-21T10:42:45","date_gmt":"2018-07-21T10:42:45","guid":{"rendered":"http:\/\/web.quotidianopiemontese.it\/cabiria\/?p=4229"},"modified":"2018-07-21T10:42:45","modified_gmt":"2018-07-21T10:42:45","slug":"zoe-tavarelli-da-torino-al-sogno-americano","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/zoe-tavarelli-da-torino-al-sogno-americano\/","title":{"rendered":"Zoe Tavarelli, da Torino al sogno americano"},"content":{"rendered":"<p>Zoe Tavarelli, classe 1996, figlia del regista Gianluca Tavarelli e della scenografa Francesca Bocca, ha avuto fin da piccola l\u2019occasione di respirare l\u2019aria dei set cinematografici.<!--more--> A neanche un anno si \u00e8 gi\u00e0 trovata davanti alla macchina da presa, a sua insaputa, in Tutti gi\u00f9 per terra di Davide Ferrario, neonata piangente tenuta maldestramente in braccio dal \u201cpadre\u201d Valerio Mastandrea.<\/p>\n<p>Da allora Zoe ha continuato a comparire in diversi film del padre per il cinema e per la televisione: da Un amore (1999), a Qui non \u00e8 il paradiso (2000) fino a Non prendere impegni stasera (2006), passando per Liberi (2003) e Paolo Borsellino (2004) di Tavarelli; e anche in Se devo essere sincera (2004) di Ferrario accanto a Luciana Littizzetto.<\/p>\n<p>Il set \u00e8 sempre stato un \u2018safe place\u2019 &#8211; commenta Zoe Tavarelli -, un luogo dove mi sentivo a mio agio, dove stavo bene, a casa. Fin da piccola ho avuto la fortuna di frequentare i set dei miei genitori: dopo scuola li raggiungevo l\u00ec, mi sedevo su una sedia e facevo i compiti mentre attorno a me si costruiva il magico mondo del cinema che, a poco a poco, \u00e8 diventato la mia seconda casa. Proprio sul set ho capito che \u2018da grande\u2019 avrei voluto recitare: \u00e8 stato un innamoramento graduale ma persistente, una passione nata per caso, ma coltivata di giorno in giorno fino a esplodere nella decisione di percorrere la strada della professione d\u2019attrice.<\/p>\n<p>Per due anni ha seguito i corsi della scuola di teatro \u201cCantiere Teatrale\u201d di Roma, citt\u00e0 dove ha frequentato il liceo e ha continuato a recitare in altri film come Piedi nudi di Luca Agostino (2006) e la serie tv Il giovane Montalbano (2012 e 2015).<\/p>\n<p>Arrivata a vent\u2019anni Zoe ha scelto la strada pi\u00f9 difficile: lasciare l\u2019Italia e la \u201cprotezione\u201d familiare per tentare la fortuna negli Stati Uniti. A Los Angeles ha superato le rigide selezioni della prestigiosa American Academy of Dramatic Arts, scuola che ha formato, tra i tanti, i Premi Oscar Anne Hathaway e Jessica Chastain, presentando un monologo drammatico tratto da \u201cSei personaggi in cerca d\u2019autore\u201d di Luigi Pirandello. Ha avuto cos\u00ec inizio il suo intenso percorso di alta formazione oltre oceano dove, tra lezioni in classe, provini e progetti con i compagni di corso sta costruendo, giorno dopo giorno, la sua strada verso Hollywood.<\/p>\n<p>Ho scelto l\u2019America e l\u2019Academy of Dramatic Arts per staccarmi dalla \u2018comfort zone\u2019 di casa, per camminare con le mie gambe e dimostrare, a me stessa in primis, che posso farcela da sola. &#8211; continua Zoe.<\/p>\n<p>Nel 2017, mentre studia negli Stati Uniti, Zoe torna per un breve periodo in Italia per continuare a lavorare, questa volta sul set della serie tv andata in onda su Rai 1 Maltese &#8211; Il romanzo del Commissario di Tavarelli. Ma la tappa pi\u00f9 significativa di questo percorso \u00e8 stata, di recente, un ruolo di coprotagonista con il premio Oscar Chris Cooper (American Beauty, I segreti di Osage County\u2026). Si tratta del progetto The Lost Films Series di Davide Ferrario, con cui Zoe chiude idealmente un cerchio da quella scena \u201cinvolontaria\u201d di Tutti gi\u00f9 per terra. The Lost Films Series \u00e8 un progetto che Ferrario sta preparando in America, destinato a un contesto di gallerie d\u2019arte. Invitato come artista residente all\u2019Experimental Film Virginia di Cape Charles appena conclusosi, Ferrario ha realizzato un \u201cpilota\u201d sotto forma di cortometraggio in cui, in un\u2019atmosfera noir, Zoe incontra Cooper, il padre che non ha mai conosciuto.<\/p>\n<p>In America Zoe ha molti progetti in cantiere, a cominciare dalla seconda stagione della serie web di Josh Mitchell Manny\u2019s Garage Sale: a Hitchcock Knot di cui \u00e8 gi\u00e0 stata protagonista. Tornerebbe a recitare in Italia? \u201cAssolutamente. Dovunque c\u2019\u00e8 un set, io ci sono.\u201d &#8211; risponde Zoe.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zoe Tavarelli, classe 1996, figlia del regista Gianluca Tavarelli e della scenografa Francesca Bocca, ha avuto fin da piccola l\u2019occasione di respirare l\u2019aria dei set cinematografici.<\/p>\n","protected":false},"author":34,"featured_media":4230,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[206],"tags":[1295],"class_list":["post-4229","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-approfondimento","tag-zoe-tavarelli"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zoe Tavarelli, da Torino al sogno americano - Cabiria<\/title>\n<meta name=\"description\" content=\"zoe tavarelli\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/zoe-tavarelli-da-torino-al-sogno-americano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zoe Tavarelli, da Torino al sogno americano - Cabiria\" \/>\n<meta property=\"og:description\" content=\"zoe tavarelli\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/zoe-tavarelli-da-torino-al-sogno-americano\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-21T10:42:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/07\/Zoe-Tavarelli_2-e1532169735648.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1060\" \/>\n\t<meta property=\"og:image:height\" content=\"821\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/zoe-tavarelli-da-torino-al-sogno-americano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/zoe-tavarelli-da-torino-al-sogno-americano\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Zoe Tavarelli, da Torino al sogno americano\",\"datePublished\":\"2018-07-21T10:42:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/zoe-tavarelli-da-torino-al-sogno-americano\\\/\"},\"wordCount\":621,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/zoe-tavarelli-da-torino-al-sogno-americano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2018\\\/07\\\/Zoe-Tavarelli_2-e1532169735648.jpg\",\"keywords\":[\"zoe tavarelli\"],\"articleSection\":[\"approfondimento\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/zoe-tavarelli-da-torino-al-sogno-americano\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/zoe-tavarelli-da-torino-al-sogno-americano\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/zoe-tavarelli-da-torino-al-sogno-americano\\\/\",\"name\":\"Zoe Tavarelli, da Torino al sogno americano - Cabiria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/zoe-tavarelli-da-torino-al-sogno-americano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/zoe-tavarelli-da-torino-al-sogno-americano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2018\\\/07\\\/Zoe-Tavarelli_2-e1532169735648.jpg\",\"datePublished\":\"2018-07-21T10:42:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"zoe tavarelli\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/zoe-tavarelli-da-torino-al-sogno-americano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/zoe-tavarelli-da-torino-al-sogno-americano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/zoe-tavarelli-da-torino-al-sogno-americano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2018\\\/07\\\/Zoe-Tavarelli_2-e1532169735648.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2018\\\/07\\\/Zoe-Tavarelli_2-e1532169735648.jpg\",\"width\":1060,\"height\":821},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/zoe-tavarelli-da-torino-al-sogno-americano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zoe Tavarelli, da Torino al sogno americano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zoe Tavarelli, da Torino al sogno americano - Cabiria","description":"zoe tavarelli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cabiria\/zoe-tavarelli-da-torino-al-sogno-americano\/","og_locale":"it_IT","og_type":"article","og_title":"Zoe Tavarelli, da Torino al sogno americano - Cabiria","og_description":"zoe tavarelli","og_url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/zoe-tavarelli-da-torino-al-sogno-americano\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2018-07-21T10:42:45+00:00","og_image":[{"width":1060,"height":821,"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/07\/Zoe-Tavarelli_2-e1532169735648.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/zoe-tavarelli-da-torino-al-sogno-americano\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/zoe-tavarelli-da-torino-al-sogno-americano\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Zoe Tavarelli, da Torino al sogno americano","datePublished":"2018-07-21T10:42:45+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/zoe-tavarelli-da-torino-al-sogno-americano\/"},"wordCount":621,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/zoe-tavarelli-da-torino-al-sogno-americano\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/07\/Zoe-Tavarelli_2-e1532169735648.jpg","keywords":["zoe tavarelli"],"articleSection":["approfondimento"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/zoe-tavarelli-da-torino-al-sogno-americano\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/zoe-tavarelli-da-torino-al-sogno-americano\/","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/zoe-tavarelli-da-torino-al-sogno-americano\/","name":"Zoe Tavarelli, da Torino al sogno americano - Cabiria","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/zoe-tavarelli-da-torino-al-sogno-americano\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/zoe-tavarelli-da-torino-al-sogno-americano\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/07\/Zoe-Tavarelli_2-e1532169735648.jpg","datePublished":"2018-07-21T10:42:45+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"zoe tavarelli","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/zoe-tavarelli-da-torino-al-sogno-americano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/zoe-tavarelli-da-torino-al-sogno-americano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/zoe-tavarelli-da-torino-al-sogno-americano\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/07\/Zoe-Tavarelli_2-e1532169735648.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/07\/Zoe-Tavarelli_2-e1532169735648.jpg","width":1060,"height":821},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/zoe-tavarelli-da-torino-al-sogno-americano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"Zoe Tavarelli, da Torino al sogno americano"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/4229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=4229"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/4229\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/4230"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=4229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=4229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=4229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}