{"id":4209,"date":"2018-07-03T05:57:10","date_gmt":"2018-07-03T05:57:10","guid":{"rendered":"http:\/\/web.quotidianopiemontese.it\/cabiria\/?p=4209"},"modified":"2018-07-03T06:35:48","modified_gmt":"2018-07-03T06:35:48","slug":"casting-per-il-cortometraggio-alaska-a-torino","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-per-il-cortometraggio-alaska-a-torino\/","title":{"rendered":"Casting per il cortometraggio Alaska a Torino"},"content":{"rendered":"<p>Venerd\u00ec 6 luglio e sabato 7 luglio 2018, dalle ore 9.00 alle 13.00 e dalle 15.00 alle 18.00, presso la Sala Casting di via Cagliari 40\/E a Torino, si svolger\u00e0 un casting per il cortometraggio dal titolo \u201cAlaska\u201d di <!--more-->Michele Seia e Jacopo Berti, studenti della Scuola Holden di Torino.<\/p>\n<p>Si ricercano le seguenti figure:<\/p>\n<p>&#8211; Bambino di et\u00e0 scenica 8\/10 anni, corporatura media<br \/>\n&#8211; Uomo di et\u00e0 scenica 30\/35 anni, fisico esile e slanciato<br \/>\n&#8211; Uomo di et\u00e0 scenica 30\/35 anni, corporatura media<\/p>\n<p>Trattandosi di un progetto in ambito didattico, non \u00e8 prevista retribuzione.<br \/>\nI minori dovranno essere accompagnati da un genitore o da un accompagnatore con delega del genitore e copia della carta d\u2019identit\u00e0 propria e del genitore.<br \/>\nPoich\u00e9 non \u00e8 previsto il rimborso spese viaggio, la ricerca \u00e8 rivolta preferibilmente ai residenti in Piemonte.<\/p>\n<p>Presentarsi venerd\u00ec 6 luglio e sabato 7 luglio in Sala Casting, portando un monologo a scelta tratto sia da testi teatrali che cinematografici.<\/p>\n<p>Periodo di riprese seconda e terza settimana di luglio a Torino per la durata di due giorni a settimana.<\/p>\n<p>Per info: michele.seia@studenti.scuolaholden.it oppure<\/p>\n<p>adriano.guario@studenti.scuolaholden.it<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Venerd\u00ec 6 luglio e sabato 7 luglio 2018, dalle ore 9.00 alle 13.00 e dalle 15.00 alle 18.00, presso la Sala Casting di via Cagliari 40\/E a Torino, si svolger\u00e0 un casting per il cortometraggio dal titolo \u201cAlaska\u201d di<\/p>\n","protected":false},"author":34,"featured_media":1368,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[1289],"class_list":["post-4209","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casting","tag-alaska"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Casting per il cortometraggio Alaska a Torino - Cabiria<\/title>\n<meta name=\"description\" content=\"alaska\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-per-il-cortometraggio-alaska-a-torino\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casting per il cortometraggio Alaska a Torino - Cabiria\" \/>\n<meta property=\"og:description\" content=\"alaska\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-per-il-cortometraggio-alaska-a-torino\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-03T05:57:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-03T06:35:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2013\/06\/film-commission.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"943\" \/>\n\t<meta property=\"og:image:height\" content=\"345\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-per-il-cortometraggio-alaska-a-torino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-per-il-cortometraggio-alaska-a-torino\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Casting per il cortometraggio Alaska a Torino\",\"datePublished\":\"2018-07-03T05:57:10+00:00\",\"dateModified\":\"2018-07-03T06:35:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-per-il-cortometraggio-alaska-a-torino\\\/\"},\"wordCount\":185,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-per-il-cortometraggio-alaska-a-torino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2013\\\/06\\\/film-commission.jpg\",\"keywords\":[\"alaska\"],\"articleSection\":[\"casting\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-per-il-cortometraggio-alaska-a-torino\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-per-il-cortometraggio-alaska-a-torino\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-per-il-cortometraggio-alaska-a-torino\\\/\",\"name\":\"Casting per il cortometraggio Alaska a Torino - Cabiria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-per-il-cortometraggio-alaska-a-torino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-per-il-cortometraggio-alaska-a-torino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2013\\\/06\\\/film-commission.jpg\",\"datePublished\":\"2018-07-03T05:57:10+00:00\",\"dateModified\":\"2018-07-03T06:35:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"alaska\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-per-il-cortometraggio-alaska-a-torino\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-per-il-cortometraggio-alaska-a-torino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-per-il-cortometraggio-alaska-a-torino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2013\\\/06\\\/film-commission.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2013\\\/06\\\/film-commission.jpg\",\"width\":943,\"height\":345},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-per-il-cortometraggio-alaska-a-torino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casting per il cortometraggio Alaska a Torino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casting per il cortometraggio Alaska a Torino - Cabiria","description":"alaska","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-per-il-cortometraggio-alaska-a-torino\/","og_locale":"it_IT","og_type":"article","og_title":"Casting per il cortometraggio Alaska a Torino - Cabiria","og_description":"alaska","og_url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-per-il-cortometraggio-alaska-a-torino\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2018-07-03T05:57:10+00:00","article_modified_time":"2018-07-03T06:35:48+00:00","og_image":[{"width":943,"height":345,"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2013\/06\/film-commission.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-per-il-cortometraggio-alaska-a-torino\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-per-il-cortometraggio-alaska-a-torino\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Casting per il cortometraggio Alaska a Torino","datePublished":"2018-07-03T05:57:10+00:00","dateModified":"2018-07-03T06:35:48+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-per-il-cortometraggio-alaska-a-torino\/"},"wordCount":185,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-per-il-cortometraggio-alaska-a-torino\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2013\/06\/film-commission.jpg","keywords":["alaska"],"articleSection":["casting"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-per-il-cortometraggio-alaska-a-torino\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-per-il-cortometraggio-alaska-a-torino\/","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-per-il-cortometraggio-alaska-a-torino\/","name":"Casting per il cortometraggio Alaska a Torino - Cabiria","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-per-il-cortometraggio-alaska-a-torino\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-per-il-cortometraggio-alaska-a-torino\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2013\/06\/film-commission.jpg","datePublished":"2018-07-03T05:57:10+00:00","dateModified":"2018-07-03T06:35:48+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"alaska","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-per-il-cortometraggio-alaska-a-torino\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-per-il-cortometraggio-alaska-a-torino\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-per-il-cortometraggio-alaska-a-torino\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2013\/06\/film-commission.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2013\/06\/film-commission.jpg","width":943,"height":345},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-per-il-cortometraggio-alaska-a-torino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"Casting per il cortometraggio Alaska a Torino"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/4209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=4209"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/4209\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/1368"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=4209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=4209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=4209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}