{"id":4195,"date":"2018-06-07T13:19:01","date_gmt":"2018-06-07T13:19:01","guid":{"rendered":"http:\/\/web.quotidianopiemontese.it\/cabiria\/?p=4195"},"modified":"2018-06-07T13:19:01","modified_gmt":"2018-06-07T13:19:01","slug":"seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\/","title":{"rendered":"SeeYouSound diventa On The Road e va a Pisa, Palermo e Lecce"},"content":{"rendered":"<p>Da Torino, Seeyousound allarga gli orizzonti ed esporta la propria formula a Pisa (23 &gt; 27 ottobre), Palermo (8 &gt; 11 novembre) e Lecce (28 novembre &gt; 1 dicembre), prime tappe di un calendario<!--more--> di appuntamenti per portare il cinema a tematica musicale nel maggior numero di regioni italiane.<\/p>\n<p>In ogni rassegna, film in anteprima nazionale e quelli che hanno conquistato il pubblico di Torino, oltre a proposte formative e progetti ideati in sinergia con le realt\u00e0 culturali del territorio.<\/p>\n<p>Come una band che va da una tappa all\u2019altra, ora anche Seeyousound diventa ON THE ROAD, per creare una rete di festival che nel corso dell\u2019anno possa essere vetrina per i migliori film di genere musicale e occasione di distribuzione per quelle produzioni nazionali e internazionali che, pur proponendo prodotti di grande valore, faticano a trovare spazio.<\/p>\n<p>\u201cTorino si conferma laboratorio di sviluppo e buone pratiche e Seeyousound prosegue in questo solco il proprio percorso di crescita.\u201d Dichiara Maurizio Pisani, direttore di Seeyousound e curatore di SYS ON THE ROAD \u201cSiamo pronti per una nuova fase e con un nuovo progetto di festival itinerante e fertilizzante. Itinerante perch\u00e9 andiamo in altri territori a sviluppare il nostro format. Fertilizzante perch\u00e9 non andiamo a colonizzare ma a collaborare, creando reti virtuose con le realt\u00e0 culturali attive sui territori.\u201d<\/p>\n<p>Alla ricerca dell\u2019immagine che il cinema pu\u00f2 restituire della musica e di quanto l\u2019una possa entrare in risonanza con l\u2019altra, Seeyousound allarga gli orizzonti ed esporta la propria formula in nuovi territori, per portare il cinema a tematica musicale nel maggior numero di regioni italiane e dare l\u2019opportunit\u00e0 al proprio pubblico di seguire Musica &amp; Cinema fuori da Torino.<\/p>\n<p>Le prime tappe SYS ON THE ROAD<\/p>\n<p>Pisa dal 23 al 27 ottobre<\/p>\n<p>Palermo dall\u20198 all\u201911 novembre<\/p>\n<p>Lecce dal 28 novembre all\u20191 dicembre<\/p>\n<p>Un calendario annuale di appuntamenti SYS che si struttura in sintonia con i grandi festival di cinema internazionali per offrire a produttori e registi l\u2019occasione giusta per mostrare in Italia le loro opere in anteprima.<\/p>\n<p>In ognuna delle tappe, infatti, verranno presentati titoli in anteprima nazionale, a cui si aggiunge una selezione di film che hanno conquistato il pubblico nelle passate edizioni di Torino &#8211; che rimane fulcro del progetto \u2013, oltre a proposte formative studiate sulle esigenze locali e progetti di sviluppo ideate in sinergia con le realt\u00e0 culturali e gli operatori di settore del territorio.<\/p>\n<p>Sinergia e contaminazione nelle pi\u00f9 svariate sfaccettature &#8211; artistica, culturale, sociale \u2013 ispirano la proposta creativa di Seeyousound, che trova nella musica e nel cinema il luogo in cui far confluire stimoli e influenze, accogliere le diversit\u00e0 e farne fonte di nuova conoscenza.<\/p>\n<p>In questo clima e con questa visione, sono molte le realt\u00e0 che hanno gi\u00e0 aderito alla rete e che si apprestano a dare vita a SYS ON THE ROAD, in una profonda condivisione di obiettivi.<\/p>\n<p>SYS ON THE ROAD \u2013 PISA, con la coproduzione di Lumi\u00e8re, Cinema Arsenale<\/p>\n<p>SYS ON THE ROAD \u2013 PALERMO, con il sostegno di Goethe Institut di Palermo, Polo Museo D\u2019Arte Moderna e Contemporanea Palazzo Belmonte Riso, in collaborazione con Freschette<\/p>\n<p>SYS ON THE ROAD \u2013 LECCE, iniziativa realizzata da Apulia Film Commission e finanziata dalla Regione Puglia &#8211; Assessorato Industria Turistica e Culturale, nell&#8217;ambito dell&#8217;intervento \u201cViva Cinema &#8211; Promuovere il Cinema e Valorizzare i Cineporti di Puglia\u201d, a valere su risorse FSC Puglia 2014-2020 &#8211; Patto per la Puglia, con il patrocinio di Comune di Lecce, con la coproduzione di DB d\u2019Essai Cineteatro, la collaborazione di DAMS Disciplina delle Arti della Musica e dello Spettacolodell&#8217;Universit\u00e0 del Salento, Passo Uno Produzioni, Festival del Cinema Europeo<\/p>\n<p>SEEYOUSOUND \u00e8 realizzato da Associazione Choobamba, con il patrocinio di Regione Piemonte, Comune di Torino, Museo Nazionale del Cinema e con il sostegno di Diplom\u00e1tico, Nikon.<\/p>\n<p>SYS ON THE ROAD \u2013 Pisa | 23 &gt; 27 ottobre<\/p>\n<p>Cineclub Arsenale (Vicolo Scaramucci 2, Pisa)<\/p>\n<p>Lumiere Pisa (Vicolo del Tidi 6, Pisa)<\/p>\n<p>La tappa di Pisa di SYS ON THE ROAD si terr\u00e0 dal 23 al 27 ottobre, grazie alla collaborazione di realt\u00e0 locali di grande tradizione come il Cineclub Arsenale e il Lumiere Pisa, coproduttrici della rassegna e casa di questa prima edizione.<\/p>\n<p>Il palinsesto proporr\u00e0 una panoramica sulle prime quattro edizioni di Seeyousound, arricchita da una selezione di anteprime: in tutto nove film internazionali, le cui proiezioni si terranno al Cineclub Arsenale, punto di riferimento per gli appassionati di cinema della zona, attivo dal 1982.<\/p>\n<p>Ogni film sar\u00e0 accompagnato da Q&amp;A con gli autori, performance musicali, dj set e incontri con personalit\u00e0 e artisti del territorio, per coinvolgere quanto pi\u00f9 possibile il tessuto locale, senza rinunciare al respiro globale.<\/p>\n<p>Performance e live show si terranno all\u2019ex-cinema Lumi\u00e8re, il cinema pi\u00f9 antico d\u2019Italia e che oggi ospita eventi dal vivo di calibro internazionale, e a completare il programma panel e attivit\u00e0 formative grazie al coinvolgimento dell\u2019Universit\u00e0 di Pisa, di istituti musicali, di associazioni locali e di festival gi\u00e0 attivi sul territorio in ambito musicale e non solo.<\/p>\n<p>\u201cUn progetto estremamente vitale, un\u2019occasione per la citt\u00e0 di aprirsi a nuove esperienze, ma anche e soprattutto un modo per immaginare insieme nuove strade e nuovi modelli di sviluppo.\u201d Afferma Gaia Dedola, local director di SYS ON THE ROAD \u2013 PISA, \u201cUn\u2019idea su cui c\u2019\u00e8 stata una convergenza immediata, in risposta alla necessit\u00e0 condivisa di far rete.\u201d<\/p>\n<p>SYS ON THE ROAD rilancia ulteriormente la vocazione collaborativa di Pisa, dandole nuovo impulso sul fronte della cultura musicale e dello sviluppo dell\u2019audiovisivo, e facendo emergere una sinergia capace da un lato di valorizzare gli operatori culturali del territorio e dall\u2019altro di favorire l\u2019assorbimento di know-how e respiro internazionale da una realt\u00e0 consolidata come Seeyousound.<\/p>\n<p>SYS ON THE ROAD \u2013 Palermo | 8 &gt; 11 novembre<\/p>\n<p>La prima edizione di SYS ON THE ROAD \u2013 Palermo si terr\u00e0 dall\u20198 all\u201911 novembre, grazie al supporto del Polo Museo D\u2019Arte Moderna e Contemporanea Palazzo Belmonte Riso, del Goethe Institut di Palermo e in collaborazione con Freschette snc.<\/p>\n<p>La tappa palermitana si svolger\u00e0 in una location \u2013 in via di definizione \u2013 che sia rappresentativa dell\u2019interdisciplinariet\u00e0 dei temi e dei linguaggi che SYS ON THE ROAD porta con s\u00e8; un luogo cardine della cultura per la citt\u00e0 di Palermo che sostenga la promozione dei giovani artisti, che \u00e8 tra gli obiettivi che il Museo Riso ha perseguito con l\u2019intento di mettere in rete la creativit\u00e0 allargando gli orizzonti di azione e in cui si inserisce SYS ON THE ROAD \u2013 Palermo.<\/p>\n<p>\u201cDa tempo con diversi operatori culturali ci interroghiamo e confrontiamo per trovare un sistema efficace per diffondere in citt\u00e0 una cultura cinematografica e infatti negli anni hanno presso vita diversi festival.\u201d Dichiara Sheila Melosu, local director di SYS ON THE ROAD &#8211; Palermo\u201cQuando sono venuta a conoscenza del progetto SYS ON THE ROAD ho percepito la novit\u00e0 del festival e le sue potenzialit\u00e0 di sviluppo. Ho subito pensato che potesse essere l\u2019occasione giusta per avvicinare al cinema un pubblico nuovo e diverso anche a Palermo.\u201d<\/p>\n<p>Nei 4 giorni di festival cinema e musica si uniranno in un dialogo che dar\u00e0 a entrambe lo spazio necessario per sprigionare la loro energia e realizzare cos\u00ec una manifestazione che si intrecci in senso profondo con la citt\u00e0, rispondendo a esigenze e bisogni di chi la abita.<\/p>\n<p>Per questo \u00e8 fondamentale il coinvolgimento di realt\u00e0 e professionisti gi\u00e0 attivi in citt\u00e0, associazioni o enti, artisti e operatori, che potranno partecipare attivamente o come pubblico a momenti formativi, performance musicali e proiezioni alla presenza degli autori dei film che rappresentano il cuore della proposta culturale SYS ON THE ROAD.<\/p>\n<p>SYS ON THE ROAD &#8211; Lecce | 28 novembre &gt; 1 dicembre<\/p>\n<p>Cinema DB d\u2019Essai (Via dei Salesiani 4, Lecce)<\/p>\n<p>Dal 28 novembre all\u20191 dicembre sar\u00e0 di scena SYS ON THE ROAD-LECCE, iniziativa realizzata da Apulia Film Commission e finanziata dalla Regione Puglia &#8211; Assessorato Industria Turistica e Culturale, nell&#8217;ambito dell&#8217;intervento \u201cViva Cinema &#8211; Promuovere il Cinema e Valorizzare i Cineporti di Puglia\u201d, a valere su risorse FSC Puglia 2014-2020 &#8211; Patto per la Puglia, con il patrocinio di Comune di Lecce, con la coproduzione di DB d\u2019Essai Cineteatro, la collaborazione di DAMS Disciplina delle Arti della Musica e dello Spettacolo dell&#8217;Universit\u00e0 del Salento, Passo Uno Produzioni, Festival del Cinema Europeo.<\/p>\n<p>Il programma dei 4 giorni prevede 12 lungometraggi da tutto il mondo, preceduti da un cortometraggio e un videoclip, in lingua originale, come vuole lo spirito internazionale di Seeyousound, alla presenza di autori e professionisti; inoltre in calendario anche opere di produzione locale o girate in Puglia sempre a tema musica&amp;cinema, e una serie di eventi off come panel, masterclass e concerti.<\/p>\n<p>&#8220;Portare Seeyousound in Puglia e soprattutto a Lecce \u00e8 un grande onore perch\u00e9 la Puglia negli ultimi anni \u00e8 diventata una delle realt\u00e0 di spicco nel panorama della produzione cinematografica e musicale nazionale, capace di attrarre operatori specializzati nell\u2019ideazione di eventi culturali legati al cinema e alla musica.&#8221; Dichiara Sara Valentino, local director di SYS ON THE ROAD \u2013 Lecce \u201cIl mio obiettivo, oltre che creare una forte rete di collaborazione con e tra le realt\u00e0 musicali, audiovisive e culturali della Puglia, sar\u00e0 soprattutto proporre al pubblico pugliese uno sguardo inedito sul panorama del cinema di genere musicale con l\u2019approfondimento degli autori e delle opere pi\u00f9 rappresentative della scena internazionale&#8221;<\/p>\n<p>A ospitare le proiezioni sar\u00e0 il Cinema DB d\u2019Essai, che da vent\u2019anni propone film d\u2019autore, mentre la collaborazione con il neonato DAMS locale vedr\u00e0 la partecipazione attiva degli studenti, chiamati a lavorare su campo e a costruire insieme la rassegna, all\u2019interno del Cinelab Giuseppe Bertolucci. Alla realizzazione della tappa leccese parteciper\u00e0 anche la casa di produzione Passo uno, tra le prime che hanno portato il videoclip a livello professionale in Puglia lavorando con artisti come Negramaro, Silvestri e Ramazzotti; e il Festival del Cinema Europeo che da 19 anni \u00e8 attivo sul territorio promuovendo il dialogo interculturale, operando per la pace e lo sviluppo attraverso il linguaggio senza frontiere del Cinema. La partecipazione di enti e realt\u00e0 locali, tra pubblico e privato, conferma la propensione alla contaminazione, la volont\u00e0 di portare al pubblico una proposta forte e valorizzare il patrimonio culturale pugliese grazie all\u2019atmosfera di scambio portata del festival, la presenza di ospiti e i numerosi artisti del territorio che animeranno il programma con concerti e dj set, in un mix di sonorit\u00e0 dal respiro internazionale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da Torino, Seeyousound allarga gli orizzonti ed esporta la propria formula a Pisa (23 &gt; 27 ottobre), Palermo (8 &gt; 11 novembre) e Lecce (28 novembre &gt; 1 dicembre), prime tappe di un calendario<\/p>\n","protected":false},"author":34,"featured_media":4196,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[694],"class_list":["post-4195","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-festival","tag-seeyousound"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SeeYouSound diventa On The Road e va a Pisa, Palermo e Lecce - Cabiria<\/title>\n<meta name=\"description\" content=\"seeyousound\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SeeYouSound diventa On The Road e va a Pisa, Palermo e Lecce - Cabiria\" \/>\n<meta property=\"og:description\" content=\"seeyousound\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-07T13:19:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/06\/SYS-ON-THE-ROAD_immagine.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1772\" \/>\n\t<meta property=\"og:image:height\" content=\"997\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"SeeYouSound diventa On The Road e va a Pisa, Palermo e Lecce\",\"datePublished\":\"2018-06-07T13:19:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\\\/\"},\"wordCount\":1719,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2018\\\/06\\\/SYS-ON-THE-ROAD_immagine.jpg\",\"keywords\":[\"seeyousound\"],\"articleSection\":[\"festival\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\\\/\",\"name\":\"SeeYouSound diventa On The Road e va a Pisa, Palermo e Lecce - Cabiria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2018\\\/06\\\/SYS-ON-THE-ROAD_immagine.jpg\",\"datePublished\":\"2018-06-07T13:19:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"seeyousound\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2018\\\/06\\\/SYS-ON-THE-ROAD_immagine.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2018\\\/06\\\/SYS-ON-THE-ROAD_immagine.jpg\",\"width\":1772,\"height\":997},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SeeYouSound diventa On The Road e va a Pisa, Palermo e Lecce\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SeeYouSound diventa On The Road e va a Pisa, Palermo e Lecce - Cabiria","description":"seeyousound","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cabiria\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\/","og_locale":"it_IT","og_type":"article","og_title":"SeeYouSound diventa On The Road e va a Pisa, Palermo e Lecce - Cabiria","og_description":"seeyousound","og_url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2018-06-07T13:19:01+00:00","og_image":[{"width":1772,"height":997,"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/06\/SYS-ON-THE-ROAD_immagine.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"SeeYouSound diventa On The Road e va a Pisa, Palermo e Lecce","datePublished":"2018-06-07T13:19:01+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\/"},"wordCount":1719,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/06\/SYS-ON-THE-ROAD_immagine.jpg","keywords":["seeyousound"],"articleSection":["festival"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\/","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\/","name":"SeeYouSound diventa On The Road e va a Pisa, Palermo e Lecce - Cabiria","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/06\/SYS-ON-THE-ROAD_immagine.jpg","datePublished":"2018-06-07T13:19:01+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"seeyousound","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/06\/SYS-ON-THE-ROAD_immagine.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/06\/SYS-ON-THE-ROAD_immagine.jpg","width":1772,"height":997},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/seeyousound-diventa-on-the-road-e-va-a-pisa-palermo-e-lecce\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"SeeYouSound diventa On The Road e va a Pisa, Palermo e Lecce"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/4195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=4195"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/4195\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/4196"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=4195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=4195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=4195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}