{"id":4171,"date":"2018-05-14T11:56:44","date_gmt":"2018-05-14T11:56:44","guid":{"rendered":"http:\/\/web.quotidianopiemontese.it\/cabiria\/?p=4171"},"modified":"2018-05-14T11:56:44","modified_gmt":"2018-05-14T11:56:44","slug":"torna-view-conference-aperte-le-iscrizioni-ai-view-awards","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\/","title":{"rendered":"Torna View Conference, aperte le iscrizioni ai View Awards"},"content":{"rendered":"<p>Anche quest&#8217;anno, dal 19 al 26 ottobre, la citt\u00e0 di Torino ospiter\u00e0 VIEW CONFERENCE\/VIEW FEST, evento internazionale di riferimento dedicato a computer grafica, nuove tecnologie interattive,<!--more--> cinema digitale, animazione 2D\/3D, videogames, effetti visivi, Realt\u00e0 Virtuale e aumentata, e nuove frontiere dello storytelling.<\/p>\n<p>Con essa, tornano anche i VIEW AWARDS 2018, <a href=\"https:\/\/www.viewconference.it\/it\/pages\/awards-and-social-contest\/\">le cui iscrizioni sono ora ufficialmente aperte<\/a>!<br \/>\nAnzitutto, il tradizionale concorso per il miglior cortometraggio animato, aperto a professionisti e studenti del settore: se avete creato un cortometraggio innovativo, animato in grafica 2D\/3D, e realizzato fra il 1 gennaio 2016 ed il 15 settembre 2018, inviatelo a VIEW (via Festhome)\u00a0e partecipate alla competizione. Il primo premio ammonta a 2000 Euro!<br \/>\nE poi l&#8217;ITALIANMIX, che premia con una tavoletta grafica Wacom i corti pi\u00f9 innovativi e originali realizzati da creativi italiani, ed \u00e8\u00a0riservato a opere in animazione, sperimentali o di taglio documentario.<\/p>\n<p>La durata massima della singola opera non pu\u00f2 superare i 30 minuti, e dovr\u00e0 pervenire a VIEW entro e non oltre il 15 settembre 2018. Sono accettati sia progetti individuali che collettivi.<\/p>\n<p>Le opere devono essere accompagnate da screenshot in alta risoluzione del corto e da fotografie, sempre in alta risoluzione, del regista o dei registi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anche quest&#8217;anno, dal 19 al 26 ottobre, la citt\u00e0 di Torino ospiter\u00e0 VIEW CONFERENCE\/VIEW FEST, evento internazionale di riferimento dedicato a computer grafica, nuove tecnologie interattive,<\/p>\n","protected":false},"author":34,"featured_media":4172,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[262,24],"tags":[171,264],"class_list":["post-4171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concorsi","category-festival","tag-view-awards","tag-view-conference"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Torna View Conference, aperte le iscrizioni ai View Awards - Cabiria<\/title>\n<meta name=\"description\" content=\"view awards, view conference\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Torna View Conference, aperte le iscrizioni ai View Awards - Cabiria\" \/>\n<meta property=\"og:description\" content=\"view awards, view conference\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-14T11:56:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/05\/VIEW-Conference-2018.png\" \/>\n\t<meta property=\"og:image:width\" content=\"653\" \/>\n\t<meta property=\"og:image:height\" content=\"317\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Torna View Conference, aperte le iscrizioni ai View Awards\",\"datePublished\":\"2018-05-14T11:56:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\\\/\"},\"wordCount\":201,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2018\\\/05\\\/VIEW-Conference-2018.png\",\"keywords\":[\"view awards\",\"view conference\"],\"articleSection\":[\"concorsi\",\"festival\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\\\/\",\"name\":\"Torna View Conference, aperte le iscrizioni ai View Awards - Cabiria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2018\\\/05\\\/VIEW-Conference-2018.png\",\"datePublished\":\"2018-05-14T11:56:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"view awards, view conference\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2018\\\/05\\\/VIEW-Conference-2018.png\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2018\\\/05\\\/VIEW-Conference-2018.png\",\"width\":653,\"height\":317},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Torna View Conference, aperte le iscrizioni ai View Awards\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Torna View Conference, aperte le iscrizioni ai View Awards - Cabiria","description":"view awards, view conference","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\/","og_locale":"it_IT","og_type":"article","og_title":"Torna View Conference, aperte le iscrizioni ai View Awards - Cabiria","og_description":"view awards, view conference","og_url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2018-05-14T11:56:44+00:00","og_image":[{"width":653,"height":317,"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/05\/VIEW-Conference-2018.png","type":"image\/png"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Torna View Conference, aperte le iscrizioni ai View Awards","datePublished":"2018-05-14T11:56:44+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\/"},"wordCount":201,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/05\/VIEW-Conference-2018.png","keywords":["view awards","view conference"],"articleSection":["concorsi","festival"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\/","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\/","name":"Torna View Conference, aperte le iscrizioni ai View Awards - Cabiria","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/05\/VIEW-Conference-2018.png","datePublished":"2018-05-14T11:56:44+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"view awards, view conference","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/05\/VIEW-Conference-2018.png","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/05\/VIEW-Conference-2018.png","width":653,"height":317},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torna-view-conference-aperte-le-iscrizioni-ai-view-awards\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"Torna View Conference, aperte le iscrizioni ai View Awards"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/4171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=4171"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/4171\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/4172"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=4171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=4171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=4171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}