{"id":4094,"date":"2018-04-12T09:09:46","date_gmt":"2018-04-12T09:09:46","guid":{"rendered":"http:\/\/web.quotidianopiemontese.it\/cabiria\/?p=4094"},"modified":"2018-04-12T09:09:46","modified_gmt":"2018-04-12T09:09:46","slug":"il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\/","title":{"rendered":"Il programma per le scuole di CinemAmbiente Junior &#8211; aperte le prenotazioni"},"content":{"rendered":"<p>Nell\u2019ambito della prossima 21a edizione, il Festival CinemAmbiente propone l\u2019ormai consueto programma riservato specificamente alle scuole, per il quale sono aperte le prenotazioni e che,<!--more--> come sempre, preceder\u00e0 e poi affiancher\u00e0 il cartellone aperto a tutto il pubblico (dal 31 maggio al 5 giugno 2018). Da quest\u2019anno inserito nella nuova sezione CinemAmbiente Junior, dedicata ai molteplici progetti didattici ed educativi elaborati dal Festival per bambini e ragazzi, il programma presenta un palinsesto di iniziative differenziate per ordine e grado scolastico (Primarie, Secondarie di I e II grado) che si protrarr\u00e0 per un mese intero, dal 3 maggio al 5 giugno, e che per l\u2019edizione 2018 si presenta articolato in una formula particolare.<\/p>\n<p>Le proposte cinematografiche saranno, infatti, scandite dai 17 obiettivi contenuti nell\u2019Agenda 2030 per lo Sviluppo Sostenibile, frutto della Risoluzione adottata dall\u2019Assemblea Generale dell\u2019ONU nel 2015. Ogni film in cartellone sar\u00e0 tematicamente legato a una finalit\u00e0 posta dall\u2019Agenda fornendo, cos\u00ec, ad alunni e studenti un\u2019importante occasione per riflettere sulle condizioni attuali del nostro mondo e su un progetto di cambiamento che li coinvolge direttamente, essendo concepito come un programma di sviluppo alternativo in grado di conciliare il soddisfacimento dei bisogni attuali senza compromettere la possibilit\u00e0 delle future generazioni di soddisfare i propri.<br \/>\nTutte le proiezioni saranno accompagnate da incontri con esperti impegnati negli specifici campi operativi connessi al tema del relativo film, scelti all\u2019interno delle realt\u00e0 legate al Festival da storici rapporti di partnership.<br \/>\nAltrettanto, la tradizionale collaborazione con realt\u00e0 e istituzioni cittadine attive nella diffusione della cultura ambientale, come Legambiente, completa l\u2019offerta con le molteplici e diversificate attivit\u00e0 didattico-sperimentali che anche quest\u2019anno il Xk\u00e9? Laboratorio della curiosit\u00e0 e il MAcA &#8211; Museo A come Ambiente hanno concepito appositamente per il Festival e che le scuole potranno prenotare gratuitamente per le giornate dal 28 maggio al 1\u00b0 giugno.<\/p>\n<p><iframe loading=\"lazy\" title=\"Programma Cinemambiente junior\" src=\"https:\/\/www.slideshare.net\/slideshow\/embed_code\/key\/xnN8BZ35DEPtfA\" width=\"479\" height=\"511\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" style=\"border:1px solid #CCC; border-width:1px; margin-bottom:5px; max-width: 100%;\" allowfullscreen> <\/iframe> <\/p>\n<div style=\"margin-bottom:5px\"> <strong> <a href=\"https:\/\/www.slideshare.net\/quotidianopiemontese\/programma-cinemambiente-junior\" title=\"Programma Cinemambiente junior\" target=\"_blank\">Programma Cinemambiente junior<\/a> <\/strong> from <strong><a href=\"https:\/\/www.slideshare.net\/quotidianopiemontese\" target=\"_blank\">Quotidiano Piemontese<\/a><\/strong> <\/div>\n<p>LE PROIEZIONI. Molto ampia la serie di proiezioni rivolta agli studenti delle Scuole Secondarie di II grado, che si collega alle finalit\u00e0 dell\u2019Agenda 2030 toccando temi di estrema attualit\u00e0 e spaziando tra titoli eterogenei per origine e durata: il mediometraggio statunitense Poverty, Inc. (obiettivo 1: \u201cPorre fine ad ogni forma di povert\u00e0 nel mondo\u201d), dedicato all\u2019analisi del sistema degli aiuti umanitari diventato ormai un\u2019\u201cindustria\u201d non sempre benefica per i paesi in via di sviluppo, il lungometraggio canadese Just Eat It \u2013 A Food Waste Story (obiettivo 2: \u201cPorre fine alla fame, raggiungere la sicurezza alimentare, migliorare la nutrizione e promuovere un\u2019agricoltura sostenibile\u201d), che esamina, invece, gli sprechi e i possibili recuperi di cibo nel mondo occidentale, il francese La Soif du monde (obiettivo 6: \u201cGarantire a tutti la disponibilit\u00e0 e la gestione sostenibile dell\u2019acqua e delle strutture igienico-sanitarie\u201d), che affronta il problema del difficile accesso e della cattiva gestione delle risorse idriche nel mondo, La terza rivoluzione industriale (obiettivo 8: \u201cIncentivare una crescita economica duratura, inclusiva e sostenibile, un\u2019occupazione piena e produttiva ed un lavoro dignitoso per tutti\u201d), in cui l\u2019economista Jeremy Rifkin, ispirandosi al suo libro omonimo, delinea linee e tendenze di sviluppo della prossima era della specie umana. E ancora: il lungometraggio tedesco Ghostland (obiettivo 10: \u201cRidurre l\u2019ineguaglianza all\u2019interno di e fra le nazioni\u201d), dedicato a una delle pi\u00f9 antiche culture del nostro pianeta, quella boscimana, e al suo incontro-scontro con la modernit\u00e0 e la societ\u00e0 occidentale, il film britannico Trashed (obiettivo 12: \u201cGarantire modelli sostenibili di produzione e di consumo\u201d), con Jeremy Irons cicerone di un viaggio attraverso l\u2019inquinamento dell\u2019aria, della terra e dell\u2019acqua nei cinque continenti, Una scomoda verit\u00e0 2 (obiettivo 13: \u201cPromuovere azioni, a tutti i livelli, per combattere il cambiamento climatico\u201d), in cui Al Gore, undici anni dopo il suo documentario premio Oscar, torna a parlare di cause ed effetti del riscaldamento globale, l\u2019italiano So It Flows \u2013 Water, Refugees, Citizens (obiettivo 17: \u201cRafforzare i mezzi di attuazione e rinnovare il partenariato mondiale per lo sviluppo sostenibile\u201d), nato dal progetto di cooperazione territoriale Safe Helath and Water Management, che ha portato un gruppo di giovani dell\u2019area metropolitana di Torino nel Nord-est del Libano, in un\u2019area fortemente colpita dalla crisi dei profughi siriani. Il cartellone per le Secondarie di II grado si completa dando spazio all\u2019evento di premiazione alla quarta edizione del bando di Media Education, ideato dal Museo Nazionale del Cinema e dal Parco Arte Vivente, The City I Like (obiettivo 11: \u201cRendere le citt\u00e0 e gli insediamenti umani inclusivi, sicuri, duraturi e sostenibili\u201d), che ha promosso la produzione di video e fotografie realizzati da ragazzi tra i 14 e i 19 anni, invitati a esplorare e raccontare il complesso mondo della ritualit\u00e0, tradizionale e contemporanea.<\/p>\n<p>Il cartellone riservato agli studenti delle Scuole Secondarie di I grado presenta quattro titoli che si collegano a punti dell\u2019Agenda cruciali per la qualit\u00e0 della vita individuale e collettiva e per le prospettive di sviluppo: il documentario statunitense che analizza la pericolosit\u00e0 del fast food e della cattiva alimentazione Super Size Me (obiettivo 3: \u201cAssicurare la salute e il benessere per tutti e per tutte le et\u00e0\u201d), il film di Otto Bell dedicato alla giovane mongola di antica stirpe kazakha decisa a imparare un mestiere riservato per tradizione solo agli uomini La principessa e l\u2019aquila (obiettivo 5: \u201cRaggiungere l\u2019uguaglianza di genere ed emancipare tutte le donne e le ragazze\u201d), il cortometraggio L\u2019uomo che piantava gli alberi (obiettivo 16: \u201cPromuovere societ\u00e0 pacifiche e inclusive\u201d), diretto da Fr\u00e9d\u00e9ric Back e tratto dall\u2019opera di Jean Giono dedicata al solitario pastore che in un\u2019epoca di guerre e distruzione coltiva la vita. Alla proiezione \u00e8 abbinato il cortometraggio torinese Grazie alberi, frutto del lavoro di un gruppo cittadino a sostegno dell\u2019ambiente che promuove e sensibilizza alla protezione del patrimonio arboreo. Completa il cartellone riservato alle Secondarie di I grado Domani (obiettivo 9: \u201cCostruire un\u2019infrastruttura resiliente e promuovere l\u2019innovazione ed una industrializzazione equa, responsabile e sostenibile\u201d), il lungometraggio dei francesi Cyril Dion e M\u00e9lanie Laurent che mostra possibili soluzioni concrete a diversi problemi contemporanei presentando modelli positivi sperimentati in diverse parti del mondo in materia di agricoltura, energia, economia, educazione, politica.<\/p>\n<p>Quattro anche i film proposti agli allievi delle Scuole Primarie per avvicinarli ad altrettanti temi dell\u2019Agenda 2030 legati alla tutela ambientale e sociale: due noti titoli d\u2019animazione, la toccante favola di Hayao Miyazaki di cui \u00e8 protagonista la pesciolina da salvare Ponyo sulla scogliera (obiettivo 14: \u201cConservare e utilizzare in modo durevole gli oceani, i mari e le risorse marine per uno sviluppo sostenibile\u201d) e il celebre film della Pixar Monsters &amp; Co. (obiettivo 7: \u201cAssicurare a tutti l\u2019accesso a sistemi di energia economici, affidabili, sostenibili e moderni\u201d), ambientato nella distopica Mostropoli, dove le urla spaventate dei bambini sono il combustile di nuova generazione, cui si aggiungono il recentissimo lungometraggio britannico Earth \u2013 Un giorno straordinario (obiettivo 15: \u201cProteggere, ripristinare e favorire un uso sostenibile dell\u2019ecosistema terrestre\u201d), viaggio spettacolare attraverso le meraviglie del nostro Pianeta e del mondo animale, e il francese Vado a scuola (obiettivo 4: \u201cFornire un\u2019educazione di qualit\u00e0, equa ed inclusiva e opportunit\u00e0 di apprendimento per tutti\u201d), sulle distanze e le difficolt\u00e0 affrontate ogni giorno dai bambini che vivono in paesi poveri per raggiungere le loro aule.<\/p>\n<p>Novit\u00e0 strutturale della 21a edizione del Festival, la sezione CinemAmbiente Junior \u00e8 stata inaugurata dal bando di un nuovo concorso nazionale rivolto alle scuole Primarie, Secondarie di I e II grado, che, scaduto il 31 marzo, ha riscosso notevole interesse, raggiungendo la cifra di oltre 300 cortometraggi iscritti all\u2019edizione d\u2019esordio. CinemAmbiente junior nasce dall\u2019esperienza di EcoKids, la sezione speciale del programma che, fin dal 1998, il Festival ha dedicato alle scuole, proponendo agli studenti proiezioni a tema, accompagnate da interventi, dibattiti e momenti di approfondimento con educatori ed esperti ambientali. A sua volta, dall\u2019esperienza di EcoKids e dalla volont\u00e0 di valorizzare l\u2019archivio filmico del Festival, uno dei pi\u00f9 ricchi di cinema a tematica ambientale a livello internazionale e il maggiore a livello nazionale, nel 2008 \u00e8 nato CinemAmbiente TV &#8211; Film per l\u2019educazione ambientale, progetto didattico che integra materiali audiovisivi tematici e dossier di approfondimento pensati per i diversi gradi scolastici.<br \/>\nCinemAmbiente Junior \u00e8 realizzato dal Festival in collaborazione con Legambiente, MAcA \u2013 Museo A come Ambiente, Xk\u00e9? Il laboratorio della curiosit\u00e0, CiAl, CISV, Citt\u00e0 Metropolitana di Torino, Co.Co.Pa., Cooperativa Arcobaleno, Dipartimento educazione del Museo Nazionale del Cinema, Iren, Elettricit\u00e0 Futura, Hydroaid, Il Ragazzo Selvaggio, Museo Regionale di Scienze Naturali, SMAT \u2013 Societ\u00e0 Metropolitane Acque Torino, Smemoranda, Una Buona Occasione \u2013 Regione Piemonte.<\/p>\n<p>Il Festival CinemAmbiente \u00e8 organizzato dall\u2019Associazione CinemAmbiente e dal Museo Nazionale del Cinema.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nell\u2019ambito della prossima 21a edizione, il Festival CinemAmbiente propone l\u2019ormai consueto programma riservato specificamente alle scuole, per il quale sono aperte le prenotazioni e che,<\/p>\n","protected":false},"author":34,"featured_media":4095,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[1268],"class_list":["post-4094","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-festival","tag-cinemambiente-junior"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il programma per le scuole di CinemAmbiente Junior - aperte le prenotazioni - Cabiria<\/title>\n<meta name=\"description\" content=\"cinemambiente junior\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/cabiria\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il programma per le scuole di CinemAmbiente Junior - aperte le prenotazioni - Cabiria\" \/>\n<meta property=\"og:description\" content=\"cinemambiente junior\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/cabiria\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-12T09:09:46+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/04\/Vado-a-scuola.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1084\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Il programma per le scuole di CinemAmbiente Junior &#8211; aperte le prenotazioni\",\"datePublished\":\"2018-04-12T09:09:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\\\/\"},\"wordCount\":1415,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2018\\\/04\\\/Vado-a-scuola.jpg\",\"keywords\":[\"cinemambiente junior\"],\"articleSection\":[\"festival\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\\\/\",\"name\":\"Il programma per le scuole di CinemAmbiente Junior - aperte le prenotazioni - Cabiria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2018\\\/04\\\/Vado-a-scuola.jpg\",\"datePublished\":\"2018-04-12T09:09:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"cinemambiente junior\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2018\\\/04\\\/Vado-a-scuola.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2018\\\/04\\\/Vado-a-scuola.jpg\",\"width\":2000,\"height\":1084},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il programma per le scuole di CinemAmbiente Junior &#8211; aperte le prenotazioni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il programma per le scuole di CinemAmbiente Junior - aperte le prenotazioni - Cabiria","description":"cinemambiente junior","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/cabiria\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\/","og_locale":"it_IT","og_type":"article","og_title":"Il programma per le scuole di CinemAmbiente Junior - aperte le prenotazioni - Cabiria","og_description":"cinemambiente junior","og_url":"http:\/\/web.quotidianopiemontese.it\/cabiria\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2018-04-12T09:09:46+00:00","og_image":[{"width":2000,"height":1084,"url":"http:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/04\/Vado-a-scuola.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Il programma per le scuole di CinemAmbiente Junior &#8211; aperte le prenotazioni","datePublished":"2018-04-12T09:09:46+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\/"},"wordCount":1415,"commentCount":0,"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/04\/Vado-a-scuola.jpg","keywords":["cinemambiente junior"],"articleSection":["festival"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/cabiria\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\/","url":"http:\/\/web.quotidianopiemontese.it\/cabiria\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\/","name":"Il programma per le scuole di CinemAmbiente Junior - aperte le prenotazioni - Cabiria","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\/#primaryimage"},"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/04\/Vado-a-scuola.jpg","datePublished":"2018-04-12T09:09:46+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"cinemambiente junior","breadcrumb":{"@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/cabiria\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/04\/Vado-a-scuola.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/04\/Vado-a-scuola.jpg","width":2000,"height":1084},{"@type":"BreadcrumbList","@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/il-programma-per-le-scuole-di-cinemambiente-junior-aperte-le-prenotazioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"Il programma per le scuole di CinemAmbiente Junior &#8211; aperte le prenotazioni"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/4094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=4094"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/4094\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/4095"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=4094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=4094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=4094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}