{"id":4077,"date":"2018-03-26T12:59:11","date_gmt":"2018-03-26T12:59:11","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/cabiria\/?p=4077"},"modified":"2018-03-26T12:59:11","modified_gmt":"2018-03-26T12:59:11","slug":"torino-torna-cinemautismo-la-x-edizione","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-torna-cinemautismo-la-x-edizione\/","title":{"rendered":"A Torino torna CinemAutismo per la X edizione"},"content":{"rendered":"<p>Cinemautismo, la prima rassegna cinematografica italiana dedicata all\u2019autismo e alla sindrome di Asperger, compie 10 anni e festeggia con un\u2019edizione speciale, ad ingresso gratuito, che si presenta con un ricco<!--more--> calendario di 6 serate di cinema, dal 2 al 7 aprile, e 12 proiezioni di film da tutto il mondo tornando, anche quest\u2019anno, a colorare di blu, colore simbolo dell&#8217;autismo, la citt\u00e0 di Torino.<\/p>\n<p>Per la ricorrenza dei dieci anni, il programma di cinemautismo, curato da Marco Mastino e Ginevra Tomei e organizzato dall\u2019Associazione Museo Nazionale del Cinema, vedr\u00e0 affiancati a nuovi lungometraggi e anteprime nazionali, anche alcuni dei film pi\u00f9 apprezzati delle passate edizioni che saranno presentati al pubblico affezionato e ai nuovi spettatori al Cinema Massimo, al Cinema Lux, al Cinema Greenwich Village e al Cinema Classico.<\/p>\n<p>Siamo felici e sorpresi di festeggiare la decima edizione di cinemautismo &#8211; commentano i curatori Marco Mastino e Ginevra Tomei &#8211; Non ci saremmo mai aspettati che, partendo da una singola giornata di proiezioni, che aveva coinvolto un centinaio di persone nel 2009, saremmo arrivati alle oltre 5.000 presenze in tutti questi anni. cinemautismo negli anni \u00e8 cresciuto sino a diventare un progetto a pi\u00f9 ampio spettro, che coinvolge scuole, associazioni e festival sparsi sul territorio italiano. Nonostante lo scarso interesse dei distributori italiani, le pellicole straniere che trattano l\u2019autismo sono numerose: abbiamo proiettato film provenienti da pi\u00f9 di venti Paesi permettendo cos\u00ec al nostro pubblico di avere punti di vista differenti, a livello estetico e culturale, su un argomento che per molti \u00e8 ancora molto poco conosciuto e accettato. Siamo per questo ancora pi\u00f9 contenti di presentare in anteprima nella giornata del 2 aprile, il film italiano &#8220;Quanto Basta&#8221; di Francesco Falaschi, che ha visto nella sua realizzazione il coinvolgimento di persone con autismo. Continuiamo a ritenere che il cinema abbia la fortissima capacit\u00e0 di coinvolgere sul piano emotivo lo spettatore, facilitando il processo di scoperta, conoscenza e accettazione della neurodiversit\u00e0.<\/p>\n<p>La rassegna inaugurer\u00e0 luned\u00ec 2 aprile, Giornata Mondiale della Consapevolezza dell&#8217;Autismo, con una doppia proiezione. Al pubblico, nel pomeriggio di Pasquetta, verr\u00e0 proposto L&#8217;autismo in&#8230; corto, una selezione di cortometraggi provenienti da tutto il mondo che vedr\u00e0 alternarsi animazione, finzione e documentario. In collaborazione con l&#8217;ASFF &#8211; Asperger Film Festival di Roma, primo concorso cinematografico organizzato con la partecipazione di ragazzi con sindrome di Asperger (ore 18.00, Cinema Massimo).<\/p>\n<p>La sera verr\u00e0 presentato in anteprima nazionale Quanto Basta di Francesco Falaschi, commedia on the road con protagonisti Vinicio Marchioni (Romanzo Criminale &#8211; La serie), Luigi Fedele (Piuma) e Valeria Solarino (Smetto quando voglio, Vallanzasca &#8211; Gli angeli del male, Signorinaeffe). La pellicola racconta l&#8217;incontro tra uno chef con precedenti penali e un giovane ragazzo con sindrome di Asperger appassionato di cucina. Alla proiezione saranno presenti il regista e parte del cast (ore 20.30, Cinema Massimo).<\/p>\n<p>La serata di marted\u00ec 3 aprile, sar\u00e0 dedicata ai siblings, i fratelli di persone con disabilit\u00e0. In prima serata la proiezione della pellicola australiana, vincitrice dell&#8217;Orso di Cristallo al Festival di Berlino 2008, The Black Balloon di Elissa Down. Il percorso verso l&#8217;accettazione da parte dell&#8217;adolescente Thomas del fratello autistico Charlie. (20.15 Cinema Lux). A seguire la commedia svedese, candidata al premio Oscar come migliore film straniero nel 2011, Simple Simon di Andreas \u00d6hman, incentrata sulla ricerca di Simon, giovane Asperger, di una fidanzata per il fratello Sam (22.30 Cinema Lux).<\/p>\n<p>La terza giornata di mercoled\u00ec 4 aprile avr\u00e0 come tema portante il rapporto genitore-figlio. Alle 20.15 verr\u00e0 proiettato Ocean Heaven di Xue Xiaolu, delicato e pluripremiato film cinese con Jet Li nei panni di un padre che tenta di avviare verso l\u2019autonomia il figlio autistico (20.15 Cinema Greenwich Village). In seconda serata il lungometraggio, a met\u00e0 tra animazione e documentario, Maria y yo di F\u00e9lix Fern\u00e1ndez de Castro (22.30 Cinema Greenwich Village).<\/p>\n<p>Gioved\u00ec 5 aprile, la rassegna avr\u00e0 come fil rouge le relazioni sentimentali. Si aprir\u00e0 con l&#8217;anteprima nazionale del film canadese Roaming di Michael Ray Fox, in cui il protagonista affronta i problemi della vita adulta, tra desiderio di vita amorosa, lavoro e accettazione della propria condizione di persona nello spettro autistico (20.15 Cinema Lux). A chiudere la serata, verr\u00e0 proiettato Autism in Love di Matt Fuller, documentario incentrato sul punto di vista delle persone con autismo e sul loro modo di vivere le emozioni e le relazioni (22.30 Cinema Lux).<\/p>\n<p>Essere nello spettro autistico, sar\u00e0 il tema di venerd\u00ec 6 aprile. In prima serata, l&#8217;anteprima nazionale di Keep the Change di Rachel Israel, commedia romantica, unica nel suo genere, in cui gli attori sono tutte persone con autismo (20.15 Cinema Greenwich Village). A concludere, il documentario Neurotypical di Adam Larsen, che esplora, attraverso lo sguardo di persone appartenenti allo spettro autistico, il significato della parola \u201cnormale\u201d nella societ\u00e0 di oggi (22.30 Cinema Greenwich Village).<\/p>\n<p>Nella serata finale di sabato 7 aprile, la rassegna si chiuder\u00e0 con la proiezione di Please Stand By di Ben Lewin, pellicola presentata all&#8217;ultima Festa del Cinema di Roma, con protagoniste Dakota Fanning e Toni Collette (20.15 Cinema Classico). A seguire, il premiatissimo film di animazione Mary and Max di Adam Elliot, poetico racconto dell\u2019amicizia epistolare tra Mary, una bambina australiana, e Max, un newyorkese con Sindrome di Asperger (22.30 Cinema Classico).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cinemautismo, la prima rassegna cinematografica italiana dedicata all\u2019autismo e alla sindrome di Asperger, compie 10 anni e festeggia con un\u2019edizione speciale, ad ingresso gratuito, che si presenta con un ricco<\/p>\n","protected":false},"author":34,"featured_media":4078,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[387],"class_list":["post-4077","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-festival","tag-cinemautismo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Torino torna CinemAutismo per la X edizione - Cabiria<\/title>\n<meta name=\"description\" content=\"cinemautismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-torna-cinemautismo-la-x-edizione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Torino torna CinemAutismo per la X edizione - Cabiria\" \/>\n<meta property=\"og:description\" content=\"cinemautismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-torna-cinemautismo-la-x-edizione\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-26T12:59:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/03\/2_aprile_QUANTO-BASTA-di-Francesco-Falaschi_nella-foto-Vinicio-Marchioni-e-Valeria-Solarino.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1299\" \/>\n\t<meta property=\"og:image:height\" content=\"731\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torino-torna-cinemautismo-la-x-edizione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torino-torna-cinemautismo-la-x-edizione\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"A Torino torna CinemAutismo per la X edizione\",\"datePublished\":\"2018-03-26T12:59:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torino-torna-cinemautismo-la-x-edizione\\\/\"},\"wordCount\":862,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torino-torna-cinemautismo-la-x-edizione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2018\\\/03\\\/2_aprile_QUANTO-BASTA-di-Francesco-Falaschi_nella-foto-Vinicio-Marchioni-e-Valeria-Solarino.jpg\",\"keywords\":[\"cinemautismo\"],\"articleSection\":[\"festival\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torino-torna-cinemautismo-la-x-edizione\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torino-torna-cinemautismo-la-x-edizione\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torino-torna-cinemautismo-la-x-edizione\\\/\",\"name\":\"A Torino torna CinemAutismo per la X edizione - Cabiria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torino-torna-cinemautismo-la-x-edizione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torino-torna-cinemautismo-la-x-edizione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2018\\\/03\\\/2_aprile_QUANTO-BASTA-di-Francesco-Falaschi_nella-foto-Vinicio-Marchioni-e-Valeria-Solarino.jpg\",\"datePublished\":\"2018-03-26T12:59:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"cinemautismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torino-torna-cinemautismo-la-x-edizione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torino-torna-cinemautismo-la-x-edizione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torino-torna-cinemautismo-la-x-edizione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2018\\\/03\\\/2_aprile_QUANTO-BASTA-di-Francesco-Falaschi_nella-foto-Vinicio-Marchioni-e-Valeria-Solarino.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2018\\\/03\\\/2_aprile_QUANTO-BASTA-di-Francesco-Falaschi_nella-foto-Vinicio-Marchioni-e-Valeria-Solarino.jpg\",\"width\":1299,\"height\":731,\"caption\":\"QUANTO BASTA di Francesco Falaschi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torino-torna-cinemautismo-la-x-edizione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Torino torna CinemAutismo per la X edizione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Torino torna CinemAutismo per la X edizione - Cabiria","description":"cinemautismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-torna-cinemautismo-la-x-edizione\/","og_locale":"it_IT","og_type":"article","og_title":"A Torino torna CinemAutismo per la X edizione - Cabiria","og_description":"cinemautismo","og_url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-torna-cinemautismo-la-x-edizione\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2018-03-26T12:59:11+00:00","og_image":[{"width":1299,"height":731,"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/03\/2_aprile_QUANTO-BASTA-di-Francesco-Falaschi_nella-foto-Vinicio-Marchioni-e-Valeria-Solarino.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-torna-cinemautismo-la-x-edizione\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-torna-cinemautismo-la-x-edizione\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"A Torino torna CinemAutismo per la X edizione","datePublished":"2018-03-26T12:59:11+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-torna-cinemautismo-la-x-edizione\/"},"wordCount":862,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-torna-cinemautismo-la-x-edizione\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/03\/2_aprile_QUANTO-BASTA-di-Francesco-Falaschi_nella-foto-Vinicio-Marchioni-e-Valeria-Solarino.jpg","keywords":["cinemautismo"],"articleSection":["festival"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-torna-cinemautismo-la-x-edizione\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-torna-cinemautismo-la-x-edizione\/","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-torna-cinemautismo-la-x-edizione\/","name":"A Torino torna CinemAutismo per la X edizione - Cabiria","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-torna-cinemautismo-la-x-edizione\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-torna-cinemautismo-la-x-edizione\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/03\/2_aprile_QUANTO-BASTA-di-Francesco-Falaschi_nella-foto-Vinicio-Marchioni-e-Valeria-Solarino.jpg","datePublished":"2018-03-26T12:59:11+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"cinemautismo","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-torna-cinemautismo-la-x-edizione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-torna-cinemautismo-la-x-edizione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-torna-cinemautismo-la-x-edizione\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/03\/2_aprile_QUANTO-BASTA-di-Francesco-Falaschi_nella-foto-Vinicio-Marchioni-e-Valeria-Solarino.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2018\/03\/2_aprile_QUANTO-BASTA-di-Francesco-Falaschi_nella-foto-Vinicio-Marchioni-e-Valeria-Solarino.jpg","width":1299,"height":731,"caption":"QUANTO BASTA di Francesco Falaschi"},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-torna-cinemautismo-la-x-edizione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"A Torino torna CinemAutismo per la X edizione"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/4077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=4077"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/4077\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/4078"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=4077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=4077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=4077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}