{"id":3928,"date":"2017-12-10T15:12:45","date_gmt":"2017-12-10T15:12:45","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/cabiria\/?p=3928"},"modified":"2017-12-10T15:12:45","modified_gmt":"2017-12-10T15:12:45","slug":"linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\/","title":{"rendered":"L&#8217;invenzione senza futuro. Viaggio nel cinema al Teatro della Juta"},"content":{"rendered":"<p>Sabato 16 dicembre al Teatro della Juta (ore 21) andr\u00e0 in scena lo spettacolo L&#8217;INVENZIONE SENZA FUTURO, Viaggio nel Cinema in 60 Minuti (di Federico Giani, Celeste Gugliandolo, Francesca Montanino e Mauro Parrinello)<!--more-->, una produzione: Tedac\u00e0\/Compagnia DeiDemoni e Offrome, in collaborazione con Fondazione Luzzati \u2013 Teatro della Tosse.<\/p>\n<p>\u201cUn\u2019invenzione senza futuro\u201d. Cos\u00ec Antoine Lumi\u00e8re (padre dei celebri fratelli) definisce il cinema, un progetto a cui i suoi figli stanno lavorando. Ma loro sono caparbi, determinati ad arrivare fino in fondo alle loro intuizioni: forse uno dei due lo \u00e8 di pi\u00f9, mentre l\u2019altro \u00e8 condizionato dalle parole del padre; forse la necessit\u00e0 di scoprire se il progetto funziona, cela in realt\u00e0 &#8211; per uno dei due &#8211; il desiderio di conquistare la donna amata.<br \/>\nLo spettacolo, lieve, toccante e poetico, racconta il rapporto tra due fratelli, Louis e Auguste &#8211; che stanno per rivoluzionare la visione del mondo &#8211; e la ricerca dell\u2019amore, attraverso un viaggio che si trasforma e si snoda per mezzo di scene di film, incontri, suoni e visioni dal sapore delle pellicole che ci hanno appassionato in pi\u00f9 di un secolo di cinema. Il racconto di una vita che si fa metafora delle evoluzioni del cinema, delle sue pi\u00f9 importanti invenzioni: dal muto al sonoro, dal montaggio al colore. Il contributo (in parte inconsapevole) di questi nostri due fratelli ad un progetto cos\u00ec rivoluzionario come l\u2019immagine in movimento, insieme con il desiderio amoroso, sono i motori per raccontare anche l\u2019illusione stessa della vita.<\/p>\n<p>In scena Federico Giani (diplomato presso la scuola del Teatro Stabile di Genova; nel suo percorso di formazione ha avuto modo di studiare recitazione con Anna Laura Messeri, Massimo Mesciulam, Fabrizio Contri, Alessandra Schiavoni ed Enrico Bonavera); Celeste Gugliandolo, diplomata in pianoforte al conservatorio di Messina e in violoncello al Conservatorio di Torino; si classifica al secondo posto al talent show X Factor, in gruppo con altri 3 cantanti-attori di Tedac\u00e0, &#8220;i Moderni&#8221; e si divide tra teatro e musica; Mauro Parrinello, allievo di Michele Di Mauro e Leo Muscato; dopo il diploma alla Scuola di Recitazione del Teatro Stabile di Genova, \u00e8 diretto da Valerio Binasco in Noccioline, di Fausto Paravidino per il Teatro Eliseo di Roma. Le musiche sono di Giorgio Mirto.<\/p>\n<p>Il Teatro della Juta fa parte del progetto della Fondazione Piemonte dal Vivo chiamato \u201cCorto Circuito\u201d, nato per favorire l\u2019attivit\u00e0 di giovani artisti in Piemonte e creare un\u2019occasione, per le varie compagnie, di contribuire allo sviluppo culturale e sociale del proprio territorio. La stagione ha il patrocinio del Comune di Arquata, il sostegno di Acos Energia e della Fondazione CRT. Il Teatro della Juta collabora inoltre con il Consorzio Le Botteghe di Arquata e con il Distretto del Novese.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabato 16 dicembre al Teatro della Juta (ore 21) andr\u00e0 in scena lo spettacolo L&#8217;INVENZIONE SENZA FUTURO, Viaggio nel Cinema in 60 Minuti (di Federico Giani, Celeste Gugliandolo, Francesca Montanino e Mauro Parrinello)<\/p>\n","protected":false},"author":34,"featured_media":3929,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-3928","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;invenzione senza futuro. Viaggio nel cinema al Teatro della Juta - Cabiria<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;invenzione senza futuro. Viaggio nel cinema al Teatro della Juta - Cabiria\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-10T15:12:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/12\/invenzione_senza_futuro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2218\" \/>\n\t<meta property=\"og:image:height\" content=\"1478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"L&#8217;invenzione senza futuro. Viaggio nel cinema al Teatro della Juta\",\"datePublished\":\"2017-12-10T15:12:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\\\/\"},\"wordCount\":463,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2017\\\/12\\\/invenzione_senza_futuro.jpg\",\"articleSection\":[\"eventi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\\\/\",\"name\":\"L'invenzione senza futuro. Viaggio nel cinema al Teatro della Juta - Cabiria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2017\\\/12\\\/invenzione_senza_futuro.jpg\",\"datePublished\":\"2017-12-10T15:12:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2017\\\/12\\\/invenzione_senza_futuro.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2017\\\/12\\\/invenzione_senza_futuro.jpg\",\"width\":2218,\"height\":1478},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;invenzione senza futuro. Viaggio nel cinema al Teatro della Juta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'invenzione senza futuro. Viaggio nel cinema al Teatro della Juta - Cabiria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cabiria\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\/","og_locale":"it_IT","og_type":"article","og_title":"L'invenzione senza futuro. Viaggio nel cinema al Teatro della Juta - Cabiria","og_url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2017-12-10T15:12:45+00:00","og_image":[{"width":2218,"height":1478,"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/12\/invenzione_senza_futuro.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"L&#8217;invenzione senza futuro. Viaggio nel cinema al Teatro della Juta","datePublished":"2017-12-10T15:12:45+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\/"},"wordCount":463,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/12\/invenzione_senza_futuro.jpg","articleSection":["eventi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\/","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\/","name":"L'invenzione senza futuro. Viaggio nel cinema al Teatro della Juta - Cabiria","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/12\/invenzione_senza_futuro.jpg","datePublished":"2017-12-10T15:12:45+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/12\/invenzione_senza_futuro.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/12\/invenzione_senza_futuro.jpg","width":2218,"height":1478},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/linvenzione-senza-futuro-viaggio-nel-cinema-al-teatro-della-juta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"L&#8217;invenzione senza futuro. Viaggio nel cinema al Teatro della Juta"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/3928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=3928"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/3928\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/3929"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=3928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=3928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=3928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}