{"id":3726,"date":"2017-07-05T06:06:49","date_gmt":"2017-07-05T06:06:49","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/cabiria\/?p=3726"},"modified":"2017-07-05T06:06:49","modified_gmt":"2017-07-05T06:06:49","slug":"cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\/","title":{"rendered":"Sono cominciate le riprese del film sulla cabina dell&#8217;Arte diffusa"},"content":{"rendered":"<p>L\u2019Associazione Culturale Trib\u00f9 del Badnightcaf\u00e8 ha avviato la lavorazione del film sulla Cabina dell\u2019Arte Diffusa. Completata la scelta del cast e l\u2019individuazione delle locations, \u00e8 stata avviata la fase operativa delle riprese<!--more--> del film.<\/p>\n<p>Prodotto in forma indipendente e in totale assenza di finanziamenti, il film segue le linee di principio del progetto della Cabina: tutto ci\u00f2 che si \u00e8 reso necessario, e si render\u00e0 necessario per la sua realizzazione, compresa la presenza degli attori e di tutte le persone coinvolte, \u00e8 realizzato in totale condivisione di risorse e secondo i dettami delle reti di collaborazione.<\/p>\n<p>La sceneggiatura del film nasce dal lavoro creativo del collettivo dell\u2019Associazione, la regia \u00e8 affidata a Luigi Mezzacappa, gi\u00e0 regista dei precedenti lavori dell\u2019Associazione, con musiche originali di Sandro Filia.<\/p>\n<p>Il tema della narrazione ruota intorno al sistema dell\u2019arte e al mondo intorno a questo.<\/p>\n<p>L\u2019uscita del film \u00e8 prevista per settembre, con una preview ad inviti ed una prima ufficiale pubblica.<\/p>\n<p>Il progetto della Cabina dell\u2019Arte Diffusa ha il patrocinio della Circoscrizione 4 di Torino.<\/p>\n<p>Ne seguiremo l&#8217;evolversi perch\u00e8 in parte questa storia ci riguarda da vicino.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Associazione Culturale Trib\u00f9 del Badnightcaf\u00e8 ha avviato la lavorazione del film sulla Cabina dell\u2019Arte Diffusa. Completata la scelta del cast e l\u2019individuazione delle locations, \u00e8 stata avviata la fase operativa delle riprese<\/p>\n","protected":false},"author":34,"featured_media":3728,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[1227],"class_list":["post-3726","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-set","tag-la-cabina-dellarte-diffusa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sono cominciate le riprese del film sulla cabina dell&#039;Arte diffusa - Cabiria<\/title>\n<meta name=\"description\" content=\"la cabina dell&#039;arte diffusa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sono cominciate le riprese del film sulla cabina dell&#039;Arte diffusa - Cabiria\" \/>\n<meta property=\"og:description\" content=\"la cabina dell&#039;arte diffusa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-05T06:06:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/07\/cabina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Sono cominciate le riprese del film sulla cabina dell&#8217;Arte diffusa\",\"datePublished\":\"2017-07-05T06:06:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\\\/\"},\"wordCount\":198,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2017\\\/07\\\/cabina.jpg\",\"keywords\":[\"la cabina dell'arte diffusa\"],\"articleSection\":[\"set\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\\\/\",\"name\":\"Sono cominciate le riprese del film sulla cabina dell'Arte diffusa - Cabiria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2017\\\/07\\\/cabina.jpg\",\"datePublished\":\"2017-07-05T06:06:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"la cabina dell'arte diffusa\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2017\\\/07\\\/cabina.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2017\\\/07\\\/cabina.jpg\",\"width\":1024,\"height\":680},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sono cominciate le riprese del film sulla cabina dell&#8217;Arte diffusa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sono cominciate le riprese del film sulla cabina dell'Arte diffusa - Cabiria","description":"la cabina dell'arte diffusa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cabiria\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\/","og_locale":"it_IT","og_type":"article","og_title":"Sono cominciate le riprese del film sulla cabina dell'Arte diffusa - Cabiria","og_description":"la cabina dell'arte diffusa","og_url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2017-07-05T06:06:49+00:00","og_image":[{"width":1024,"height":680,"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/07\/cabina.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Sono cominciate le riprese del film sulla cabina dell&#8217;Arte diffusa","datePublished":"2017-07-05T06:06:49+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\/"},"wordCount":198,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/07\/cabina.jpg","keywords":["la cabina dell'arte diffusa"],"articleSection":["set"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\/","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\/","name":"Sono cominciate le riprese del film sulla cabina dell'Arte diffusa - Cabiria","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/07\/cabina.jpg","datePublished":"2017-07-05T06:06:49+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"la cabina dell'arte diffusa","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/07\/cabina.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/07\/cabina.jpg","width":1024,"height":680},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/cominciate-le-riprese-del-film-sulla-cabina-dellarte-diffusa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"Sono cominciate le riprese del film sulla cabina dell&#8217;Arte diffusa"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/3726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=3726"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/3726\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/3728"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=3726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=3726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=3726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}