{"id":3635,"date":"2017-06-14T09:55:36","date_gmt":"2017-06-14T09:55:36","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/cabiria\/?p=3635"},"modified":"2017-06-14T09:55:36","modified_gmt":"2017-06-14T09:55:36","slug":"casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\/","title":{"rendered":"Casting, si cercano attori, attrici e comparse per un film sulla Cabina dell&#8217;Arte Diffusa"},"content":{"rendered":"<p>L\u2019associazione Culturale senza fini di lucro Trib\u00f9 del Badnightcaf\u00e8 con il presente annuncio pubblico avvia le selezioni per la composizione del cast di un film indipendente di immediata realizzazione. Il film verr\u00e0 girato a <!--more-->Torino e racconter\u00e0 la storia della Cabina dell&#8217;arte diffusa. La regia \u00e8 di Luigi Mezzacappa.<\/p>\n<p>Il film non solo \u00e8 autoprodotto, ma non \u00e8 finanziato in alcun modo: non abbiamo contributi, sponsor, stakeholders o mecenati di alcun genere.<br \/>\nViene realizzato in forma totalmente gratuita da tutti i componenti del team che in qualsiasi forma ne contribuiscono alla sua realizzazione.<br \/>\nNon viene garantita visibilit\u00e0 farlocca, non disponiamo di canali di distribuzione n\u00e9 ufficiali n\u00e9 clandestini, non facciamo questo film n\u00e9 per il successo, n\u00e9 per il denaro, e nemmeno per l\u2019amore.<\/p>\n<p>Chi partecipa lo fa conscio di aderire integralmente alle finalit\u00e0 di aggregazione artistica che costituiscono la mission dell\u2019Associazione e dei progetti da questa sino ad ora realizzati e di prossima realizzazione.<br \/>\nL\u2019unica cosa che possiamo dire \u00e8 che forse in futuro a qualcuno potr\u00e0 capitare di dire \u201cio c\u2019ero\u201d, ma non prendetela come una verit\u00e0 accertata, tutt\u2019altro.<\/p>\n<p>Il casting si svolger\u00e0 sabato 17 giugno alla Tesoriera a partire dalle ore 16.<\/p>\n<p>Per il film vengono pertanto ricercate le seguenti figure:<br \/>\nUNA ATTRICE anni: 30-40 non altissima , bruna, atteggiamento vivace nel parlare muoversi e gesticolare \u00e8 una donna indipendente, abituata a muoversi, ad affrontare i problemi quotidiani, sicura di s\u00e9 pur conoscendo i propri limiti \u00e8 richiesta una almeno minima esperienza interpretativa pregressa, cinema o teatro, anche a livello amatoriale.<br \/>\nUN ATTORE (A) anni: &gt; 40 pelle chiara, veste con uno stile serio, borghese a chi lo incontra la prima volta sembra un professionista avviato in carriera \u00e8 richiesta una almeno minima esperienza interpretativa pregressa, cinema o teatro, anche a livello amatoriale.<br \/>\nUN ATTORE (B) anni: 40-50 eventualmente anche leggermente sovrappeso, \u00e8 un uomo che vive nel magico mondo della cultura, ha una parlantina veloce, ridondante, a tratti a scatti, deve essere in grado di reggere un breve monologo parzialmente a braccio. \u00e8 richiesta una almeno minima esperienza interpretativa pregressa, cinema o teatro, anche a livello amatoriale.<br \/>\nUN ATTORE (C) anni: &gt;50 pallido, occhiali dalle spesse lenti con la spessa montatura, un intellettuale di dubbio gusto, capelli grassi, sulla scena d\u00e0 un senso di sporco\/trasandato \u00e8 richiesta una almeno minima esperienza interpretativa pregressa, cinema o teatro, anche a livello amatoriale.<\/p>\n<p>Le scene vengono girate a Torino, tra giugno e luglio prossimi, ambientate ai giorni nostri: gli abiti sono quelli del quotidiano di ognuno di noi, con eventuali integrazioni fornite per l\u2019occasione dalla produzione.<\/p>\n<p>Si prevede un impegno di<br \/>\n1 sessione di riprese (mattino o pomeriggio) per ATTORE C e ATTORE B<br \/>\n7-8 sessioni di riprese (tra mattini e\/o pomeriggi) per ATTRICE e ATTORE A<\/p>\n<p>Il calendario dei set verr\u00e0 concordato in funzione delle disponibilit\u00e0 di tutti, attori compresi, preferibilmente durante i week-end o comunque al di fuori di normali impegni di lavoro.<\/p>\n<p>Si cercano inoltre comparse, senza vincoli di alcun genere, purch\u00e9 maggiorenni, anche senza alcun tipo di esperienza pregressa. Viene richiesta la disponibilit\u00e0 per 1-2 sessioni di mezza giornata.<\/p>\n<p>Riferimento per presentare le proprie candidature per le posizioni elencate:<br \/>\nDaniele D\u2019Antonio lacabinadellartediffusa@gmail.com oppure con messaggio privato alla <a href=\"https:\/\/www.facebook.com\/badnightcafe\">pagina FB Trib\u00f9 del Badnightcaf\u00e8<\/a> indicando generalit\u00e0, indirizzo di posta elettronica, un telefono, e alcune note descrittive, con foto.<br \/>\nData, ora e luogo del provino verranno comunicati ai candidati con apposito contatto diretto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019associazione Culturale senza fini di lucro Trib\u00f9 del Badnightcaf\u00e8 con il presente annuncio pubblico avvia le selezioni per la composizione del cast di un film indipendente di immediata realizzazione. Il film verr\u00e0 girato a<\/p>\n","protected":false},"author":34,"featured_media":3636,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[1185],"class_list":["post-3635","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casting","tag-tribu-del-badnightcafe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Casting, si cercano attori, attrici e comparse per un film sulla Cabina dell&#039;Arte Diffusa - Cabiria<\/title>\n<meta name=\"description\" content=\"trib\u00f9 del badnightcaf\u00e8\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casting, si cercano attori, attrici e comparse per un film sulla Cabina dell&#039;Arte Diffusa - Cabiria\" \/>\n<meta property=\"og:description\" content=\"trib\u00f9 del badnightcaf\u00e8\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-14T09:55:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/06\/cabina-arte-diffusa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Casting, si cercano attori, attrici e comparse per un film sulla Cabina dell&#8217;Arte Diffusa\",\"datePublished\":\"2017-06-14T09:55:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\\\/\"},\"wordCount\":578,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2017\\\/06\\\/cabina-arte-diffusa.jpg\",\"keywords\":[\"trib\u00f9 del badnightcaf\u00e8\"],\"articleSection\":[\"casting\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\\\/\",\"name\":\"Casting, si cercano attori, attrici e comparse per un film sulla Cabina dell'Arte Diffusa - Cabiria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2017\\\/06\\\/cabina-arte-diffusa.jpg\",\"datePublished\":\"2017-06-14T09:55:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"trib\u00f9 del badnightcaf\u00e8\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2017\\\/06\\\/cabina-arte-diffusa.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2017\\\/06\\\/cabina-arte-diffusa.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casting, si cercano attori, attrici e comparse per un film sulla Cabina dell&#8217;Arte Diffusa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casting, si cercano attori, attrici e comparse per un film sulla Cabina dell'Arte Diffusa - Cabiria","description":"trib\u00f9 del badnightcaf\u00e8","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\/","og_locale":"it_IT","og_type":"article","og_title":"Casting, si cercano attori, attrici e comparse per un film sulla Cabina dell'Arte Diffusa - Cabiria","og_description":"trib\u00f9 del badnightcaf\u00e8","og_url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2017-06-14T09:55:36+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/06\/cabina-arte-diffusa.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Casting, si cercano attori, attrici e comparse per un film sulla Cabina dell&#8217;Arte Diffusa","datePublished":"2017-06-14T09:55:36+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\/"},"wordCount":578,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/06\/cabina-arte-diffusa.jpg","keywords":["trib\u00f9 del badnightcaf\u00e8"],"articleSection":["casting"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\/","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\/","name":"Casting, si cercano attori, attrici e comparse per un film sulla Cabina dell'Arte Diffusa - Cabiria","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/06\/cabina-arte-diffusa.jpg","datePublished":"2017-06-14T09:55:36+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"trib\u00f9 del badnightcaf\u00e8","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/06\/cabina-arte-diffusa.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/06\/cabina-arte-diffusa.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/casting-si-cercano-attori-attrici-comparse-un-film-sulla-cabina-dellarte-diffusa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"Casting, si cercano attori, attrici e comparse per un film sulla Cabina dell&#8217;Arte Diffusa"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/3635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=3635"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/3635\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/3636"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=3635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=3635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=3635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}