{"id":3589,"date":"2017-05-29T10:16:32","date_gmt":"2017-05-29T10:16:32","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/cabiria\/?p=3589"},"modified":"2017-05-29T10:16:32","modified_gmt":"2017-05-29T10:16:32","slug":"lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\/","title":{"rendered":"Il Lovers Film Festival lancia la borsa Querelle per autori under 40 con Salone del Libro e Torino Film Lab"},"content":{"rendered":"<p>Il Lovers Film Festival, per la prima volta, lancia la Borsa Querelle, rivolta a giovani autori Under 40 per lo sviluppo di trattamenti originali a tematica LGBTQI.<!--more--><\/p>\n<p>La Borsa \u00e8 un omaggio a Querelle de Brest, romanzo di Jean Genet, pubblicato nel 1947, e all\u2019omonimo film tratto dal libro, ultima pellicola diretta da Rainer Werner Fassbinder, uscito nel 1982. Due opere importanti per la cultura LGBTQI.<\/p>\n<p>L\u2019iniziativa \u00e8 promossa insieme al 30\u00b0 Salone Internazionale del Libro di Torino e al TorinoFilmLab, con la convinzione che la buona scrittura, gi\u00e0 nelle fasi preliminari, costituisca una delle impalcature pi\u00f9 solide per un lavoro cinematografico.<\/p>\n<p>Al vincitore, selezionato da una giuria, sar\u00e0 assegnata una borsa del valore di 3000 euro, offerti dal Salone del Libro come contributo allo sviluppo del trattamento in forma di sceneggiatura, alla quale saranno poi assicurati visibilit\u00e0 e incontri con professionisti all\u2019interno della 33a edizione di Lovers Film Festival.<\/p>\n<p>Faranno parte della giuria: Irene Dionisio (direttrice del 32\u00b0 Lovers Film Festival), Savina Neirotti (direttrice del TorinoFilmLab), Stefano Boni (responsabile della programmazione del Cinema Massimo) e Nicola Lagioia (direttore editoriale del Salone Internazionale del Libro) e un altro delegato del Salone.<\/p>\n<p>Il bando per la partecipazione sar\u00e0 lanciato il 15 giugno, all&#8217;apertura del Festival. Gli autori interessati dovranno inviare entro il 15 ottobre un trattamento che coinvolga in maniera preponderante personaggi e tematiche LGBTQI.<\/p>\n<p>Entro il 15 ottobre 2017 sar\u00e0 pubblicata una graduatoria. I cinque finalisti, durante il TorinoFilmLab (novembre 2017) affronteranno un colloquio con i membri della giuria e un delegato del Coordinamento Torino Pride, che valuteranno l\u2019originalit\u00e0 delle tracce e la fattibilit\u00e0 del progetto.<\/p>\n<p>Inoltre il Festival, da un\u2019idea dello scrittore Willy Vaira, dedica un riconoscimento alla memoria di Gi\u00f2 Stajano, una delle figure pi\u00f9 importanti e significative della cultura LGBTQI italiana, per troppo tempo passata in secondo piano.<\/p>\n<p>Il premio consiste nella somma di 500 euro, che saranno donati al film, scelto tra tutte le sezioni del programma, individuato dal comitato di selezione del festival e da Willy Vaira.<\/p>\n<p>Gi\u00f2 Stajano, nata Gioacchino Stajano, fu il primo omosessuale pubblicamente dichiarato in Italia e il primo scrittore italiano a dare alle stampe, nel 1959, un romanzo a tematica LGBTQI, Roma capovolta (Quattrucci), che cre\u00f2 scalpore.<\/p>\n<p>Cur\u00f2 due rubriche, sul settimanale \u00abMen\u00bb, che furono a lungo le uniche pagine di cultura gay su un giornale italiano. Nel \u201992 pubblic\u00f2 la sua autobiografia, La mia vita scandalosa (Sperling &amp; Kupfer), cui segu\u00ec, nel 2007, Pubblici scandali e private virt\u00f9 (Manni Editori), con Willy Vaira.<\/p>\n<p>Gi\u00f2 Stajano fu uno dei personaggi pi\u00f9 vivaci della \u201cdolce vita\u201d romana, apprezzata anche da Federico Fellini, e scomparve nel 2011.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Lovers Film Festival, per la prima volta, lancia la Borsa Querelle, rivolta a giovani autori Under 40 per lo sviluppo di trattamenti originali a tematica LGBTQI.<\/p>\n","protected":false},"author":34,"featured_media":3590,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[1177],"class_list":["post-3589","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-festival","tag-lovers-film-fest"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il Lovers Film Festival lancia la borsa Querelle per autori under 40 con Salone del Libro e Torino Film Lab - Cabiria<\/title>\n<meta name=\"description\" content=\"lovers film fest\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/cabiria\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Lovers Film Festival lancia la borsa Querelle per autori under 40 con Salone del Libro e Torino Film Lab - Cabiria\" \/>\n<meta property=\"og:description\" content=\"lovers film fest\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/cabiria\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-29T10:16:32+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/05\/querelle-de-best.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"803\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Il Lovers Film Festival lancia la borsa Querelle per autori under 40 con Salone del Libro e Torino Film Lab\",\"datePublished\":\"2017-05-29T10:16:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\\\/\"},\"wordCount\":442,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2017\\\/05\\\/querelle-de-best.jpg\",\"keywords\":[\"lovers film fest\"],\"articleSection\":[\"festival\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\\\/\",\"name\":\"Il Lovers Film Festival lancia la borsa Querelle per autori under 40 con Salone del Libro e Torino Film Lab - Cabiria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2017\\\/05\\\/querelle-de-best.jpg\",\"datePublished\":\"2017-05-29T10:16:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"lovers film fest\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2017\\\/05\\\/querelle-de-best.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2017\\\/05\\\/querelle-de-best.jpg\",\"width\":1200,\"height\":803},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Lovers Film Festival lancia la borsa Querelle per autori under 40 con Salone del Libro e Torino Film Lab\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Lovers Film Festival lancia la borsa Querelle per autori under 40 con Salone del Libro e Torino Film Lab - Cabiria","description":"lovers film fest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/cabiria\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\/","og_locale":"it_IT","og_type":"article","og_title":"Il Lovers Film Festival lancia la borsa Querelle per autori under 40 con Salone del Libro e Torino Film Lab - Cabiria","og_description":"lovers film fest","og_url":"http:\/\/web.quotidianopiemontese.it\/cabiria\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2017-05-29T10:16:32+00:00","og_image":[{"width":1200,"height":803,"url":"http:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/05\/querelle-de-best.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Il Lovers Film Festival lancia la borsa Querelle per autori under 40 con Salone del Libro e Torino Film Lab","datePublished":"2017-05-29T10:16:32+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\/"},"wordCount":442,"commentCount":0,"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/05\/querelle-de-best.jpg","keywords":["lovers film fest"],"articleSection":["festival"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/cabiria\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\/","url":"http:\/\/web.quotidianopiemontese.it\/cabiria\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\/","name":"Il Lovers Film Festival lancia la borsa Querelle per autori under 40 con Salone del Libro e Torino Film Lab - Cabiria","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\/#primaryimage"},"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/05\/querelle-de-best.jpg","datePublished":"2017-05-29T10:16:32+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"lovers film fest","breadcrumb":{"@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/cabiria\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/05\/querelle-de-best.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/05\/querelle-de-best.jpg","width":1200,"height":803},{"@type":"BreadcrumbList","@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/lovers-film-festival-lancia-la-borsa-querelle-autori-under-40-salone-del-libro-torino-film-lab\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"Il Lovers Film Festival lancia la borsa Querelle per autori under 40 con Salone del Libro e Torino Film Lab"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/3589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=3589"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/3589\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/3590"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=3589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=3589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=3589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}