{"id":3511,"date":"2017-03-20T11:55:12","date_gmt":"2017-03-20T11:55:12","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/cabiria\/?p=3511"},"modified":"2017-03-20T11:55:12","modified_gmt":"2017-03-20T11:55:12","slug":"2-aprile-jane-wants-boyfriend-apre-cinemautismo","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\/","title":{"rendered":"Il 2 aprile Jane Wants a Boyfriend apre cinemAutismo"},"content":{"rendered":"<p>cinemAutismo, la prima rassegna cinematografica italiana dedicata all\u2019autismo e alla sindrome di Asperger, torna anche quest\u2019anno per la sua IX edizione a colorare di blu, colore simbolo dell&#8217;autismo, la citt\u00e0 di Torino con quattro <!--more-->giornate di cinema e incontri, dal 2 al 5 aprile al Cinema Massimo, al Cecchi Point Hub Multiculturale e al Cinema Lux.<\/p>\n<p>Il programma, che propone un\u2019attenta selezione di pellicole tematiche provenienti da tutto il mondo di cui due in anteprima nazionale, \u00e8 curato da Marco Mastino e Ginevra Tomei e organizzato dall\u2019Associazione Museo Nazionale del Cinema, grazie alla collaborazione e al sostegno di Fondazione Paideia Onlus, Gruppo Asperger Onlus e Angsa Piemonte Onlus sez. di al sostegno di Fondazione CRT e di Motore di Ricerca &#8211; Comunit\u00e0 Attiva. Media partnership di Radio Energy e artinmovimento.com<\/p>\n<p>La rassegna inaugurer\u00e0 domenica 2 aprile, Giornata Mondiale della Consapevolezza dell&#8217;Autismo, con una serata in collaborazione con Sottodiciotto Film Festival &amp; Campus. Al pubblico verr\u00e0 presentato in anteprima nazionale il film americano Jane Wants a Boyfriend del regista indipendente di New York William C. Sullivan, commedia romantica con protagonista una giovane ragazza con sindrome di Asperger alla ricerca dell\u2019amore. Il film affronta, caso raro tra le produzioni cinematografiche, il punto di vista femminile, sfatando il mito dell\u2019autismo come sinonimo di isolamento ed evidenziando invece la volont\u00e0 della protagonista di vivere una storia d\u2019amore, con tutte le difficolt\u00e0 e le emozioni che questo comporta (ore 20.30, Cinema Massimo).<\/p>\n<p>La serata di luned\u00ec 3 aprile, vedr\u00e0 protagonista l\u2019acclamato documentario Life, Animated di Roger Ross Williams, vincitore al Sundance Film Festival e candidato agli Oscar di quest\u2019anno. Il film racconta il viaggio verso la vita adulta di Owen, giovane autistico che si relaziona con il mondo attraverso i classici della Walt Disney. Alla serata parteciper\u00e0 Giovanni Morandini, co-autore del documentario radiofonico Alias &#8211; cronache dal pianeta Asperger (ore 20.45, Cinema Massimo).<\/p>\n<p>La terza giornata di marted\u00ec 4 aprile prevede due appuntamenti al Cecchi Point Hub Multiculturale: nel tardo pomeriggio sar\u00e0 presentato il progetto AspieDubProject a cura di Teatro 8 che prevede la proiezione di cortometraggi, gi\u00e0 presentati nelle precedenti edizioni di cinemAutismo, doppiati da ragazzi con sindrome di Asperger. Interverranno i partecipanti del laboratorio (ore 19.00, Cecchi Point). La sera sar\u00e0 la volta di Normal Autistic Film di Miroslav Janek documentario ceco presentato all\u2019ultimo Trieste Film Festival, che racconta la vita quotidiana di alcuni bambini e ragazzi all\u2019interno dello spettro autistico (ore 21.00, Cecchi Point).<\/p>\n<p>Nella serata finale di mercoled\u00ec 5 aprile, la rassegna si chiuder\u00e0 con l\u2019anteprima nazionale del lungometraggio Redha di Tunku Mona Riza, delicato racconto di una famiglia che si confronta con la diagnosi di autismo del figlio. La pellicola malese sar\u00e0 preceduta dal cortometraggio brasiliano Delivery Boy di Vinicius Saramago proveniente dal 4\u00b0 ASFF &#8211; Asperger Film Festival di Roma, primo concorso cinematografico organizzato con la partecipazione di ragazzi con sindrome di Asperger (ore 20.30, Cinema Lux).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>cinemAutismo, la prima rassegna cinematografica italiana dedicata all\u2019autismo e alla sindrome di Asperger, torna anche quest\u2019anno per la sua IX edizione a colorare di blu, colore simbolo dell&#8217;autismo, la citt\u00e0 di Torino con quattro<\/p>\n","protected":false},"author":34,"featured_media":3512,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[387],"class_list":["post-3511","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-festival","tag-cinemautismo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il 2 aprile Jane Wants a Boyfriend apre cinemAutismo - Cabiria<\/title>\n<meta name=\"description\" content=\"cinemautismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il 2 aprile Jane Wants a Boyfriend apre cinemAutismo - Cabiria\" \/>\n<meta property=\"og:description\" content=\"cinemautismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-20T11:55:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/03\/Cinemautismo_Jane-wants-a-boyfriend_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1772\" \/>\n\t<meta property=\"og:image:height\" content=\"997\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Il 2 aprile Jane Wants a Boyfriend apre cinemAutismo\",\"datePublished\":\"2017-03-20T11:55:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\\\/\"},\"wordCount\":487,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2017\\\/03\\\/Cinemautismo_Jane-wants-a-boyfriend_1.jpg\",\"keywords\":[\"cinemautismo\"],\"articleSection\":[\"festival\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\\\/\",\"name\":\"Il 2 aprile Jane Wants a Boyfriend apre cinemAutismo - Cabiria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2017\\\/03\\\/Cinemautismo_Jane-wants-a-boyfriend_1.jpg\",\"datePublished\":\"2017-03-20T11:55:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"cinemautismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2017\\\/03\\\/Cinemautismo_Jane-wants-a-boyfriend_1.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2017\\\/03\\\/Cinemautismo_Jane-wants-a-boyfriend_1.jpg\",\"width\":1772,\"height\":997},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il 2 aprile Jane Wants a Boyfriend apre cinemAutismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il 2 aprile Jane Wants a Boyfriend apre cinemAutismo - Cabiria","description":"cinemautismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cabiria\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\/","og_locale":"it_IT","og_type":"article","og_title":"Il 2 aprile Jane Wants a Boyfriend apre cinemAutismo - Cabiria","og_description":"cinemautismo","og_url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2017-03-20T11:55:12+00:00","og_image":[{"width":1772,"height":997,"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/03\/Cinemautismo_Jane-wants-a-boyfriend_1.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Il 2 aprile Jane Wants a Boyfriend apre cinemAutismo","datePublished":"2017-03-20T11:55:12+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\/"},"wordCount":487,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/03\/Cinemautismo_Jane-wants-a-boyfriend_1.jpg","keywords":["cinemautismo"],"articleSection":["festival"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\/","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\/","name":"Il 2 aprile Jane Wants a Boyfriend apre cinemAutismo - Cabiria","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/03\/Cinemautismo_Jane-wants-a-boyfriend_1.jpg","datePublished":"2017-03-20T11:55:12+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"cinemautismo","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/03\/Cinemautismo_Jane-wants-a-boyfriend_1.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2017\/03\/Cinemautismo_Jane-wants-a-boyfriend_1.jpg","width":1772,"height":997},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/2-aprile-jane-wants-boyfriend-apre-cinemautismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"Il 2 aprile Jane Wants a Boyfriend apre cinemAutismo"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/3511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=3511"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/3511\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/3512"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=3511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=3511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=3511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}