{"id":3148,"date":"2016-11-10T09:31:52","date_gmt":"2016-11-10T09:31:52","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/cabiria\/?p=3148"},"modified":"2016-11-10T09:31:52","modified_gmt":"2016-11-10T09:31:52","slug":"torino-le-giornate-europee-del-cinema-dellaudiovisivo","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\/","title":{"rendered":"A Torino le giornate europee del cinema e dell&#8217;audiovisivo"},"content":{"rendered":"<p>Tornano a Torino le Giornate Europee del Cinema e dell\u2019Audiovisivo, giunte alla loro XIII edizione. Saranno ripartite in quattro fasi nel passaggio 2016-2017, per venire incontro a esigenze editoriali sempre pi\u00f9 variegate: una <!--more-->successione di incontri, workshop, proiezioni e dibattiti professionali dedicati all&#8217;emersione dei media civici e alle proposte di contenuti dirette al pubblico.<\/p>\n<p>Primo passo \u00e8 una giornata di studi sulla storia economica della produzione indie, di cui Torino \u00e8 considerata luogo di nascita. Questo primo evento inizia a canalizzare l\u2019attenzione sul 2019, centenario della fondazione dello Studio Fert di Torino, culla del cinema indipendente italiano ed europeo.<\/p>\n<p>Venerd\u00ec 18 Novembre 2016 dalle ore 10 alle 17.30 &#8220;Storia \u00e8 &#8211; il contributo di Alberto Friedemann alla conoscenza delle radici torinesi del cinema europeo e della sua industria nella Ricerca Storica Fert&#8221;<\/p>\n<p>L&#8217;evento ha luogo nella suggestiva cornice dell\u2019Auditorium Vivaldi della Biblioteca Nazionale Universitaria di Torino. Condotta da Gian Carlo Franceschetti, amico di Alberto e gi\u00e0 Presidente dell&#8217;Associazione F.E.R.T., la giornata \u00e8 dedicata al lavoro del professor Friedemann, ricercatore e studioso del cinema torinese delle origini, e al suo ruolo di formatore. Ogni relatore contribuir\u00e0 a \u201cdipingere un ritratto\u201d della persona e della sua opera, nel ventennale dell\u2019avvio della ricerca storica. Mappe e foto permetteranno di cogliere la dimensione del lavoro e la concreta importanza di Torino e del Piemonte nella produzione cinematografica indipendente, dal primo dopoguerra agli anni &#8217;70.<\/p>\n<p>Agli interventi si alterneranno proiezioni di filmati (restaurati di recente dal Museo Nazionale del Cinema) realizzati da Segundo de Chom\u00f3n nei suoi anni torinesi, accompagnati al pianoforte dal musicista Mario Congiu. La figura pirotecnica di Segundo de Chom\u00f3n regista, sceneggiatore, direttore di fotografia, pioniere del cinema a colori, costruttore di macchine da presa, maestro del cinema di animazione, ma soprattutto inesauribile inventore di trucchi e di effetti speciali \u00e8 delineata in un volume delle edizioni storiche Fert: &#8220;Manuale tecnico per visionari. Segundo de Chom\u00f3n in Italia 1912-1925&#8221;.<\/p>\n<p>A corollario della giornata del 18 novembre, l&#8217;omaggio ad Alberto Friedemann prosegue nel quartiere Campidoglio di Torino, con una serie di serate. La scelta della Circoscrizione 4 non \u00e8 casuale: essa fu sede, nel periodo del cinema muto, di alcuni teatri di posa e stabilimenti di sviluppo e stampa, la cui attivit\u00e0 \u00e8 stata oggetto di ricerca e pubblicazione nel volume &#8220;Stabilimenti e teatri di posa&#8221; della collana \u201cAppunti\u201d Fert. Alberto ha inoltre abitato nel quartiere per pi\u00f9 di trenta anni. Gian Carlo Franceschetti, che ha accompagnato il professor Friedemann per l&#8217;intero lavoro, a partire dai volumi della collana Biblioteca Fert, illustrer\u00e0 i contenuti della ricerca.<\/p>\n<p>Le Serate di Narrazioni Cinematografiche al Campidoglio, che sono state rese possibili grazie agli aiuti tecnici di Ecomuseo Urbano &#8211; Circoscrizione 4 e del Museo Nazionale del Cinema di Torino, si protrarranno fino a dicembre e prevedono ancora due appuntamenti.<\/p>\n<p>Marted\u00ec 22 novembre 2016 ore 21.00<br \/>\nCollana &#8220;Appunti&#8221; Fert<br \/>\nL\u2019evoluzione della ricerca e il suo ampliamento a comprendere la storia produttiva del cinema muto torinese.<\/p>\n<p>Marted\u00ec 13 dicembre 2016 ore 21.00<br \/>\nCollana &#8220;Documenti&#8221; Fert<br \/>\nLa creazione di un archivio virtuale e i teatri di posa del muto presenti e attivi nella Circoscrizione.<\/p>\n<p>Le serate si svolgeranno nella sede dell&#8217;Ecomuseo Urbano &#8211; Circoscrizione 4 (Via Medici, 28 &#8211; angolo Via Digione), con ingresso libero sino a esaurimento dei posti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tornano a Torino le Giornate Europee del Cinema e dell\u2019Audiovisivo, giunte alla loro XIII edizione. Saranno ripartite in quattro fasi nel passaggio 2016-2017, per venire incontro a esigenze editoriali sempre pi\u00f9 variegate: una<\/p>\n","protected":false},"author":34,"featured_media":3149,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1026],"class_list":["post-3148","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi","tag-giornate-europee-del-cinema-e-dellaudiovisivo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Torino le giornate europee del cinema e dell&#039;audiovisivo - Cabiria<\/title>\n<meta name=\"description\" content=\"giornate europee del cinema e dell&#039;audiovisivo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Torino le giornate europee del cinema e dell&#039;audiovisivo - Cabiria\" \/>\n<meta property=\"og:description\" content=\"giornate europee del cinema e dell&#039;audiovisivo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-10T09:31:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2016\/11\/Alberto-Friedemann2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"966\" \/>\n\t<meta property=\"og:image:height\" content=\"725\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"A Torino le giornate europee del cinema e dell&#8217;audiovisivo\",\"datePublished\":\"2016-11-10T09:31:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\\\/\"},\"wordCount\":544,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2016\\\/11\\\/Alberto-Friedemann2.jpg\",\"keywords\":[\"giornate europee del cinema e dell'audiovisivo\"],\"articleSection\":[\"eventi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\\\/\",\"name\":\"A Torino le giornate europee del cinema e dell'audiovisivo - Cabiria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2016\\\/11\\\/Alberto-Friedemann2.jpg\",\"datePublished\":\"2016-11-10T09:31:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"giornate europee del cinema e dell'audiovisivo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2016\\\/11\\\/Alberto-Friedemann2.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2016\\\/11\\\/Alberto-Friedemann2.jpg\",\"width\":966,\"height\":725},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Torino le giornate europee del cinema e dell&#8217;audiovisivo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Torino le giornate europee del cinema e dell'audiovisivo - Cabiria","description":"giornate europee del cinema e dell'audiovisivo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\/","og_locale":"it_IT","og_type":"article","og_title":"A Torino le giornate europee del cinema e dell'audiovisivo - Cabiria","og_description":"giornate europee del cinema e dell'audiovisivo","og_url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2016-11-10T09:31:52+00:00","og_image":[{"width":966,"height":725,"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2016\/11\/Alberto-Friedemann2.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"A Torino le giornate europee del cinema e dell&#8217;audiovisivo","datePublished":"2016-11-10T09:31:52+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\/"},"wordCount":544,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2016\/11\/Alberto-Friedemann2.jpg","keywords":["giornate europee del cinema e dell'audiovisivo"],"articleSection":["eventi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\/","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\/","name":"A Torino le giornate europee del cinema e dell'audiovisivo - Cabiria","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2016\/11\/Alberto-Friedemann2.jpg","datePublished":"2016-11-10T09:31:52+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"giornate europee del cinema e dell'audiovisivo","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2016\/11\/Alberto-Friedemann2.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2016\/11\/Alberto-Friedemann2.jpg","width":966,"height":725},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/torino-le-giornate-europee-del-cinema-dellaudiovisivo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"A Torino le giornate europee del cinema e dell&#8217;audiovisivo"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/3148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=3148"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/3148\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/3149"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=3148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=3148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=3148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}