{"id":3142,"date":"2016-11-02T10:56:31","date_gmt":"2016-11-02T10:56:31","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/cabiria\/?p=3142"},"modified":"2016-11-02T10:56:31","modified_gmt":"2016-11-02T10:56:31","slug":"dal-4-al-7-novembre-lavori-corto-oltre-muro","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/dal-4-al-7-novembre-lavori-corto-oltre-muro\/","title":{"rendered":"Dal 4 al 7 novembre Lavori in Corto &#8211; Oltre il muro"},"content":{"rendered":"<p>Cinque appuntamenti in cinque diverse location per la quinta edizione di Lavori in Corto, concorso cinematografico nazionale rivolto a giovani registi under 35, organizzato dall\u2019Associazione Museo Nazionale del Cinema (AMNC) e <!--more-->dall\u2019Associazione Riccardo Braghin: un vero e proprio festival a Torino da venerd\u00ec 4 a luned\u00ec 7 novembre.<\/p>\n<p>Sono 24 i CORTOMETRAGGI e i DOCUMENTARI presentati a LAVORI IN CORTO, dei quali 16 IN CONCORSO e 8 FUORI CONCORSO, per un totale di 13 ANTEPRIME (9 in anteprima assoluta, 2 in anteprima nazionale e 2 in anteprima regionale), che declinano il tema di questa edizione, la libert\u00e0 e il carcere, e accendono la riflessione sui diritti. Una manciata di lavori impegnati realizzati da ragazzi di tutta Italia per un\u2019et\u00e0 media di 28 anni.<\/p>\n<p>Il primo appuntamento in programma venerd\u00ec 4 novembre alla Bibliomediateca Mario Gromo sar\u00e0 un omaggio al regista Teo De Luigi, con la proiezione di due documentari seguiti da un dibattito con l&#8217;autore.<\/p>\n<p>Questo il programma completo<\/p>\n<p><iframe loading=\"lazy\" title=\"Programma Lavori in corto 2016\" src=\"https:\/\/www.slideshare.net\/slideshow\/embed_code\/key\/pTOAZ8BCtX2ghi\" width=\"479\" height=\"511\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" style=\"border:1px solid #CCC; border-width:1px; margin-bottom:5px; max-width: 100%;\" allowfullscreen> <\/iframe> <\/p>\n<div style=\"margin-bottom:5px\"> <strong> <a href=\"https:\/\/www.slideshare.net\/quotidianopiemontese\/programma-lavori-in-corto-2016\" title=\"Programma Lavori in corto 2016\" target=\"_blank\">Programma Lavori in corto 2016<\/a> <\/strong> from <strong><a href=\"https:\/\/www.slideshare.net\/quotidianopiemontese\" target=\"_blank\">Quotidiano Piemontese<\/a><\/strong> <\/div>\n<p>I cortometraggi in concorso a LAVORI IN CORTO concorrono per aggiudicarsi i seguenti PREMI:<\/p>\n<p>-PRIMO PREMIO ARMANDO CESTE di 1.000 euro offerto dall\u2019Associazione Sapereplurale e intitolato per il terzo anno ad Armando Ceste, importante autore scomparso nel 2009 che nel corso della sua carriera cinematografica e del suo impegno politico, dalla fondazione del Collettivo Cinema Militante di Torino a Movimento (2008) passando per Liberaterra (2002), ha sempre trattato le questioni sociali affrontate dalle prime quattro edizioni di Lavori in corto (lavoro, immigrazione, inclusione sociale, questioni abitative, movimenti, sogni e bisogni delle nuove generazioni). Dal 2016 \u00e8 attivo il sito web http:\/\/www.armandoceste.it\/;<\/p>\n<p>-PREMIO RAI CINEMA CHANNEL di 1.000 euro offerto da Rai Cinema Channel al corto pi\u00f9 web; il riconoscimento vuole premiare l\u2019efficacia di un racconto che ben si presti ad essere diffuso sui canali web. Il premio consiste in un contratto di acquisto dei diritti del corto, da parte di Rai Cinema e godr\u00e0 della visibilit\u00e0 suwww.raicinemachannel.it e sui siti partner;<\/p>\n<p>-PREMIO eVisioni (4^ edizione) &#8211; I DIRITTI VISTI DA DENTRO di 300 euro erogato dal Polo Universitario della Casa Circondariale Lorusso Cutugno di Torino e assegnato da una Giuria Speciale, composta dagli studenti del carcere di Torino.<\/p>\n<p>-PREMIO RICOMINCIARE di 300 euro offerto dalla rivista nazionale \u201cSicurezza e lavoro\u201d, rivista nazionale per la promozione di salute, sicurezza e diritti nei luoghi di lavoro, al lavoro cinematografico che sapr\u00e0 meglio documentare la situazione e le speranze delle persone detenute ed ex detenute alla ricerca di un\u2019occupazione dignitosa che permetta loro di realizzare il proprio progetto di vita;<\/p>\n<p>-PREMIO DELLA GIURIA consistente in servizi offerti da Film Commission Torino Piemonte (utilizzo di un modulo produttivo della sede di via Cagliari 42 per due settimane).<\/p>\n<p>I premi verranno conferiti nella serata finale di luned\u00ec 7 novembre al Cinema Massimo da una GIURIA presieduta dal regista Davide Ferrario e composta da Ilaria Cucchi, che da anni si batte per fare giustizia sulla morte del fratello; Susanna Ronconi dell&#8217;Associazione Sapereplurale; Gabriella Bodiglio dell&#8217;Associazione Riccardo Braghin; Moritz Ceste, giovane attore; Roberto Agagliate, compositore e musicista, filmmaker e direttore della 1911 Lokomotif Orchestra; Rossella Schillaci, regista di documentari sul tema delle migrazioni e delle identit\u00e0 culturali; Marco Di Castri, filmmaker e musicista, fondatore della casa editrice Cataloga; Paolo Rendina, Avvocato responsabile dello sportello legale Lavoro per \u201cSicurezza e Lavoro\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cinque appuntamenti in cinque diverse location per la quinta edizione di Lavori in Corto, concorso cinematografico nazionale rivolto a giovani registi under 35, organizzato dall\u2019Associazione Museo Nazionale del Cinema (AMNC) e<\/p>\n","protected":false},"author":34,"featured_media":3143,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[262],"tags":[216],"class_list":["post-3142","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concorsi","tag-lavori-in-corto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dal 4 al 7 novembre Lavori in Corto - Oltre il muro - Cabiria<\/title>\n<meta name=\"description\" content=\"lavori in corto\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/dal-4-al-7-novembre-lavori-corto-oltre-muro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dal 4 al 7 novembre Lavori in Corto - Oltre il muro - Cabiria\" \/>\n<meta property=\"og:description\" content=\"lavori in corto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/dal-4-al-7-novembre-lavori-corto-oltre-muro\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-02T10:56:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2016\/11\/LAVORI-IN-CORTO_Awake.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/dal-4-al-7-novembre-lavori-corto-oltre-muro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/dal-4-al-7-novembre-lavori-corto-oltre-muro\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Dal 4 al 7 novembre Lavori in Corto &#8211; Oltre il muro\",\"datePublished\":\"2016-11-02T10:56:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/dal-4-al-7-novembre-lavori-corto-oltre-muro\\\/\"},\"wordCount\":547,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/dal-4-al-7-novembre-lavori-corto-oltre-muro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2016\\\/11\\\/LAVORI-IN-CORTO_Awake.jpg\",\"keywords\":[\"lavori in corto\"],\"articleSection\":[\"concorsi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/dal-4-al-7-novembre-lavori-corto-oltre-muro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/dal-4-al-7-novembre-lavori-corto-oltre-muro\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/dal-4-al-7-novembre-lavori-corto-oltre-muro\\\/\",\"name\":\"Dal 4 al 7 novembre Lavori in Corto - Oltre il muro - Cabiria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/dal-4-al-7-novembre-lavori-corto-oltre-muro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/dal-4-al-7-novembre-lavori-corto-oltre-muro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2016\\\/11\\\/LAVORI-IN-CORTO_Awake.jpg\",\"datePublished\":\"2016-11-02T10:56:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"lavori in corto\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/dal-4-al-7-novembre-lavori-corto-oltre-muro\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/dal-4-al-7-novembre-lavori-corto-oltre-muro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/dal-4-al-7-novembre-lavori-corto-oltre-muro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2016\\\/11\\\/LAVORI-IN-CORTO_Awake.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2016\\\/11\\\/LAVORI-IN-CORTO_Awake.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/dal-4-al-7-novembre-lavori-corto-oltre-muro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dal 4 al 7 novembre Lavori in Corto &#8211; Oltre il muro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dal 4 al 7 novembre Lavori in Corto - Oltre il muro - Cabiria","description":"lavori in corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cabiria\/dal-4-al-7-novembre-lavori-corto-oltre-muro\/","og_locale":"it_IT","og_type":"article","og_title":"Dal 4 al 7 novembre Lavori in Corto - Oltre il muro - Cabiria","og_description":"lavori in corto","og_url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/dal-4-al-7-novembre-lavori-corto-oltre-muro\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2016-11-02T10:56:31+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2016\/11\/LAVORI-IN-CORTO_Awake.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/dal-4-al-7-novembre-lavori-corto-oltre-muro\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/dal-4-al-7-novembre-lavori-corto-oltre-muro\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Dal 4 al 7 novembre Lavori in Corto &#8211; Oltre il muro","datePublished":"2016-11-02T10:56:31+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/dal-4-al-7-novembre-lavori-corto-oltre-muro\/"},"wordCount":547,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/dal-4-al-7-novembre-lavori-corto-oltre-muro\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2016\/11\/LAVORI-IN-CORTO_Awake.jpg","keywords":["lavori in corto"],"articleSection":["concorsi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/dal-4-al-7-novembre-lavori-corto-oltre-muro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/dal-4-al-7-novembre-lavori-corto-oltre-muro\/","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/dal-4-al-7-novembre-lavori-corto-oltre-muro\/","name":"Dal 4 al 7 novembre Lavori in Corto - Oltre il muro - Cabiria","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/dal-4-al-7-novembre-lavori-corto-oltre-muro\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/dal-4-al-7-novembre-lavori-corto-oltre-muro\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2016\/11\/LAVORI-IN-CORTO_Awake.jpg","datePublished":"2016-11-02T10:56:31+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"lavori in corto","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/dal-4-al-7-novembre-lavori-corto-oltre-muro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/dal-4-al-7-novembre-lavori-corto-oltre-muro\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/dal-4-al-7-novembre-lavori-corto-oltre-muro\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2016\/11\/LAVORI-IN-CORTO_Awake.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2016\/11\/LAVORI-IN-CORTO_Awake.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/dal-4-al-7-novembre-lavori-corto-oltre-muro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"Dal 4 al 7 novembre Lavori in Corto &#8211; Oltre il muro"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/3142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=3142"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/3142\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/3143"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=3142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=3142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=3142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}