{"id":3054,"date":"2016-07-28T12:10:47","date_gmt":"2016-07-28T12:10:47","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/cabiria\/?p=3054"},"modified":"2016-07-28T12:10:47","modified_gmt":"2016-07-28T12:10:47","slug":"della-casa-venezia73-perche-un-genio-lorenza-mazzetti","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\/","title":{"rendered":"Della Casa a #Venezia73 con &#8220;Perch\u00e9 sono un genio! Lorenza Mazzetti&#8221;"},"content":{"rendered":"<p>Ci sar\u00e0 anche Steve Della Casa alla Mostra di Arte Cinematografica di Venezia73 (che ricordo \u00e8 diretta da Alberto Barbera), che oggi ha presentato il suo programma. Della Casa sar\u00e0 nella sezione Venezia Classici <!--more-->con \u201cPerch\u00e9 sono un genio! Lorenza Mazzetti\u201d, diretto insieme a Francesco Frisari.<\/p>\n<p>Il documentario di Della Casa &#8211; Frisari ci accompagna nello straordinario mondo di Lorenza alla ricerca di quel \u201cgenio\u201d che brilla nel suo sguardo leggero, fiabesco e profondo con cui si racconta e si muove nella vita di oggi e che anima i suoi film, libri e quadri.<\/p>\n<p>Quella di Lorenza Mazzetti, classe 1927, \u00e8 una vita da film: ancora bambina si ritrova orfana e con la sorella gemella viene adottata da Robert Einstein, cugino di Albert. L\u00ec, nella campagna toscana, vive una tragedia che per anni non riuscir\u00e0 a raccontare, l\u2019uccisione della sua famiglia da parte dei nazisti e che lei stessa riveler\u00e0 solo da adulta nel suo libro \u201cIl cielo cade\u201d. Ad inizio anni \u201950 si trasferisce a Londra per dimenticare, ma l\u00ec si ritrova povera e sola, non si perde per\u00f2 d\u2019animo e riesce ad entrare alla prestigiosa Slade School of Fine Art chiedendo di essere ammessa \u00abPerch\u00e9 sono un genio!\u00bb, una frase chiave per la sua vita su cui ancora oggi continua a scherzare. Qui la fiaba di Lorenza inizia a volgere al meglio: tra rocambolesche avventure, rubando cinepresa e pellicola, si inventa regista e firma, nel 1953, il suo primo film K, tratto da \u201cLa Metamorfosi\u201d di Kafka, grazie al successo del quale realizza il suo secondo filmTogether nel 1956. I registi Lindsay Anderson, Tony Richardson, Karel Reisz si innamorano del suo approccio filmico tra neorealismo e poesia e, con lei, scrivono il manifesto del Free Cinema, un cinema \u201clibero\u201d, opposto e antagonista alla produzione media inglese e attento a quanto stava accadendo nella societ\u00e0: una presa di posizione che diede il via a un vero e proprio movimento politico, estetico e culturale di rinnovamento che toccher\u00e0, per gemmazione spontanea, tutte le cinematografie pi\u00f9 importanti. Con Together, la storia di due operai sordomuti in una Londra bombardata dai nazisti, Lorenza va al festival di Cannes dove si aggiudica un premio e conosce Zavattini che le propone di collaborare. Torna in Italia e scrive \u201cIl cielo cade\u201d, il diario divertente e tragico di una bambina che racconta in modo spiazzante il fascismo, la guerra e quanto le era successo, un libro che le far\u00e0 vincere il Premio Viareggio nel 1962 e che da cinquant\u2019anni continua a venire ristampato. Inizia a collaborare con Vie Nuove, il settimanale del PCI, dove stringe amicizia con Pier Paolo Pasolini, continua a scrivere libri, dirige a Roma il Puppet Theatre e si dedica, con successo, anche alla pittura, fino a pubblicare nel 2014 con Sellerio\u201cDiario Londinese\u201d, il racconto dei suoi anni giovanili nella capitale inglese.<\/p>\n<p>In \u201cPerch\u00e9 sono un genio! Lorenza Mazzetti\u201d \u00e8 Lorenza stessa a raccontarsi, mentre ci accompagna nei luoghi del suo passato e nella vita di oggi, con la gemella Paola e il suo mondo fatto di incontri e ricordi, sempre con la libert\u00e0 all\u2019infanzia addosso. Con le sue parole, la partecipazione degli amici Bernardo Bertolucci, Malcolm McDowell e David Grieco, le immagini dei suoi film e di quelle del Free Cinema e le animazioni dei suoi quadri, \u201cPerch\u00e9 sono un genio! Lorenza Mazzetti\u201d racconta una vita che \u00e8 un\u2019unica, personale opera d\u2019arte.<\/p>\n<p>Una produzione Tangram Film, prodotto da Carolina Levi in associazione con Francesca Padula; regia di Steve Della Casa e Francesco Frisari; scritto da Emanuela Del Monaco e Francesco Frisari; con Lorenza Mazzetti, Bernardo Bertolucci, Malcolm McDowell, David Grieco, Paola Mazzetti, Dante Morganti; montaggio Alice Roffinengo; fotografia e riprese Martina Cocco; animazioni Fiammetta Horvat; Suono Paolo Testa; musica originale Ratchev &amp; Carratello; materiali foto e video di Repertorio: British Film Institute National Archive, archivio Storico Luce e archivio Lorenza Mazzetti; distribuzione Italia Home Video Cinecitt\u00e0 Istituto Luce. Film riconosciuto di interesse culturale con contributo economico del Ministero dei Beni e delle Attivit\u00e0 Culturali e del Turismo-Direzione Generale per il Cinema e sostenuto dal British Film Institute (BFI). (Italia, 2016, 62\u2019).<\/p>\n<p>La casa editrice La nave di Teseo di Elisabetta Sgarbi ristamper\u00e0, in autunno, alcuni dei libri di Lorenza Mazzetti.<\/p>\n<p>Lorenza Mazzetti ha ricevuto il Premio Maria Adriana Prolo alla carriera allo scorso Torino Film Festival.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ci sar\u00e0 anche Steve Della Casa alla Mostra di Arte Cinematografica di Venezia73 (che ricordo \u00e8 diretta da Alberto Barbera), che oggi ha presentato il suo programma. Della Casa sar\u00e0 nella sezione Venezia Classici<\/p>\n","protected":false},"author":34,"featured_media":3055,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[813,364],"class_list":["post-3054","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-festival","tag-lorenza-mazzetti","tag-steve-della-casa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Della Casa a Venezia73 con &quot;Perch\u00e9 sono un genio! Lorenza Mazzetti&quot;<\/title>\n<meta name=\"description\" content=\"Ci sar\u00e0 anche Steve Della Casa alla Mostra di Arte Cinematografica di Venezia73, che oggi ha presentato il suo programma.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Della Casa a #Venezia73 con &quot;Perch\u00e9 sono un genio! Lorenza Mazzetti&quot;\" \/>\n<meta property=\"og:description\" content=\"Ci sar\u00e0 anche Steve Della Casa alla Mostra di Arte Cinematografica di Venezia73 (che ricordo \u00e8 diretta da Alberto Barbera), che oggi ha presentato il suo programma.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-28T12:10:47+00:00\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Della Casa a #Venezia73 con &#8220;Perch\u00e9 sono un genio! Lorenza Mazzetti&#8221;\",\"datePublished\":\"2016-07-28T12:10:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\\\/\"},\"wordCount\":721,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2016\\\/07\\\/Perche\u0300-sono-un-genio-di-Della-Casa-e-Frisari_nella-foto-Lorenza-Mazzetti_1.jpg\",\"keywords\":[\"lorenza mazzetti\",\"Steve Della Casa\"],\"articleSection\":[\"festival\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\\\/\",\"name\":\"Della Casa a Venezia73 con \\\"Perch\u00e9 sono un genio! Lorenza Mazzetti\\\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2016\\\/07\\\/Perche\u0300-sono-un-genio-di-Della-Casa-e-Frisari_nella-foto-Lorenza-Mazzetti_1.jpg\",\"datePublished\":\"2016-07-28T12:10:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"Ci sar\u00e0 anche Steve Della Casa alla Mostra di Arte Cinematografica di Venezia73, che oggi ha presentato il suo programma.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2016\\\/07\\\/Perche\u0300-sono-un-genio-di-Della-Casa-e-Frisari_nella-foto-Lorenza-Mazzetti_1.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2016\\\/07\\\/Perche\u0300-sono-un-genio-di-Della-Casa-e-Frisari_nella-foto-Lorenza-Mazzetti_1.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Della Casa a #Venezia73 con &#8220;Perch\u00e9 sono un genio! Lorenza Mazzetti&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Della Casa a Venezia73 con \"Perch\u00e9 sono un genio! Lorenza Mazzetti\"","description":"Ci sar\u00e0 anche Steve Della Casa alla Mostra di Arte Cinematografica di Venezia73, che oggi ha presentato il suo programma.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cabiria\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\/","og_locale":"it_IT","og_type":"article","og_title":"Della Casa a #Venezia73 con \"Perch\u00e9 sono un genio! Lorenza Mazzetti\"","og_description":"Ci sar\u00e0 anche Steve Della Casa alla Mostra di Arte Cinematografica di Venezia73 (che ricordo \u00e8 diretta da Alberto Barbera), che oggi ha presentato il suo programma.","og_url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2016-07-28T12:10:47+00:00","author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Della Casa a #Venezia73 con &#8220;Perch\u00e9 sono un genio! Lorenza Mazzetti&#8221;","datePublished":"2016-07-28T12:10:47+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\/"},"wordCount":721,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2016\/07\/Perche\u0300-sono-un-genio-di-Della-Casa-e-Frisari_nella-foto-Lorenza-Mazzetti_1.jpg","keywords":["lorenza mazzetti","Steve Della Casa"],"articleSection":["festival"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\/","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\/","name":"Della Casa a Venezia73 con \"Perch\u00e9 sono un genio! Lorenza Mazzetti\"","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2016\/07\/Perche\u0300-sono-un-genio-di-Della-Casa-e-Frisari_nella-foto-Lorenza-Mazzetti_1.jpg","datePublished":"2016-07-28T12:10:47+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"Ci sar\u00e0 anche Steve Della Casa alla Mostra di Arte Cinematografica di Venezia73, che oggi ha presentato il suo programma.","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2016\/07\/Perche\u0300-sono-un-genio-di-Della-Casa-e-Frisari_nella-foto-Lorenza-Mazzetti_1.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2016\/07\/Perche\u0300-sono-un-genio-di-Della-Casa-e-Frisari_nella-foto-Lorenza-Mazzetti_1.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/della-casa-venezia73-perche-un-genio-lorenza-mazzetti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"Della Casa a #Venezia73 con &#8220;Perch\u00e9 sono un genio! Lorenza Mazzetti&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/3054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=3054"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/3054\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/3055"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=3054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=3054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=3054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}