{"id":3048,"date":"2016-07-19T05:21:11","date_gmt":"2016-07-19T05:21:11","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/cabiria\/?p=3048"},"modified":"2016-07-19T05:21:11","modified_gmt":"2016-07-19T05:21:11","slug":"aperte-le-iscrizioni-lavori-corto-2016-oltre-muro","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\/","title":{"rendered":"Aperte le iscrizioni a Lavori in Corto 2016 &#8211; oltre il muro"},"content":{"rendered":"<p>L&#8217;Associazione Museo Nazionale del Cinema e l&#8217;Associazione Riccardo Braghin presentano la quinta edizione del bando del concorso cinematografico nazionale LAVORI IN CORTO 2016, rivolto a giovani <!--more-->registi interessati al tema della libert\u00e0 e del carcere. L\u2019obiettivo di LAVORI IN CORTO 2016 \u00e8 accendere la riflessione, attraverso le immagini in movimento, sui diritti e le condizioni di vita in carcere raccontando storie ed esperienze di segregazione, inclusione e reclusione sociale.<\/p>\n<p>Il bando di LAVORI IN CORTO &#8211; concorso cinematografico nazionale per cortometraggi e documentari, rivolto ad autori under 35 residenti sul territorio nazionale, curato e coordinato da Valentina D&#8217;Amelio &#8211; \u00e8 aperto fino al 30 settembre.<\/p>\n<p>Il progetto del concorso continua, giunto alla sua quinta edizione, a svolgere la sua mission: la volont\u00e0 di sensibilizzare e porre l\u2019attenzione su temi di rilevanza sociale attraverso le immagini e le storie dei lavori in concorso. Oltre il muro \u00e8 il sottotitolo scelto per questa edizione: in un mondo di frontiere sempre pi\u00f9 invalicabili, di barriere sempre pi\u00f9 alte che dividono il dentro dal fuori, LAVORI IN CORTO sceglie di interrogarsi sul vero significato della libert\u00e0, uno dei diritti fondamentali dell&#8217;individuo, invitando i giovani filmmakers a ragionare su un tema di ampio afflato, confrontabile con altri momenti storici e contesti sociali, non solo nazionali.<br \/>\nA LAVORI IN CORTO possono partecipare autori che non abbiano compiuto 35 anni alla data della scadenza del bando con opere di finzione o documentarie di massimo 30 minuti realizzate dopo il primo gennaio 2012; gli over 35 e i film sopra i 30 minuti potranno partecipare nella sezione Fuori Concorso.I lavori selezionati saranno presentati al pubblico a novembre presso gli spazi della rete delle Case del Quartiere di Torino e al Cinema Massimo per la premiazione finale in programma luned\u00ec 7 novembre.<\/p>\n<p>I PREMI di LAVORI IN CORTO:<\/p>\n<p>Primo premio di 1000 Euro, offerto dall\u2019Associazione Sapereplurale e intitolato per il terzo anno ad Armando Ceste, importante autore scomparso nel 2009 che nel corso della sua carriera cinematografica e del suo impegno politico, dalla fondazione del Collettivo Cinema Militante di Torino a Movimento (2008) passando per Liberaterra (2002), ha sempre trattato le questioni sociali affrontate dalle prime tre edizioni di Lavori in corto (lavoro, immigrazione, inclusione sociale, questioni abitative, movimenti). Dal 2016 \u00e8 attivo il sito web http:\/\/www.armandoceste.it\/;<\/p>\n<p>Premio Rai Cinema Channel di 1000 Euro, offerto da Rai Cinema al corto pi\u00f9 web; il riconoscimento vuole premiare l\u2019efficacia di un racconto che ben si presti ad essere diffuso sui canali web. Il premio consiste in un contratto di acquisto dei diritti del corto, da parte di Rai Cinema e godr\u00e0 della visibilit\u00e0 su www.raicinemachannel.it. e sui suoi siti partner;<\/p>\n<p>Premio \u201cRicominciare\u201d di 300 Euro offerto da Sicurezza e Lavoro, rivista nazionale per la promozione di salute, sicurezza e diritti nei luoghi di lavoro. Il premio verr\u00e0 assegnato al lavoro cinematografico che sapr\u00e0 meglio documentare la situazione e le speranze delle persone detenute ed ex detenute alla ricerca di un\u2019occupazione dignitosa che permetta loro di realizzare il proprio progetto di vita;<\/p>\n<p>Premio Film Commission Torino Piemonte che consistente nell&#8217;utilizzo di un modulo produttivo della sede di via Cagliari per due settimane.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Associazione Museo Nazionale del Cinema e l&#8217;Associazione Riccardo Braghin presentano la quinta edizione del bando del concorso cinematografico nazionale LAVORI IN CORTO 2016, rivolto a giovani<\/p>\n","protected":false},"author":34,"featured_media":3049,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[767,262],"tags":[216],"class_list":["post-3048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi","category-concorsi","tag-lavori-in-corto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aperte le iscrizioni a Lavori in Corto 2016 - oltre il muro<\/title>\n<meta name=\"description\" content=\"L&#039;Associazione Museo Nazionale del Cinema e l&#039;Associazione Riccardo Braghin presentano la quinta edizione del bando del concorso cinematografico nazionale LAVORI IN CORTO 2016\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aperte le iscrizioni a Lavori in Corto 2016 - oltre il muro\" \/>\n<meta property=\"og:description\" content=\"L&#039;Associazione Museo Nazionale del Cinema e l&#039;Associazione Riccardo Braghin presentano la quinta edizione del bando del concorso cinematografico nazionale LAVORI IN CORTO 2016\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-19T05:21:11+00:00\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Aperte le iscrizioni a Lavori in Corto 2016 &#8211; oltre il muro\",\"datePublished\":\"2016-07-19T05:21:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\\\/\"},\"wordCount\":526,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2016\\\/07\\\/lavorincorto-bansky.jpg\",\"keywords\":[\"lavori in corto\"],\"articleSection\":[\"bandi\",\"concorsi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\\\/\",\"name\":\"Aperte le iscrizioni a Lavori in Corto 2016 - oltre il muro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2016\\\/07\\\/lavorincorto-bansky.jpg\",\"datePublished\":\"2016-07-19T05:21:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"L'Associazione Museo Nazionale del Cinema e l'Associazione Riccardo Braghin presentano la quinta edizione del bando del concorso cinematografico nazionale LAVORI IN CORTO 2016\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2016\\\/07\\\/lavorincorto-bansky.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2016\\\/07\\\/lavorincorto-bansky.jpg\",\"width\":778,\"height\":486},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aperte le iscrizioni a Lavori in Corto 2016 &#8211; oltre il muro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aperte le iscrizioni a Lavori in Corto 2016 - oltre il muro","description":"L'Associazione Museo Nazionale del Cinema e l'Associazione Riccardo Braghin presentano la quinta edizione del bando del concorso cinematografico nazionale LAVORI IN CORTO 2016","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cabiria\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\/","og_locale":"it_IT","og_type":"article","og_title":"Aperte le iscrizioni a Lavori in Corto 2016 - oltre il muro","og_description":"L'Associazione Museo Nazionale del Cinema e l'Associazione Riccardo Braghin presentano la quinta edizione del bando del concorso cinematografico nazionale LAVORI IN CORTO 2016","og_url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2016-07-19T05:21:11+00:00","author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Aperte le iscrizioni a Lavori in Corto 2016 &#8211; oltre il muro","datePublished":"2016-07-19T05:21:11+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\/"},"wordCount":526,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2016\/07\/lavorincorto-bansky.jpg","keywords":["lavori in corto"],"articleSection":["bandi","concorsi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\/","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\/","name":"Aperte le iscrizioni a Lavori in Corto 2016 - oltre il muro","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2016\/07\/lavorincorto-bansky.jpg","datePublished":"2016-07-19T05:21:11+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"L'Associazione Museo Nazionale del Cinema e l'Associazione Riccardo Braghin presentano la quinta edizione del bando del concorso cinematografico nazionale LAVORI IN CORTO 2016","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2016\/07\/lavorincorto-bansky.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2016\/07\/lavorincorto-bansky.jpg","width":778,"height":486},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/aperte-le-iscrizioni-lavori-corto-2016-oltre-muro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"Aperte le iscrizioni a Lavori in Corto 2016 &#8211; oltre il muro"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/3048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=3048"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/3048\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/3049"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=3048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=3048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=3048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}