{"id":2427,"date":"2015-07-14T14:09:34","date_gmt":"2015-07-14T14:09:34","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/cabiria\/?p=2427"},"modified":"2015-07-14T14:09:34","modified_gmt":"2015-07-14T14:09:34","slug":"gaglianone-presenta-la-mia-classe-a-palazzo-reale","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\/","title":{"rendered":"Gaglianone presenta La mia classe a Palazzo Reale"},"content":{"rendered":"<p>Ci sar\u00e0 il regista Daniele Gaglianone a presentare il suo film &#8220;La mia classe&#8221; mercoled\u00ec 15 luglio nel cortile di Palazzo Reale a Torino.<\/p>\n<p>Il film verr\u00e0 proiettato all&#8217;interno della rassegna &#8220;Cinema a Palazzo&#8221; con inizio alle ore 22.00.<!--more--><\/p>\n<blockquote><p>&#8220;La mia classe&#8221; vede protagonista un attore (Mastrandrea) che \u00e8 maestro e insegna in una classe, reale, di extracomunitari che vogliono imparare l&#8217;italiano per avere il permesso di soggiorno e per integrarsi nella societ\u00e0 italiana. A un certo punto il regista d\u00e0 lo &#8220;stop&#8221; alle riprese: tutta la troupe diventa una cosa sola con la storia del film.<\/p>\n<p>L\u2019idea, particolarissima, che gioca con il fatto stesso di fare cinema, \u00e8 nata da Claudia Russo e Gino Clemente, coautori della sceneggiatura insieme al regista, sulla falsariga di \u201cDiario di un maestro\u201d di Vittorio De Seta. Un po\u2019 film, un po\u2019 documentario, con il set che entra ed esce dal campo per marcare il territorio delle scene in costruzione, \u201cLa mia classe\u201d parla e riflette su immigrazione, integrazione ma finisce con l\u2019interrogarsi sul senso stesso del cinema.<\/p><\/blockquote>\n<p>Il costo del biglietto intero \u00e8 di 5,50 euro. Ridotto per universitari e i proprietari della Tessera Torino Musei a 5 euro. Gli over 65 pagano 4 euro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ci sar\u00e0 il regista Daniele Gaglianone a presentare il suo film &#8220;La mia classe&#8221; mercoled\u00ec 15 luglio nel cortile di Palazzo Reale a Torino. Il film verr\u00e0 proiettato all&#8217;interno della rassegna &#8220;Cinema a Palazzo&#8221; con inizio alle ore 22.00.<\/p>\n","protected":false},"author":34,"featured_media":2428,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[104,238,770,75],"class_list":["post-2427","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi","tag-cinema-a-palazzo","tag-daniele-gaglianone","tag-la-mia-classe","tag-valerio-mastrandrea"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gaglianone presenta La mia classe a Palazzo Reale - Cabiria<\/title>\n<meta name=\"description\" content=\"cinema a palazzo, Daniele Gaglianone, la mia classe, valerio mastrandrea\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/cabiria\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gaglianone presenta La mia classe a Palazzo Reale - Cabiria\" \/>\n<meta property=\"og:description\" content=\"cinema a palazzo, Daniele Gaglianone, la mia classe, valerio mastrandrea\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/cabiria\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-14T14:09:34+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2015\/07\/Valerio-Mastandrea-La-mia-Classe-di-Daniele-Gaglianone.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Gaglianone presenta La mia classe a Palazzo Reale\",\"datePublished\":\"2015-07-14T14:09:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\\\/\"},\"wordCount\":205,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2015\\\/07\\\/Valerio-Mastandrea-La-mia-Classe-di-Daniele-Gaglianone.jpg\",\"keywords\":[\"cinema a palazzo\",\"Daniele Gaglianone\",\"la mia classe\",\"valerio mastrandrea\"],\"articleSection\":[\"eventi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\\\/\",\"name\":\"Gaglianone presenta La mia classe a Palazzo Reale - Cabiria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2015\\\/07\\\/Valerio-Mastandrea-La-mia-Classe-di-Daniele-Gaglianone.jpg\",\"datePublished\":\"2015-07-14T14:09:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"cinema a palazzo, Daniele Gaglianone, la mia classe, valerio mastrandrea\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2015\\\/07\\\/Valerio-Mastandrea-La-mia-Classe-di-Daniele-Gaglianone.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2015\\\/07\\\/Valerio-Mastandrea-La-mia-Classe-di-Daniele-Gaglianone.jpg\",\"width\":800,\"height\":478},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gaglianone presenta La mia classe a Palazzo Reale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gaglianone presenta La mia classe a Palazzo Reale - Cabiria","description":"cinema a palazzo, Daniele Gaglianone, la mia classe, valerio mastrandrea","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/cabiria\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\/","og_locale":"it_IT","og_type":"article","og_title":"Gaglianone presenta La mia classe a Palazzo Reale - Cabiria","og_description":"cinema a palazzo, Daniele Gaglianone, la mia classe, valerio mastrandrea","og_url":"http:\/\/web.quotidianopiemontese.it\/cabiria\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2015-07-14T14:09:34+00:00","og_image":[{"width":800,"height":478,"url":"http:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2015\/07\/Valerio-Mastandrea-La-mia-Classe-di-Daniele-Gaglianone.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Gaglianone presenta La mia classe a Palazzo Reale","datePublished":"2015-07-14T14:09:34+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\/"},"wordCount":205,"commentCount":0,"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2015\/07\/Valerio-Mastandrea-La-mia-Classe-di-Daniele-Gaglianone.jpg","keywords":["cinema a palazzo","Daniele Gaglianone","la mia classe","valerio mastrandrea"],"articleSection":["eventi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/cabiria\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\/","url":"http:\/\/web.quotidianopiemontese.it\/cabiria\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\/","name":"Gaglianone presenta La mia classe a Palazzo Reale - Cabiria","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\/#primaryimage"},"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2015\/07\/Valerio-Mastandrea-La-mia-Classe-di-Daniele-Gaglianone.jpg","datePublished":"2015-07-14T14:09:34+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"cinema a palazzo, Daniele Gaglianone, la mia classe, valerio mastrandrea","breadcrumb":{"@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/cabiria\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2015\/07\/Valerio-Mastandrea-La-mia-Classe-di-Daniele-Gaglianone.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2015\/07\/Valerio-Mastandrea-La-mia-Classe-di-Daniele-Gaglianone.jpg","width":800,"height":478},{"@type":"BreadcrumbList","@id":"http:\/\/web.quotidianopiemontese.it\/cabiria\/gaglianone-presenta-la-mia-classe-a-palazzo-reale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"Gaglianone presenta La mia classe a Palazzo Reale"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/2427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=2427"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/2427\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/2428"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=2427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=2427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=2427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}