{"id":2389,"date":"2015-06-05T07:04:15","date_gmt":"2015-06-05T07:04:15","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/cabiria\/?p=2389"},"modified":"2015-06-05T07:04:16","modified_gmt":"2015-06-05T07:04:16","slug":"questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\/","title":{"rendered":"Questa estate ad Alpignano si va al cinema al castello&#8230; e pure gratis"},"content":{"rendered":"<p>Estate di cinema gratuito ad Alpignano, nell&#8217;affascinante cornice del castello dei Provana di Lein\u00ec, eccezionalmente aperto al pubblico grazie grazie all\u2019accordo con i Missionari della Consolata.<\/p>\n<p><a href=\"http:\/\/www.quotidianopiemontese.it\/cabiria\/2015\/06\/05\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\/i_pinguini_madagascar\/\" rel=\"attachment wp-att-2390\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-2390\" src=\"http:\/\/www.quotidianopiemontese.it\/cabiria\/files\/2015\/06\/i_pinguini_madagascar-500x400.jpg\" alt=\"i_pinguini_madagascar\" width=\"500\" height=\"400\" srcset=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2015\/06\/i_pinguini_madagascar-500x400.jpg 500w, https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2015\/06\/i_pinguini_madagascar-1024x819.jpg 1024w, https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2015\/06\/i_pinguini_madagascar.jpg 1280w\" sizes=\"auto, (max-width: 500px) 85vw, 500px\" \/><\/a><br \/>\nLa rassegna si chiama \u201cNotti di cinema al castello\u201d e sar\u00e0 ad ingresso gratuito. L\u2019appuntamento \u00e8 tutti i venerd\u00ec e i sabato sera, alle 21,45, con una pausa solo per il Palio dij Coss\u00f2t e per la Festa del Peperoncino.<\/p>\n<p>Questo il programma (che bisogna dire \u00e8 davvero di alto livello)<!--more--><\/p>\n<p>12 giugno<br \/>\nConfusi e felici di M. Bruno<\/p>\n<p>13 giugno<br \/>\nI pinguini di Madagascar di E. Darnell<\/p>\n<p>19 giugno<br \/>\nMagic in the Moonlight di W. Allen<\/p>\n<p>20 giugno<br \/>\nQuasi famosi di C. Crowe<\/p>\n<p>3 luglio<br \/>\nPaddington di P. King<\/p>\n<p>4 luglio<br \/>\nSi accettano miracoli di A. Siani<\/p>\n<p>10 luglio<br \/>\nAmore, cucina e curry di L. Hallstr\u00f6m<\/p>\n<p>11 luglio<br \/>\nPasolini di A. Ferrara<\/p>\n<p>24 luglio<br \/>\nTrash di Stephen Daldry<\/p>\n<p>25 luglio<br \/>\nAndiamo a quel paese di S. Ficarra, V. Picone<\/p>\n<p>31 luglio<br \/>\nI nostri ragazzi di I. De Matteo<\/p>\n<p>1 agosto<br \/>\nIl ricco il povero il maggiordomo di A. Baglio, G. Storti, G. Poretti<\/p>\n<p>7 agosto<br \/>\nBoyhood di R. Linklater<\/p>\n<p>8 agosto<br \/>\nBirdman di A. I\u00f1\u00e1rritu<\/p>\n<p>14 agosto<br \/>\nSoap opera di A. Genovesi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estate di cinema gratuito ad Alpignano, nell&#8217;affascinante cornice del castello dei Provana di Lein\u00ec, eccezionalmente aperto al pubblico grazie grazie all\u2019accordo con i Missionari della Consolata. La rassegna si chiama \u201cNotti di cinema al castello\u201d e sar\u00e0 ad ingresso gratuito. L\u2019appuntamento \u00e8 tutti i venerd\u00ec e i sabato sera, alle 21,45, con una pausa solo &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Questa estate ad Alpignano si va al cinema al castello&#8230; e pure gratis&#8221;<\/span><\/a><\/p>\n","protected":false},"author":34,"featured_media":2390,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[758,759],"class_list":["post-2389","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi","tag-alpignano","tag-rassegna-estiva"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Questa estate ad Alpignano si va al cinema al castello... e pure gratis - Cabiria<\/title>\n<meta name=\"description\" content=\"alpignano, rassegna estiva\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Questa estate ad Alpignano si va al cinema al castello... e pure gratis - Cabiria\" \/>\n<meta property=\"og:description\" content=\"alpignano, rassegna estiva\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-05T07:04:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-06-05T07:04:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2015\/06\/i_pinguini_madagascar.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Questa estate ad Alpignano si va al cinema al castello&#8230; e pure gratis\",\"datePublished\":\"2015-06-05T07:04:15+00:00\",\"dateModified\":\"2015-06-05T07:04:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\\\/\"},\"wordCount\":200,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2015\\\/06\\\/i_pinguini_madagascar.jpg\",\"keywords\":[\"alpignano\",\"rassegna estiva\"],\"articleSection\":[\"eventi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\\\/\",\"name\":\"Questa estate ad Alpignano si va al cinema al castello... e pure gratis - Cabiria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2015\\\/06\\\/i_pinguini_madagascar.jpg\",\"datePublished\":\"2015-06-05T07:04:15+00:00\",\"dateModified\":\"2015-06-05T07:04:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"alpignano, rassegna estiva\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2015\\\/06\\\/i_pinguini_madagascar.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2015\\\/06\\\/i_pinguini_madagascar.jpg\",\"width\":1280,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Questa estate ad Alpignano si va al cinema al castello&#8230; e pure gratis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Questa estate ad Alpignano si va al cinema al castello... e pure gratis - Cabiria","description":"alpignano, rassegna estiva","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cabiria\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\/","og_locale":"it_IT","og_type":"article","og_title":"Questa estate ad Alpignano si va al cinema al castello... e pure gratis - Cabiria","og_description":"alpignano, rassegna estiva","og_url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2015-06-05T07:04:15+00:00","article_modified_time":"2015-06-05T07:04:16+00:00","og_image":[{"width":1280,"height":1024,"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2015\/06\/i_pinguini_madagascar.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Questa estate ad Alpignano si va al cinema al castello&#8230; e pure gratis","datePublished":"2015-06-05T07:04:15+00:00","dateModified":"2015-06-05T07:04:16+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\/"},"wordCount":200,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2015\/06\/i_pinguini_madagascar.jpg","keywords":["alpignano","rassegna estiva"],"articleSection":["eventi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\/","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\/","name":"Questa estate ad Alpignano si va al cinema al castello... e pure gratis - Cabiria","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2015\/06\/i_pinguini_madagascar.jpg","datePublished":"2015-06-05T07:04:15+00:00","dateModified":"2015-06-05T07:04:16+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"alpignano, rassegna estiva","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2015\/06\/i_pinguini_madagascar.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2015\/06\/i_pinguini_madagascar.jpg","width":1280,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/questa-estate-ad-alpignano-si-va-al-cinema-al-castello-e-pure-gratis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"Questa estate ad Alpignano si va al cinema al castello&#8230; e pure gratis"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/2389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=2389"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/2389\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/2390"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=2389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=2389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=2389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}