{"id":1959,"date":"2014-11-14T11:21:32","date_gmt":"2014-11-14T11:21:32","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/cabiria\/?p=1959"},"modified":"2014-11-14T11:21:39","modified_gmt":"2014-11-14T11:21:39","slug":"25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\/","title":{"rendered":"Il 25 e 26 novembre &#8220;Michael Jackson &#8211; life, death and legacy&#8221; arriva al cinema &#8211; le sale in Piemonte che lo proiettano"},"content":{"rendered":"<p><strong>Michael Jackson &#8211; life, death and legacy<\/strong>, il film sulla vita di Michael Jackson, arriva al cinema. 250 sale in tutta Italia, ma per soli due giorni. Il 25 e il 26 novembre. Se volete vederlo quindi non c&#8217;\u00e8 tempo da perdere. Qui di seguito le sale in Piemonte che lo proietteranno.<\/p>\n<p><a href=\"http:\/\/www.quotidianopiemontese.it\/cabiria\/2014\/11\/14\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\/michael-jackson\/\" rel=\"attachment wp-att-1960\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-1960\" src=\"http:\/\/www.quotidianopiemontese.it\/cabiria\/files\/2014\/11\/Michael-Jackson-Life-Death-and-Legacy-500x325.jpg\" alt=\"Michael Jackson\" width=\"500\" height=\"325\" srcset=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2014\/11\/Michael-Jackson-Life-Death-and-Legacy-500x325.jpg 500w, https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2014\/11\/Michael-Jackson-Life-Death-and-Legacy-1024x667.jpg 1024w\" sizes=\"auto, (max-width: 500px) 85vw, 500px\" \/><\/a><!--more--><br \/>\nTORINO Cinema Greenwich Village (25 novembre)<br \/>\nTORINO Cinema Fratelli Marx (25 e 26 novembre)<br \/>\nTORINO Uci Cinemas Lingotto (25 e 26 novembre)<br \/>\nTORINO The Space Cinema (eccezionalmente il 27 novembre)<br \/>\nMONCALIERI Uci Cinemas (25 e 26 novembre)<br \/>\nBEINASCO The Space Cinema (eccezionalmente il 27 novembre)<br \/>\nIVREA Cinema Politeama (25 e 26 novembre)<br \/>\nALESSANDRIA Uci Cinemas (25 e 26 novembre)<br \/>\nBELLINZAGO NOVARESE Movie Planet (25 e 26 novembre)<br \/>\nBORGOMANERO Cinema Nuovo (25 novembre)<br \/>\nBORGO VERCELLI Movie Planet (25 e 26 novembre)<br \/>\nBRA Impero (25 novembre)<br \/>\nFOSSANO Cinema Teatro I Portici (25 e 26 novembre)<\/p>\n<blockquote><p>Grazie al lavoro della regista Maureen Goldthorpe, arriva in PIEMONTE uno straordinario tributo al Re del Pop, Michael Jackson, alla sua vita e all\u2019eredit\u00e0 artistica che ha lasciato dopo la sua morte prematura, avvenuta nel 2009 e ricordata con un funerale seguito da centinaia di milioni di spettatori in tutto il mondo.<br \/>\nTestimonianze inedite di coloro che hanno lavorato con Michael Jackson, amici, familiari e giornalisti, accompagnate da commoventi ricordi, si alternano a nuovi e mai visti filmati che lo ritraggono nella sua brillante quotidianit\u00e0 e alle emozionanti esibizioni che lo hanno reso uno degli artisti di maggiore successo e pi\u00f9 amati dell\u2019era moderna, in grado di ispirare milioni di fan in tutto il mondo.<br \/>\nIl film permette di riascoltare tutti i suoi brani pi\u00f9 celebri e amati: da I Want You Back, inciso con i Jackson Five quando era ancora un bambino; la popolarit\u00e0 da solista ottenuta con il brano Don&#8217;t Stop &#8216;til You Get Enough; per arrivare al successo planetario raggiunto grazie a canzoni come Thriller e Billie Jean; fino alle conferme di Bad e Black or White, solo per citare alcuni dei classici presenti in Michael Jackson: Life, Death and Legacy.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Michael Jackson &#8211; life, death and legacy, il film sulla vita di Michael Jackson, arriva al cinema. 250 sale in tutta Italia, ma per soli due giorni. Il 25 e il 26 novembre. Se volete vederlo quindi non c&#8217;\u00e8 tempo da perdere. Qui di seguito le sale in Piemonte che lo proietteranno.<\/p>\n","protected":false},"author":34,"featured_media":1960,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[597,596],"class_list":["post-1959","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi","tag-death-and-legacy","tag-michael-jackson-life"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il 25 e 26 novembre &quot;Michael Jackson - life, death and legacy&quot; arriva al cinema - le sale in Piemonte che lo proiettano - Cabiria<\/title>\n<meta name=\"description\" content=\"death and legacy, Michael Jackson - life\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il 25 e 26 novembre &quot;Michael Jackson - life, death and legacy&quot; arriva al cinema - le sale in Piemonte che lo proiettano - Cabiria\" \/>\n<meta property=\"og:description\" content=\"death and legacy, Michael Jackson - life\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2014-11-14T11:21:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-11-14T11:21:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2014\/11\/Michael-Jackson-Life-Death-and-Legacy.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3057\" \/>\n\t<meta property=\"og:image:height\" content=\"1992\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Il 25 e 26 novembre &#8220;Michael Jackson &#8211; life, death and legacy&#8221; arriva al cinema &#8211; le sale in Piemonte che lo proiettano\",\"datePublished\":\"2014-11-14T11:21:32+00:00\",\"dateModified\":\"2014-11-14T11:21:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\\\/\"},\"wordCount\":338,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2014\\\/11\\\/Michael-Jackson-Life-Death-and-Legacy.jpg\",\"keywords\":[\"death and legacy\",\"Michael Jackson - life\"],\"articleSection\":[\"eventi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\\\/\",\"name\":\"Il 25 e 26 novembre \\\"Michael Jackson - life, death and legacy\\\" arriva al cinema - le sale in Piemonte che lo proiettano - Cabiria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2014\\\/11\\\/Michael-Jackson-Life-Death-and-Legacy.jpg\",\"datePublished\":\"2014-11-14T11:21:32+00:00\",\"dateModified\":\"2014-11-14T11:21:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"death and legacy, Michael Jackson - life\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2014\\\/11\\\/Michael-Jackson-Life-Death-and-Legacy.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2014\\\/11\\\/Michael-Jackson-Life-Death-and-Legacy.jpg\",\"width\":3057,\"height\":1992},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il 25 e 26 novembre &#8220;Michael Jackson &#8211; life, death and legacy&#8221; arriva al cinema &#8211; le sale in Piemonte che lo proiettano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il 25 e 26 novembre \"Michael Jackson - life, death and legacy\" arriva al cinema - le sale in Piemonte che lo proiettano - Cabiria","description":"death and legacy, Michael Jackson - life","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cabiria\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\/","og_locale":"it_IT","og_type":"article","og_title":"Il 25 e 26 novembre \"Michael Jackson - life, death and legacy\" arriva al cinema - le sale in Piemonte che lo proiettano - Cabiria","og_description":"death and legacy, Michael Jackson - life","og_url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2014-11-14T11:21:32+00:00","article_modified_time":"2014-11-14T11:21:39+00:00","og_image":[{"width":3057,"height":1992,"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2014\/11\/Michael-Jackson-Life-Death-and-Legacy.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Il 25 e 26 novembre &#8220;Michael Jackson &#8211; life, death and legacy&#8221; arriva al cinema &#8211; le sale in Piemonte che lo proiettano","datePublished":"2014-11-14T11:21:32+00:00","dateModified":"2014-11-14T11:21:39+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\/"},"wordCount":338,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2014\/11\/Michael-Jackson-Life-Death-and-Legacy.jpg","keywords":["death and legacy","Michael Jackson - life"],"articleSection":["eventi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\/","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\/","name":"Il 25 e 26 novembre \"Michael Jackson - life, death and legacy\" arriva al cinema - le sale in Piemonte che lo proiettano - Cabiria","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2014\/11\/Michael-Jackson-Life-Death-and-Legacy.jpg","datePublished":"2014-11-14T11:21:32+00:00","dateModified":"2014-11-14T11:21:39+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"death and legacy, Michael Jackson - life","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2014\/11\/Michael-Jackson-Life-Death-and-Legacy.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2014\/11\/Michael-Jackson-Life-Death-and-Legacy.jpg","width":3057,"height":1992},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/25-26-novembre-michael-jackson-life-death-and-legacy-arriva-cinema-sale-in-piemonte-proiettano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"Il 25 e 26 novembre &#8220;Michael Jackson &#8211; life, death and legacy&#8221; arriva al cinema &#8211; le sale in Piemonte che lo proiettano"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/1959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=1959"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/1959\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/1960"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=1959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=1959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=1959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}