{"id":1233,"date":"2012-12-27T11:29:43","date_gmt":"2012-12-27T11:29:43","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/cabiria\/?p=1233"},"modified":"2012-12-27T11:29:55","modified_gmt":"2012-12-27T11:29:55","slug":"cosa-vorrei-dal-tff-di-paolo-virzi","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/cosa-vorrei-dal-tff-di-paolo-virzi\/","title":{"rendered":"Cosa vorrei dal TFF di Paolo Virz\u00ec"},"content":{"rendered":"<p>Cos\u00ec <a href=\"http:\/\/www.quotidianopiemontese.it\/2012\/12\/21\/paolo-virzi-e-il-nuovo-direttore-del-torino-film-festival\/\" target=\"_blank\">sar\u00e0 <strong>Paolo Virz\u00ec<\/strong><\/a> il direttore del Torino Film Festival del prossimo anno, immagino affiancato da <strong>Emanuela Martini<\/strong> (che <a title=\"E se fosse Emanuela Martini il nuovo direttore del Torino Film Festival?\" href=\"http:\/\/www.quotidianopiemontese.it\/cabiria\/2012\/12\/12\/e-se-fosse-emanuela-martini-il-nuovo-direttore-del-torino-film-festival\/\">a me sembrava la soluzione ideale<\/a> vista la situazione) e da tutta la squadra (su questo non mi sembra di aver letto conferme ma era una delle richieste fondamentali del MNC).<\/p>\n<p>Ora, <em>Virz\u00ec<\/em> \u00e8 un regista che ha fatto cose molto buone dietro la macchina da presa ma come sapete questo poco conta nella direzione di un festival, quello che conta \u00e8 avere una grande passione quando ci si siede davanti allo schermo.<\/p>\n<p><a href=\"http:\/\/www.quotidianopiemontese.it\/cabiria\/2012\/12\/27\/cosa-vorrei-dal-tff-di-paolo-virzi\/paolo-virzi-tff\/\" rel=\"attachment wp-att-1234\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-1234\" alt=\"paolo-virz\u00ec-tff\" src=\"http:\/\/www.quotidianopiemontese.it\/cabiria\/files\/2012\/12\/paolo-virz\u00ec-tff-500x333.jpg\" width=\"500\" height=\"333\" srcset=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2012\/12\/paolo-virz\u00ec-tff-500x333.jpg 500w, https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2012\/12\/paolo-virz\u00ec-tff.jpg 638w\" sizes=\"auto, (max-width: 500px) 85vw, 500px\" \/><\/a><\/p>\n<p>Non so se Virz\u00ec sia un cinefilo appassionato (immagino di si, perch\u00e8 nonostante tutto mi fido di chi lavora dietro le quinte del cinema torinese), so per\u00f2 che conosce abbastanza il Torino Film Festival perch\u00e8 ogni tanto da queste parti l&#8217;abbiamo visto nel corso degli anni.<br \/>\nE sappiamo bene (questo \u00e8 il primo punto dei miei consigli al nuovo direttore &#8211; mi azzardo solo perch\u00e8 <a href=\"https:\/\/twitter.com\/PaoloVirz\/status\/282843712831234048\" target=\"_blank\">l&#8217;ha chiesto lui<\/a>) come questo sia il punto fondamentale perch\u00e8 il TFF ha immenso bisogno di mantenere la sua identit\u00e0 di ricerca, di sperimentazione, di qualit\u00e0.<!--more--><\/p>\n<p>Tra gli aspetti meno positivi della nomina di Virz\u00ec c&#8217;\u00e8 il fatto che il suo non \u00e8 certo un nome di rilevanza internazionale paragonabile a quelli dei suoi due augusti predecessori (ne converr\u00e0 egli stesso). Questo vuol dire che il potere d&#8217;acquisto sui distributori internazionali \u00e8 un po&#8217; diminuito, ma confido che ormai le conoscenze buone le abbia la Martini e soprattutto che basti il nome del TFF per creare appeal sufficiente a concedere un film.<\/p>\n<p>Passiamo alla <em>wish-list<\/em>.<br \/>\nVorrei un TFF che mantenesse la sua linea storica, che puntasse tutto sulla qualit\u00e0, sulla ricerca, sui bei film e nulla sul red carpet. Da sempre a Torino i registi si incontrano al caff\u00e8 sorseggiando un bicerin tutti incappottati e non si guardano sfilare dietro alle transenne infreddoliti in abiti di gala.<br \/>\nSostanzialmente vorrei vedere film che difficilmante potrei vedere in altro modo.<\/p>\n<p>Vorrei che fosse mantenuto il Gran Premio Torino (che \u00e8 un&#8217;idea buona gi\u00e0 solo perch\u00e8 porta il nome della citt\u00e0) ma soprattutto vorrei che fosse mantenuto il Premio Cipputi che \u00e8 parte integrante dell&#8217;anima del TFF.<\/p>\n<p>Vorrei che non si perdessero di vista i documentari, che per anni si sono visti solo a Torino e solo ultimamente hanno trovato un loro spazio anche altrove.<\/p>\n<p>Vorrei che la personale non fosse su un grosso nome conosciuto da tutti ma su un nome che in Italia pochi conoscono.<\/p>\n<p>Vorrei vedere (come sempre) un bel po&#8217; di horror (e mi sa che a quello ci pensa la Martini) e parecchia sperimentazione estrema.<\/p>\n<p>Vorrei che rimanesse vivo il <em>Film Lab<\/em> e prendesse nuova linfa quel bello spazio dedicato ai distributori che ha funzionato bene due o tre anni fa.<\/p>\n<p>Vorrei poi che la citt\u00e0 fosse maggiormente coinvolta, che il TFF diventasse davvero un tutt&#8217;uno con Torino, un simbolo riconosciuto nel mondo.<\/p>\n<p>Vorrei anche per\u00f2 che Virz\u00ec ci mettesse la firma su questo Festival, per non passare come una meteora o peggio un prestanome. Ed allora spetta a lui inventarsi qualcosa di nuovo, una sezione, un premio, un concorso, un evento parallelo&#8230; qualcosa che poi vorremo conservare negli anni prossimi e poter dire: questo se l&#8217;era inventato Virz\u00ec.<\/p>\n<p>Naturalmente c&#8217;\u00e8 la curiosit\u00e0 di vedere cosa ne verr\u00e0 fuori (ricordandosi sempre che i fondi a disposizione sono irrisori) e altrettanto naturalmente ne approfitto per fare il mio personale in bocca al lupo a Paolo Virz\u00ec, invitandolo a non perdere la pazienza quando dovr\u00e0 scontrarsi con i politici locali, a non farsi impressionare, a non piegare la testa&#8230; ma lui \u00e8 livornese, in queste cose sar\u00e0 un maestro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cos\u00ec sar\u00e0 Paolo Virz\u00ec il direttore del Torino Film Festival del prossimo anno, immagino affiancato da Emanuela Martini (che a me sembrava la soluzione ideale vista la situazione) e da tutta la squadra (su questo non mi sembra di aver letto conferme ma era una delle richieste fondamentali del MNC). Ora, Virz\u00ec \u00e8 un regista &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/cosa-vorrei-dal-tff-di-paolo-virzi\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Cosa vorrei dal TFF di Paolo Virz\u00ec&#8221;<\/span><\/a><\/p>\n","protected":false},"author":34,"featured_media":1234,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[367,25],"class_list":["post-1233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-festival","tag-paolo-virzi","tag-tff"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cosa vorrei dal TFF di Paolo Virz\u00ec - Cabiria<\/title>\n<meta name=\"description\" content=\"paolo virz\u00ec, tff\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/cosa-vorrei-dal-tff-di-paolo-virzi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cosa vorrei dal TFF di Paolo Virz\u00ec - Cabiria\" \/>\n<meta property=\"og:description\" content=\"paolo virz\u00ec, tff\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/cosa-vorrei-dal-tff-di-paolo-virzi\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2012-12-27T11:29:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-12-27T11:29:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2012\/12\/paolo-virz\u00ec-tff.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"638\" \/>\n\t<meta property=\"og:image:height\" content=\"425\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/cosa-vorrei-dal-tff-di-paolo-virzi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/cosa-vorrei-dal-tff-di-paolo-virzi\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Cosa vorrei dal TFF di Paolo Virz\u00ec\",\"datePublished\":\"2012-12-27T11:29:43+00:00\",\"dateModified\":\"2012-12-27T11:29:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/cosa-vorrei-dal-tff-di-paolo-virzi\\\/\"},\"wordCount\":612,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/cosa-vorrei-dal-tff-di-paolo-virzi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2012\\\/12\\\/paolo-virz\u00ec-tff.jpg\",\"keywords\":[\"paolo virz\u00ec\",\"tff\"],\"articleSection\":[\"festival\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/cosa-vorrei-dal-tff-di-paolo-virzi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/cosa-vorrei-dal-tff-di-paolo-virzi\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/cosa-vorrei-dal-tff-di-paolo-virzi\\\/\",\"name\":\"Cosa vorrei dal TFF di Paolo Virz\u00ec - Cabiria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/cosa-vorrei-dal-tff-di-paolo-virzi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/cosa-vorrei-dal-tff-di-paolo-virzi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2012\\\/12\\\/paolo-virz\u00ec-tff.jpg\",\"datePublished\":\"2012-12-27T11:29:43+00:00\",\"dateModified\":\"2012-12-27T11:29:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"paolo virz\u00ec, tff\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/cosa-vorrei-dal-tff-di-paolo-virzi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/cosa-vorrei-dal-tff-di-paolo-virzi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/cosa-vorrei-dal-tff-di-paolo-virzi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2012\\\/12\\\/paolo-virz\u00ec-tff.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2012\\\/12\\\/paolo-virz\u00ec-tff.jpg\",\"width\":638,\"height\":425},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/cosa-vorrei-dal-tff-di-paolo-virzi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cosa vorrei dal TFF di Paolo Virz\u00ec\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cosa vorrei dal TFF di Paolo Virz\u00ec - Cabiria","description":"paolo virz\u00ec, tff","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cabiria\/cosa-vorrei-dal-tff-di-paolo-virzi\/","og_locale":"it_IT","og_type":"article","og_title":"Cosa vorrei dal TFF di Paolo Virz\u00ec - Cabiria","og_description":"paolo virz\u00ec, tff","og_url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/cosa-vorrei-dal-tff-di-paolo-virzi\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2012-12-27T11:29:43+00:00","article_modified_time":"2012-12-27T11:29:55+00:00","og_image":[{"width":638,"height":425,"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2012\/12\/paolo-virz\u00ec-tff.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/cosa-vorrei-dal-tff-di-paolo-virzi\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/cosa-vorrei-dal-tff-di-paolo-virzi\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Cosa vorrei dal TFF di Paolo Virz\u00ec","datePublished":"2012-12-27T11:29:43+00:00","dateModified":"2012-12-27T11:29:55+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/cosa-vorrei-dal-tff-di-paolo-virzi\/"},"wordCount":612,"commentCount":1,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/cosa-vorrei-dal-tff-di-paolo-virzi\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2012\/12\/paolo-virz\u00ec-tff.jpg","keywords":["paolo virz\u00ec","tff"],"articleSection":["festival"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/cosa-vorrei-dal-tff-di-paolo-virzi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/cosa-vorrei-dal-tff-di-paolo-virzi\/","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/cosa-vorrei-dal-tff-di-paolo-virzi\/","name":"Cosa vorrei dal TFF di Paolo Virz\u00ec - Cabiria","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/cosa-vorrei-dal-tff-di-paolo-virzi\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/cosa-vorrei-dal-tff-di-paolo-virzi\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2012\/12\/paolo-virz\u00ec-tff.jpg","datePublished":"2012-12-27T11:29:43+00:00","dateModified":"2012-12-27T11:29:55+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"paolo virz\u00ec, tff","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/cosa-vorrei-dal-tff-di-paolo-virzi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/cosa-vorrei-dal-tff-di-paolo-virzi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/cosa-vorrei-dal-tff-di-paolo-virzi\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2012\/12\/paolo-virz\u00ec-tff.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2012\/12\/paolo-virz\u00ec-tff.jpg","width":638,"height":425},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/cosa-vorrei-dal-tff-di-paolo-virzi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"Cosa vorrei dal TFF di Paolo Virz\u00ec"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/1233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=1233"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/1233\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/1234"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=1233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=1233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=1233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}