{"id":1005,"date":"2012-06-18T12:39:46","date_gmt":"2012-06-18T12:39:46","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/cabiria\/?p=1005"},"modified":"2012-06-18T14:41:02","modified_gmt":"2012-06-18T14:41:02","slug":"intervista-con-maxi-dejoie-seconda-parte","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/cabiria\/intervista-con-maxi-dejoie-seconda-parte\/","title":{"rendered":"Intervista con Max\u00ec Dejoie &#8211; seconda parte"},"content":{"rendered":"<p><em>Leggi <a href=\"http:\/\/www.quotidianopiemontese.it\/cabiria\/2012\/06\/18\/contribuisci-alla-realizzazione-di-5-il-doc-sul-quinto-direttorato-di-maxi-dejoie-intervista\/\">la prima parte dell&#8217;intervista con Max\u00ec Dejoie<\/a> per capire da cosa nasce l&#8217;idea di realizzare Five, il documentario sul Quinto Direttorato del KGB.<\/em><\/p>\n<p><a href=\"http:\/\/www.quotidianopiemontese.it\/cabiria\/2012\/06\/18\/intervista-con-maxi-dejoie-seconda-parte\/five-kgb\/\" rel=\"attachment wp-att-1007\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1007\" src=\"http:\/\/www.quotidianopiemontese.it\/cabiria\/files\/2012\/06\/five-kgb-500x375.jpg\" alt=\"\" width=\"500\" height=\"375\" srcset=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2012\/06\/five-kgb-500x375.jpg 500w, https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2012\/06\/five-kgb.jpg 600w\" sizes=\"auto, (max-width: 500px) 85vw, 500px\" \/><\/a><\/p>\n<p><strong>3. Il titolo del film, Five, richiama direttamente il quinto direttorato ma ha anche un riferimento alla struttura che vuoi dare al documentario.<\/strong><\/p>\n<p>Il titolo Five (o ???? in russo) \u00e8 riferito sia al quinto direttorato del KGB, su cui il documentario si concentrer\u00e0, sia alla struttura del film, che sar\u00e0 suddiviso in cinque parti. Il primo obiettivo del mio prossimo viaggio a Vilnius sar\u00e0 quello di identificare 5 persone che mi racconteranno la loro storia. Ogni storia, ogni segmento, verr\u00e0 trattato in modo diverso, e conto di utilizzare strumenti diversi per ottenere effetti diversi. <!--more-->Strumenti come il reportage, la ricostruzione di uno scenario in forma di fiction (quindi con degli attori) o l\u2019animazione. Ovviamente nel corso di produzione del film molte cose potranno cambiare, ma al momento questo \u00e8 il mio piano.<\/p>\n<p><strong>4. L&#8217;idea ti \u00e8 venuta durante un viaggio a Vilnius, in Lituania. Cosa hai visto che ti ha spinto ad intraprendere quest&#8217; avventura?<\/strong><strong><!--more--><\/strong><\/p>\n<p>Mi trovavo a Vilnius in occasione del Kino Pavasaris, il Vilnius Film Festival, dove ho avuto il piacere di presentare <em><a href=\"http:\/\/www.soloparolesparse.com\/2011\/11\/thff11-the-gerber-syndrome-come-si-fa-un-mockumentary\/\" target=\"_blank\">The Gerber Syndrome<\/a><\/em>. Durante la mia settimana di permanenza, lo staff del festival (straordinariamente cordiale e disponibile) mi ha portato in visita dei luoghi di maggior interesse della citt\u00e0. Uno degli ultimi giorni, Virginija Vareikyte (con cui sono rimasto in contatto e che \u00e8 diventata la mia principale collaboratrice nella realizzazione di questo documentario) mi ha proposto di visitare il Museo della Resistenza e del Genocidio Lituano, che si trova nell\u2019ex sede del KGB a Vilnius. Nel seminterrato dell\u2019edificio (un bel palazzo in stile Barocco che non lascia minimamente immaginare cosa contenesse) si trova l\u2019ex prigione del KGB che \u00e8 rimasta esattamente come \u00e8 stata lasciata dagli ufficiali sovietici nel 1991. Quella visita, guidata da una straordinaria guida locale, \u00e8 stata un\u2019esperienza terrificante ma affascinante. Nel corso della visita siamo passati attraverso le celle in cui venivano tenuti i detenuti, ogni cella con strumenti differenti ma tutte con lo stesso obiettivo: spezzare la volont\u00e0 e il fisico dei suoi inquilini. Non saprei descrivere l\u2019atmosfera che si respirava in quei corridoi, ma vi assicuro che \u00e8 stata un\u2019esperienza notevole.<br \/>\nConsiglio una visita al <a href=\"www.genocid.lt\" target=\"_blank\">sito del museo<\/a>.<\/p>\n<p><strong>5. Per realizzare il progetto hai aperto un crowdfunding su IndieGogo. Perch\u00e9 i futuri spettatori dovrebbero contribuire al documentario? Convincili in poche righe!<\/strong><\/p>\n<p>Penso che il crowd funding non sia soltanto un metodo per trovare fondi, ma anche uno strumento efficace per verificare l\u2019effettivo funzionamento di un progetto o di un\u2019idea.<br \/>\nCi si mette a diretto contatto col pubblico, solo che lo si fa prima di aver realizzato il film. Quindi si \u00e8 ancora nella fase in cui le cose possono essere cambiate e migliorate.<br \/>\nQuesto per quanto riguarda chi il film lo fa. Invece dalla parte del pubblico, penso che sia un\u2019esperienza nuova e stimolante. Per la prima volta si ha la possibilit\u00e0 di prendere parte alla realizzazione di qualcosa in cui si crede, si pu\u00f2 interagire con gli autori, suggerire, supportare. Tutto questo \u00e8 molto bello secondo me. Chiss\u00e0 se un giorno anche le grandi produzioni prenderanno questa strada per realizzare i grossi Blockbusters&#8230;<br \/>\nQuindi, tornando a ????(5): penso che questo sia un progetto importante perch\u00e9 tratta temi che come ho detto prima, sono universali, e toccano ognuno di noi nel profondo. Sono storie che si sono sentite raramente, quindi per molti suoneranno nuove, forse incredibili. Questo potrebbe essere un piccolo contributo ad una causa pi\u00f9 grande: conoscere errori che sono stati fatti nel passato, nella speranza che non si ripetano di nuovo. Per questo invito tutte le persone che leggeranno questa intervista a dare un\u2019occhiata alla pagina <a href=\"http:\/\/www.indiegogo.com\/kgb\">www.indiegogo.com\/kgb<\/a> e a leggerne la presentazione. Se lo riterrete un progetto degno del vostro supporto, contribuire sar\u00e0 molto semplice: basta scegliere l\u2019offerta che volete (1, 10, 50, 100, 500 dollari) e inserire i dati della vostra carta di credito (le transazioni sono gestite da Paypal, quindi la sicurezza \u00e8 garantita). Per ogni offerta viene corrisposto un bonus diverso; sono tutti bonus \u201cattivi\u201d che contribuiranno a farvi sentire parte del progetto. E se non lo riterrete un progetto degno del vostro supporto, nessun problema e amici come prima. Ma io spero che vi piaccia.<\/p>\n<p><em>Vi invito ovviamente ad approfondire il progetto sulla <a href=\"www.indiegogo.com\/kgb\" target=\"_blank\">pagina dedicata su IndieGogo<\/a> e anche ad ascoltare la viva voce di Max\u00ec che lo racconta.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leggi la prima parte dell&#8217;intervista con Max\u00ec Dejoie per capire da cosa nasce l&#8217;idea di realizzare Five, il documentario sul Quinto Direttorato del KGB. 3. Il titolo del film, Five, richiama direttamente il quinto direttorato ma ha anche un riferimento alla struttura che vuoi dare al documentario. Il titolo Five (o ???? in russo) \u00e8 &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/intervista-con-maxi-dejoie-seconda-parte\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Intervista con Max\u00ec Dejoie &#8211; seconda parte&#8221;<\/span><\/a><\/p>\n","protected":false},"author":34,"featured_media":1007,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[297,178],"class_list":["post-1005","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interviste","tag-five","tag-maxi-dejoie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Intervista con Max\u00ec Dejoie - seconda parte - Cabiria<\/title>\n<meta name=\"description\" content=\"five, Max\u00ec Dejoie\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/intervista-con-maxi-dejoie-seconda-parte\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Intervista con Max\u00ec Dejoie - seconda parte - Cabiria\" \/>\n<meta property=\"og:description\" content=\"five, Max\u00ec Dejoie\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/intervista-con-maxi-dejoie-seconda-parte\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabiria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2012-06-18T12:39:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-06-18T14:41:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2012\/06\/five-kgb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/intervista-con-maxi-dejoie-seconda-parte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/intervista-con-maxi-dejoie-seconda-parte\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Intervista con Max\u00ec Dejoie &#8211; seconda parte\",\"datePublished\":\"2012-06-18T12:39:46+00:00\",\"dateModified\":\"2012-06-18T14:41:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/intervista-con-maxi-dejoie-seconda-parte\\\/\"},\"wordCount\":744,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/intervista-con-maxi-dejoie-seconda-parte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2012\\\/06\\\/five-kgb.jpg\",\"keywords\":[\"five\",\"Max\u00ec Dejoie\"],\"articleSection\":[\"interviste\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/intervista-con-maxi-dejoie-seconda-parte\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/intervista-con-maxi-dejoie-seconda-parte\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/intervista-con-maxi-dejoie-seconda-parte\\\/\",\"name\":\"Intervista con Max\u00ec Dejoie - seconda parte - Cabiria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/intervista-con-maxi-dejoie-seconda-parte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/intervista-con-maxi-dejoie-seconda-parte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2012\\\/06\\\/five-kgb.jpg\",\"datePublished\":\"2012-06-18T12:39:46+00:00\",\"dateModified\":\"2012-06-18T14:41:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"five, Max\u00ec Dejoie\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/intervista-con-maxi-dejoie-seconda-parte\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/intervista-con-maxi-dejoie-seconda-parte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/intervista-con-maxi-dejoie-seconda-parte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2012\\\/06\\\/five-kgb.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/files\\\/2012\\\/06\\\/five-kgb.jpg\",\"width\":\"600\",\"height\":\"450\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/intervista-con-maxi-dejoie-seconda-parte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Intervista con Max\u00ec Dejoie &#8211; seconda parte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/\",\"name\":\"Cabiria\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/cabiria\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Intervista con Max\u00ec Dejoie - seconda parte - Cabiria","description":"five, Max\u00ec Dejoie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/cabiria\/intervista-con-maxi-dejoie-seconda-parte\/","og_locale":"it_IT","og_type":"article","og_title":"Intervista con Max\u00ec Dejoie - seconda parte - Cabiria","og_description":"five, Max\u00ec Dejoie","og_url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/intervista-con-maxi-dejoie-seconda-parte\/","og_site_name":"Cabiria","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2012-06-18T12:39:46+00:00","article_modified_time":"2012-06-18T14:41:02+00:00","og_image":[{"width":600,"height":450,"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2012\/06\/five-kgb.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/intervista-con-maxi-dejoie-seconda-parte\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/intervista-con-maxi-dejoie-seconda-parte\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Intervista con Max\u00ec Dejoie &#8211; seconda parte","datePublished":"2012-06-18T12:39:46+00:00","dateModified":"2012-06-18T14:41:02+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/intervista-con-maxi-dejoie-seconda-parte\/"},"wordCount":744,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/intervista-con-maxi-dejoie-seconda-parte\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2012\/06\/five-kgb.jpg","keywords":["five","Max\u00ec Dejoie"],"articleSection":["interviste"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/intervista-con-maxi-dejoie-seconda-parte\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/intervista-con-maxi-dejoie-seconda-parte\/","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/intervista-con-maxi-dejoie-seconda-parte\/","name":"Intervista con Max\u00ec Dejoie - seconda parte - Cabiria","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/intervista-con-maxi-dejoie-seconda-parte\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/intervista-con-maxi-dejoie-seconda-parte\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2012\/06\/five-kgb.jpg","datePublished":"2012-06-18T12:39:46+00:00","dateModified":"2012-06-18T14:41:02+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"five, Max\u00ec Dejoie","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/intervista-con-maxi-dejoie-seconda-parte\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/cabiria\/intervista-con-maxi-dejoie-seconda-parte\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/intervista-con-maxi-dejoie-seconda-parte\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2012\/06\/five-kgb.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/cabiria\/files\/2012\/06\/five-kgb.jpg","width":"600","height":"450"},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/intervista-con-maxi-dejoie-seconda-parte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/cabiria\/"},{"@type":"ListItem","position":2,"name":"Intervista con Max\u00ec Dejoie &#8211; seconda parte"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#website","url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/","name":"Cabiria","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/cabiria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/cabiria\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/cabiria\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/1005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/comments?post=1005"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/posts\/1005\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media\/1007"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/media?parent=1005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/categories?post=1005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/cabiria\/wp-json\/wp\/v2\/tags?post=1005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}